{"id":961,"date":"2010-12-02T23:55:25","date_gmt":"2010-12-02T21:55:25","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=961"},"modified":"2018-12-22T03:12:51","modified_gmt":"2018-12-22T01:12:51","slug":"los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/","title":{"rendered":"\u00abLos Comentarios Reales\u00bb (I-VIII) [Inca Garcilaso de la Vega]"},"content":{"rendered":"<p><strong>PRIMERA PARTE<\/strong><\/p>\n<p><strong>CAP\u00cdTULO VIII<\/strong><\/p>\n<p>LA DESCRIPCI\u00d3N DEL TEMPLO DEL SOL Y SUS GRANDES RIQUEZAS<\/p>\n<p>Uno de los principales \u00eddolos que los reyes Incas y sus vasallos tuvieron fue la imperial ciudad del Cozco, que la adoraban los indios como a cosa sagrada, por haberla fundado el primer Inca Manco C\u00e1pac, y por las innumerables victorias que ella tuvo en las conquistas que hizo, y porque era casa y corte de los Incas sus dioses. De tal manera era su adoraci\u00f3n, que aun en cosas muy menudas la demostraban; que si dos indios de igual condici\u00f3n se topaban en los caminos, el uno que fuese del Cozco y el otro que viniese a \u00e9l, el que iba era respetado y acatado del que ven\u00eda, como superior del inferior, s\u00f3lo por haber estado e ir de la ciudad, cuanto m\u00e1s si era vecino della, y mucho m\u00e1s si era natural. Lo mismo era en las semillas y legumbres, o cualquiera otra cosa que llevasen del Cozco a otras partes; que aunque en la calidad no se aventajase, s\u00f3lo por ser de aquella ciudad era m\u00e1s estimada que las de otras regiones y provincias. De aqu\u00ed se sacar\u00e1 lo que habr\u00eda en cosas mayores. Por tenerla en esta veneraci\u00f3n la ennoblecieron aquellos reyes lo m\u00e1s que pudieron con edificios suntuosos y casas reales, que muchos dellos hicieron para s\u00ed, como en la descripci\u00f3n della diremos que algunas de las casas; entre las cuales, y en la que m\u00e1s se esmeraron, fue la Casa y Templo del Sol, que la adornaron de incre\u00edbles las grandezas de aquella casa, que no me atreviera yo a escribirlas si no las hubieran escrito todos los espa\u00f1oles historiadores del Per\u00fa; ni lo que ellos dicen, ni lo que yo dir\u00e9, alcanza a significar las que fueron. Atribuyen el edificio de aquel templo al rey Inca Yupanqui, abuelo de Huayna C\u00e1pac, no porque \u00e9l lo fundase, que desde el primer Inca qued\u00f3 fundado, sino porque lo acab\u00f3 de ordenar y poner en la riqueza y majestad que los espa\u00f1oles lo hallaron.<\/p>\n<p>Viniendo, pues, a la traza del templo, es de saber que el aposento del Sol era lo que agora es la iglesia del divino Santo Domingo, que por no tener la precisa anchura y largura suya, no la pongo aqu\u00ed; la piedra, en cuanto su tama\u00f1o, vive hoy. Es labrada de canter\u00eda llana, muy prima y pulida.<\/p>\n<p>El altar mayor (dig\u00e1moslo as\u00ed para darnos a entender, aunque aquellos indios no supiesen hacer altar) estaba al Oriente. La techumbre era de madera muy alta, porque tuviese mucha corriente; la cubija fue de paja, porque no alcanzaron a hacer teja. Todas las cuatro paredes del templo estaban cubiertas de arriba abajo de planchas y tablones de oro. En el testero, que llamamos altar mayor, ten\u00edan puesta la figura del Sol, hecha de una plancha de oro, al doble m\u00e1s gruesa que las otras planchas que cubr\u00edan las paredes. La figura estaba hecha con su rostro en redondo, y con sus rayos y llamas de fuego, todo de una pieza, ni m\u00e1s ni menos que la pintan los pintores. Era tan grande, que tomaba todo el testero del templo de pared a pared. No tuvieron los Incas otros \u00eddolos suyos ni ajenos con la imagen del Sol en aquel templo ni otro alguno, porque no adoraban otros sino al Sol, aunque no falta quien diga lo contrario.<\/p>\n<p>Esta figura del Sol cupo en suerte, cuando los espa\u00f1oles entraron en aquella ciudad, a un hombre noble, conquistador de los primeros, llamado Mancio Sierra de Leguizam\u00f3n, que yo conoc\u00ed y dej\u00e9 vivo cuando me vine a Espa\u00f1a, gran jugador de todos los juegos, que con ser tan grande la imagen la jug\u00f3 y perdi\u00f3 en una noche. De donde podremos decir, siguiendo al padre M. Acosta, que naci\u00f3 el refr\u00e1n que dice: \u00abJuega el sol antes que amanezca\u00bb. Despu\u00e9s el tiempo adelante, viendo el cabildo de aquella ciudad cu\u00e1n perdido andaba este su hijo por el juego, por apartarlo d\u00e9l lo eligi\u00f3 un a\u00f1o por alcalde ordinario. El cual acudi\u00f3 al servicio de su patria con tanto cuidado y diligencia (porque ten\u00eda muy buenas partes de caballero), que todo aquel a\u00f1o no tom\u00f3 naipe en la mano. La ciudad, viendo esto, le ocup\u00f3 otro a\u00f1o, y otros muchos en oficios p\u00fablicos. Mancio Sierra, con la ocupaci\u00f3n ordinaria, olvid\u00f3 el juego, y lo aborreci\u00f3 para siempre, acord\u00e1ndose de los muchos trabajos y necesidades en que cada d\u00eda se pon\u00eda. Donde se ve claro cu\u00e1nto ayude la ociosidad al vicio, y cu\u00e1n de provecho sea la ocupaci\u00f3n a la virtud. Volviendo a nuestra historia, decimos que por sola aquella pieza que cupo de parte de un espa\u00f1ol, se podr\u00e1 sacar el tesoro que en aquella ciudad y su templo hallaron los espa\u00f1oles. A un lado y a otro de la imagen del Sol estaban los cuerpos de los reyes muertos puestos por su antig\u00fcedad como hijos de ese Sol, embalsamados que (no se sabe c\u00f3mo) parec\u00edan estar vivos; estaban asentados en sus sillas de oro, puestas sobre los tablones de oro en que sol\u00edan asentarse. Ten\u00edan los rostros hacia el pueblo; s\u00f3lo Huayna C\u00e1pac se aventajaba de los de m\u00e1s, que estaba puesto delante de la figura del Sol, vuelto el rostro hacia \u00e9l, como hijo m\u00e1s querido y amado, por haberse aventajado de los dem\u00e1s; pues mereci\u00f3 que en vida le adorasen por dios por las virtudes y ornamentos reales que mostr\u00f3 desde muy mozo. Estos cuerpos escondieron los indios con el dem\u00e1s tesoro, que los m\u00e1s dellos no han parecido hasta hoy. El a\u00f1o 1559, el licenciado Polo descubri\u00f3 cinco dellos, tres de reyes y dos de reinas. La puerta principal del templo miraba al Norte, como hoy est\u00e1, sin la cual hab\u00eda otras menores para servicio del templo. Todas \u00e9stas estaban aforradas con planchas de oro en forma de portada. Por defuera del templo, por lo alto de las paredes del templo, corr\u00eda una azanefa de oro de un tabl\u00f3n de m\u00e1s de una vara en ancho en forma de corona que abrazaba todo el templo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRIMERA PARTE CAP\u00cdTULO VIII LA DESCRIPCI\u00d3N DEL TEMPLO DEL SOL Y SUS GRANDES RIQUEZAS Uno de los principales \u00eddolos que los reyes Incas y sus vasallos tuvieron fue la imperial ciudad del Cozco, que la adoraban los indios como a cosa sagrada, por haberla fundado el primer Inca Manco C\u00e1pac,\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[5,1109],"tags":[1016,1012,1331,1017,1052,1033],"class_list":["post-961","post","type-post","status-publish","format-standard","hentry","category-literatura","category-textos-literarios","tag-arte","tag-ave","tag-garcilaso","tag-historia","tag-iglesia","tag-vino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Los Comentarios Reales&quot; (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"&quot;Los Comentarios Reales&quot; (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Los Comentarios Reales&quot; (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"&quot;Los Comentarios Reales&quot; (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-02T21:55:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-22T01:12:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"\u00abLos Comentarios Reales\u00bb (I-VIII) [Inca Garcilaso de la Vega]\",\"datePublished\":\"2010-12-02T21:55:25+00:00\",\"dateModified\":\"2018-12-22T01:12:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\\\/\"},\"wordCount\":1087,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"keywords\":[\"arte\",\"ave\",\"Garcilaso\",\"historia\",\"iglesia\",\"vino\"],\"articleSection\":[\"Literatura \\\/ Po\u00e9tica\",\"Textos literarios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\\\/\",\"name\":\"\\\"Los Comentarios Reales\\\" (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"datePublished\":\"2010-12-02T21:55:25+00:00\",\"dateModified\":\"2018-12-22T01:12:51+00:00\",\"description\":\"\\\"Los Comentarios Reales\\\" (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abLos Comentarios Reales\u00bb (I-VIII) [Inca Garcilaso de la Vega]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Los Comentarios Reales\" (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa","description":"\"Los Comentarios Reales\" (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/","og_locale":"es_ES","og_type":"article","og_title":"\"Los Comentarios Reales\" (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa","og_description":"\"Los Comentarios Reales\" (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2010-12-02T21:55:25+00:00","article_modified_time":"2018-12-22T01:12:51+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"\u00abLos Comentarios Reales\u00bb (I-VIII) [Inca Garcilaso de la Vega]","datePublished":"2010-12-02T21:55:25+00:00","dateModified":"2018-12-22T01:12:51+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/"},"wordCount":1087,"commentCount":0,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"keywords":["arte","ave","Garcilaso","historia","iglesia","vino"],"articleSection":["Literatura \/ Po\u00e9tica","Textos literarios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/","url":"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/","name":"\"Los Comentarios Reales\" (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"datePublished":"2010-12-02T21:55:25+00:00","dateModified":"2018-12-22T01:12:51+00:00","description":"\"Los Comentarios Reales\" (I-VIII) [Inca Garcilaso de la Vega] - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/los-comentarios-reales-i-viii-inca-garcilaso-de-la-vega\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"\u00abLos Comentarios Reales\u00bb (I-VIII) [Inca Garcilaso de la Vega]"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":0,"uagb_excerpt":"PRIMERA PARTE CAP\u00cdTULO VIII LA DESCRIPCI\u00d3N DEL TEMPLO DEL SOL Y SUS GRANDES RIQUEZAS Uno de los principales \u00eddolos que los reyes Incas y sus vasallos tuvieron fue la imperial ciudad del Cozco, que la adoraban los indios como a cosa sagrada, por haberla fundado el primer Inca Manco C\u00e1pac,\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=961"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/961\/revisions"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}