{"id":901,"date":"2010-11-27T00:17:05","date_gmt":"2010-11-26T22:17:05","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=901"},"modified":"2018-12-22T03:12:48","modified_gmt":"2018-12-22T01:12:48","slug":"la-odisea-iii-homero","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/","title":{"rendered":"\u00abLa Odisea\u201d (III) [Homero]"},"content":{"rendered":"<p><strong>CANTO III <\/strong><\/p>\n<p>1<\/p>\n<p>Ya el sol desamparaba el hermos\u00edsimo lago, subiendo al bronc\u00edneo cielo para alumbrar a los inmortales dioses y a los mortales hombres sobre la f\u00e9rtil tierra; cuando Tel\u00e9maco y los suyos llegaron a Pilos, la bien construida ciudad de Neleo, y hallaron en la orilla del mar a los habitantes, que inmolaban toros de negro pelaje al que sacude la tierra, al dios de cer\u00falea cabellera. Nueve asientos hab\u00eda, y en cada uno estaban sentados quinientos hombres y se sacrificaban nueve toros. Mientras los pilios quemaban los muslos para el dios, despu\u00e9s de probar las entra\u00f1as, los de Itaca tomaron puerto, amainaron las velas de la bien proporcionada nave, ancl\u00e1ronla y saltaron en tierra. Tel\u00e9maco desembarc\u00f3 precedido por Atenea. Y la deidad de ojos de lechuza rompi\u00f3 el silencio con estas palabras:<\/p>\n<p>14<\/p>\n<p>\u2014\u00a1Tel\u00e9maco! Ya no te cumple mostrar verg\u00fcenza en cosa alguna, habiendo atravesado el ponto con el fin de saber noticias de tu padre: qu\u00e9 tierra lo tiene oculto y qu\u00e9 suerte le ha cabido. Ea, ve directamente a N\u00e9stor, domador de caballos, y sepamos qu\u00e9 guarda all\u00e1 en su pecho. Ru\u00e9gale t\u00fa mismo que sea veraz, y no mentir\u00e1, porque es muy sensato.<\/p>\n<p>21<\/p>\n<p>Repuso el prudente Tel\u00e9maco:<br \/>\n\u2014\u00a1M\u00e9ntor! \u00bfC\u00f3mo quieres que yo me acerque a \u00e9l, c\u00f3mo puedo ir a saludarle? Aun no soy pr\u00e1ctico en hablar con discreci\u00f3n y da verg\u00fcenza que un joven interrogue a un anciano.<\/p>\n<p>25<\/p>\n<p>D\u00edjole Atenea, la deidad de ojos de lechuza:<br \/>\n\u2014\u00a1Tel\u00e9maco! Discurrir\u00e1s en tu mente algunas cosas y un numen te sugerir\u00e1 las restantes pues no creo que tu nacimiento y tu crianza se haya efectuado contra la voluntad de los dioses.<\/p>\n<p>29<\/p>\n<p>Cuando as\u00ed hubo hablado, Palas Atenea camin\u00f3 a buen paso y Tel\u00e9maco fue siguiendo las pisadas de la deidad. Llegaron adonde estaba la junta de los varones pilios en los asientos: all\u00ed se hab\u00eda sentado N\u00e9stor con sus hijos y a su alrededor los compa\u00f1eros preparaban el banquete, ya asando carne, ya espet\u00e1ndola en los asadores. Y apenas vieron a los hu\u00e9spedes, adelant\u00e1ronse todos juntos, los saludaron con las manos y les invitaron a sentarse. Pis\u00edstrato Nest\u00f3rida fue el primero que se les acerc\u00f3, y asi\u00e9ndolos de la mano, los hizo sentar para el convite en unas blancas pieles, sobre la arena del mar, cerca de su hermano Trasimedes y de su propio padre. En seguida dioles parte de las entra\u00f1as ech\u00f3 vino en una copa de oro y ofreci\u00e9ndosela a Palas Atenea, hija de Zeus que lleva la \u00e9gida, as\u00ed le dijo:<\/p>\n<p>43<\/p>\n<p>\u2014\u00a1Forastero! Eleva tus preces al soberano Poseid\u00f3n, ya que al venir ac\u00e1 os hab\u00e9is encontrado con el fest\u00edn que en su honor celebramos. Mas tan pronto como hicieres la libaci\u00f3n y hubieres rogado, como es justo, dale a \u00e9se la copa de dulce vino para que lo libe tambi\u00e9n, pues supongo que ruega asimismo a los inmortales; ya que todos los hombres est\u00e1n necesitados de los dioses. Pero por ser el m\u00e1s joven -debe de tener mis a\u00f1os- te dar\u00e9 primero a ti la \u00e1urea copa.<\/p>\n<p>51<\/p>\n<p>En diciendo esto, p\u00fasole en la mano la copa de dulce vino. Atenea holg\u00f3se de ver la prudencia y la equidad del var\u00f3n que le daba la copa de oro a ella antes que a Tel\u00e9maco. Y al punto hizo muchas s\u00faplicas al soberano Poseid\u00f3n.<\/p>\n<p>55<\/p>\n<p>\u2014\u00a1Oyeme, Poseid\u00f3n, que circundas la tierra! No te niegues a llevar a cabo lo que ahora te pedimos. Ante todas cosas llena de gloria a N\u00e9stor y a sus v\u00e1stagos; dales a los pilios grata recompensa por tan \u00ednclita hecatombe y concede tambi\u00e9n que Tel\u00e9maco y yo no nos vayamos sin lograr el intento que nos trajo en la veloz nave negra.<\/p>\n<p>62<\/p>\n<p>Tal fue su ruego, y ella misma cumpli\u00f3 lo que acababa de pedir. Entreg\u00f3 en seguida la hermosa copa doble a Tel\u00e9maco, y el caro hijo de Odiseo or\u00f3 de semejante manera. Asados ya los cuartos delanteros, retir\u00e1ndolos, dividi\u00e9ronlos en partes y celebraron un gran banquete. Y cuando hubieron satisfecho el deseo de comer y de beber, N\u00e9stor, el caballero gerenio, comenz\u00f3 a decirles:<\/p>\n<p>69<\/p>\n<p>\u2014Esta es la ocasi\u00f3n m\u00e1s oportuna para interrogar a los hu\u00e9spedes e inquirir qui\u00e9nes son, ahora que se han saciado de comida. \u00ab\u00a1Forasteros! \u00bfQuienes sois? \u00bfDe d\u00f3nde llegasteis, navegando por h\u00famedos caminos? \u00bfVen\u00eds por alg\u00fan negocio o and\u00e1is por el mar, a la ventura, como los piratas que divagan, exponiendo su vida y produciendo da\u00f1o a los hombres de extra\u00f1as tierras?\u00bb<\/p>\n<p>75<\/p>\n<p>Respondi\u00f3le el prudente Tel\u00e9maco, muy alentado, pues la misma Atenea le infundi\u00f3 audacia en el pecho para que preguntara por el ausente padre y adquiriera gloriosa fama entre los hombres:<\/p>\n<p>79<\/p>\n<p>\u2014N\u00e9stor Nelida, gloria insigne de los aqueos! Preguntas de d\u00f3nde somos. Pues yo te lo dir\u00e9. Venimos de Itaca, situada al pie del Neyo, y el negocio que nos trae no es p\u00fablico, sino particular. Ando en pos de la gran fama de mi padre, por si oyere hablar del divino y paciente Odiseo, el cual seg\u00fan afirman, destruyo la ciudad troyana combatiendo contigo. De todos los que guerrearon contra los teucros sabemos d\u00f3nde padecieron deplorable muerte; pero el Croni\u00f3n ha querido que la de aqu\u00e9l sea ignorada: nadie puede indicarnos claramente d\u00f3nde pereci\u00f3, ni si ha sucumbido en el continente, por mano de enemigos, o en el pi\u00e9lago, entre las ondas de Anfitrite. Por esto he venido a abrazar tus rodillas, por si quisieras contarme la triste muerte de aqu\u00e9l, ora la hayas visto con tus ojos, ora te la haya relatado alg\u00fan peregrino, que muy sin ventura le pari\u00f3 su madre. Y nada aten\u00faes por respeto o compasi\u00f3n que me tengas; al contrario, ent\u00e9rame bien de lo que hayas visto. Yo te lo ruego: si mi padre, el noble Odiseo, te cumpli\u00f3 alg\u00fan d\u00eda la palabra que te hubiese dado, o llev\u00f3 a su t\u00e9rmino una acci\u00f3n que te hubiera prometido, all\u00e1 en el pueblo de los troyanos donde tantos males padecisteis los aqueos; acu\u00e9rdate de ello y dime la verdad de lo que te pregunto.<\/p>\n<p>102<\/p>\n<p>Respondi\u00f3le N\u00e9stor, el caballero gerenio:<br \/>\n\u2014\u00a1Oh amigo! Me traes a la memoria calamidades que en aquel pueblo padecimos los aqueos, indomables por el valor, unas veces vagando en las naves por el sombr\u00edo ponto hacia donde nos llevaba Aquileo en busca de bot\u00edn y otras combatiendo alrededor de la gran ciudad del rey Pr\u00edamo. All\u00ed recibieron la muerte, los mejores capitanes: all\u00ed yace el belicoso Ayante; all\u00ed, Aquileo; all\u00ed, Patroclo consejero igual a los dioses: all\u00ed, mi amado hijo fuerte y eximio, Ant\u00edloco, muy veloz en el correr y buen guerrero. Padecimos, adem\u00e1s, muchos infortunios. \u00bfCu\u00e1l de los mortales hombres podr\u00eda referirlos totalmente? Aunque, deteni\u00e9ndote aqu\u00ed cinco o seis a\u00f1os, te ocupar\u00e1s en preguntar cu\u00e1ntos males padecieron all\u00e1 los divinos aqueos, no te fuera posible saberlos todos; sino que, antes de llegar al t\u00e9rmino, cansado ya, te ir\u00edas a tu patria tierra. Nueve a\u00f1os estuvimos tramando cosas malas contra ellos y poniendo a su alrededor asechanzas de toda clase y apenas entonces puso fin el Croni\u00f3n a nuestros trabajos. All\u00ed no hubo nadie que en prudencia quisiese igualarse con el divinal Odiseo, con tu padre, que entre todos descollaba por sus ardides de todo g\u00e9nero, si verdaderamente eres t\u00fa su hijo, pues me he quedado at\u00f3nito al contemplarte. Semejantes son, asimismo, tus palabras a las suyas y no se creer\u00eda que un hombre tan joven pudiera hablar de modo tan parecido. Nunca Odiseo y yo estuvimos discordes al arengar en el \u00e1gora o en el consejo; sin que, teniendo el mismo \u00e1nimo, aconsej\u00e1bamos con inteligencia y prudente decisi\u00f3n a los argivos para que todo fuese de la mejor manera.<\/p>\n<p>130<\/p>\n<p>Mas tan pronto como despu\u00e9s de haber destruido la excelsa ciudad de Pr\u00edamo, nos embarcamos en las naves y una deidad dispers\u00f3 a los aqueos, Zeus tram\u00f3 en su mente que fuera luctuosa la vuelta de los argivos; que no todos hab\u00edan sido sensatos y justos, y a causa de ello les vino a muchos una funesta suerte por la perniciosa c\u00f3lera de la deidad de ojo de lechuza, hija del prepotente padre, la cual suscit\u00f3 entre ambos Atridas gran contienda. Llamaron al \u00e1gora a los aqueos, pero temeraria e inoportunamente -fue al ponerse el sol y todos comparecieron cargados de vino-, y expusi\u00e9ronle las razones de haber congregado al pueblo. Menelao exhort\u00f3 a todos los aqueos a que pensaran en volver a la patria por el ancho dorso del mar; cosa que desplugo totalmente a Agamemn\u00f3n pues quer\u00eda detener al pueblo y aplacar con sacras hecatombes la terrible c\u00f3lera de Atenea. \u00a1Oh necio! \u00a1No alcanzaba que no hab\u00eda de convencerla, porque no cambia de s\u00fabito la mente de los sempiternos dioses! as\u00ed ambos, despu\u00e9s de altercar con duras palabras, segu\u00edan en pie; y los aqueos, de hermosas grebas, se levantaron, produci\u00e9ndose un vocer\u00edo inmenso, porque uno y otro parecer ten\u00edan sus partidarios. Aquella noche la pasamos revolviendo en nuestra inteligencia graves trazas los unos contra los otros, pues ya Zeus nos aparejaba funestas calamidades. Al descubrirse la aurora, echamos las naves al mar divino y embarcamos nuestros bienes y las mujeres de estrecha cintura. La mitad del pueblo se qued\u00f3 all\u00ed con el Atrida Agamemn\u00f3n, pastor de hombres y los restantes nos hicimos a la mar, pues un numen calm\u00f3 el ponto, que abunda en grandes cet\u00e1ceos. No bien llegamos a T\u00e9nedos!, ofrecimos sacrificios a los dioses con el anhelo de tornar a nuestras casas, pero Zeus a\u00fan no ten\u00eda ordenada la vuelta y suscit\u00f3, \u00a1oh cruel!, una nueva y perniciosa disputa. Y los que acompa\u00f1aban a Odiseo, rey prudente y sagaz, se volvieron en los corvos bajeles para complacer nuevamente a Agamemn\u00f3n Atrida. Pero yo, con las naves que juntas me segu\u00edan, continu\u00e9 huyendo porque entend\u00ed que alguna divinidad meditaba causarnos da\u00f1o. Huy\u00f3 tambi\u00e9n el belicoso hijo de Tideo con los suyos, despu\u00e9s de incitarlos a que le siguieran, y junt\u00f3senos algo m\u00e1s tarde el rubio Menelao, el cual nos encontr\u00f3 en Lesbos mientras deliber\u00e1bamos acerca de la larga navegaci\u00f3n que nos esperaba, a saber, si pasar\u00edamos por cima de la escabrosa Qu\u00edos, hacia la isla de Psiria, para dejar esta \u00faltima a la izquierda, o por debajo de la primera a lo largo del ventoso Mimante. Suplicamos a la divinidad que nos mostrase alguna se\u00f1al y nos la dio orden\u00e1ndonos que atraves\u00e1ramos el pi\u00e9lago hacia la Eubea, a fin de que huy\u00e9ramos lo antes posible del infortunio venidero. Comenz\u00f3 a soplar un sonoro viento, y las naves, surcando con gran celeridad el camino abundante en peces, llegaron por la noche a Geresto: all\u00ed ofrecimos a Poseid\u00f3n buen n\u00famero de perniles de toro por haber hecho la traves\u00eda del dilatado pi\u00e9lago.<\/p>\n<p>180<\/p>\n<p>Ya era el cuarto d\u00eda cuando los compa\u00f1eros de Diomedes Tidida, domador de caballos, se detuvieron en Argos con sus bien proporcionadas naves; pero yo tom\u00e9 la rota de Pilos y nunca me falt\u00f3 el viento desde que un dios lo envi\u00f3 para que soplase. As\u00ed vine, hijo querido, sin saber nada, ignorando cu\u00e1les aqueos se salvaron y cu\u00e1les perecieron. Mas, cuanto o\u00ed referir desde que torn\u00e9 a mi palacio lo sabr\u00e1s ahora, como es justo; que no debo ocultarte nada. Dicen que han llegado bien los valerosos mirmidones a quienes conduc\u00eda el hijo ilustre del magn\u00e1nimo Aquileo, que asimismo aport\u00f3 con felicidad Filoctetes, hijo preclaro de Peante; y que Idomeneo llev\u00f3 a Creta todos sus compa\u00f1eros que escaparon de los combates, sin que el mar le quitara ni uno solo. Del Atrida vosotros habr\u00e9is o\u00eddo contar, aunque viv\u00eds tan lejos, c\u00f3mo vino y c\u00f3mo Egisto le aparej\u00f3 una deplorable muerte. Pero de lamentable modo hubo de pagarlo. \u00a1Cu\u00e1n bueno es para el que muere dejar un hijo! as\u00ed Orestes se ha vengado del matador de su padre, del doloso Egisto, que le hab\u00eda muerto a su ilustre progenitor. Tambi\u00e9n t\u00fa, amigo, ya veo eres gallardo y de elevada estatura, s\u00e9 fuerte para que los venideros te elogien.<\/p>\n<p>201<\/p>\n<p>Contest\u00f3le el prudente Tel\u00e9maco:<br \/>\n\u2014\u00a1N\u00e9stor Nelida, gloria insigne de los aqueos! Aqu\u00e9l tom\u00f3 no poca venganza y los aqueos difundir\u00e1n su excelsa gloria, que llegar\u00e1 a conocimiento de los futuros hombres. \u00a1Hubi\u00e9ranme concedido los dioses br\u00edos bastantes para castigar la penosa soberbia de los pretendientes, que me insultan maquinando inicuas acciones! Mas los dioses no nos otorgaron tama\u00f1a ventura ni a mi padre ni a mi, y ahora es preciso pasar por todo sufridamente.<\/p>\n<p>210<\/p>\n<p>Respondi\u00f3le N\u00e9stor, el caballero gerenio:<br \/>\n\u2014\u00a1Oh amigo,! Ya que me recuerdas lo que has contado, afirman que son muchos los que, pretendiendo a tu madre, cometen a despecho tuyo acciones inicuas en el palacio. Dime si te sometes voluntariamente o te odia quiz\u00e1s la gente del pueblo, a causa de lo revelado por un dios. \u00bfQui\u00e9n sabe si alg\u00fan d\u00eda castigar\u00e1 esas demas\u00edas tu propio padre viniendo solo o juntamente con todos los aqueos? Ojal\u00e1 Atenea la de ojos de lechuza, te quisiera como en otro tiempo se cuidaba del glorioso Odiseo en el pa\u00eds troyano, donde los aqueos arrostramos tantos males -nunca o\u00ed que los dioses amasen tan manifiestamente a ninguno como manifiestamente le asist\u00eda Palas Atenea-, pues si de semejante modo la diosa te quisiera y se cuidara de ti en su coraz\u00f3n, alguno de los pretendientes tendr\u00eda que despedir de s\u00ed la esperanza de la boda.<\/p>\n<p>225<\/p>\n<p>Replic\u00f3le el prudente Tel\u00e9maco:<br \/>\n\u2014\u00a1Oh anciano! Ya no creo que tales cosas se cumplan. Es muy grande lo que dijiste y me tienes pasmado, mas no espero que se realice aunque as\u00ed lo quisieran los mismos dioses.<\/p>\n<p>229<\/p>\n<p>D\u00edjole Atenea, la deidad de ojos de lechuza:<br \/>\n\u2014\u00a1Tel\u00e9maco! \u00a1Qu\u00e9 palabras se te escaparon del cerco de los dientes! F\u00e1cil le es a una deidad, cuando lo quiere, salvar a un hombre aun desde lejos. Y yo preferir\u00eda restituirme a mi casa y ver lucir el d\u00eda de la vuelta, habiendo pasado muchos males, a perecer tan luego como llegara a mi hogar; como Agamemn\u00f3n, que muri\u00f3 en la celada que le tendieron Egisto y su propia esposa. Mas ni aun los dioses pueden librar de la muerte, igual para todos, a un hombre que les sea caro despu\u00e9s que se apoder\u00f3 de el la Moira funesta de la aterradora muerte.<\/p>\n<p>239<\/p>\n<p>Contest\u00f3le el prudente Tel\u00e9maco:<br \/>\n\u2014\u00a1M\u00e9ntor; No hablemos m\u00e1s de tales cosas aunque nos sintamos afligidos. Ya la vuelta de aquel no puede verificarse; pues los inmortales deben de haberle enviado la muerte y la negra Moira. Pero ahora quiero interrogar a N\u00e9stor y hacerle otra pregunta, ya que en justicia y prudencia sobresale entre todos y dicen que ha reinado durante tres generaciones de hombres; de suerte que, al contemplarlo me parece un inmortal. \u00a1Oh N\u00e9stor Nelida! Dime la verdad. \u00a1C\u00f3mo muri\u00f3 el poderos\u00edsimo Agamemn\u00f3n Atrida? \u00bfD\u00f3nde estaba Menelao? \u00bfQu\u00e9 g\u00e9nero de muerte fue la que urdi\u00f3 el doloso Egisto, para que pereciera un var\u00f3n que tanto le aventajaba? \u00bfFue quiz\u00e1s el no encontrarse Menelao en Argos, la de Acaya, pues andar\u00eda peregrino entre otras gentes, la causa de que Egisto cobrara esp\u00edritu y matase a aquel h\u00e9roe?<\/p>\n<p>253<\/p>\n<p>Respondi\u00f3le N\u00e9stor, el caballero gerenio:<br \/>\n\u2014Te dir\u00e9, hijo m\u00edo, la verdad entera. Ya puedes imaginar c\u00f3mo el hecho ocurri\u00f3. Si el rubio Menelao Atrida, al volver de Troya, hubiera hallado en el palacio a Egisto, vivo aun, ni tan solo hubiesen cubierto de tierra el cad\u00e1ver de este: arrojado a la llanura, lejos de la ciudad, hubiera sido despedazado por los perros y las aves de rapi\u00f1a, sin que le llorase ninguna de las aqueas, porque hab\u00eda cometido una maldad muy grande. Pues mientras nosotros permanec\u00edamos all\u00e1, llevando al cabo muchas empresas belicosas, \u00e9l se estaba tranquilo en lo mas hondo de Argos, tierra criadora de corceles y pon\u00eda gran empe\u00f1o en seducir con sus palabras a la esposa de Agamemn\u00f3n. Al principio la divinal Clitemnestra rehus\u00f3 cometer el hecho infame, porque ten\u00eda buenos sentimientos y la acompa\u00f1aba un aedo a quien el Atrida, al partir para Troya, encarg\u00f3 en gran manera que la guardase. Mas, cuando vino el momento en que, cumpli\u00e9ndose el hado de los dioses, ten\u00eda que sucumbir, Egisto condujo al aedo a una isla inhabitada, donde lo abandon\u00f3 para que fuese presa y pasto de las aves de rapi\u00f1a; y llev\u00f3se de buen grado a su casa a la mujer, que tambi\u00e9n lo deseaba, quemando despu\u00e9s gran cantidad de muslos en los sacros altares de los dioses y colgando muchas figuras, tejidos y oro, por haber salido con la gran empresa que nunca su \u00e1nimo hab\u00eda esperada ejecutar. Ven\u00edamos, pues, de Troya el Atrida y yo, navegando juntos y en buena amistad; pero, as\u00ed que arribamos al sacro promontorio de Sunio, cerca de Atenas, Febo Apolo mat\u00f3 con sus suaves flechas al piloto de Menelao, a Frontis Onet\u00f3rida, que entonces ten\u00eda en la mano el tim\u00f3n de la nave y a todos venc\u00eda en el arte de gobernar una embarcaci\u00f3n cuando arreciaban las tempestades. as\u00ed fue c\u00f3mo, a pesar de su deseo de proseguir el camino, se vio obligado a detenerse para enterrar al compa\u00f1ero y hacerle las honras funerales. Luego, atravesando el vinoso ponto en las c\u00f3ncavas naves, pudo llegar a toda prisa al elevado promontorio de Malea, y el largovidente Zeus h\u00edzole trabajoso el camino con enviarle vientos de sonoro soplo y olas hinchadas, enormes, que parec\u00edan monta\u00f1as. Entonces el dios dispers\u00f3 las naves y a algunas las llevo hasta Creta, donde habitaban los Cidones, junto a las corrientes del Y\u00e1rdano. Hay en el obscuro ponto una pe\u00f1a escarpada y alta que sale al mar cerca de Gortina en el tenebroso ponto: all\u00ed el Noto lanza grandes olas contra el promontorio de la izquierda, contra Festo, y una roca peque\u00f1a rompe la grande oleada. En semejante sitio fueron a dar y cost\u00f3les mucho escapar con vida; pues, habiendo las olas arrojado los bajeles contra los escollos, padecieron naufragio. Menelao, con cinco naves de cer\u00falea proa, aport\u00f3 a Egipto, adonde el viento y el mar le hab\u00edan conducido: y en tanto que con sus galeras iba errante por extra\u00f1os pa\u00edses, juntando riquezas y mucho oro, Egisto tram\u00f3 en el palacio aquellas deplorables acciones.<\/p>\n<p>305<\/p>\n<p>Siete a\u00f1os rein\u00f3 este en Micenas, rica en oro, y tuvo sojuzgado al pueblo, con posterioridad a la muerte del Atrida. Mas, por su desgracia, en el octavo lleg\u00f3 de Atenas el divinal Orestes, quien dio muerte al matador de su padre, al doloso Egisto, que le hab\u00eda muerto su ilustre progenitor. Despu\u00e9s de matarle, Orestes dio a los argivos el banquete f\u00fanebre en las exequias de su diosa madre y del cobarde Egisto; y aquel d\u00eda lleg\u00f3 Menelao, valiente en el combate, con muchas riquezas, tantas como los barcos pod\u00edan llevar.<\/p>\n<p>313<\/p>\n<p>Y t\u00fa, amigo, no andes mucho tiempo fuera de tu casa, habiendo dejado en ella las riquezas y unos hombres tan soberbios: no sea que se repartan tus bienes y los devoren y luego el viaje te salga en vano. Pero yo te exhorto e incito a que endereces tus pasos hacia Menelao; el cual poco ha que volvi\u00f3 de gentes de donde no esperara tornar quien se viera, desviado por las tempestades, en un pi\u00e9lago tal y tan extenso, que ni las aves vendr\u00edan del mismo en todo un a\u00f1o, pues es dilatad\u00edsimo y horrendo. Ve ahora en tu nave y con tus compa\u00f1eros a dar con \u00e9l, y si deseas ir por tierra, aqu\u00ed tienes carro y corceles, y a mis hijos, que te acompa\u00f1ar\u00e1n hasta la divina Lacedemonia donde se halla el rubio Menelao y, en llegando, ru\u00e9gale t\u00fa mismo que sea veraz, y no mentir\u00e1 porque es muy sensato.<\/p>\n<p>329<\/p>\n<p>As\u00ed dijo. P\u00fasose el sol y sobrevino la obscuridad. Y entonces habl\u00f3 Atenea la diosa de ojos de lechuza:<br \/>\n\u2014\u00a1Oh anciano! Todo lo has referido discretamente. Pero, ea, cortad las lenguas y mezclad vino, para que, despu\u00e9s de hacer libaci\u00f3n a Poseid\u00f3n y a los dem\u00e1s inmortales, pensemos en acostarnos, que ya es hora. La luz del sol se fue al ocaso y no conviene permanecer largo tiempo en el banquete de los dioses, pues es preciso recogerse.<\/p>\n<p>337<\/p>\n<p>As\u00ed habl\u00f3 la hija de Zeus, y todos la obedecieron. Los heraldos di\u00e9ronles aguamanos: unos mancebos coronaron de bebida las crateras y distribuyeron el vino a los presentes, despu\u00e9s de haber ofrecido en copas las primicias; y, una vez arrojadas las lenguas al fuego, pusi\u00e9ronse de pie e hicieron libaciones. Ofrecidas \u00e9stas y habiendo bebido cuanto desearan, Atenea y el deiforme Tel\u00e9maco quisieron retirarse a la c\u00f3ncava nave. Pero N\u00e9stor los detuvo reprendi\u00e9ndolos con estas palabras:<\/p>\n<p>346<\/p>\n<p>\u2014Zeus y los otros dioses inmortales nos libren de que vosotros os vay\u00e1is de mi lado para volver a la velera nave, como si os fuerais de junto a un var\u00f3n que carece de ropa; del lado de un pobre, en cuya casa no hay mantos ni gran cantidad de colchas para que \u00e9l y sus hu\u00e9spedes puedan dormir blandamente. Pero a m\u00ed no me faltan mantos ni lindas colchas. Y el caro hijo de Odiseo no se acostar\u00e1 ciertamente en las tablas de su bajel mientras yo viva o queden mis hijos en el palacio para alojar a los hu\u00e9spedes que a mi casa vengan.<\/p>\n<p>356<\/p>\n<p>D\u00edjole Atenea, la deidad de ojos de lechuza:<br \/>\n\u2014Bien hablaste, anciano querido, y conviene que Tel\u00e9maco te obedezca porque es lo mejor que puede hacer. Ir\u00e1se, pues, contigo para dormir en tu palacio, y yo volver\u00e9 al negro bajel a fin de animar a los compa\u00f1eros y ordenarles cuanto sea oportuno. Pues me glorio de ser entre ellos el m\u00e1s anciano, que todos los hombres que vienen con nosotros por amistad son j\u00f3venes y tienen los mismos a\u00f1os que el magn\u00e1nimo Tel\u00e9maco. All\u00ed me acostar\u00e9 en el negro y c\u00f3ncavo bajel, y al rayar el d\u00eda, me llegare a los magn\u00e1nimos caucones en cuyo pa\u00eds he de cobrar una deuda antigua y no peque\u00f1a; y t\u00fa, puesto que Tel\u00e9maco ha venido a tu casa, env\u00edale en compa\u00f1\u00eda de un hijo tuyo y dale un carro, y los corceles que sean m\u00e1s ligeros en el correr y mejores por su fuerza.<\/p>\n<p>371<\/p>\n<p>Dicho esto, parti\u00f3 Atenea la de los ojos de lechuza, cual si fuese \u00e1guila; y pasm\u00e1ronse todos al contemplarlo. Adm\u00edrose tambi\u00e9n el anciano cuando lo vio con sus propios ojos y, asiendo de la mano a Tel\u00e9maco, pronunci\u00f3 estas palabras:<\/p>\n<p>375<\/p>\n<p>\u2014\u00a1Amigo! No temo qu\u00e9, ya que de tan joven te acompa\u00f1an y gu\u00edan los propios dioses. Pues esa deidad no es otra, de la que poseen ol\u00edmpicas moradas, que la hija de Zeus, la glorios\u00edsima Tritogenea, la que tambi\u00e9n honraba a tu esforzado padre entre los argivo. Mas tu, oh reina, s\u00e9nos propicia y danos gloria ilustre a mi, a mis hijos, y a mi venerable consorte; y te sacrificar\u00e9 una novilla a\u00f1al de espaciosa frente, que jam\u00e1s hombre alguno haya domado ni uncido al yugo, inmol\u00e1ndola en tu honor despu\u00e9s de verter oro alrededor de sus cuernos.<\/p>\n<p>385<\/p>\n<p>As\u00ed dijo rogando, y le oy\u00f3 Palas Atenea. N\u00e9stor, el caballero gerenio, se puso al frente de sus hijos y de sus yernos, y con ellos se encamin\u00f3 al hermoso palacio. Tan pronto como llegaron a la \u00ednclita morada del rey, sent\u00e1ronse por orden en sillas y sillones. De all\u00ed a poco mezcl\u00e1bales el viejo una cratera de dulce vino el cual hab\u00eda estado once a\u00f1os en una tinaja que abri\u00f3, la despensera; mezcl\u00e1balo, pues, el anciano y, haciendo libaciones, rogaba fervientemente a la hija de Zeus, que lleva la \u00e9gida.<\/p>\n<p>395<\/p>\n<p>Hechas las libaciones y habiendo bebido todos cuanto les plugo, fueron a recogerse a sus respectivas casas; pero N\u00e9stor, el caballero gerenio, hizo que Tel\u00e9maco, el caro hijo del divinal Odiseo se acostase all\u00ed, en torneado lecho, debajo del sonoro p\u00f3rtico, y que a su lado durmiese el belicoso Pis\u00edstrato, caudillo de los hombres, que era en el palacio el \u00fanico hijo que se conservaba mozo. Y N\u00e9stor durmi\u00f3, a su vez, en el interior de la excelsa morada, donde se hallaba la cama en que su esposa, la reina, le aderez\u00f3 el lecho.<\/p>\n<p>404<\/p>\n<p>Mas apenas se descubri\u00f3 la hija de la ma\u00f1ana, Eos de ros\u00e1ceos dedos, levant\u00f3se de la cama N\u00e9stor, el caballero gerenio, y fue a tomar asiento en unas piedras muy pulidas, blancas, lustrosas por el aceite, que estaban ante el elevado port\u00f3n y en ellas se sentaba anteriormente Neleo, consejero igual a los dioses; pero ya \u00e9ste, vencido por la Moira, se hallaba en el Hades, y entonces quien ocupaba aquel sitio era N\u00e9stor, el caballero gerenio, el protector de los aqueos, cuya mano empu\u00f1aba el cetro. En torno suyo junt\u00e1ronse los hijos, que iban saliendo de sus habitaciones -Equefr\u00f3n, Estratio, Perseo, Areto, Trasimedes igual a un dios, y el h\u00e9roe Pis\u00edstrato, que lleg\u00f3 el sexto-, y juntos acompa\u00f1aron al deiforme Tel\u00e9maco y le hicieron sentar cerca del anciano. Entonces comenz\u00f3 a decirles N\u00e9stor, el caballero gerenio:<\/p>\n<p>418<\/p>\n<p>\u2014Hijos amados! Cumplid pronto mi deseo, para que sin tardar me haga propicia a Atenea, la cual acudi\u00f3 visiblemente al op\u00edparo fest\u00edn que celebramos en honor del dios. Ea, uno de vosotros vaya al campo para que el vaquero traiga con la mayor prontitud una novilla; encam\u00ednese otro al negro bajel del magn\u00e1nimo Tel\u00e9maco y conduzca aqu\u00ed a todos los compa\u00f1eros sin dejar mas que dos; y mande otro al or\u00edfice Laerces que venga a verter el oro alrededor de los cuernos. Los dem\u00e1s permaneced reunidos y decid a las esclavas que est\u00e1n dentro de la \u00ednclita casa, que preparen un banquete y saquen asientos, le\u00f1a y agua clara.<\/p>\n<p>430<\/p>\n<p>As\u00ed habl\u00f3, y todos se dispusieron a obedecerle. Vino del campo la novilla, llegaron de junto a la velera y bien proporcionada nave los compa\u00f1eros del magn\u00e1nimo Tel\u00e9maco; present\u00f3se el broncista trayendo en la mano las bronc\u00edneas herramientas -el yunque, el martillo y las bien construidas tenazas-, instrumentos de su oficio con los cuales trabajaba el oro; compareci\u00f3 Atenea para asistir al sacrificio; y N\u00e9stor, el anciano jinete, dio el oro, y el art\u00edfice, despu\u00e9s de prepararlo, lo verti\u00f3 alrededor de los cuernos de la novilla para que la diosa se holgase de ver tal adorno. Estratio y el divinal Equefr\u00f3n trajeron la novilla asi\u00e9ndola por las astas; Areto sali\u00f3 de su estancia con un lebrillo floreado, lleno de agua para lavarse, en una mano, y una cesta con la mola en la otra; el intr\u00e9pido Trasimedes se present\u00f3 empu\u00f1ando aguda segur para herir la novilla; Perseo sosten\u00eda el vaso para recoger la sangre; y N\u00e9stor, el anciano jinete, comenz\u00f3 a derramar el agua y a esparcir la mola, y ofreciendo las primicias, oraba con gran fervor a Atenea y arrojaba en el fuego los pelos de la cabeza de la v\u00edctima.<\/p>\n<p>447<\/p>\n<p>Hecha la plegaria y esparcida la mola, aquel hijo de N\u00e9stor, el magn\u00e1nimo Trasimedes, dio desde cerca un golpe a la novilla y le cort\u00f3 con la segur los tendones del cuello, dej\u00e1ndola sin fuerzas; y gritaron las hijas y nueras de N\u00e9stor, y tambi\u00e9n su venerable esposa, Eur\u00eddice, que era la mayor de las hijas de Cl\u00edmeno. Seguidamente alzaron de la espaciosa tierra a la novilla, sostuvi\u00e9ronla en alto y degoll\u00f3la Pis\u00edstrato, pr\u00edncipe de hombres. Tan pronto como la novilla se desangr\u00f3 y los huesos quedaron sin vigor, la descuartizaron, cort\u00e1ronle luego los muslo, haci\u00e9ndolo seg\u00fan el rito, y, despu\u00e9s de pringarlos con grasa por uno y otro lado y de cubrirlos con trozos de carne, el anciano los puso sobre la le\u00f1a encendida y los roci\u00f3 de vino tinto. Cerca de \u00e9l, unos mancebos ten\u00edan en sus manos asadores de cinco puntas. Quemados los muslos, probaron las entra\u00f1as, y sin parar dividieron lo restante en pedazos muy peque\u00f1os, lo atravesaron con pinchos y lo asaron, sosteniendo con sus manos las puntiagudas varillas.<\/p>\n<p>465<\/p>\n<p>En esto lavaba a Tel\u00e9maco la bella Policasta, hija menor de N\u00e9stor Nelida. Despu\u00e9s que lo hubo lavado y ungido con ping\u00fce aceite, visti\u00f3le un hermoso manto y una t\u00fanica, y Tel\u00e9maco sali\u00f3 del ba\u00f1o, con el cuerpo parecido al de los inmortales, y fue a sentarse junto a N\u00e9stor, pastor de pueblos.<\/p>\n<p>470<\/p>\n<p>Asados los cuartos delanteros, retir\u00e1ronlos de las llamas, y sent\u00e1ndose todos, celebraron el banquete. Varones excelentes se levantaban a escanciar el vino en \u00e1ureas copas. Y una vez saciado el deseo de comer y de beber, N\u00e9stor, el caballero gerenio, comenz\u00f3 a decirles:<\/p>\n<p>475<\/p>\n<p>\u2014Ea, hijos m\u00edos, aparejad caballos de hermosas crines y uncidlos al carro, para que Tel\u00e9maco pueda llevar a t\u00e9rmino su viaje.<\/p>\n<p>477<\/p>\n<p>As\u00ed dijo, y ellos le escucharon y obedecieron unciendo prestamente al carro los veloces corceles. La despensera les trajo pan, vino y manjares como los que suelen comer los reyes, alumnos de Zeus. Subi\u00f3 Tel\u00e9maco al magn\u00edfico carro y tras \u00e9l Pis\u00edstrato Nest\u00f3rida, pr\u00edncipe de hombres, quien empu\u00f1\u00f3 las riendas y azot\u00f3 a los caballos para que arrancasen. Y \u00e9stos volaron gozosos hacia la llanura, dejando atr\u00e1s la excelsa ciudad de Pilos y no cesando en todo el d\u00eda de agitar el yugo.<\/p>\n<p>487<\/p>\n<p>Pon\u00edase el sol y las tinieblas empezaban a ocupar los caminos, cuando llegaron a Feras, a la morada de Diocles, hijo de Ors\u00edloco, a quien hab\u00eda engendrado Alfeo. All\u00ed durmieron aquella noche, pues Diocles les dio hospitalidad.<\/p>\n<p>491<\/p>\n<p>Mas, apenas se descubri\u00f3 la hija de la ma\u00f1ana, Eos de ros\u00e1ceos dedos, uncieron los corceles, subieron al labrado carro y gui\u00e1ronlo por el vest\u00edbulo y el p\u00f3rtico sonoro. Pis\u00edstrato azot\u00f3 a los corceles, para que arrancaran, y \u00e9stos volaron gozosos. Y habiendo llegado a una llanura que era un trigal, en seguida terminaron el viaje: \u00a1con tal rapidez los condujeron los briosos caballos! Y el sol se puso y las tinieblas ocuparon todos los caminos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CANTO III 1 Ya el sol desamparaba el hermos\u00edsimo lago, subiendo al bronc\u00edneo cielo para alumbrar a los inmortales dioses y a los mortales hombres sobre la f\u00e9rtil tierra; cuando Tel\u00e9maco y los suyos llegaron a Pilos, la bien construida ciudad de Neleo, y hallaron en la orilla del mar\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[5,1109],"tags":[1016,1012,1059,1015,1058,1289,1115,1143,1060,1061,1288,1025,1046,1033],"class_list":["post-901","post","type-post","status-publish","format-standard","hentry","category-literatura","category-textos-literarios","tag-arte","tag-ave","tag-empresa","tag-flor","tag-hogar","tag-homero","tag-jovenes","tag-justicia","tag-lengua","tag-lenguas","tag-odisea","tag-rosa","tag-salud","tag-vino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"&quot;La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"&quot;La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-11-26T22:17:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-22T01:12:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"27 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-odisea-iii-homero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-odisea-iii-homero\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"\u00abLa Odisea\u201d (III) [Homero]\",\"datePublished\":\"2010-11-26T22:17:05+00:00\",\"dateModified\":\"2018-12-22T01:12:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-odisea-iii-homero\\\/\"},\"wordCount\":5312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"keywords\":[\"arte\",\"ave\",\"empresa\",\"flor\",\"hogar\",\"Homero\",\"j\u00f3venes\",\"justicia\",\"lengua\",\"lenguas\",\"Odisea\",\"rosa\",\"salud\",\"vino\"],\"articleSection\":[\"Literatura \\\/ Po\u00e9tica\",\"Textos literarios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-odisea-iii-homero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-odisea-iii-homero\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-odisea-iii-homero\\\/\",\"name\":\"\\\"La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"datePublished\":\"2010-11-26T22:17:05+00:00\",\"dateModified\":\"2018-12-22T01:12:48+00:00\",\"description\":\"\\\"La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-odisea-iii-homero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-odisea-iii-homero\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-odisea-iii-homero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abLa Odisea\u201d (III) [Homero]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa","description":"\"La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/","og_locale":"es_ES","og_type":"article","og_title":"\"La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa","og_description":"\"La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2010-11-26T22:17:05+00:00","article_modified_time":"2018-12-22T01:12:48+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"27 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"\u00abLa Odisea\u201d (III) [Homero]","datePublished":"2010-11-26T22:17:05+00:00","dateModified":"2018-12-22T01:12:48+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/"},"wordCount":5312,"commentCount":0,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"keywords":["arte","ave","empresa","flor","hogar","Homero","j\u00f3venes","justicia","lengua","lenguas","Odisea","rosa","salud","vino"],"articleSection":["Literatura \/ Po\u00e9tica","Textos literarios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/","url":"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/","name":"\"La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"datePublished":"2010-11-26T22:17:05+00:00","dateModified":"2018-12-22T01:12:48+00:00","description":"\"La Odisea\u201d (III) [Homero] - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/la-odisea-iii-homero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"\u00abLa Odisea\u201d (III) [Homero]"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":0,"uagb_excerpt":"CANTO III 1 Ya el sol desamparaba el hermos\u00edsimo lago, subiendo al bronc\u00edneo cielo para alumbrar a los inmortales dioses y a los mortales hombres sobre la f\u00e9rtil tierra; cuando Tel\u00e9maco y los suyos llegaron a Pilos, la bien construida ciudad de Neleo, y hallaron en la orilla del mar\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=901"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/901\/revisions"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}