{"id":828,"date":"2010-10-16T01:14:41","date_gmt":"2010-10-15T23:14:41","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=828"},"modified":"2010-10-16T01:14:41","modified_gmt":"2010-10-15T23:14:41","slug":"el-fraude-financiero-a-traves-de-internet","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/","title":{"rendered":"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET"},"content":{"rendered":"<div>\n<p>Cortes\u00eda de la Polic\u00eda Local de Cambrils:<br \/>\n\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2013\u00a0<\/p>\n<p>Es p\u00fablico i notorio el hecho que\u00a0 la navegaci\u00f3n a trav\u00e9s de Internet no son seguros al 100%. I todav\u00eda no hemos capaces de crear programas i soportes inform\u00e1ticos que protejan nuestro patrimonio, intimidad y seguridad. Informaticamente hablando, vivimos en un mundo de riesgo en el que nos podran vulnerar estos derechos.\u00a0 Y todos podemos ser victimas de vulnerabilidades en el funcionamiento de nuestros equipos inform\u00e1ticos mediante las cuales se pueda forzar\u00a0 para que realicem tareas o funciones no previstas inicialmente.<\/p>\n<p>En el caso de las entidades financieras que operan en a trav\u00e9s de Internet, por el momento, se est\u00e1n detectando casos alarmantes de fraude. Aunque no ocurre de forma significativa en Espa\u00f1a, en pa\u00edses como Estados Unidos, Canad\u00e1, Gran Breta\u00f1a o Australia,\u00a0 el incremento de estos casos a lo largo de los \u00faltimos meses comienza a preocupar seriamente. Por ello, es importante querido internauta que estes al tanto de los tipos de fraude mas conocidos que se cometen sobre todo tipo de entidades financieras y de pago, etc.<\/p>\n<h2><strong>T\u00c9CNICAS DE ENGA\u00d1O: <\/strong><\/h2>\n<p>El \u00a0phishing\u00a0:\u00a0 de entre la multitud de t\u00e9cnicas para cometer fraudes financieros a trav\u00e9s de Internet, es una de las t\u00e9cnicas que est\u00e1 obteniendo importantes \u00edndices de crecimiento en la red. Consiste en la suplantaci\u00f3n fidedigna de p\u00e1ginas o sitios de Internet\u00a0 de las entidades bancarias y de cr\u00e9dito. El \u201cphishing\u201d permite el robo de datos privados de acceso personal a sitios de confianza. \u00a0Uno de los principios en el que se fundamenta el \u201cphishing\u201d es la utilizaci\u00f3n de mensajes con una fuerte carga social (t\u00e9cnicas que se aprovechan de las debilidades de las personas) con los que intentar\u00e1n mostrarse cada vez m\u00e1s veros\u00edmiles. Lo har\u00e1n aprovechando\u00a0 el temor de los usuarios; la confianza depositada en su entidad financiera; y su desconocimiento t\u00e9cnico en inform\u00e1tica e Internet. \u00a0\u00a0Los mensajes enviados para provocar el enga\u00f1o son cada vez mas ingeniosos y muchas veces emplean argumentos relacionados con la seguridad de la entidad, con lo cual justificar la necesidad de introducir sus datos de acceso. Un ejemplo de los m\u00e1s comunes pueden ser los siguientes:<\/p>\n<ul>\n<li>\u00a0\u00a0\u00a0\u00a0Problemas de car\u00e1cter t\u00e9cnico.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Recientes detecciones de fraude y urge un incremento del nivel de seguridad.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Nuevas recomendaciones de seguridad para prevenci\u00f3n del fraude.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Cambios en la pol\u00edtica de seguridad de la entidad.<\/li>\n<\/ul>\n<p>\u00a0Tambi\u00e9n podr\u00e1n intentarlo mediante mensajes de:<\/p>\n<ul>\n<li>\u00a0\u00a0\u00a0\u00a0Promoci\u00f3n de nuevos productos de la entidad.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Premios o regalos por ser buen cliente o por sorteos.<\/li>\n<\/ul>\n<p>Juegan con el temor: suelen siempre forzar al usuario \u2013 v\u00edctima a tomar una decisi\u00f3n casi de forma inmediata, planteando amenazas de que si no realiza los cambios solicitados, en pocas horas o d\u00edas su acceso quedar\u00e1 deshabilitado.<\/p>\n<p>Sin duda el correo electr\u00f3nico es actualmente la t\u00e9cnica m\u00e1s utilizada en este tipo de fraude, tal vez porque resulte el m\u00e1s efectivo a corto plazo para el atacante.<\/p>\n<p>Los \u201cSPAM\u201d\u00a0son otros grandes aliados para el \u201cphishing\u201d debido a lo sencillo y barato que resulta para llegar hasta millones de usuarios con mensajes similares al siguiente:<\/p>\n<p>\u00a0<em>\u00a0\u00a0\u00a0Estimado cliente; El departamento de seguridad del banco ha detectado en las \u00faltimas fechas diversos tipos de t\u00e9cnicas fraudulentas en Internet, por medio de las cuales es posible que las claves de acceso de algunos de nuestros clientes hayan sido capturadas para, haciendo un uso ilegal de las mismas, acceder a su cuenta y operar en ella como si fuese usted mismo quien realice las operaciones. Debido a ello, el banco ha decidido renovar las claves de acceso de todos los clientes como medida de protecci\u00f3n que garantice la seguridad y evite el fraude. \u00a0El \u00fanico lugar donde podr\u00e1 realizar el cambio de claves se encuentra tras el siguiente enlace: https:\/\/xxxxx.xx.xxxxx.. donde quedar\u00e1 disponible hasta el pr\u00f3ximo d\u00eda XX-XX-XXXX momento a partir del cual, se proceder\u00e1 a la cancelaci\u00f3n de los accesos de todos aquellos usuarios que no hayan realizado el cambio de sus claves. Agradecemos su colaboraci&amp;oacn y la confianza depositada en nuestra entidad. <\/em><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0Fdo: Director Entidad Bancaria: Departamento de seguridad<\/p>\n<p>En estos mensajes, la direcci\u00f3n del remitente estar\u00e1 falsificada. Suele ser muy parecida o\u00a0 podr\u00e1 coincidir con alguna cuenta leg\u00edtima de la entidad en cuesti\u00f3n.\u00a0 El objetivo es que alguno de los millones de receptores de ese correo sea cliente de esa entidad y pulse sobre el enlace propuesto para realizar el cambio o confirmaci\u00f3n de sus claves. Obviamente, la p\u00e1gina enlazada tambi\u00e9n ser\u00e1 falsa y estar\u00e1 controlada por los estafadores quienes habr\u00e1n cuidado hasta el m\u00e1s m\u00ednimo detalle, en replicar con toda fidelidad la imagen, logotipos, colores y formatos de las p\u00e1ginas leg\u00edtimas de la entidad. En la p\u00e1gina, se pedir\u00e1n todos los datos necesarios para poder realizar operaciones en las cuentas de la entidad: nombre de usuario, clave de acceso y clave personal o firma. Una vez que sean confirmados los cambios, los estafadores tendr\u00e1n a su disposici\u00f3n toda la informaci\u00f3n necesaria para acceder a las cuentas de aquellos usuarios que hayan ca\u00eddo en el enga\u00f1o.<\/p>\n<p>\u00bf C\u00d3MO PROTEGERSE ? Al igual que ocurre con el Spam y los virus, la prudencia y cierta desconfianza inicial, son\u00a0 medidas que mejor pueden protegerle contra el fraude financiero en Internet.\u00a0 Hay que reconocer a tiempo este tipo de mensajes. Por norma, las entidades financieras, de cr\u00e9dito, etc. nunca pedir\u00e1n los datos de acceso a ning\u00fan cliente por medio de mensajes de correo electr\u00f3nico. En su lugar, deber\u00e1n dirigirse a usted a trav\u00e9s de su tel\u00e9fono particular con los mecanismos de reconocimiento de voz activados, o por correo postal ordinario, incluso certificado, o como el caso de algunas entidades de pago, los correos que Vd. reciba, deber\u00e1n estar personalizados con su nombre y apellidos y llevar\u00e1n asociada la identificaci\u00f3n de su cuenta.<\/p>\n<p>Sin duda, la mejor de las protecciones, ser\u00e1 la colaboraci\u00f3n de clientes y usuarios de estos servicios para poder interceptar a tiempo los lugares desde donde se emiten estos mensajes o donde se reciben los datos capturados. Si en alg\u00fan momento usted detecta alguno, o sospecha de la falsa identidad del remitente:<\/p>\n<ul>\n<li>\u00a0\u00a0\u00a0\u00a0No responda nunca a este tipo de mensajes salvo que tenga las m\u00e1ximas garant\u00edas de que provienen de la fuente correcta.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0P\u00f3ngase lo antes posible en contacto con los servicios de atenci\u00f3n al cliente de la entidad referida.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Realice un seguimiento diario de los movimientos de su cuenta durante los d\u00edas posteriores.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Tranquilo: tenga en cuenta que por el simple hecho de recibir ese tipo de correos, sus datos personales no se encuentran en peligro.<\/li>\n<\/ul>\n<p>Recomendaciones para su seguridad en Internet.\u00a0<\/p>\n<ul>\n<li>\u00a0\u00a0\u00a0\u00a0No revele nunca sus claves. Y menos las 3 juntas, usuario \u2013 clave secreta \u2013 firma<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Antes de realizar una transacci\u00f3n verifique los datos de su saldo y compruebe las fechas de las \u00faltimas operaciones.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Mant\u00e9ngase regularmente informado del estado de sus cuentas<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Mantenga correctamente actualizado su antivirus y vigile los registros de seguridad de su cortafuego (firewall).<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Desactive las funciones de almacenamiento de claves en la cach\u00e9 del sistema.<\/li>\n<\/ul>\n<p>Y si se lo piden por tel\u00e9fono, procure asegurarse de que el interlocutor pertenece de forma leg\u00edtima a la entidad referida:<\/p>\n<ul>\n<li>\u00a0\u00a0\u00a0\u00a0Inicialmente intente ser usted mismo quien realice la llamada al n\u00famero habitual del servicio de atenci\u00f3n al cliente de la entidad.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Pida que se identifique de forma clara y correcta.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Como empleado de la entidad, y ya que nos est\u00e1 pidiendo informaci\u00f3n personal, solicite que le ampl\u00ede mayores detalles sobre sus propios datos:<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0D.N.I, domicilio, n\u00famero de cuenta<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Saldo disponible en la actualidad<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0Datos de la \u00faltima operaci\u00f3n o apunte en su cuenta.<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0En general, cualquier informaci\u00f3n que no pueda estar disponible f\u00e1cilmente salvo para empleados de la entidad.<\/li>\n<\/ul>\n<p>Recomendaciones sobre T\u00e9cnicas b\u00e1sicas de seguridad.<\/p>\n<p>Haga caso a su entidad bancaria. Procure seguir las recomendaciones de seguridad establecidas por la entidad a la que est\u00e1 accediendo. Todas ellas disponen de p\u00e1ginas de seguridad donde explican con detalle las medidas a tener en cuenta para proteger su acceso.<\/p>\n<p>\u201cHTTPS\u201d: En general, casi todos los sitios Internet relacionados con bancos, entidades financieras o de cr\u00e9dito, le dirigir\u00e1n hacia un servidor seguro durante el proceso de introducci\u00f3n de sus datos de identificaci\u00f3n personal. La direcci\u00f3n debe comenzar con https en lugar de solo http: (note la \u201cs\u201d al final).\u00a0 Un WEB con una URL \u201chttps:\u201d es un sitio seguro, aunque https no garantiza en ning\u00fan caso que el sitio al que se ha conectado pertenece realmente a quien dice pertenecer.<\/p>\n<p><strong>LA DIFERENCIA ENTRE \u201chttp:\/\/\u201d y \u201chttps:\/\/\u201d\u00a0<\/strong>\u00a0\u00a0<br \/>\n\u00a0<br \/>\nLa\u00a0 mayor\u00eda\u00a0 de\u00a0 la gente ignora que la diferencia entre http:\/\/ y https:\/\/ es, sencillamente, su seguridad. Si la sabes y ya la tienes en cuenta no es necesario que sigas leyendo.<br \/>\n\u00a0<br \/>\nHTTP\u00a0 son\u00a0 las\u00a0 siglas\u00a0 de\u00a0 \u201cHyper Text Transport Protocol\u201d, que es un modo elegante\u00a0 de\u00a0 definir,\u00a0 por\u00a0 as\u00ed\u00a0 decirlo,\u00a0 un\u00a0 lenguaje\u00a0 para intercambiar informaci\u00f3n entre servidores y clientes de la red.<br \/>\n\u00a0<br \/>\nLo\u00a0 importante,\u00a0 y\u00a0 lo\u00a0 que\u00a0 marca\u00a0 la\u00a0 diferencia,\u00a0 es la letra \u201cS\u201d que se corresponde con \u201cSecure\u201d ( seguro). Si\u00a0 visitas\u00a0 una\u00a0 p\u00e1gina\u00a0 web\u00a0 y\u00a0 te\u00a0 fijas en su direcci\u00f3n, ver\u00e1s que, muy probablemente,\u00a0 empieza\u00a0 por <strong>http:\/\/<\/strong>.\u00a0\u00a0\u00a0\u00a0 Esto significa que esa p\u00e1gina te est\u00e1 hablando en un lenguaje normal, pero inseguro. En otras palabras, existe la posibilidad\u00a0 de que alguien pueda estar espiando la \u201cconversaci\u00f3n\u201d entre tu ordenador\u00a0 y\u00a0 la\u00a0 p\u00e1gina.\u00a0 Si\u00a0 trasladas\u00a0 una informaci\u00f3n a esa p\u00e1gina, ese alguien puede verla y hacer uso de ella. \u00a0 Por\u00a0 este\u00a0 motivo,\u00a0 jam\u00e1s deber\u00edas dar el n\u00famero de tu tarjeta de cr\u00e9dito a una p\u00e1gina http:\/\/\u00a0\u00a0\u00a0\u00a0 Pero\u00a0 si\u00a0 la\u00a0 direcci\u00f3n empieza por https:\/\/, tu ordenador est\u00e1 conectado a una\u00a0 p\u00e1gina\u00a0 que\u00a0 te\u00a0 est\u00e1\u00a0 hablando\u00a0 en un lenguaje codificado y seguro, a prueba de esp\u00edas.<br \/>\n\u00a0<br \/>\nPor\u00a0 tu\u00a0 seguridad,\u00a0 si\u00a0 para\u00a0 hacer una compra o por cualquier otro motivo tienes\u00a0 que\u00a0 dar\u00a0 el\u00a0 n\u00famero\u00a0 de\u00a0 tu\u00a0 tarjeta\u00a0 u otra informaci\u00f3n sensible, comprueba\u00a0 primero\u00a0 que\u00a0 la\u00a0 direcci\u00f3n\u00a0 de\u00a0 la\u00a0 p\u00e1gina\u00a0 web\u00a0 con la que has conectado empieza por https:\/\/<\/p>\n<p>\u201cCertificados\u201d:una vez en un sitio seguro, otro indicador es la presencia de un peque\u00f1o candado amarillo justo a la derecha del navegador (en la versi\u00f3n 7 de Internet Explorer). Un doble clic sobre el mismo debe mostrarle la informaci\u00f3n del certificado de Autoridad que debe coincidir con el nombre de la entidad a la que hemos solicitado su p\u00e1gina, adem\u00e1s de estar vigente y ser v\u00e1lido.\u00a0\u00a0\u00a0\u00a0<\/p>\n<p>La combinaci\u00f3n de los dos elementos\u00a0 https + certificado v\u00e1lido , si se puede considerar como una garant\u00eda suficientemente aceptable de que el lugar en el que se encuentra es aut\u00e9ntico, es decir, pertenece a la entidad representada, aunque hoy por hoy, no existe todav\u00eda en la inform\u00e1tica un 100% absoluto de seguridad total.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cortes\u00eda de la Polic\u00eda Local de Cambrils: \u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2013\u00a0 Es p\u00fablico i notorio el hecho que\u00a0 la navegaci\u00f3n a trav\u00e9s de Internet no son seguros al 100%. I todav\u00eda no hemos capaces de crear programas i soportes inform\u00e1ticos que protejan nuestro patrimonio, intimidad y seguridad. Informaticamente hablando, vivimos en un mundo\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[1108,38],"tags":[1012,1041,1047,1060,1147,1138,1051,1119],"class_list":["post-828","post","type-post","status-publish","format-standard","hentry","category-leyesjusticia","category-temas-profesionales","tag-ave","tag-informatica","tag-internet","tag-lengua","tag-lenguaje","tag-patrimonio-2","tag-planta","tag-social"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-15T23:14:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-fraude-financiero-a-traves-de-internet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-fraude-financiero-a-traves-de-internet\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET\",\"datePublished\":\"2010-10-15T23:14:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-fraude-financiero-a-traves-de-internet\\\/\"},\"wordCount\":1895,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"keywords\":[\"ave\",\"informatica\",\"internet\",\"lengua\",\"lenguaje\",\"patrimonio\",\"planta\",\"social\"],\"articleSection\":[\"Leyes\\\/Justicia\",\"Temas profesionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-fraude-financiero-a-traves-de-internet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-fraude-financiero-a-traves-de-internet\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-fraude-financiero-a-traves-de-internet\\\/\",\"name\":\"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"datePublished\":\"2010-10-15T23:14:41+00:00\",\"description\":\"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-fraude-financiero-a-traves-de-internet\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-fraude-financiero-a-traves-de-internet\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-fraude-financiero-a-traves-de-internet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa","description":"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/","og_locale":"es_ES","og_type":"article","og_title":"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa","og_description":"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2010-10-15T23:14:41+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET","datePublished":"2010-10-15T23:14:41+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/"},"wordCount":1895,"commentCount":1,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"keywords":["ave","informatica","internet","lengua","lenguaje","patrimonio","planta","social"],"articleSection":["Leyes\/Justicia","Temas profesionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/","url":"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/","name":"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"datePublished":"2010-10-15T23:14:41+00:00","description":"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/el-fraude-financiero-a-traves-de-internet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"EL FRAUDE FINANCIERO A TRAV\u00c9S DE INTERNET"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":1,"uagb_excerpt":"Cortes\u00eda de la Polic\u00eda Local de Cambrils: \u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2013\u00a0 Es p\u00fablico i notorio el hecho que\u00a0 la navegaci\u00f3n a trav\u00e9s de Internet no son seguros al 100%. I todav\u00eda no hemos capaces de crear programas i soportes inform\u00e1ticos que protejan nuestro patrimonio, intimidad y seguridad. Informaticamente hablando, vivimos en un mundo\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=828"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/828\/revisions"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}