{"id":738,"date":"2010-06-28T20:59:43","date_gmt":"2010-06-28T18:59:43","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=738"},"modified":"2018-12-22T03:13:05","modified_gmt":"2018-12-22T01:13:05","slug":"cl-aniversario-de-anton-pavlovich-chejov","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/","title":{"rendered":"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">M\u00e9dico de profesi\u00f3n, nace el 29 de enero de 1860 en Taganrog (sur de Rusia) y muere el 15 de julio de 1904 en Badenweiler (Alemania). Fue uno de los grandes novelistas y dramaturgos rusos, frecuentemente sus obras fueron llevadas al teatro y representadas con gran \u00e9xito de cr\u00edtica y p\u00fablico, junto a otros cl\u00e1sicos de la literatura rusa como Dostoievsky o Tolstoi.<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/natureduca.com\/images_culturblog\/tchekhov-10-2.gif\" alt=\"\" width=\"265\" height=\"204\" \/><\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">Este a\u00f1o 2010 fue declarado por la UNESCO el \u201cA\u00f1o Ch\u00e9jov\u201d y como bien sentenci\u00f3 otro de los grandes literatos rusos: \u201cSu obra es comprensible, familiar y af\u00edn, no s\u00f3lo al ruso, sino tambi\u00e9n a cualquier persona de la Tierra\u201d (Le\u00f3n Tosltoi), incluso para algunos profesionales de la literatura, como Patrick Miles: \u201cFue el Shakespeare del siglo XX\u201d. La originalidad del autor ruso fue la t\u00e9cnica del mon\u00f3logo que m\u00e1s tarde adoptan Joyce y otros escritores modernistas anglosajones.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">El sello que le dedic\u00f3 el correo monegasco en el primer grupo de emisiones del 2010, muestra al escritor y, como fondo, una escena inspirada en \u201cLas tres hermanas\u201d. El dise\u00f1o fue obra de Gu\u00e9orgui Chichkine, el grabado realizado por Pierre Albuisson, se confeccion\u00f3 en talla dulce, tama\u00f1o 52&#215;40 mm horizontal y la impresi\u00f3n en minipliegos de seis ejemplares.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">De acuerdo con los datos de La Voz de Rusia que le dedic\u00f3 un especial dentro de la serie MOSC\u00da y LOS MOSCOVITAS emitido el pasado 29 de enero, d\u00eda del aniversario. Su floraci\u00f3n como escritor se da en la capital a donde lleg\u00f3 con 19 a\u00f1os. Estudi\u00f3 medicina en la Universidad moscovita (1879-1884) y cre\u00f3 la mayor\u00eda de las obras que hoy son patrimonio de la literatura universal. Pronto su nombre ser\u00e1 asociado a publicaciones humor\u00edsticas, en 1886 apareci\u00f3 <em>\u201cCuentos de varios colores\u201d<\/em>.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">Sol\u00eda decir que \u201c<em>la medicina es mi esposa leal y la literatura, mi amante<\/em>\u201d; tras sus primeros cuentos y novelas cortas, se inicia la etapa en la que se ver\u00e1 encumbrado a lo m\u00e1s alto de la literatura universal: \u201c<em>La estepa<\/em>\u201d (1888), \u201c<em>El T\u00edo Vania<\/em>\u201d (1898-99),\u00a0 \u201c<em>Las tres hermanas<\/em>\u201d (1901), \u201c<em>El jard\u00edn de los cerezos<\/em>\u201d (1904), etc.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">Su primer estreno teatral fue \u201c<em>Ivanov\u201d <\/em>(1887); fue la mala acogida inicial a \u201c<em>La gaviota<\/em>\u201d en el Teatro Aleksandrinski de San Petersburgo, lo que le impuls\u00f3, en 1896, a abandonar las obras teatrales, aunque dos a\u00f1os despu\u00e9s alcanzar\u00eda un extraordinario \u00e9xito tras ser interpretada en Mosc\u00fa. Le siguieron \u201c<em>El T\u00edo Vania, Las tres hermanas y El jard\u00edn de los cerezos<\/em>\u201d, representadas en el Teatro del Arte de Konstantin Stanislavsky.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">Ese cambio tan dr\u00e1stico en la suerte corrida por \u201c<em>La gaviota<\/em>\u201d [en ella satirizaba el lenguaje de los decadentes, en estos momentos ser\u00eda el equivalente de los seudo-progres que nos gobiernan] le convenci\u00f3 de lo correcto de su trabajo como autor dram\u00e1tico que lleg\u00f3 a crear una atm\u00f3sfera que hoy se adjetiviza con su apellido: \u201cchejoviano\u201d o lo que es lo mismo, un estado de \u00e1nimo que caracteriza al alegre melanc\u00f3lico. La actriz Olga Knipper, con quien se cas\u00f3 en 1898, lo compar\u00f3 precisamente con esta ave marina que sobrevuela el mar [es un decir, hoy sabemos que es una de las carro\u00f1eras con una de las colonias m\u00e1s grandes de toda la pen\u00ednsula Ib\u00e9rica en Madrid] y no sabe d\u00f3nde posarse.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">\u00c9l supo, como pocos, que su aguda intuici\u00f3n, sobre la tristeza de la vida, era en realidad un adelanto; Ch\u00e9jov madur\u00f3, con un gran bagaje en su poder, vio con horror, lo que la vida encierra, donde nada es lo que parece y no todo es color de rosa. Aunque, visto lo visto, es l\u00f3gico pensar que los grandes hombres se crecen con las dificultades, que la vida licenciosa, sosegada o el ir a ninguna parte como nos ha tocado en el siglo XXI es a\u00fan m\u00e1s dura de sobrellevar, precisamente por las incertidumbres que plantea al ser humano en un momento de su historia en el que se le ofrece m\u00e1s libertad [o al menos eso cree] pero, en realidad, es m\u00e1s esclavo de su propio egocentrismo, de su propio mundo que lo tiene atrapado, aislado de su entorno; nada m\u00e1s atravesar esa frontera se encuentra con una realidad que le desborda, le atrapa y le desnuda en el m\u00e1s amplio sentido de la palabra.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">Ch\u00e9jov se mostr\u00f3 extraordinariamente simple, aunque no guard\u00f3 palabras para describir la complejidad y la tristeza que se hallan ocultas en la propia naturaleza humana y es que, sobre todo, un autor que am\u00f3 y vivi\u00f3 la vida, no s\u00f3lo de la Rusia de su tiempo, sino la que todav\u00eda estaba por venir. A veces nos puede resultar un autor triste, pero le\u00eddo con calma, con entrega, uno descubre a un autor que [como pocos] supo retratar las interioridades humanas y, a pesar de lo dram\u00e1tico de su legado, hacernos part\u00edcipes de un momento de la historia del hombre que a\u00fan est\u00e1 vigente; aunque las nuevas generaciones, a veces, no sepan sacar los frutos de sus textos y es que, tampoco es f\u00e1cil entender sus obras, sin una entrega, sin un tiempo y parece, precisamente, la sociedad idiotizada y consumista del momento que nos toca vivir en este desnortado XXI, no lo tiene. Donde en lugar de ciudadanos cr\u00edticos y coherentes, nos encontramos una sociedad caprichosa y nihilista que s\u00f3lo vive para su propia contemplaci\u00f3n, no contenta con su suerte, cae en la tentaci\u00f3n consumista de los dise\u00f1adores del momento que le ofrecen un mundo irreal, cuando se encuentra desbordado ya es demasiado tarde y no hay forma de recuperar el tiempo perdido.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">Como resultado generaciones enteras son lanzadas a la basura sin ning\u00fan tipo de contemplaciones. Generaciones rotas, precisamente, por no querer mirar m\u00e1s all\u00e1 del espejo que les deja obnubilados; \u00e9l, adelantado, apuesta por la ruptura y con decisi\u00f3n se aleja del moralismo imperante y la intencionalidad pedag\u00f3gica que intentan sembrar los intelectuales del momento, especialmente sus coet\u00e1neos; gui\u00e1ndose por un nuevo camino y rechazando el compromiso con el momento hist\u00f3rico que le toc\u00f3 vivir, posiblemente esta falta de compromiso con el orden establecido provenga de sus mismos or\u00edgenes, su padre era un modesto comerciante que descend\u00eda de un siervo de la gleba y poco le un\u00eda con el mundo acomodado de los literatos de su tiempo.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">Est\u00e1 considerado el m\u00e1s directo representante de la denominada escuela realista rusa, fue Suvorin, entonces director de <em>Novoe Vremja<\/em> (Tiempo Nuevo) el que le anim\u00f3 a escribir. En 1888 era un autor sobradamente conocido por el gran p\u00fablico. Poco a poco fue abandonando su lado humor\u00edstico para adentrarse en relatos m\u00e1s costumbristas, donde retrataba, con toda crudeza, las miserias humanas en el m\u00e1s amplio sentido del t\u00e9rmino. Ese mismo a\u00f1o public\u00f3 \u201c<em>La estepa<\/em>\u201d que narraba un viaje realizado al sur de su pa\u00eds en donde\u00a0 describ\u00eda c\u00f3mo hab\u00edan desaparecido los id\u00edlicos paisajes de su infancia a favor de la industrializaci\u00f3n y se rebela contra la destrucci\u00f3n de la naturaleza (finales del XIX) \u00bfQu\u00e9 dir\u00eda de este maltratado planeta donde parece que todo sobra y cada vez hay menos espacio para ella?<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">En esa etapa llegaba a producir un centenar de relatos al a\u00f1o (muchos de ellos los encontramos colgados en la red y pueden bajarse libremente); en 1888 ya decide producir s\u00f3lo una decena y aparece <em>\u201cUna historia aburrida\u201d<\/em> (1889), se centra en un profesional de la medicina, adentr\u00e1ndose en la parte ps\u00edquica, en la mente que tanto le preocup\u00f3 y en donde tal vez haya no una parte novelada, sino autobiogr\u00e1fica del gran escritor. Seguramente <em>\u201cPalata n\u00famero 6\u201d <\/em>(1892) fue el relato m\u00e1s conocido dentro de los textos que \u00e9l denomin\u00f3 literatura cl\u00ednica y donde podr\u00edamos concluir hay algo de novela negra, pues el doctor Ragin acaba internado en su propia cl\u00ednica y uno de sus celadores le causar\u00e1 la muerte.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">Otra gran aventura nos la relata tras un largo viaje que le lleva hasta las costas del Pac\u00edfico, a\u00fan hoy, uno de esos lugares m\u00edticos y salvajes que no han sido destrozados por el turismo de masas; en <em>\u201cLa isla de Sakhalin\u201d <\/em>(1891), en cierta medida, se recoge parte de otra anterior <em>\u201cEl demonio de madera\u201d <\/em>que ser\u00eda la base para <em>\u201cEl T\u00edo Vania\u201d<\/em> que tanto \u00e9xito cosech\u00f3 tras producirse su estreno en 1900. La isla era un lugar de destierro, de abandono, en los confines de la inmensa Rusia. All\u00ed se enfrent\u00f3 a la m\u00e1s cruda realidad del sufrimiento humano al ver la vida de los prisioneros totalmente desprotegidos; su testimonio signific\u00f3 el viaje de una Comisi\u00f3n de Estado para tratar de reparar los excesos cometidos en la isla-prisi\u00f3n de los m\u00e1s d\u00e9spotas de los funcionarios all\u00ed enviados que, al fin y al cabo, no dejaban de ser otros desterrados en los confines del imperio.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">En esa obra narra su largo viaje a trav\u00e9s de Siberia y el regreso por la India. Al a\u00f1o siguiente, ante la cat\u00e1strofe que se cierne, tras la crisis alimenticia, participa en la ayuda sanitaria al pueblo ruso y poco despu\u00e9s se instala en su peque\u00f1a propiedad de Melichovo que era su particular rinc\u00f3n literario. Enferm\u00f3, esa fue la causa de su desplazamiento a Crimea, luego a Francia y Alemania en busca de mejores aires que le dieran un respiro a su tuberculosis. Fue una etapa en la que se radicaliz\u00f3 y se alej\u00f3 de sus viejos amigos, incluso dimiti\u00f3 de la Academia: ya no estaba dispuesto a tolerar la inercia moral, la desidia ni la falta de compromiso y responsabilidad de sus paisanos [\u00bfQu\u00e9 dir\u00eda de la Espa\u00f1a de ZP?]. En definitiva, no compart\u00eda la decadencia del hombre y ello le reportaba grandes quebraderos de cabeza. Ve, en toda su crudeza, la imposibilidad de llevar a cabo su deseo de reforma en la manera de pensar de sus coet\u00e1neos; el gran drama de los genios, los adelantados a su tiempo biol\u00f3gico que viven su vida en un constante devenir que recala en el dram\u00e1tico fin de su propia existencia.<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">En su legado teatral las pausas caracter\u00edsticas, m\u00e1s que un silencio interior [de los personajes] subrayan, dram\u00e1ticamente, el vac\u00edo de unos seres sin voluntad ni fe para enfrentarse a la dura realidad del momento. Aniquilada la dignidad, queda aniquilado el individuo. Los pol\u00edticos del XXI son pr\u00f3digos en este tipo de \u201cenga\u00f1o masivo\u201d y as\u00ed nos va cuando nos hacen creer en el \u201cverbo\u201d y olvidamos su contenido. Grecia ser\u00e1 poco para lo que se nos viene encima, algunos rincones del mundo todav\u00eda no salieron del agujero negro en que los metieron los s\u00e1trapas populistas y en otros lugares siguen empe\u00f1ados en negar las evidencias del desastre. \u00bfQuo Vadis Espa\u00f1a?<\/span><\/span><\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">Por aquello de su relaci\u00f3n con el mundo postal, las comunicaciones y el funcionariado, recomiendo leer \u201c<em>En la administraci\u00f3n de correos\u201d, \u201cEl tel\u00e9fono\u201d, \u201cLa colecci\u00f3n\u201d <\/em>o<em> \u201cLa muerte de un funcionario p\u00fablico\u201d, <\/em>[<\/span><\/span><a href=\"http:\/\/www.ciudadseva.com\/textos\/cuentos\/rus\/chejov\/ac.htm\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">www.ciudadseva.com\/textos\/cuentos\/rus\/chejov\/ac.htm<\/span><\/span><\/a><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">].<\/span><\/span><\/p>\n<p><a href=\"http:\/\/www.oetp-monaco.com\/\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">www.oetp-monaco.com<\/span><\/span><\/a><br \/>\n<span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">www.vor.ru<\/span><\/span><br \/>\n<span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">www.ruvr.ru<\/span><\/span><br \/>\n<a href=\"mailto:oetp@gouv.mc\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">oetp@gouv.mc<\/span><\/span><\/a><\/p>\n<p align=\"center\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">JUAN FRANCO CRESPO<br \/>\n<\/span><\/span><a href=\"mailto:lacandon999@yahoo.es\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: small;\">lacandon999@yahoo.es<\/span><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9dico de profesi\u00f3n, nace el 29 de enero de 1860 en Taganrog (sur de Rusia) y muere el 15 de julio de 1904 en Badenweiler (Alemania). Fue uno de los grandes novelistas y dramaturgos rusos, frecuentemente sus obras fueron llevadas al teatro y representadas con gran \u00e9xito de cr\u00edtica y\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":8,"featured_media":-1,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[16,14,7],"tags":[1016,1012,1018,1067,1049,1140,1015,1017,1054,1060,1147,1043,1065,1014,1138,1025,1066,1021,1026,1150,1064],"class_list":["post-738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-tradiciones","category-filatelia","category-personajes","tag-arte","tag-ave","tag-ayuda","tag-crisis","tag-drama","tag-escena","tag-flor","tag-historia","tag-industria","tag-lengua","tag-lenguaje","tag-literatura-2","tag-medicina","tag-naturaleza","tag-patrimonio-2","tag-rosa","tag-rusia","tag-sociedad","tag-teatro","tag-textos","tag-universidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-28T18:59:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-22T01:13:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Franco Crespo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Franco Crespo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/\"},\"author\":{\"name\":\"Juan Franco Crespo\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/f6dccdcd6c23ee151a1d5a173ca21baf\"},\"headline\":\"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV\",\"datePublished\":\"2010-06-28T18:59:43+00:00\",\"dateModified\":\"2018-12-22T01:13:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/\"},\"wordCount\":1928,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/tchekhov-10-2.gif\",\"keywords\":[\"arte\",\"ave\",\"ayuda\",\"crisis\",\"drama\",\"escena\",\"flor\",\"historia\",\"industria\",\"lengua\",\"lenguaje\",\"literatura\",\"medicina\",\"naturaleza\",\"patrimonio\",\"rosa\",\"rusia\",\"sociedad\",\"teatro\",\"textos\",\"universidad\"],\"articleSection\":[\"Cultura \\\/ tradiciones\",\"Filatelia\",\"Personajes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/\",\"name\":\"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/tchekhov-10-2.gif\",\"datePublished\":\"2010-06-28T18:59:43+00:00\",\"dateModified\":\"2018-12-22T01:13:05+00:00\",\"description\":\"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/#primaryimage\",\"url\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/tchekhov-10-2.gif\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/tchekhov-10-2.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cl-aniversario-de-anton-pavlovich-chejov\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/f6dccdcd6c23ee151a1d5a173ca21baf\",\"name\":\"Juan Franco Crespo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g\",\"caption\":\"Juan Franco Crespo\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/juan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa","description":"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/","og_locale":"es_ES","og_type":"article","og_title":"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa","og_description":"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2010-06-28T18:59:43+00:00","article_modified_time":"2018-12-22T01:13:05+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Juan Franco Crespo","twitter_misc":{"Escrito por":"Juan Franco Crespo","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/"},"author":{"name":"Juan Franco Crespo","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/f6dccdcd6c23ee151a1d5a173ca21baf"},"headline":"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV","datePublished":"2010-06-28T18:59:43+00:00","dateModified":"2018-12-22T01:13:05+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/"},"wordCount":1928,"commentCount":0,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/#primaryimage"},"thumbnailUrl":"https:\/\/natureduca.com\/images_culturblog\/tchekhov-10-2.gif","keywords":["arte","ave","ayuda","crisis","drama","escena","flor","historia","industria","lengua","lenguaje","literatura","medicina","naturaleza","patrimonio","rosa","rusia","sociedad","teatro","textos","universidad"],"articleSection":["Cultura \/ tradiciones","Filatelia","Personajes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/","url":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/","name":"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/#primaryimage"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/#primaryimage"},"thumbnailUrl":"https:\/\/natureduca.com\/images_culturblog\/tchekhov-10-2.gif","datePublished":"2010-06-28T18:59:43+00:00","dateModified":"2018-12-22T01:13:05+00:00","description":"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/#primaryimage","url":"https:\/\/natureduca.com\/images_culturblog\/tchekhov-10-2.gif","contentUrl":"https:\/\/natureduca.com\/images_culturblog\/tchekhov-10-2.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/cl-aniversario-de-anton-pavlovich-chejov\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"CL ANIVERSARIO DE ANT\u00d3N PAVLOVICH CH\u00c9JOV"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/f6dccdcd6c23ee151a1d5a173ca21baf","name":"Juan Franco Crespo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g","caption":"Juan Franco Crespo"},"url":"https:\/\/natureduca.com\/culturblog\/author\/juan\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Juan Franco Crespo","author_link":"https:\/\/natureduca.com\/culturblog\/author\/juan\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Juan Franco Crespo","author_link":"https:\/\/natureduca.com\/culturblog\/author\/juan\/"},"uagb_comment_info":0,"uagb_excerpt":"M\u00e9dico de profesi\u00f3n, nace el 29 de enero de 1860 en Taganrog (sur de Rusia) y muere el 15 de julio de 1904 en Badenweiler (Alemania). Fue uno de los grandes novelistas y dramaturgos rusos, frecuentemente sus obras fueron llevadas al teatro y representadas con gran \u00e9xito de cr\u00edtica y\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=738"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}