{"id":683,"date":"2010-04-28T03:01:56","date_gmt":"2010-04-28T01:01:56","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=683"},"modified":"2015-05-21T15:19:17","modified_gmt":"2015-05-21T13:19:17","slug":"descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/","title":{"rendered":"DESCUBRIR LA CULTURA Y LAS ARTES  \u00abAcceder a los libros\u00bb fuente de sabiduria Colegio San Esteban de San Fernando VI- Region &#8211; Chile"},"content":{"rendered":"<p>ESTIMADOS AMIGOS LECTORES E INTERNAUTAS DE ESPA\u00d1A Y EL MUNDO;<\/p>\n<p style=\"text-align: justify\">Descubrir la Cultura y las Artes, son un buen motivo para acceder a los libros,\u00a0 es educarnos cada dia mejor haciendo uso de una magnifica herramienta para el desarrollo integral e intelectual de ni\u00f1os y jovenes del Colegio San Esteban de San Fernando, del mismo\u00a0modo hacerlos germinar como\u00a0 semillas y brindarnos a nosotros mismos su abundante cosecha en sabuduria y mayores conocimientos durante el presente a\u00f1o lectivo 2010.<\/p>\n<p style=\"text-align: justify\">Las tecnicas del conocimiento, entendimiento y comprension con claro sentido social al servicio de la humanidad, esa es y sera la contribucion de la Corporacion Colegio San Esteban y su selecto equipo Docente y profesionales a cargo de su Directora Sra. FABIOLA OYANEDEL.\u00a0 En efecto, nuestro mundo real ha cambiado diametralmente de lo que fue hace ya un siglo,\u00a0 marcado por grandes descubrimientos y cambios sociales,\u00a0guerras y destruccion;\u00a0 Tiempos aquellos\u00a0de\u00a0\u00a0hombres fuertes que ya no estan,\u00a0 pero que nos dejaron su legado de sacrificio y heroismo en la vistoriosa construccion del mundo en que vivimos,\u00a0 para construir otro mundo mucho mejor y descubrirnos a nosotros mismos de la mano con el creador, tambien con\u00a0la Ciencia y la Tecnologia.<\/p>\n<p style=\"text-align: justify\">Otra forma innovadora de educar son la participacion de nuestros educandos en las diferentes areas de\u00a0 Planes y Programas educativos, pensando vocacionalmente, sin prescindir de nuestro pasado, sino que por el contrario\u00a0 proyectarlo con la vision del futuro, ello ya no es una utopia.\u00a0 Involucrarnos en sus temas\u00a0 en concordancia con los con\u00a0 los nuevos tiempos,\u00a0 en creatividad e imaginacion es como\u00a0sentirlos correr en sus juegos juveniles e infantiles son una muestra\u00a0 que\u00a0el \u00a0alumnado ha comprendido\u00a0del Colegio San Esteban de San Fernando&#8230;que comienza a deslumbrar con sus nuevas experiencias vocacionales y educativas.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n<p style=\"text-align: justify\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 COLEGIO SAN ESTEBAN DE SAN FERNANDO VI REGION CHILE<\/p>\n<p style=\"text-align: justify\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 EXPRESIONES EDUCACIONALES\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-687\" src=\"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0776-200x150.jpg\" alt=\"Foto0776\" width=\"200\" height=\"150\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-684\" src=\"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0737-200x150.jpg\" alt=\"Foto0737\" width=\"200\" height=\"150\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-685\" src=\"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0769-200x150.jpg\" alt=\"Foto0769\" width=\"200\" height=\"150\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-686\" src=\"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0770-200x150.jpg\" alt=\"Foto0770\" width=\"200\" height=\"150\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-688\" src=\"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0814-200x150.jpg\" alt=\"Foto0814\" width=\"200\" height=\"150\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-689\" src=\"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0818-200x150.jpg\" alt=\"Foto0818\" width=\"200\" height=\"150\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-690\" src=\"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0823-200x150.jpg\" alt=\"Foto0823\" width=\"200\" height=\"150\" \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n<p style=\"text-align: justify\">PRESENTACION DEL \u00abCIRCO LOS MONTINI\u00bb EN\u00a0 COLEGIO SAN ESTEBAN\u00a0 &#8211; SAN FERNANDO<\/p>\n<p style=\"text-align: justify\">Hasta la proxima vez amigos&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.<\/p>\n<p style=\"text-align: justify\">RAUL DELONGARO PAREDES<\/p>\n<p style=\"text-align: justify\">San Fernando, VI Region-Chile<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTIMADOS AMIGOS LECTORES E INTERNAUTAS DE ESPA\u00d1A Y EL MUNDO; Descubrir la Cultura y las Artes, son un buen motivo para acceder a los libros,\u00a0 es educarnos cada dia mejor haciendo uso de una magnifica herramienta para el desarrollo integral e intelectual de ni\u00f1os y jovenes del Colegio San Esteban\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":31,"featured_media":-1,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[3],"tags":[1016,1139,1013,1009,1050,1034,1149,1119,1084],"class_list":["post-683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-temas-generales","tag-arte","tag-artes","tag-ciencia","tag-cultura","tag-educacion-2","tag-guerra","tag-libros-2","tag-social","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DESCUBRIR LA CULTURA Y LAS ARTES &quot;Acceder a los libros&quot; fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"DESCUBRIR LA CULTURA Y LAS ARTES &quot;Acceder a los libros&quot; fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DESCUBRIR LA CULTURA Y LAS ARTES &quot;Acceder a los libros&quot; fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"DESCUBRIR LA CULTURA Y LAS ARTES &quot;Acceder a los libros&quot; fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-28T01:01:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-21T13:19:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ra\u00fal Delongaro Paredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ra\u00fal Delongaro Paredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/\"},\"author\":{\"name\":\"Ra\u00fal Delongaro Paredes\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/04c94b47ed7f2c46865d6ba674032575\"},\"headline\":\"DESCUBRIR LA CULTURA Y LAS ARTES \u00abAcceder a los libros\u00bb fuente de sabiduria Colegio San Esteban de San Fernando VI- Region &#8211; Chile\",\"datePublished\":\"2010-04-28T01:01:56+00:00\",\"dateModified\":\"2015-05-21T13:19:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/\"},\"wordCount\":356,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.natureduca.com\\\/culturblog\\\/wp-content\\\/Foto0776-200x150.jpg\",\"keywords\":[\"arte\",\"artes\",\"ciencia\",\"cultura\",\"educacion\",\"guerra\",\"libros\",\"social\",\"tecnologia\"],\"articleSection\":[\"Temas generales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/\",\"name\":\"DESCUBRIR LA CULTURA Y LAS ARTES \\\"Acceder a los libros\\\" fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.natureduca.com\\\/culturblog\\\/wp-content\\\/Foto0776-200x150.jpg\",\"datePublished\":\"2010-04-28T01:01:56+00:00\",\"dateModified\":\"2015-05-21T13:19:17+00:00\",\"description\":\"DESCUBRIR LA CULTURA Y LAS ARTES \\\"Acceder a los libros\\\" fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.natureduca.com\\\/culturblog\\\/wp-content\\\/Foto0776-200x150.jpg\",\"contentUrl\":\"http:\\\/\\\/www.natureduca.com\\\/culturblog\\\/wp-content\\\/Foto0776-200x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DESCUBRIR LA CULTURA Y LAS ARTES \u00abAcceder a los libros\u00bb fuente de sabiduria Colegio San Esteban de San Fernando VI- Region &#8211; Chile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/04c94b47ed7f2c46865d6ba674032575\",\"name\":\"Ra\u00fal Delongaro Paredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dc1f1148412f220968957ccd272f11f23f3df09a03c02fb563a20e695a872df?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dc1f1148412f220968957ccd272f11f23f3df09a03c02fb563a20e695a872df?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dc1f1148412f220968957ccd272f11f23f3df09a03c02fb563a20e695a872df?s=96&d=monsterid&r=g\",\"caption\":\"Ra\u00fal Delongaro Paredes\"},\"description\":\"escritor - relacionador publico\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/raul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DESCUBRIR LA CULTURA Y LAS ARTES \"Acceder a los libros\" fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa","description":"DESCUBRIR LA CULTURA Y LAS ARTES \"Acceder a los libros\" fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/","og_locale":"es_ES","og_type":"article","og_title":"DESCUBRIR LA CULTURA Y LAS ARTES \"Acceder a los libros\" fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa","og_description":"DESCUBRIR LA CULTURA Y LAS ARTES \"Acceder a los libros\" fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2010-04-28T01:01:56+00:00","article_modified_time":"2015-05-21T13:19:17+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Ra\u00fal Delongaro Paredes","twitter_misc":{"Escrito por":"Ra\u00fal Delongaro Paredes","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/"},"author":{"name":"Ra\u00fal Delongaro Paredes","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/04c94b47ed7f2c46865d6ba674032575"},"headline":"DESCUBRIR LA CULTURA Y LAS ARTES \u00abAcceder a los libros\u00bb fuente de sabiduria Colegio San Esteban de San Fernando VI- Region &#8211; Chile","datePublished":"2010-04-28T01:01:56+00:00","dateModified":"2015-05-21T13:19:17+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/"},"wordCount":356,"commentCount":4,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/#primaryimage"},"thumbnailUrl":"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0776-200x150.jpg","keywords":["arte","artes","ciencia","cultura","educacion","guerra","libros","social","tecnologia"],"articleSection":["Temas generales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/","url":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/","name":"DESCUBRIR LA CULTURA Y LAS ARTES \"Acceder a los libros\" fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/#primaryimage"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/#primaryimage"},"thumbnailUrl":"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0776-200x150.jpg","datePublished":"2010-04-28T01:01:56+00:00","dateModified":"2015-05-21T13:19:17+00:00","description":"DESCUBRIR LA CULTURA Y LAS ARTES \"Acceder a los libros\" fuente de sabiduria Colegio San Esteban de San Fernando VI- Region - Chile - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/#primaryimage","url":"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0776-200x150.jpg","contentUrl":"http:\/\/www.natureduca.com\/culturblog\/wp-content\/Foto0776-200x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/descubrir-la-cultura-y-las-artes-acceder-a-los-libros-fuente-de-sabiduria-colegio-san-esteban-de-san-fernando-vi-region-chile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"DESCUBRIR LA CULTURA Y LAS ARTES \u00abAcceder a los libros\u00bb fuente de sabiduria Colegio San Esteban de San Fernando VI- Region &#8211; Chile"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/04c94b47ed7f2c46865d6ba674032575","name":"Ra\u00fal Delongaro Paredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1dc1f1148412f220968957ccd272f11f23f3df09a03c02fb563a20e695a872df?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1dc1f1148412f220968957ccd272f11f23f3df09a03c02fb563a20e695a872df?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1dc1f1148412f220968957ccd272f11f23f3df09a03c02fb563a20e695a872df?s=96&d=monsterid&r=g","caption":"Ra\u00fal Delongaro Paredes"},"description":"escritor - relacionador publico","url":"https:\/\/natureduca.com\/culturblog\/author\/raul\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Ra\u00fal Delongaro Paredes","author_link":"https:\/\/natureduca.com\/culturblog\/author\/raul\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Ra\u00fal Delongaro Paredes","author_link":"https:\/\/natureduca.com\/culturblog\/author\/raul\/"},"uagb_comment_info":4,"uagb_excerpt":"ESTIMADOS AMIGOS LECTORES E INTERNAUTAS DE ESPA\u00d1A Y EL MUNDO; Descubrir la Cultura y las Artes, son un buen motivo para acceder a los libros,\u00a0 es educarnos cada dia mejor haciendo uso de una magnifica herramienta para el desarrollo integral e intelectual de ni\u00f1os y jovenes del Colegio San Esteban\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=683"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}