{"id":4579,"date":"2016-05-24T11:25:14","date_gmt":"2016-05-24T09:25:14","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=4579"},"modified":"2018-12-22T11:08:03","modified_gmt":"2018-12-22T09:08:03","slug":"250-aniversario-de-nolsoyar-pall","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/","title":{"rendered":"250 ANIVERSARIO DE NOLSOYAR PALL"},"content":{"rendered":"<p>\u00bfDe qu\u00e9 madera est\u00e1n hechos los h\u00e9roes nacionales que, resisten, imperturbables, el paso del tiempo?<\/p>\n<p>Con esta pregunta nos introduce el correo fero\u00e9s en uno de esos personajes b\u00e1sicos\u00a0 para entender la historia de este pueblo insular y sus grandes navegantes. Dicen las leyendas que cualquier fero\u00e9s conoce la historia de este personaje que vino al mundo en 1766; justo al a\u00f1o siguiente abr\u00eda sus puertas un comerciante dan\u00e9s en la capital insular: Niels Ryberg, ten\u00eda como objetivo evitar las restricciones comerciales que provoc\u00f3 en la regi\u00f3n la revoluci\u00f3n americana [hoy vemos que seguimos anclados en la misma pol\u00edtica, si hay problemas, lo primero que eliminamos es el comercio, caso 2016 en la ONU y el boicot contra Pyongyang, o sea: la poblaci\u00f3n civil a pasar penurias mientras que los promotores ponen a buen recaudo sus inmensas fortunas, levantadas a sus pueblos, en los opacos para\u00edsos fiscales] y del enfrentamiento b\u00e9lico entre Francia e Inglaterra.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" id=\"__wp-temp-img-id\" class=\"aligncenter\" src=\"https:\/\/natureduca.com\/images_culturblog\/filatelia_feroes_nolsoyar1.jpg\" alt=\"250 ANIVERSARIO DE NOLSOYAR PALL\" width=\"300\" height=\"416\" \/><\/p>\n<p>De esa manera Ryberg se abr\u00eda al mundo y se creaba un gran monopolio comercial que marcar\u00e1 a los habitantes de las islas que hasta entonces realizaban peque\u00f1os cultivos de subsistencia, pesca costera, caza o recolecci\u00f3n de huevos en sus escarpados acantilados donde anidan miles de aves, especialmente frailecillos. Los feroeses comenzaron a ir m\u00e1s all\u00e1 de sus habituales rutas, uno de ellos ser\u00eda nuestro intr\u00e9pido personaje filatelizado ahora y que durante algunos a\u00f1os cubri\u00f3 la ruta Feroe-Dinamarca y acabar\u00e1 enrol\u00e1ndose como oficial en nav\u00edos daneses y americanos que le llevar\u00e1n a recorrer el globo terr\u00e1queo en aquello que mejor sab\u00eda hacer: navegar.<\/p>\n<p>En 1798 era capit\u00e1n de la flota comercial del monopolio real del momento, se cas\u00f3, tuvo una hija y, poco despu\u00e9s, mor\u00eda su esposa. Al a\u00f1o siguiente de ese luctuoso hecho volv\u00eda a contraer nupcias y se instalaba en lo que actualmente conocemos como Klaksvik [entonces Biskupsstad] que pasa por ser la segunda ciudad m\u00e1s importante de las islas gracias al comercio que en aquellos momentos se desarrollaba y que signific\u00f3 una inusitada explosi\u00f3n econ\u00f3mica que r\u00e1pidamente devolver\u00eda la prosperidad y las sacar\u00eda del letargo.<\/p>\n<p>Pero nuestro hombre de mar hab\u00eda saboreado la agitada vida viajera, as\u00ed que Poul Poulsen Nolsoe tampoco se acababa de adaptar a la tranquilidad del hogar y la cotidianidad en una sociedad insular bastante est\u00e1tica. Digamos que estaba cantado que el acceso a los otros mares, la libertad que encontraba en sus viajes, la aventura, le acabar\u00e1n arrancando el esp\u00edritu de navegante y comerciante que recorr\u00edan sus arterias vitales. Busc\u00f3 socios y se hicieron con un barco para trabajar la pesca en aquellas ricas latitudes norte\u00f1as y entonces tambi\u00e9n se lanzaban al comercio con la zona continental a pesar del monopolio de la corona.<\/p>\n<p>En 1804 dar\u00e1 un salto cualitativo cuando se hace con un nav\u00edo que hab\u00eda naufragado en Valva (Suduroy) y, tras los correspondientes arreglos realizados en V\u00e1gur, junto a sus hermanos, acaban transformando el peque\u00f1o nav\u00edo en un tiempo record [ten\u00eda unas medias de 14,5 metros de largo, 4,4 de ancho y 2,5 de profundidad]. El 6 de agosto, despu\u00e9s del per\u00edodo de secano, se lanzaba al agua el Royndin Frida e inmediatamente comenzaban su primera singladura pesquera, al a\u00f1o siguiente transformaban el nav\u00edo en una ligera goleta y con ello pasaban a ampliar tambi\u00e9n su radio de acci\u00f3n.<\/p>\n<p>Tratar de ir m\u00e1s all\u00e1 chocaba tambi\u00e9n con los funcionarios reales del momento, ser\u00e1n muchos los contratiempos entre Poul, sus hermanos y la administraci\u00f3n. Pero si algfo distingue a los hombres de mar es la tenacidad y entonces tratar\u00e1n de romper el encorsetado monopolio dan\u00e9s que ten\u00eda los derechos exclusivos para el comercio insular y la metr\u00f3poli. Incluso las peque\u00f1as exportaciones estaban sujetas a los ineludibles derechos reales. Sigue su lucha y sus primeras derrotas en 1805 fueron sendos transportes de carb\u00f3n fero\u00e9s hasta Bergen (Noruega) y Copenhague, pero ten\u00eda que regresar en lastre por los fuertes aranceles que sufr\u00edan los que intentaban cambiar las cosas.<\/p>\n<p>En 1806 realizar\u00e1 un viaje realmente comercial tras finalizar la pesca primaveral, cargaban con tejidos, pesca salada y aceite de foca junto a otros productos locales que no aparec\u00edan registrados en las listas de materiales protegidos por las estrictas leyes aduaneras, aunque las dificultades no cejaban, los funcionarios enviaros sus quejas a la capital del reino y recibir\u00e1 la prohibici\u00f3n de carga para su retorno. Entonces trata de romper ese nudo gordiano e incluso a veces declarar\u00e1 que viaja a otros puertos para evitar la controversia y las prohibiciones. R\u00e1pidamente ser\u00eda acusado de sobornar [corromper] y contrabandear, hasta que fue condenado, pero acusado ahora de haber violado la ley de cuarentena [ya sabemos que cuando alguien quiere \u201cengancharte\u201d te engancha: el sistema tiene recursos para hacer la vida imposible a quien goza saltarse las normas] y la multa de 735 rixdeles, una fortuna en su \u00e9poca, tampoco le arredr\u00f3. Nunca pudo ser probada su conexi\u00f3n con el mercado negro, pero se intent\u00f3 por todos los medios que no rompiera las estipulaciones comerciales.<\/p>\n<p>As\u00ed que continu\u00f3 su vida, incluso se convierte en un gran poeta y en el bienio 1806-1807 escribi\u00f3 una c\u00e9lebre balada difamatoria que sobrevivi\u00f3 a su tiempo, nadie se acuerda de los estrictos funcionarios, pero todos los feroeses conocen la composici\u00f3n po\u00e9tica de <em>La balada del p\u00e1jaro, <\/em>toda una osad\u00eda sobre sus infatigables adversarios, los funcionarios que, como cuervos [hoy les llamamos buitres] de mal ag\u00fcero, no le dejaban volar.<\/p>\n<p>En junio de 1807 vuelve a Copenhague junto con una delegaci\u00f3n insular con el firme prop\u00f3sito de arrancar en la corte un per\u00edodo de prueba comercial libre con productos no tasados por las aduanas danesas y que le permitieran no estar lastrado con la losa de plomo que significaban los altos aranceles. La guerra franco-brit\u00e1nica, la neutralidad de Dinamarca, etc., har\u00e1n que el pr\u00edncipe heredero no est\u00e9 en palacio y la delegaci\u00f3n feroesa habr\u00e1 de seguir viaje hasta Kiel (Holstein-Alemania). Hay suerte y el viaje de regreso, finalmente, ser\u00e1 con carga, temporalmente ha conseguido la victoria frente a los estrictos aduaneros reales de Torshavn. La guerra, sin embargo, acaba provocando el amarre de la flota danesa, algo que provocar\u00e1 fatales consecuencias entre la poblaci\u00f3n de Feroe que depend\u00eda ya del suministro regular de determinadas materias. Es lo que sucede cuando tu automantenimiento se \u201cesfuma\u201d y entonces los especuladores de turno te \u201cestrujan\u201d hasta la \u00faltima gota.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" id=\"__wp-temp-img-id\" class=\"aligncenter\" src=\"https:\/\/natureduca.com\/images_culturblog\/filatelia_feroes_nolsoyar2.jpg\" alt=\"250 ANIVERSARIO DE NOLSOYAR PALL\" width=\"500\" height=\"354\" \/><\/p>\n<p>Tras las capitulaciones, nuestro h\u00e9roe logra una autorizaci\u00f3n del almirante ingl\u00e9s que le permitir\u00e1 cargar y regresar sin impedimentos a su tierra. Su cargamento acaba descarg\u00e1ndose en la m\u00e1s sure\u00f1a de las islas: Suduroy. Fue una \u00e9poca dura, la regi\u00f3n se ver\u00e1 sacudida por piratas y corsarios que incluso acabar\u00e1n destruyendo las fr\u00e1giles fortificaciones y los dep\u00f3sitos de mercanc\u00edas reales saqueados sin piedad.<\/p>\n<p>Su nav\u00edo fue interceptado y decomisado siendo su puerto de amarre el sueco de Gotemburgo [actual Suecia], la excusa: no reun\u00eda condiciones de navegabilidad y los nubarrones del hambre acabar\u00e1n extendi\u00e9ndose sobre todo el archipi\u00e9lago. Nolsoe se pone en marcha, contacta con dos almirantes brit\u00e1nicos, viaja a Londres y con la ayuda del c\u00f3nsul dan\u00e9s en la capital brit\u00e1nica lograr\u00e1 que le autoricen a comerciar con sus islas. El Consejero del Ministerio de Comercio le acaba entregando la Estrella del Norte que llevar\u00e1 v\u00edveres de urgencia para la desabastecida poblaci\u00f3n.<\/p>\n<p>En diciembre\/enero (1808-1809) zarpaban desde el Reino Unido por \u00faltima vez: acababa de iniciarse la singladura que lo convert\u00eda en leyenda: el nav\u00edo y toda su tripulaci\u00f3n desaparecer\u00e1n en las turbulentas aguas del Atl\u00e1ntico Norte, Nolsoe entraba as\u00ed en la leyenda que pr\u00e1cticamente todo fero\u00e9s que se precie te cuenta a poco que logres romper el hielo con aquellos escurridizos habitantes de unas islas poco conocidas en estas g\u00e9lidas latitudes. El sello conmemorativo inici\u00f3 su validez postal el 26 de abril de 2016, fue obra de Archibald Black, grabados Martin Morck, impresos en talla dulce y offset, facial de 24 coronas para la tarifa vigente de 51-100 gramos de peso destinadas al continente europeo.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">JUAN FRANCO CRESPO<br \/>\n<a href=\"mailto:lacandon999@yahoo.es\">lacandon999@yahoo.es<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfDe qu\u00e9 madera est\u00e1n hechos los h\u00e9roes nacionales que, resisten, imperturbables, el paso del tiempo? Con esta pregunta nos introduce el correo fero\u00e9s en uno de esos personajes b\u00e1sicos\u00a0 para entender la historia de este pueblo insular y sus grandes navegantes. Dicen las leyendas que cualquier fero\u00e9s conoce la historia\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":8,"featured_media":-1,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[14,7],"tags":[1384,1459],"class_list":["post-4579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filatelia","category-personajes","tag-aniversario","tag-nolsoyar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-24T09:25:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-22T09:08:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Franco Crespo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Franco Crespo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/\"},\"author\":{\"name\":\"Juan Franco Crespo\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/f6dccdcd6c23ee151a1d5a173ca21baf\"},\"headline\":\"250 ANIVERSARIO DE NOLSOYAR PALL\",\"datePublished\":\"2016-05-24T09:25:14+00:00\",\"dateModified\":\"2018-12-22T09:08:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/\"},\"wordCount\":1433,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/filatelia_feroes_nolsoyar1.jpg\",\"keywords\":[\"aniversario\",\"nolsoyar\"],\"articleSection\":[\"Filatelia\",\"Personajes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/\",\"name\":\"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/filatelia_feroes_nolsoyar1.jpg\",\"datePublished\":\"2016-05-24T09:25:14+00:00\",\"dateModified\":\"2018-12-22T09:08:03+00:00\",\"description\":\"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/filatelia_feroes_nolsoyar1.jpg\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/filatelia_feroes_nolsoyar1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/250-aniversario-de-nolsoyar-pall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"250 ANIVERSARIO DE NOLSOYAR PALL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/f6dccdcd6c23ee151a1d5a173ca21baf\",\"name\":\"Juan Franco Crespo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g\",\"caption\":\"Juan Franco Crespo\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/juan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa","description":"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/","og_locale":"es_ES","og_type":"article","og_title":"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa","og_description":"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2016-05-24T09:25:14+00:00","article_modified_time":"2018-12-22T09:08:03+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Juan Franco Crespo","twitter_misc":{"Escrito por":"Juan Franco Crespo","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/"},"author":{"name":"Juan Franco Crespo","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/f6dccdcd6c23ee151a1d5a173ca21baf"},"headline":"250 ANIVERSARIO DE NOLSOYAR PALL","datePublished":"2016-05-24T09:25:14+00:00","dateModified":"2018-12-22T09:08:03+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/"},"wordCount":1433,"commentCount":0,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/#primaryimage"},"thumbnailUrl":"https:\/\/natureduca.com\/images_culturblog\/filatelia_feroes_nolsoyar1.jpg","keywords":["aniversario","nolsoyar"],"articleSection":["Filatelia","Personajes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/","url":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/","name":"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/#primaryimage"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/#primaryimage"},"thumbnailUrl":"https:\/\/natureduca.com\/images_culturblog\/filatelia_feroes_nolsoyar1.jpg","datePublished":"2016-05-24T09:25:14+00:00","dateModified":"2018-12-22T09:08:03+00:00","description":"250 ANIVERSARIO DE NOLSOYAR PALL - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/#primaryimage","url":"https:\/\/natureduca.com\/images_culturblog\/filatelia_feroes_nolsoyar1.jpg","contentUrl":"https:\/\/natureduca.com\/images_culturblog\/filatelia_feroes_nolsoyar1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/250-aniversario-de-nolsoyar-pall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"250 ANIVERSARIO DE NOLSOYAR PALL"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/f6dccdcd6c23ee151a1d5a173ca21baf","name":"Juan Franco Crespo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g","caption":"Juan Franco Crespo"},"url":"https:\/\/natureduca.com\/culturblog\/author\/juan\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Juan Franco Crespo","author_link":"https:\/\/natureduca.com\/culturblog\/author\/juan\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Juan Franco Crespo","author_link":"https:\/\/natureduca.com\/culturblog\/author\/juan\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00bfDe qu\u00e9 madera est\u00e1n hechos los h\u00e9roes nacionales que, resisten, imperturbables, el paso del tiempo? Con esta pregunta nos introduce el correo fero\u00e9s en uno de esos personajes b\u00e1sicos\u00a0 para entender la historia de este pueblo insular y sus grandes navegantes. Dicen las leyendas que cualquier fero\u00e9s conoce la historia\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/4579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=4579"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/4579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=4579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=4579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=4579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}