{"id":3725,"date":"2013-03-18T20:40:54","date_gmt":"2013-03-18T18:40:54","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=3725"},"modified":"2019-02-22T02:37:53","modified_gmt":"2019-02-22T00:37:53","slug":"clxx-aniversario-de-bertha-von-suttner","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/","title":{"rendered":"CLXX ANIVERSARIO DE BERTHA VON SUTTNER"},"content":{"rendered":"<p>Posiblemente pocos tengan en la mente a esta adelantada de su tiempo que, por m\u00e9ritos propios, est\u00e1 ligada al pacifismo radical. Hija p\u00f3stuma del conde Franz Kinsky von Wchinitz und Tettau que muri\u00f3 poco antes de que ella naciera (contaba 75 a\u00f1os) el 9 de junio de 1843 en Praga; muri\u00f3 el 21 de junio de 1914 en Viena. Se cri\u00f3 con su madre Sofia Wilhelmine (von K\u00f6nner) en un ambiente de crispaci\u00f3n militarista que acabar\u00eda desmembrando el imperio austro-h\u00fangaro y llevando al continente europeo a la I Guerra Mundial.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/images_culturblog\/bertha_suttner.jpg\" alt=\"\" width=\"220\" height=\"115\" \/>\u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/images_culturblog\/bertha_suttner2.jpg\" alt=\"\" width=\"160\" height=\"95\" \/><\/p>\n<p>Se especula que fue la tradici\u00f3n familiar (su padre mariscal de campo y consejero militar; su abuelo capit\u00e1n de caballer\u00eda) la que inocul\u00f3 su pasi\u00f3n pacifista que se acab\u00f3 convirtiendo en el Leitmotiv de su vida. Como otras j\u00f3venes arist\u00f3cratas de su tiempo, fue educada bajo las estrictas normas correspondientes a su clase y posici\u00f3n. Adquiere una s\u00f3lida formaci\u00f3n ling\u00fc\u00edstica (dominaba alem\u00e1n, franc\u00e9s, italiano e ingl\u00e9s) que le acabar\u00e1 facilitando sus frecuentes viajes y los contactos con personas prominentes para promover su idea sobre la paz mediante multitudinarias conferencias por el todo el continente europeo y funda una asociaci\u00f3n pacifista en Austria. Tambi\u00e9n fue una ferviente europe\u00edsta, en el Congreso de la Paz (Londres, 1908) afirm\u00f3 que lo mejor que podr\u00eda hacerse era la unificaci\u00f3n del continente europeo como remedio para evitar las cat\u00e1strofes que los negros nubarrones presagiaban en la agitada Europa de principios del siglo XX:<\/p>\n<p>A temprana edad se habr\u00eda prometido con el pr\u00edncipe Adolfo Wittgenstein, un gran apasionado del canto y del que previsiblemente brot\u00f3 la idea de convertirse en cantante de \u00f3pera, pero el pr\u00edncipe muri\u00f3 en un viaje a Am\u00e9rica y ella, tras ver dilapidada su fortuna familiar (su madre era una empedernida jugadora), se ver\u00e1 impelida a sobrevivir, entra como institutriz en la casa del bar\u00f3n Karl von Suttner (un exitoso empresario en la Viena de su tiempo) y se acaba casando con su hijo menor Arthur Gundaccar.<\/p>\n<p>Tras dejar ese trabajo en Viena emprende viaje a Par\u00eds, donde se convierte en la secretaria particular de Alfred Nobel durante quince d\u00edas que sellar\u00e1n una amistad con el mecenas sueco que perdur\u00f3 hasta su muerte. Nobel se inspir\u00f3 en esta mujer para dotar el prestigioso premio que ella acabar\u00eda recibiendo en su primera edici\u00f3n. Sus esfuerzos se centraron en denunciar el nacionalismo como idea mal encauzada y que divide a la sociedad y la enfrenta a terribles problemas que, generalmente, acaban con actos violentos, cuando no la guerra abierta.<\/p>\n<p>Los dos j\u00f3venes contraen matrimonio secreto, provocan la ira de ambas familias y emprenden un largo viaje que fue motivo de algunos de los momentos m\u00e1s dif\u00edciles de su vida: ella contaba 33 a\u00f1os y \u00e9l 26, si nos atenemos a los datos, parece ser que ambos sucumbieron al amor rom\u00e1ntico. Llegan a Georgia donde la vida serena y tranquila de Centro Europa contrasta con las dificultades a las que ambos se deber\u00e1n enfrentar. La pareja sobrevive gracias a la pluma, \u00e9l colaborando con la prensa alemana y ella con la austriaca. Cubren exitosamente la guerra ruso-turca de 1877-1878 escriben novelas, relatos de guerra, viajes, etc. Ello les permite vivir con cierta holgura en una sociedad bastante ajena a la sociedad europea del momento. All\u00ed produjo cuatro novelas y su primer libro m\u00e1s o menos importante Inventario de un alma (Inventarium einer Seele).<\/p>\n<p>En la d\u00e9cada siguiente ponen de nuevo rumbo a Viena y se instalan en la residencia familiar en la Baja Austria. Al a\u00f1o siguiente (1886) escribe un libro donde abordar\u00e1 el respeto del hombre y su libre albedr\u00edo; despu\u00e9s engarza con destacados pensadores del momento que le acabar\u00e1n perfilando su pacifismo \u00e9tico fundado en la capacidad moral del hombre que no deja de sorprendernos con el que actualmente inunda nuestras plazas y ciudades.<\/p>\n<p>Tres a\u00f1os m\u00e1s tarde publicar\u00e1, sin duda, la mejor de sus obras: Die Waffen Nieder (\u00a1Abajo las armas!) cuya primera traducci\u00f3n al espa\u00f1ol apareci\u00f3 en Barcelona en 1915 de la mano de Rogelio Z. Falguera. Inicialmente no fue un texto antimilitarista sino una cr\u00edtica a la guerra y sus funestas consecuencias, sobre todo para la poblaci\u00f3n civil. Podr\u00eda decirse que es una visi\u00f3n de los horribles resultados provocados por los conflictos armados. El t\u00edtulo acab\u00f3 convirti\u00e9ndose en un c\u00e9lebre peri\u00f3dico pacifista y del que ser\u00eda editora hasta 1899 cuando la cabecera ser\u00e1 cambiada por Friedenswarte y en donde estar\u00e1 trabajando hasta producirse su muerte. Esa obra acaba llegando al cine en ese belicoso a\u00f1o de 1914 y el texto se ha convertido en un cl\u00e1sico en el ideario del pacifismo internacional.<\/p>\n<p>El matrimonio se instal\u00f3 a comienzos de siglo en la ciudad de los canales y all\u00ed acaban conociendo al marqu\u00e9s Pandolfi y dar\u00e1n vida al embri\u00f3n de lo que se convertir\u00e1 en la Uni\u00f3n Interparlamentaria nacida en 1910. En 1912 pronunci\u00f3 numerosos discursos sobre la paz en el territorio norteamericano. Cuatro a\u00f1os antes ya hab\u00eda entregado a la imprenta sus obras completas que abarcan poco m\u00e1s de una veintena de t\u00edtulos.<\/p>\n<p>Su trayectoria vital le acaba generando uno de los premios m\u00e1s prestigiosos: El Nobel de la Paz de 1905 que por primera vez se entregaba a una mujer y, curiosidades de la vida, poco menos de una d\u00e9cada despu\u00e9s, mor\u00eda al poco de comenzar el primer gran conflicto b\u00e9lico continental. Fue presidenta de la Sociedad Austriaca de la Paz; vicepresidenta y presidenta de honor del Bureau International de la Paix.<\/p>\n<p>Esta arist\u00f3crata y pacifista ha sido homenajeada en varias ocasiones en la filatelia, la notafilia y la numism\u00e1tica. En 1966 fue el Banco de Austria el que le dedic\u00f3 un billete de mil chelines en donde la vemos con un tocado que realza su noble linaje y la idea de responsabilidad y compromiso militante. En el 2005 ser\u00e1 el correo alem\u00e1n el que le dedicar\u00e1 un sello de 55 c\u00e9ntimos, la vemos con una pose menos institucional pero que realza su noble figura; en el centro de ese sello aparece la portada de su c\u00e9lebre \u00a1Abajo las armas! La siguiente oportunidad ser\u00e1 en el 2008 cuando Austria acu\u00f1a una moneda de 2 \u20acuros.<\/p>\n<p>Y ahora le ha tocado al correo de la ciudad que la vio nacer, conmemoran el 170 aniversario de su nacimiento y le honra, la posta checa, con un sello de 18 coronas que comenz\u00f3 a circular el 13 de febrero de 2013. La impresi\u00f3n, en multicolor, se realiz\u00f3 en offset y fue cancelado el sobre oficial de primer d\u00eda en Praga, ambas caras de la medalla (que se entrega a cada laureado) aparecen a modo de matasellos. El sobre lleva una ilustraci\u00f3n con ambos personajes sentados en un jard\u00edn en, suponemos, amigable charla. El dise\u00f1o fue obra de R\u00e9nata Fu\u010dikov\u00e1 y el grabador V\u00e1clav Fajt, fue impreso en hojas de 50 ejemplares, tama\u00f1o vertical de 23&#215;40 mm que comenzaron a circular hace pocos d\u00edas y honrando a la primera mujer que recibi\u00f3 ese premio en Oslo el 18 de abril de 1906.<\/p>\n<p>Hay otras administraciones postales que, filat\u00e9licamente hablando, abusan del bolsillo del coleccionista y emiten miles de sellos de nulo valor postal (vamos que tampoco es un hecho extraordinario, pues algo similar hace tambi\u00e9n el correo espa\u00f1ol \u00bfalguien en estos momentos ve sellos de correos en las cartas?, entonces \u00bfpor qu\u00e9 cada a\u00f1o Madrid aumenta el valor facial de los sellos que emite si luego no son utilizados postalmente? Pues eso, cada A\u00f1o Espa\u00f1a emite m\u00e1s y m\u00e1s quincaller\u00eda; decenas de \u201csesudos\u201d coleccionistas, incluso se emiten sus frusler\u00edas que aqu\u00ed llamamos TU SELLO que vale cinco o seis veces m\u00e1s que el poder liberatorio de franqueo o los que nos sirve a los abonados el Servicio Filat\u00e9lico que cada vez llegan m\u00e1s tarde y no dejan de subir su coste si comparamos cada ejercicio). Los tem\u00e1ticos, a veces, se vac\u00edan sus bolsillo para intentar completar huecos y los encuentran en estos \u201cespeculadores\u201d que venden cromos a precio de oro (generalmente son sellos distribuidos por la norteamericana IGPC). Pero tambi\u00e9n podemos encontrarnos a la baronesa en varias estampillas m\u00e1s, por ejemplo en alguna emisi\u00f3n de Sierra Leona o San Vicente y las Granadinas. En fin, que cada uno se gasta sus cuartos en aquello que considera m\u00e1s adecuado, pero los \u201ccromos\u201d no siempre son recuperables. Al final, los que puedan, tendr\u00e1n que volver al patr\u00f3n oro, como el gran Millet (Palau de la M\u00fasica-Barcelona).<\/p>\n<p>&nbsp;<\/p>\n<p>CZECH POST &#8211; POSTFILA<br \/>\nORTENOVO NAM. 16<br \/>\nCZ-170 24 PRAGA 7 (REPUBLICA CHECA)<\/p>\n<p>CESK\u00c1 POSTA\u2013SLUZBY FILATELISTUM<br \/>\nP O BOX 111<br \/>\nCZ-360 02 KARLOVY VARY 2<br \/>\n(REPUBLICA CHECA)<br \/>\nwww.cpost.cz<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">JUAN FRANCO CRESPO<br \/>\nlacandon999@yahoo.es<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Posiblemente pocos tengan en la mente a esta adelantada de su tiempo que, por m\u00e9ritos propios, est\u00e1 ligada al pacifismo radical. Hija p\u00f3stuma del conde Franz Kinsky von Wchinitz und Tettau que muri\u00f3 poco antes de que ella naciera (contaba 75 a\u00f1os) el 9 de junio de 1843 en Praga;\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":8,"featured_media":-1,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[16,14,1,7],"tags":[1081,1010,1384,1094,1127,1042,1034,1115,1145,1021],"class_list":["post-3725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-tradiciones","category-filatelia","category-historia","category-personajes","tag-ambiente","tag-amor","tag-aniversario","tag-curiosidades","tag-europa","tag-filatelia-2","tag-guerra","tag-jovenes","tag-libro","tag-sociedad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CLXX ANIVERSARIO DE BERTHA VON SUTTNER<\/title>\n<meta name=\"description\" content=\"CLXX ANIVERSARIO DE BERTHA VON SUTTNER\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CLXX ANIVERSARIO DE BERTHA VON SUTTNER\" \/>\n<meta property=\"og:description\" content=\"CLXX ANIVERSARIO DE BERTHA VON SUTTNER\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-18T18:40:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-22T00:37:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Franco Crespo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Franco Crespo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/clxx-aniversario-de-bertha-von-suttner\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/clxx-aniversario-de-bertha-von-suttner\\\/\"},\"author\":{\"name\":\"Juan Franco Crespo\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/f6dccdcd6c23ee151a1d5a173ca21baf\"},\"headline\":\"CLXX ANIVERSARIO DE BERTHA VON SUTTNER\",\"datePublished\":\"2013-03-18T18:40:54+00:00\",\"dateModified\":\"2019-02-22T00:37:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/clxx-aniversario-de-bertha-von-suttner\\\/\"},\"wordCount\":1517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"keywords\":[\"ambiente\",\"amor\",\"aniversario\",\"curiosidades\",\"europa\",\"filatelia\",\"guerra\",\"j\u00f3venes\",\"libro\",\"sociedad\"],\"articleSection\":[\"Cultura \\\/ tradiciones\",\"Filatelia\",\"Historia\",\"Personajes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/clxx-aniversario-de-bertha-von-suttner\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/clxx-aniversario-de-bertha-von-suttner\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/clxx-aniversario-de-bertha-von-suttner\\\/\",\"name\":\"CLXX ANIVERSARIO DE BERTHA VON SUTTNER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"datePublished\":\"2013-03-18T18:40:54+00:00\",\"dateModified\":\"2019-02-22T00:37:53+00:00\",\"description\":\"CLXX ANIVERSARIO DE BERTHA VON SUTTNER\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/clxx-aniversario-de-bertha-von-suttner\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/clxx-aniversario-de-bertha-von-suttner\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/clxx-aniversario-de-bertha-von-suttner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CLXX ANIVERSARIO DE BERTHA VON SUTTNER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/f6dccdcd6c23ee151a1d5a173ca21baf\",\"name\":\"Juan Franco Crespo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g\",\"caption\":\"Juan Franco Crespo\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/juan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CLXX ANIVERSARIO DE BERTHA VON SUTTNER","description":"CLXX ANIVERSARIO DE BERTHA VON SUTTNER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/","og_locale":"es_ES","og_type":"article","og_title":"CLXX ANIVERSARIO DE BERTHA VON SUTTNER","og_description":"CLXX ANIVERSARIO DE BERTHA VON SUTTNER","og_url":"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2013-03-18T18:40:54+00:00","article_modified_time":"2019-02-22T00:37:53+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Juan Franco Crespo","twitter_misc":{"Escrito por":"Juan Franco Crespo","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/"},"author":{"name":"Juan Franco Crespo","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/f6dccdcd6c23ee151a1d5a173ca21baf"},"headline":"CLXX ANIVERSARIO DE BERTHA VON SUTTNER","datePublished":"2013-03-18T18:40:54+00:00","dateModified":"2019-02-22T00:37:53+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/"},"wordCount":1517,"commentCount":0,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"keywords":["ambiente","amor","aniversario","curiosidades","europa","filatelia","guerra","j\u00f3venes","libro","sociedad"],"articleSection":["Cultura \/ tradiciones","Filatelia","Historia","Personajes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/","url":"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/","name":"CLXX ANIVERSARIO DE BERTHA VON SUTTNER","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"datePublished":"2013-03-18T18:40:54+00:00","dateModified":"2019-02-22T00:37:53+00:00","description":"CLXX ANIVERSARIO DE BERTHA VON SUTTNER","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/clxx-aniversario-de-bertha-von-suttner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"CLXX ANIVERSARIO DE BERTHA VON SUTTNER"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/f6dccdcd6c23ee151a1d5a173ca21baf","name":"Juan Franco Crespo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a938c68d1292af5b03d9c8f39678b30bdf6e89857a75a3aa18efa5e77e33f8a?s=96&d=monsterid&r=g","caption":"Juan Franco Crespo"},"url":"https:\/\/natureduca.com\/culturblog\/author\/juan\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Juan Franco Crespo","author_link":"https:\/\/natureduca.com\/culturblog\/author\/juan\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Juan Franco Crespo","author_link":"https:\/\/natureduca.com\/culturblog\/author\/juan\/"},"uagb_comment_info":0,"uagb_excerpt":"Posiblemente pocos tengan en la mente a esta adelantada de su tiempo que, por m\u00e9ritos propios, est\u00e1 ligada al pacifismo radical. Hija p\u00f3stuma del conde Franz Kinsky von Wchinitz und Tettau que muri\u00f3 poco antes de que ella naciera (contaba 75 a\u00f1os) el 9 de junio de 1843 en Praga;\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/3725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=3725"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/3725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=3725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=3725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=3725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}