{"id":351,"date":"2009-10-10T18:39:51","date_gmt":"2009-10-10T16:39:51","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=351"},"modified":"2009-10-11T11:45:14","modified_gmt":"2009-10-11T09:45:14","slug":"351","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/351\/","title":{"rendered":"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico"},"content":{"rendered":"<p align=\"justify\"><strong>Por: Dr. Alejandro Cruzado Balc\u00e1zar<\/strong><\/p>\n<p align=\"justify\"><font color=\"#ffffff\">.<\/font><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>La inseminaci\u00f3n de la mujer con el semen del marido, en ciertos casos de esterilidad matrimonial, es hoy una pr\u00e1ctica generalmente admitida. En cambio, son muchos los que se oponen a la heteroinseminaci\u00f3n, es decir, a la fecundaci\u00f3n artificial con semen de un donante. Este problema ha sido estudiado por diversos organismos y, en las siguientes l\u00edneas tratar\u00e9 de exponer algunos criterios algo restringidos de este delicado asunto.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 <strong>Concepto:<\/strong> La inseminaci\u00f3n artificial es el conjunto de operaciones necesarias para introducir gametos masculinos en el aparato genital femenino por un procedimiento distinto de la copulaci\u00f3n normal.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Antes de pronunciarse sobre su ilicitud, es necesario examinar diversos aspectos de este complejo problema. No solo hay que tener en cuenta el acto en s\u00ed, sino tambi\u00e9n las condiciones pre-existentes que lo hacen necesario y, seguidamente, sus consecuencias morales, filos\u00f3ficas, sociales y jur\u00eddicas sobre uno o varios seres humanos, considerados desde el punto de vista de su propia persona y de su medio ambiente social. La inseminaci\u00f3n artificial, en efecto, afecta a diversas personas, cuyas funciones, responsabilidad, derechos y reacciones han de sopesarse con todo cuidado antes de responder categ\u00f3ricamente a la cuesti\u00f3n planteada. Estas personas son, por orden de entrada en escena: 1. La mujer; 2. El marido [si existe]; 3. El m\u00e9dico; 4. El donante; 5. La esposa del donante [si existe]; 6. El ni\u00f1o que va a nacer; y, 7. La sociedad, en tanto que persona moral. \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 <strong>Caracter\u00edsticas:<\/strong> La inseminaci\u00f3n artificial puede adoptar dos modalidades diferentes: A. Inseminaci\u00f3n interconyugal o autoinseminaci\u00f3n: con esperma del marido; y, B. Inseminaci\u00f3n extraconyugal o heteroinseminaci\u00f3n.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 En el estudio de la inseminaci\u00f3n extraconyugal tendremos en cuenta, como axioma de partida dos nociones que todos los autores que se han ocupado de la cuesti\u00f3n [sean o no partidarios del m\u00e9todo] consideran esenciales:\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 1. \u00a0La receptora no debe conocer nunca la identidad del donante; y,\u00a0\u00a0\u00a0\u00a0 2. \u00a0El donante no debe conocer nunca la identidad de la receptora.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Estos axiomas implican que la \u00fanica persona que puede conocer las identidades del donante y de la receptora es el m\u00e9dico<strong><sup>2<\/sup><\/strong><sup> <\/sup>que, es adem\u00e1s, el llamado a aconsejar a la familia de la receptora sobre la elecci\u00f3n del donante y la intervenci\u00f3n t\u00e9cnica, as\u00ed como a registrar en buena y debida forma la aceptaci\u00f3n de los diversos interesados. As\u00ed pues, toda la responsabilidad de la operaci\u00f3n recae \u00fanica y exclusivamente en el m\u00e9dico.<\/p>\n<p>\u00a0<strong>\u00bfEs la inseminaci\u00f3n artificial un acto m\u00e9dico l\u00edcito?<sup>3<\/sup><\/strong>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Analicemos \u00a0ahora \u00a0el \u00a0acto \u00a0m\u00e9dico y, en \u00a0particular, \u00a0examinemos \u00a0hasta \u00a0que \u00a0\u00a0punto \u00a0la inseminaci\u00f3n \u00a0artificial \u00a0responde a las \u00a0condiciones \u00a0requeridas para que el acto m\u00e9dico sea l\u00edcito.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Todo acto m\u00e9dico genera una responsabilidad, que a su vez presenta varias facetas:\u00a0<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El aspecto moral que, por lo general, aunque no necesariamente es deontol\u00f3gico.-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El aspecto civil, y-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El aspecto penal.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 La responsabilidad m\u00e9dica exige que la prestaci\u00f3n satisfaga los siguientes requisitos de todo acto normal l\u00edcito:\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 1.\u00a0 \u00a0Ejecuci\u00f3n por un m\u00e9dico legalmente autorizado.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 2.\u00a0 \u00a0Cuidadoso an\u00e1lisis previo de los pros y los contras, teniendo en cuenta que todo acto que supone un peligro debe estar justificado por un estado de necesidad.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0 3.\u00a0 \u00a0\u00a0Consentimiento de la persona [si es mayor de edad y tiene capacidad para darlo] que,\u00a0 adem\u00e1s, ha de beneficiarse directamente de la intervenci\u00f3n.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Se ha dicho que el consentimiento del enfermo no es exclusivo de la responsabilidad del m\u00e9dico, ya que la persona no tiene derecho a violar sobre s\u00ed misma las reglas que regulan el orden p\u00fablico. <em>El consentimiento de la persona no es nunca eximente de un delito<\/em>. En el caso especial que nos ocupa, hemos ya se\u00f1alado que la inseminaci\u00f3n artificial comprende al menos cuatro actores, todos ellos personas f\u00edsicas, y que incluso puede haber un quinto. Esta multiplicidad supone evidentemente cierto n\u00famero de consentimientos.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 4.\u00a0 La obligaci\u00f3n \u00a0de tener en cuenta la \u00a0jerarqu\u00eda de los diversos derechos y, en consecuencia de respetar todo derecho superior al invocado para justificar el acto considerado.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 El derecho subjetivo deja de existir cuando entra en conflicto con un derecho superior, en cuyo caso intervienen necesariamente el derecho y la moral.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Si aplicamos estas consideraciones a la inseminaci\u00f3n artificial, comprobaremos inmediatamente que la inseminaci\u00f3n interconyugal responde a las cuatro condiciones enumeradas, siempre que haya consentimiento. El hijo, en efecto, nacer\u00e1 de la conjugaci\u00f3n de los gametos masculinos y femeninos de los esposos y \u00e9stos ser\u00e1n as\u00ed el padre y la madre efectivos y legales, con todas las consecuencias morales, sociales y jur\u00eddicas que ello entra\u00f1a. La autoinseminaci\u00f3n es sin duda l\u00edcita desde el punto de vista de la \u00e9tica m\u00e9dica y, en nuestra opini\u00f3n tambi\u00e9n de la moral y del derecho.\u00a0<\/p>\n<p>\u00a0En la inseminaci\u00f3n extraconyugal, dando aun por satisfecho el requisito 1, el punto 2 supone la existencia de una decisi\u00f3n consciente y deliberada, ya que todo acto que incluye un riesgo debe estar justificado por una situaci\u00f3n de necesidad. El m\u00e9dico es el \u00fanico juez de las disposiciones morales y psicol\u00f3gicas tomadas por los esposos, ya que solo \u00e9l conoce todos los elementos sociales, filos\u00f3ficos, jur\u00eddicos y cient\u00edficos del problema y puede informar debidamente a las partes interesadas. Todos los autores, sean partidarios o detractores de la heteroinseminaci\u00f3n, coinciden en que el m\u00e9dico debe estudiar la psicolog\u00eda de los esposos antes de aconsejar o practicar una heteroinseminaci\u00f3n. En primer lugar est\u00e1 obligado a explicarles las frecuencias de los fracasos, que var\u00edan seg\u00fan los autores entre el 55 y 90%, y a indicarles que, pese a todas las precauciones tomadas, el hijo puede ser f\u00edsica o mentalmente anormal; asimismo ha de informarles sobre las consecuencias psicol\u00f3gicas, morales y jur\u00eddicas que entra\u00f1a o puede entra\u00f1ar un nacimiento obtenido por heteroinseminaci\u00f3n.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Todav\u00eda incumbe al m\u00e9dico otra grave decisi\u00f3n, ya que es el \u00fanico responsable de la elecci\u00f3n del donante, cuya identidad solo \u00e9l debe conocer.<strong><sup>4 <\/sup><\/strong><strong><sup>\u00a0 <\/sup><\/strong>\u00a0\u00a0\u00a0\u00a0 En cuanto al punto 3, que supone el conocimiento de la persona interesada y el inter\u00e9s directo de la misma, hay que tener en cuenta que en este caso el consentimiento de la mujer es insuficiente para justificar el acto; importa, en efecto, el consentimiento del marido, quien habr\u00e1 de comprometerse por escrito a aceptar un hijo que de hecho ser\u00e1 un bastardo y que durante toda la vida ser\u00e1 una prueba de la esterilidad paterna.\u00a0<\/p>\n<p><strong>\u00a0 CONSENTIMIENTO DE LOS INTERESADOS<sup>5<\/sup><\/strong>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Casi todos los autores que se han ocupado de esta cuesti\u00f3n, coinciden que el consentimiento debe darse por escrito, e incluso algunos estiman que por <strong>acta notarial<\/strong>. A este respecto se\u00f1alan que en bastantes casos la mujer que solicita una inseminaci\u00f3n extraconyugal \u00a0lo hace a espaldas de su marido o de su amante y por motivos muy variados entre los que, adem\u00e1s del deseo de ser madre, puede estar el de dar la ilusi\u00f3n de una virilidad inexistente a un marido est\u00e9ril. Ahora bien, no por ello el hijo deja de ser extraconyugal y de hecho <strong>adulterino<\/strong>, por lo tanto inaceptable en derecho y en moral.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Adem\u00e1s del consentimiento de los esposos, habr\u00e1 que recabar, tambi\u00e9n el del donante, y si \u00e9ste est\u00e1 casado, el de su esposa. Aunque el consentimiento del donante puede darse por descontado, interesa que conste oficialmente y, por supuesto, la renuncia a todo derecho sobre el hijo. Importa tambi\u00e9n obtener el consentimiento de la esposa del presunto donante, aunque solo sea para poner al m\u00e9dico a cubierto de toda acusaci\u00f3n de complicidad.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 <strong>Validez de los consentimientos:<\/strong> Personalmente, estimamos que carecen de todo valor, ya que, entre las obligaciones que impone el matrimonio a los contrayentes, algunas, como la fidelidad, est\u00e1n justificadas por el orden p\u00fablico. Aunque sea solo por esto, cualquier acuerdo en sentido contrario [v. gr. el consentimiento de los c\u00f3nyuges] no tiene ning\u00fan valor jur\u00eddico. La fidelidad no se basa solo en la utilizaci\u00f3n exclusiva del c\u00f3nyuge desde el punto de vista de la relaci\u00f3n sexual, sino tambi\u00e9n, evidentemente, desde el punto de vista de la procreaci\u00f3n.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 En cuanto el punto 4 [obligaci\u00f3n del m\u00e9dico de tener en cuenta la jerarqu\u00eda de los derechos y valores y de respetar todo derecho superior al que justifica el acto], analizaremos el punto de vista jur\u00eddico dejando de lado el religioso, moral y social. Empero, debemos precisar solamente que no ser\u00eda posible pasar en silencio los criterios de las diversas religiones en relaci\u00f3n con la heteroinseminaci\u00f3n, a las que se oponen formalmente las religiones cat\u00f3lica, ortodoxa, anglicana, israelita y mahometana. Tambi\u00e9n la mayor\u00eda de las iglesias protestantes la rechazan y solo contadas sectas la admiten. Y despu\u00e9s de esta breve digresi\u00f3n veamos lo que sigue.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong>ASPECTOS\u00a0\u00a0 JUR\u00cdDICOS<\/strong><strong>\u00a0<\/strong><strong>\u00a0\u00a0\u00a0\u00a0 Desde el punto de vista jur\u00eddico, la inseminaci\u00f3n extraconyugal plantea problemas extremadamente graves, por ejemplo:\u00a0<\/strong><strong>\u00a0\u00a0\u00a0\u00a0 1.\u00a0\u00a0 El problema de la filiaci\u00f3n;\u00a0<\/strong><strong>\u00a0\u00a0\u00a0\u00a0 2.\u00a0\u00a0 El problema de la responsabilidad civil;\u00a0<\/p>\n<p><\/strong>\u00a0\u00a0\u00a0\u00a0 3.\u00a0\u00a0 El problema de la responsabilidad penal; y,\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 4.\u00a0\u00a0 Las demandas de divorcio y de anulaci\u00f3n de matrimonio.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Dentro de este conjunto que no podemos estudiar aqu\u00ed por falta no solo de espacio sino tambi\u00e9n de competencia, subrayaremos la investigaci\u00f3n de la paternidad y las demandas de impugnaci\u00f3n de paternidad; no hay que olvidar que la paternidad desempe\u00f1a un importante papel en el mantenimiento, la educaci\u00f3n y los derechos de herencia.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Ahora bien, es indudable que un hijo nacido de una heteroinseminaci\u00f3n es, si la mujer est\u00e1 casada, un hijo adulterino, nacido realmente de padre desconocido. Y, en el estado actual de la ciencia, con frecuencia es posible demostrar que el presunto padre legal no ha intervenido en la concepci\u00f3n. Incluso si este dio su consentimiento en el momento de la inseminaci\u00f3n, cabe la posibilidad de que cambie de opini\u00f3n en el transcurso de los a\u00f1os y rechace al <em>hijo <\/em>con todas las consecuencias que contiene este repudio. \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 <strong>Jurisprudencia internacional:<\/strong> El 13 de diciembre de 1954, el Tribunal Supremo de los E.E.U.U. decidi\u00f3 que un hijo engendrado por inseminaci\u00f3n extraconyugal es, en cualquier circunstancia, adulterino y no tiene derecho alguno a la herencia de sus padres legales. A este respecto, quiz\u00e1 no est\u00e9n dem\u00e1s unas palabras acerca del problema del hijo adoptivo. Entre un hijo adoptivo y un hijo engendrado por heteroinseminaci\u00f3n existen diferencias profundase incluso esenciales tanto jur\u00eddicas como morales. El hijo adoptivo es biol\u00f3gicamente extra\u00f1o tanto al padre como a la madre legal que, a este respecto, se encuentran en iguales condiciones. La adopci\u00f3n es un acto oficial y p\u00fablico, sometida a prescripciones y obligaciones determinadas por la ley. La heteroinseminaci\u00f3n, en cambio, supone una falsificaci\u00f3n consciente y oficial del acta de nacimiento, falsificaci\u00f3n que encubre un adulterio biol\u00f3gico y clandestino. Convencidos de este hecho algunos autores estiman que el m\u00e9dico que practica la inseminaci\u00f3n no debe asistir al parto, a fin de no verse obligado a firmar un certificado de nacimiento falso. En teor\u00eda el m\u00e9dico, asume la responsabilidad de cualquier da\u00f1o f\u00edsico producido por un error t\u00e9cnico durante la inseminaci\u00f3n; sin embargo, este riesgo es m\u00ednimo. En cambio, el peligro es mucho mayor en la esfera moral.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong>CONSECUENCIAS A LARGO PLAZO<\/strong><strong>\u00a0<\/strong><strong>\u00a0\u00a0\u00a0\u00a0 <\/strong>Analicemos ahora los argumentos que aducen los partidarios de la heteroinseminaci\u00f3n. En primer lugar, se dice que responde al deseo de maternidad de la mujer que, sino se satisface, puede provocar trastornos funcionales importantes con repercusiones lamentables sobre la paz y la estabilidad del matrimonio. El segundo argumento es que la inseminaci\u00f3n extraconyugal contribuye a esa estabilidad sin quebrantar la promesa de los esposos de pertenecerse mutuamente y no buscar satisfacciones fuera del matrimonio. El primer argumento es correcto pero incompleto. Es indudable que en ciertos casos la esterilidad causa estados psicol\u00f3gicos complejos con perfiles de patolog\u00eda.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Ahora bien, no menos cierto es que un hijo engendrado por inseminaci\u00f3n extraconyugal puede provocar trastornos graves entre los esposos en lugar de aportar la paz. Situaciones parecidas pueden producirse a consecuencia de otros factores, por ejemplo las dificultades econ\u00f3micas dentro el matrimonio. Sin embargo, para resolver estas dificultades econ\u00f3micas la sociedad no permite transgredir el C\u00f3digo Penal, el C\u00f3digo Civil, la deontolog\u00eda y la moral religiosa o no religiosa. A su vez, el segundo argumento infringe por omisi\u00f3n, ya que la promesa del matrimonio no se refiere solo a la pertenencia f\u00edsica, sino tambi\u00e9n a las consecuencias de esta pertenencia y a la coexistencia de los c\u00f3nyuges en el hijo. Si el deseo de tener descendencia bastara para justificar en un matrimonio la intervenci\u00f3n de un tercero, intervenci\u00f3n contraria tanto a la ley moral como a la civil, tambi\u00e9n bastar\u00eda para justificar el divorcio en los casos de esterilidad, desde el momento en que el derecho a tener descendencia se considera superior a las obligaciones impuestas por el estado matrimonial.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Es m\u00e1s, el deseo de paternidad puede existir tambi\u00e9n en el hombre, cuyos derechos en el matrimonio son id\u00e9nticos a los de la mujer y, \u00bfQu\u00e9 cabr\u00eda pensar de una ley que autoriza al hombre a enviar su esperma, por conducto de un m\u00e9dico, a una mujer an\u00f3nima que se prestara al acto mismo y al abandono de todos sus derechos sobre el hijo? A nuestro juicio, semejante legislaci\u00f3n es absurda y, de existir, ser\u00eda bastante monstruosa. \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 El argumento de la consolidaci\u00f3n del matrimonio es tambi\u00e9n muy discutible y ciertos autores piensan incluso que la inestabilidad conyugal constituye una contradicci\u00f3n formal de la heteroinseminaci\u00f3n.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 <strong>Datos estad\u00edsticos<\/strong><strong><sup>6<\/sup><\/strong><strong>:<\/strong> Teniendo en cuenta las consideraciones precedentes, veamos en la pr\u00e1ctica lo que representa estad\u00edsticamente, en funci\u00f3n del n\u00famero de matrimonios involuntariamente est\u00e9riles, el n\u00famero de los que se beneficiar\u00edan, en el mejor de los casos, de la heteroinseminaci\u00f3n. Seg\u00fan la estad\u00edstica, el 15% de los matrimonios son est\u00e9riles y la esterilidad se debe en el 35% de los casos al hombre y en el 65% de los casos a la mujer. Nos encontramos as\u00ed que solo un 35% de los matrimonios est\u00e9riles podr\u00edan beneficiarse de la heteroinseminaci\u00f3n, lo que representa un 35% de un 15% del total de matrimonios: es decir, un 5% de las parejas casadas. \u00bfCu\u00e1ntas parejas de ese 5% desear\u00edan recurrir a la inseminaci\u00f3n extraconyugal? Aunque no existe ninguna estad\u00edstica al respecto, estimamos que la proporci\u00f3n ser\u00e1 m\u00ednima y que, en el mejor de los casos, no pasar\u00eda del 10%. Nos encontramos as\u00ed con un 10% del 5%, es decir el 0.5% del total de matrimonios.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Eliminemos ahora ese 0.5% de los fracasos biol\u00f3gicos que, seg\u00fan los distintos autores, oscilan entre 56 y 85%. En buena matem\u00e1tica nos quedan as\u00ed el 0.1% a 0.15% de \u00e9xito biol\u00f3gico [Por \u00e9xito biol\u00f3gico entendemos todo embarazo que llega felizmente a t\u00e9rmino. No se tiene en cuenta, naturalmente, el resto de la vida de los padres y del hijo y aqu\u00ed la situaci\u00f3n no es necesariamente rosa ni para los primeros ni para el segundo]. En aras de ese porcentaje diminuto, superior de hecho a la realidad, la heteroinseminaci\u00f3n atropella los principios morales, jur\u00eddicos y sociales que constituyen la base de nuestra sociedad, sin m\u00e1s objeto que la satisfacci\u00f3n de un deseo personal. As\u00ed pues, si por una parte sopesamos los aspectos psicol\u00f3gicos de la heteroinseminaci\u00f3n y las objeciones que suscita en los planos moral, social y jur\u00eddico, y por otra parte los beneficios psicol\u00f3gicos y sentimentales que puede proporcionar en el 0.15% de todos los matrimonios y en el 1% de los matrimonios est\u00e9riles, la conclusi\u00f3n parece obvia. Adem\u00e1s de la clara transgresi\u00f3n del orden de valores, hay una desproporci\u00f3n evidente entre los fines y los medios.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 En 1949 la Academia de Ciencias Morales y Pol\u00edticas de Francia dictamin\u00f3 que <em>el hecho de integrar fraudulentamente en una familia a un ni\u00f1o que llevara el nombre del padre legal y que se creer\u00e1 hijo de \u00e9ste, debe considerarse como un atentado a las bases del matrimonio, de la familia y de la sociedad<\/em> y que <em>la heteroinseminaci\u00f3n utilizada para suplir la esterilidad del marido suscita tales objeciones morales, jur\u00eddicas y sociales que la hacen netamente desaconsejable.<\/em>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 En marzo de 1965, el Consejo de la Asociaci\u00f3n M\u00e9dica de B\u00e9lgica lleg\u00f3 a la misma conclusi\u00f3n: <em>La heteroinseminaci\u00f3n no solo constituye un acto que se aparta de las caracter\u00edsticas normales de todo acto m\u00e9dico, sino tambi\u00e9n, teniendo en cuenta la incertidumbre total en el plano psicol\u00f3gico, una experiencia que rebasa los l\u00edmites autorizados. No hay que olvidar que la validez del consentimiento dado por los esposos, incluso aunque act\u00faen libremente y con pleno conocimiento de las consecuencias de su acto, es discutible y ha sido debatido; en cualquier caso, dicho consentimiento no libera al m\u00e9dico de su responsabilidad<\/em>.\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 <strong>Conclusiones:<\/strong> Las ventajas de la heteroinseminaci\u00f3n solo alcanzan a uno de los c\u00f3nyuges y en principio son te\u00f3ricas. Solo el tiempo puede demostrar que son efectivas, ya que los fracasos son muy numerosos. Los inconvenientes personales que puede originar tambi\u00e9n son te\u00f3ricos en principio y del mismo orden de magnitud que las ventajas. Pero el grave atentado a los fundamentos del matrimonio, de la familia y de la sociedad es indudable desde el primer momento. Su nocividad social neutraliza ampliamente cualquier ventaja personal te\u00f3rica que pueda reportar en el mejor de los casos. As\u00ed pues, la inseminaci\u00f3n extraconyugal constituye no solo un acto que se aparta de las caracter\u00edsticas normales de todo acto m\u00e9dico l\u00edcito, sino tambi\u00e9n teniendo en cuenta la inseguridad de sus resultados, un experimento que rebasa los l\u00edmites establecidos por la deontolog\u00eda, el derecho y la moral. En consecuencia, el m\u00e9dico debe abstenerse de practicarla.\u00a0<\/p>\n<p><strong>Dr. Alejandro Cruzado Balc\u00e1zar<\/strong>\u00a0<\/p>\n<p><strong>_____________________<\/strong><strong>\u00a0<\/strong><strong> <\/strong><strong>Bibliograf\u00eda<\/strong><strong>\u00a0<\/strong><strong>1.\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><u>Revista Jur\u00eddica del Per\u00fa<\/u>. \u00a0A\u00f1o XXIX \u2013 N\u00famero IV. P\u00e1gs. 217-224<strong>2.\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><u>Cfr.<strong> <\/strong>L\u00f3pez G\u00f3mez, Leopoldo y Gisbert Calabuig<\/u>, Juan Antonio: <em>Tratado de Medicina \u00a0Legal<\/em>. Tomo I. Editorial SABER. Valencia, Espa\u00f1a, 1962, p\u00e1gs. 43-53<strong>3<\/strong><strong>. \u00a0\u00a0<\/strong><u>Cuadros Villena, Carlos \u00a0Ferdinand<\/u>: <em>\u00c9tica de la \u00a0Abogac\u00eda \u00a0y \u00a0Deontolog\u00eda Forense<\/em>.\u00a0\u00a0\u00a0 Editorial FECAT. Lima-Per\u00fa, 1994, <em>p\u00e1ssim<\/em>. <strong>4.\u00a0\u00a0 \u00a0\u00a0\u00a0<\/strong><u>Cfr.<\/u><strong> <\/strong><u>L\u00f3pez G\u00f3mez, Leopoldo y Gisbert Calabuig<\/u>, Juan Antonio: Ob. Cit., p\u00e1gs. 36-43<strong>5.\u00a0\u00a0\u00a0 <\/strong><u>Enciclopedia Jur\u00eddica Omeba<\/u>. Editorial Driskill S.A. Buenos Aires-Argentina, \u00a01979. Tomo XII, p\u00e1g. 74<strong>6.\u00a0 \u00a0<\/strong><u>Cfr. Sol\u00eds Espinoza, Alejandro<\/u>: <em>Metodolog\u00eda de la investigaci\u00f3n \u00a0jur\u00eddico-social<\/em>. Ediciones Jur\u00eddicas. Lima-Per\u00fa, 2003, p\u00e1ssim. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Cfr. Tafur Portilla, Ra\u00fal: <em>Introducci\u00f3n a la investigaci\u00f3n cient\u00edfica<\/em>. Editorial Mantaro. Lima-Per\u00fa, 1994, p\u00e1ssim.\u00a0<\/p>\n<p><strong>Otros libros consultados:<\/strong><strong>\u00a0<\/strong><strong>7.<\/strong>\u00a0 \u00a0\u00a0<u>Bunge, Mario<\/u>: <em>La ciencia, su m\u00e9todo y su filosof\u00eda<\/em>. Editorial Siglo Veinte. Buenos Aires, Argentina. 1972; p\u00e1ssim. <strong>8.\u00a0\u00a0 <\/strong><u>An\u00edbal \u00a0\u00cdsmodes Cairo<\/u>: <em>Metodolog\u00eda de la investigaci\u00f3n jur\u00eddico social<\/em>. Editorial \u00a0\u00a0\u00a0Princeliness. Lima-Per\u00fa, 1991, p\u00e1ssim.<strong> <\/strong><strong>9.<\/strong>\u00a0 \u00a0\u00a0<u>Tafur Portilla, Ra\u00fal<\/u>: <em>Introducci\u00f3n a la \u00a0investigaci\u00f3n \u00a0cient\u00edfica<\/em>.\u00a0 Editorial Mantaro. Lima-Per\u00fa. 1994; p\u00e1ssim.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Dr. Alejandro Cruzado Balc\u00e1zar .\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La inseminaci\u00f3n de la mujer con el semen del marido, en ciertos casos de esterilidad matrimonial, es hoy una pr\u00e1ctica generalmente admitida. En cambio, son muchos los que se oponen a la heteroinseminaci\u00f3n, es decir, a la fecundaci\u00f3n artificial con semen de un donante.\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/351\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[13],"tags":[1081,1016,1012,1013,1140,1052,1142,1149,1065,1037,1025,1119,1021],"class_list":["post-351","post","type-post","status-publish","format-standard","hentry","category-colaboraciones","tag-ambiente","tag-arte","tag-ave","tag-ciencia","tag-escena","tag-iglesia","tag-ley","tag-libros-2","tag-medicina","tag-religion","tag-rosa","tag-social","tag-sociedad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/351\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/351\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-10T16:39:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-10-11T09:45:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alejandro Cruzado Balcazar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alejandro Cruzado Balcazar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/351\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/351\\\/\"},\"author\":{\"name\":\"Alejandro Cruzado Balcazar\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/35528fa93aedfbaac2e4b908d0a96c02\"},\"headline\":\"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico\",\"datePublished\":\"2009-10-10T16:39:51+00:00\",\"dateModified\":\"2009-10-11T09:45:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/351\\\/\"},\"wordCount\":3270,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"keywords\":[\"ambiente\",\"arte\",\"ave\",\"ciencia\",\"escena\",\"iglesia\",\"ley\",\"libros\",\"medicina\",\"religion\",\"rosa\",\"social\",\"sociedad\"],\"articleSection\":[\"Colaboraciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/351\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/351\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/351\\\/\",\"name\":\"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"datePublished\":\"2009-10-10T16:39:51+00:00\",\"dateModified\":\"2009-10-11T09:45:14+00:00\",\"description\":\"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/351\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/351\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/351\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/35528fa93aedfbaac2e4b908d0a96c02\",\"name\":\"Alejandro Cruzado Balcazar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c12a672a9d14f20011a5d97e34a64d07dc1318230c45640249f2818111f3ce61?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c12a672a9d14f20011a5d97e34a64d07dc1318230c45640249f2818111f3ce61?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c12a672a9d14f20011a5d97e34a64d07dc1318230c45640249f2818111f3ce61?s=96&d=monsterid&r=g\",\"caption\":\"Alejandro Cruzado Balcazar\"},\"description\":\"Abogado, jurista, historiador y profesor universitario. Asesor legal de la Municipalidad de Chiclayo (1980), y del Instituto Nacional del Cultura de la misma ciudad (1988); Director Regional de los Registros P\u00fablicos de la Regi\u00f3n Nor Oriental del Mara\u00f1\u00f3n (1993-1994). Miembro Lector del Archivo General de Indias de Sevilla, Espa\u00f1a (2004). Miembro correspondiente extranjero de la Academia Nacional de Historia del Ecuador (2006); de la \\\"Inter-American Bar Association\\\" de Washigton, E.E.U.U. (2008); de la \\\"Union Internationale des Avocats\\\" de Par\u00eds, Francia (2008); de Amnesty International, y de Human Right Watch International. Miembro de la Asociaci\u00f3n Americana de Juristas (AAJ). Socio de la Academia Mundial de Literatura, Historia, Arte y Cultura (AMLHAC).\",\"sameAs\":[\"http:\\\/\\\/cruzadobalcazarabogados.com\"],\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/alejandro-cruzado-balcazar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa","description":"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/351\/","og_locale":"es_ES","og_type":"article","og_title":"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa","og_description":"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/351\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2009-10-10T16:39:51+00:00","article_modified_time":"2009-10-11T09:45:14+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Alejandro Cruzado Balcazar","twitter_misc":{"Escrito por":"Alejandro Cruzado Balcazar","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/351\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/351\/"},"author":{"name":"Alejandro Cruzado Balcazar","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/35528fa93aedfbaac2e4b908d0a96c02"},"headline":"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico","datePublished":"2009-10-10T16:39:51+00:00","dateModified":"2009-10-11T09:45:14+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/351\/"},"wordCount":3270,"commentCount":1,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"keywords":["ambiente","arte","ave","ciencia","escena","iglesia","ley","libros","medicina","religion","rosa","social","sociedad"],"articleSection":["Colaboraciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/351\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/351\/","url":"https:\/\/natureduca.com\/culturblog\/351\/","name":"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"datePublished":"2009-10-10T16:39:51+00:00","dateModified":"2009-10-11T09:45:14+00:00","description":"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/351\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/351\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/351\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"Inseminaci\u00f3n artificial, deontolog\u00eda y Derecho m\u00e9dico"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/35528fa93aedfbaac2e4b908d0a96c02","name":"Alejandro Cruzado Balcazar","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c12a672a9d14f20011a5d97e34a64d07dc1318230c45640249f2818111f3ce61?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c12a672a9d14f20011a5d97e34a64d07dc1318230c45640249f2818111f3ce61?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c12a672a9d14f20011a5d97e34a64d07dc1318230c45640249f2818111f3ce61?s=96&d=monsterid&r=g","caption":"Alejandro Cruzado Balcazar"},"description":"Abogado, jurista, historiador y profesor universitario. Asesor legal de la Municipalidad de Chiclayo (1980), y del Instituto Nacional del Cultura de la misma ciudad (1988); Director Regional de los Registros P\u00fablicos de la Regi\u00f3n Nor Oriental del Mara\u00f1\u00f3n (1993-1994). Miembro Lector del Archivo General de Indias de Sevilla, Espa\u00f1a (2004). Miembro correspondiente extranjero de la Academia Nacional de Historia del Ecuador (2006); de la \"Inter-American Bar Association\" de Washigton, E.E.U.U. (2008); de la \"Union Internationale des Avocats\" de Par\u00eds, Francia (2008); de Amnesty International, y de Human Right Watch International. Miembro de la Asociaci\u00f3n Americana de Juristas (AAJ). Socio de la Academia Mundial de Literatura, Historia, Arte y Cultura (AMLHAC).","sameAs":["http:\/\/cruzadobalcazarabogados.com"],"url":"https:\/\/natureduca.com\/culturblog\/author\/alejandro-cruzado-balcazar\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Alejandro Cruzado Balcazar","author_link":"https:\/\/natureduca.com\/culturblog\/author\/alejandro-cruzado-balcazar\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Alejandro Cruzado Balcazar","author_link":"https:\/\/natureduca.com\/culturblog\/author\/alejandro-cruzado-balcazar\/"},"uagb_comment_info":1,"uagb_excerpt":"Por: Dr. Alejandro Cruzado Balc\u00e1zar .\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La inseminaci\u00f3n de la mujer con el semen del marido, en ciertos casos de esterilidad matrimonial, es hoy una pr\u00e1ctica generalmente admitida. En cambio, son muchos los que se oponen a la heteroinseminaci\u00f3n, es decir, a la fecundaci\u00f3n artificial con semen de un donante.\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=351"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/351\/revisions"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}