{"id":24,"date":"2008-06-26T01:44:19","date_gmt":"2008-06-25T23:44:19","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=24"},"modified":"2014-12-31T17:02:26","modified_gmt":"2014-12-31T15:02:26","slug":"la-poesia-renacentista-2","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/","title":{"rendered":"La poes\u00eda renacentista (2)"},"content":{"rendered":"<p>Se ha dicho y mantenido, que el Renacimiento literario fue una \u00abrevoluci\u00f3n m\u00e9trica\u00bb, en lo que supone de variaci\u00f3n, innovaci\u00f3n y abandono casi total de las antiguas formas po\u00e9ticas. No obstante, el tema amoroso sigue siendo el centro de la actividad l\u00edrica, y el Renacimiento po\u00e9tico supuso tambi\u00e9n introducir una forma nueva de tratar los temas. Por tanto, m\u00e9trica y tem\u00e1tica son dos par\u00e1metros fundamentales en esta revoluci\u00f3n de la poes\u00eda renacentista.<\/p>\n<p><span style=\"text-decoration: underline;\">La m\u00e9trica<\/span><\/p>\n<p>La forma culta del verso de arte mayor castellano (dodecas\u00edlabo o de doce s\u00edlabas), que estuvo presente hasta el siglo XV, es abandonado y sustituido por el endecas\u00edlabo (once s\u00edlabas) de origen italiano. De la misma forma, tambi\u00e9n decae considerablemente el octos\u00edlabo (ocho s\u00edlabas) y no volver\u00e1 a ser utilizado hasta finales del siglo XVI con el nuevo gusto por los romances.<\/p>\n<p>Por su parte, el heptas\u00edlabo (siete s\u00edlabas), que se utilizaba en versos independientes, pasa a combinarse con endecas\u00edlabos en estrofas de origen italiano, como la lira, la canci\u00f3n o la silva.<\/p>\n<p>En la poes\u00eda del siglo XVI el endecas\u00edlabo es el verso que m\u00e1s se cultiva, y por tanto el m\u00e1s abundante; la poes\u00eda culta posterior tambi\u00e9n se definir\u00eda en este sentido. Puede decirse que fue el heredero del hex\u00e1metro latino, siendo usado en composiciones tanto rimadas como en versos blancos (sin rima).<\/p>\n<p>El ritmo del endecas\u00edlabo es lento y pausado, y es percibido como una unidad dentro del poema. Es por ello que, al menos durante el periodo de mayor imitaci\u00f3n petrarquista, no resulte habitual el encabalgamiento entre endecas\u00edlabos, pues Petrarca hu\u00eda de ese recurso en la composici\u00f3n de sus sonetos para no romper la armon\u00eda del poema.<\/p>\n<p>Las estrofas m\u00e1s cultivadas por los poetas proceden de Italia, tales como el soneto, terceto, encadenado, octava real y las canciones (con sus diversas combinaciones: silva, lira, estancia). La especializaci\u00f3n de algunas de estas estrofas acabaron imponiendo formas espec\u00edficas en determinados temas, hasta el extremo de considerarse obligatorio por convenci\u00f3n literaria; es el ejemplo de la octava real en la poes\u00eda \u00e9pica, los tercetos encadenados en las ep\u00edstolas moralizantes, la canci\u00f3n en las composiciones extensas de amor, como las \u00e9glogas. Por su parte, el soneto servir\u00eda de veh\u00edculo para cualquier tipo de temas, aunque fue el amoroso el m\u00e1s cultivado en un primer momento.<\/p>\n<p><span style=\"text-decoration: underline;\">La tem\u00e1tica<\/span><\/p>\n<p>El amor es, sin duda, el gran tema de la poes\u00eda renacentista, aunque ya lo hab\u00eda sido en casi todas las \u00e9pocas de la historia po\u00e9tica. No obstante, en este periodo la concepci\u00f3n que se tiene del amor cambia. El amor cort\u00e9s provenzal tuvo su \u00faltima consecuencia en la poes\u00eda de amor del petrarquismo, que situaba este tema en el centro de su poes\u00eda: un amor sin esperanza y bastante idealizado.<\/p>\n<p>La base te\u00f3rica de la literatura y concepci\u00f3n amorosa del Renacimiento, nace de tratadistas italianos como Baltasar de Castiglione (<em>El cortesano<\/em>, 1528) o Le\u00f3n Hebreo (<em>Di\u00e1logos de amor<\/em>, 1535), cuyas obras fueron traducidas enseguida en Espa\u00f1a y conocidas r\u00e1pidamente. En ellas, las ideas basadas en el neoplatonismo (las ideas de Plat\u00f3n), divulgaron el concepto que se ten\u00eda del amor y del caballero cortesano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se ha dicho y mantenido, que el Renacimiento literario fue una \u00abrevoluci\u00f3n m\u00e9trica\u00bb, en lo que supone de variaci\u00f3n, innovaci\u00f3n y abandono casi total de las antiguas formas po\u00e9ticas. No obstante, el tema amoroso sigue siendo el centro de la actividad l\u00edrica, y el Renacimiento po\u00e9tico supuso tambi\u00e9n introducir una\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[1330,1017,1043,1329,1154,1107,1220,1327],"class_list":["post-24","post","type-post","status-publish","format-standard","hentry","category-literatura","tag-boscan","tag-historia","tag-literatura-2","tag-petrarca","tag-poema","tag-poesia","tag-poetica","tag-renacimiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La poes\u00eda renacentista (2)<\/title>\n<meta name=\"description\" content=\"La poes\u00eda renacentista (2)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La poes\u00eda renacentista (2)\" \/>\n<meta property=\"og:description\" content=\"La poes\u00eda renacentista (2)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-06-25T23:44:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-31T15:02:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-poesia-renacentista-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-poesia-renacentista-2\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"La poes\u00eda renacentista (2)\",\"datePublished\":\"2008-06-25T23:44:19+00:00\",\"dateModified\":\"2014-12-31T15:02:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-poesia-renacentista-2\\\/\"},\"wordCount\":582,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"keywords\":[\"Bosc\u00e1n\",\"historia\",\"literatura\",\"Petrarca\",\"poema\",\"poesia\",\"po\u00e9tica\",\"Renacimiento\"],\"articleSection\":[\"Literatura \\\/ Po\u00e9tica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-poesia-renacentista-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-poesia-renacentista-2\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-poesia-renacentista-2\\\/\",\"name\":\"La poes\u00eda renacentista (2)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"datePublished\":\"2008-06-25T23:44:19+00:00\",\"dateModified\":\"2014-12-31T15:02:26+00:00\",\"description\":\"La poes\u00eda renacentista (2)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-poesia-renacentista-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-poesia-renacentista-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/la-poesia-renacentista-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La poes\u00eda renacentista (2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La poes\u00eda renacentista (2)","description":"La poes\u00eda renacentista (2)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/","og_locale":"es_ES","og_type":"article","og_title":"La poes\u00eda renacentista (2)","og_description":"La poes\u00eda renacentista (2)","og_url":"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2008-06-25T23:44:19+00:00","article_modified_time":"2014-12-31T15:02:26+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"La poes\u00eda renacentista (2)","datePublished":"2008-06-25T23:44:19+00:00","dateModified":"2014-12-31T15:02:26+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/"},"wordCount":582,"commentCount":0,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"keywords":["Bosc\u00e1n","historia","literatura","Petrarca","poema","poesia","po\u00e9tica","Renacimiento"],"articleSection":["Literatura \/ Po\u00e9tica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/","url":"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/","name":"La poes\u00eda renacentista (2)","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"datePublished":"2008-06-25T23:44:19+00:00","dateModified":"2014-12-31T15:02:26+00:00","description":"La poes\u00eda renacentista (2)","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/la-poesia-renacentista-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"La poes\u00eda renacentista (2)"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":0,"uagb_excerpt":"Se ha dicho y mantenido, que el Renacimiento literario fue una \u00abrevoluci\u00f3n m\u00e9trica\u00bb, en lo que supone de variaci\u00f3n, innovaci\u00f3n y abandono casi total de las antiguas formas po\u00e9ticas. No obstante, el tema amoroso sigue siendo el centro de la actividad l\u00edrica, y el Renacimiento po\u00e9tico supuso tambi\u00e9n introducir una\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/24\/revisions"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=24"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=24"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}