{"id":21,"date":"2008-06-26T01:21:06","date_gmt":"2008-06-25T23:21:06","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=21"},"modified":"2014-12-31T16:34:23","modified_gmt":"2014-12-31T14:34:23","slug":"el-marques-de-santillana","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/","title":{"rendered":"El Marqu\u00e9s de Santillana"},"content":{"rendered":"<p><span style=\"font-family: arial, helvetica, sans-serif;\">\u00a0\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/natureduca.com\/images_culturblog\/marques_santillana.jpg\" alt=\"El Marqu\u00e9s de Santillana\" width=\"146\" height=\"182\" align=\"right\" hspace=\"10\" vspace=\"10\" \/>El Marqu\u00e9s de Santillana (1398-1458), cuyo nombre era \u00cd\u00f1igo L\u00f3pez de Mendoza, fue un t\u00edpico representante del primer Renacimiento espa\u00f1ol y hombre de extensa cultura, gran adversario de don \u00c1lvaro de Luna.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\u00a0\u00a0 Pertenec\u00eda a una ilustre familia de gran influencia en los asuntos pol\u00edticos; su padre era almirante de Castilla. Desde joven permaneci\u00f3 en la corte aragonesa, donde se relacion\u00f3 con poetas valencianos y catalanes, como Jordi de Sant Jordi, al cual dedic\u00f3 una de sus obras. Tuvo ocasi\u00f3n de conocer la poes\u00eda de los trovadores en profundidad.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\u00a0\u00a0 Escribi\u00f3 en prosa y en verso. Intent\u00f3 aclimatar las formas m\u00e9tricas italianas en una serie de sonetos y escribi\u00f3 una Carta Proemio, que en cierta modo constituye el primer intento para establecer las l\u00edneas po\u00e9ticas de la literatura romance espa\u00f1ola.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\u00a0\u00a0 Su obra po\u00e9tica se agrupa por una parte en poemas de tendencia italianizante, como la <em>Comediata de Pon\u00e7a<\/em> (que describe la derrota naval que sufrieron Alfonso V y sus hermanos en Pon\u00e7a), o <em>El infierno de los enamorados<\/em>; y por otra parte en poemas doctrinales y sentenciosos, como las <em>Coplas a la ca\u00edda de don \u00c1lvaro de Luna<\/em> y el <em>Doctrinal de Privados<\/em> (donde ataca a don \u00c1lvaro de Luna con gran violencia verbal), <em>Di\u00e1logo de Blas contra fortuna<\/em>, etc.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\u00a0\u00a0 Sin embargo, es en la poes\u00eda cortesana de inspiraci\u00f3n galaico-provenzal donde el Marqu\u00e9s de Santillana obtuvo su mayor acierto, en una serie de canciones, decires y serranillas, de las que destaca como m\u00e1s conocida <em>La vaquera de Finojosa<\/em>:<\/span><\/p>\n<p><dir><span style=\"text-decoration: underline;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Serranilla V<\/span><\/span><\/dir><dir><span style=\"font-family: arial, helvetica, sans-serif;\">Moza tan fermosa<br \/>\nnon v\u00ed en la frontera,<br \/>\ncomo una vaquera<br \/>\nde la Finojosa.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span><\/dir><dir><span style=\"font-family: arial, helvetica, sans-serif;\">Faciendo la v\u00eda<br \/>\ndel Calatrave\u00f1o<br \/>\na Santa Mar\u00eda,<br \/>\nvencido del sue\u00f1o,<br \/>\npor tierra fragosa<br \/>\nperd\u00ed la carrera,<br \/>\ndo v\u00ed la vaquera<br \/>\nde la Finojosa.<\/span><\/dir><dir><span style=\"font-family: arial, helvetica, sans-serif;\">En un verde prado<br \/>\nde rosas e flores,<br \/>\nguardando ganado<br \/>\ncon otros pastores,<br \/>\nla v\u00ed tan graciosa<br \/>\nque apenas creyera<br \/>\nque fuese vaquera<br \/>\nde la Finojosa.<\/span><\/dir><dir><span style=\"font-family: arial, helvetica, sans-serif;\">Non creo las rosas<br \/>\nde la primavera<br \/>\nsean tan fermosas<br \/>\nnin de tal manera,<br \/>\nfablando sin glosa,<br \/>\nsi antes supiera<br \/>\nde aquella vaquera<br \/>\nde la Finojosa. <\/span><\/dir><dir><span style=\"font-family: arial, helvetica, sans-serif;\">Non tanto mirara<br \/>\nsu mucha beldad,<br \/>\nporque me dexara<br \/>\nen mi libertad.<br \/>\nMas dixe:&#8211;\u00abDonosa<br \/>\n(por saber qui\u00e9n era),<br \/>\n\u00bfaquella es la vaquera<br \/>\nde la Finojosa?&#8230;\u00bb\u00bb<\/span><\/dir><dir><span style=\"font-family: Arial;\">\u00a0Bien como riendo,<br \/>\ndixo: &#8211;\u00abBien vengades;<br \/>\nque ya bien entiendo<br \/>\nlo que demandades:<br \/>\nnon es desseosa<br \/>\nde amar, nin lo espera,<br \/>\naquessa vaquera<br \/>\nde la Finojosa.\u00bb<\/span><\/dir><span style=\"font-family: arial, helvetica, sans-serif;\">\u00a0\u00a0 Las Serranillas son composiciones l\u00edricas generalmente en versos cortos, derivada de las antiguas c\u00e1nticas de serrana, las cuales hizo famosas el Marqu\u00e9s de Santillana hizo.\u00a0 <\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\u00a0<\/span><span style=\"font-family: arial, helvetica, sans-serif;\">\u00a0\u00a0 Las Serranillas refieren el encuentro de un caballero con una serrana o pastora, en un lugar agreste, con alabanzas del enamorada a la serrana y, en la mayor\u00eda de los casos, la negativa de \u00e9sta al cortejo amoroso.<\/span><\/p>\n<p><span style=\"font-family: Arial;\">\u00a0\u00a0\u00a0 En el caso del marqu\u00e9s, las figuras femeninas que aborda no est\u00e1n rodeadas de la rudeza de las salteadoras de caminos que imprim\u00eda el Arcipreste de Hita.<\/span><\/p>\n<p><span style=\"font-family: Arial;\">\u00a0\u00a0Bien al contrario, alcanza en su poes\u00eda una frescura y sencillez insuperable que permaneci\u00f3 con todo su valor con el transcurso de los siglos. <\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">\u00a0\u00a0 Entre las obras m\u00e1s importantes del Marqu\u00e9s de Santillana, caben destacar en verso, adem\u00e1s de las canciones, decires y serranillas, los siguientes:\u00a0 <\/span><\/p>\n<p><em><span style=\"font-family: arial, helvetica, sans-serif;\">&#8211; Sonetos fechos al it\u00e1lico modo\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span><\/em><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><em>&#8211; <\/em>Poemas aleg\u00f3ricos<em> (Comediata de Pon\u00e7a, Infierno de los enamorados, Coronaci\u00f3n de mos\u00e9n Jorde de Sant Jordi, Planto de la reina Margarita<\/em>).\u00a0 <\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><em>&#8211;<\/em> Poemas de tipo moral y pol\u00edtico <em>(Di\u00e1logo de B\u00edas contra Fortuna, Doctrinal de privados).<\/em> <\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Tambi\u00e9n escribi\u00f3 en prosa, como la<em> Carta Proemio al condestable don Pedro de Portugal.<\/em><\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Se le atribuye igualmente la autor\u00eda de Refranes que dicen las viejas tras el fuego, una primera recopilaci\u00f3n de refranes castellanos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0 El Marqu\u00e9s de Santillana (1398-1458), cuyo nombre era \u00cd\u00f1igo L\u00f3pez de Mendoza, fue un t\u00edpico representante del primer Renacimiento espa\u00f1ol y hombre de extensa cultura, gran adversario de don \u00c1lvaro de Luna. \u00a0\u00a0 Pertenec\u00eda a una ilustre familia de gran influencia en los asuntos pol\u00edticos; su padre era almirante\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":-1,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[7],"tags":[1043,1326,1156,1107,1220,1327],"class_list":["post-21","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personajes","tag-literatura-2","tag-marques-de-santillana","tag-poemas","tag-poesia","tag-poetica","tag-renacimiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Marqu\u00e9s de Santillana<\/title>\n<meta name=\"description\" content=\"El Marqu\u00e9s de Santillana\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Marqu\u00e9s de Santillana\" \/>\n<meta property=\"og:description\" content=\"El Marqu\u00e9s de Santillana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-06-25T23:21:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-31T14:34:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"El Marqu\u00e9s de Santillana\",\"datePublished\":\"2008-06-25T23:21:06+00:00\",\"dateModified\":\"2014-12-31T14:34:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/\"},\"wordCount\":659,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/marques_santillana.jpg\",\"keywords\":[\"literatura\",\"Marqu\u00e9s de Santillana\",\"poemas\",\"poesia\",\"po\u00e9tica\",\"Renacimiento\"],\"articleSection\":[\"Personajes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/\",\"name\":\"El Marqu\u00e9s de Santillana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/marques_santillana.jpg\",\"datePublished\":\"2008-06-25T23:21:06+00:00\",\"dateModified\":\"2014-12-31T14:34:23+00:00\",\"description\":\"El Marqu\u00e9s de Santillana\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/marques_santillana.jpg\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/images_culturblog\\\/marques_santillana.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-marques-de-santillana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Marqu\u00e9s de Santillana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Marqu\u00e9s de Santillana","description":"El Marqu\u00e9s de Santillana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/","og_locale":"es_ES","og_type":"article","og_title":"El Marqu\u00e9s de Santillana","og_description":"El Marqu\u00e9s de Santillana","og_url":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2008-06-25T23:21:06+00:00","article_modified_time":"2014-12-31T14:34:23+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"El Marqu\u00e9s de Santillana","datePublished":"2008-06-25T23:21:06+00:00","dateModified":"2014-12-31T14:34:23+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/"},"wordCount":659,"commentCount":1,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/#primaryimage"},"thumbnailUrl":"https:\/\/natureduca.com\/images_culturblog\/marques_santillana.jpg","keywords":["literatura","Marqu\u00e9s de Santillana","poemas","poesia","po\u00e9tica","Renacimiento"],"articleSection":["Personajes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/","url":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/","name":"El Marqu\u00e9s de Santillana","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/#primaryimage"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/#primaryimage"},"thumbnailUrl":"https:\/\/natureduca.com\/images_culturblog\/marques_santillana.jpg","datePublished":"2008-06-25T23:21:06+00:00","dateModified":"2014-12-31T14:34:23+00:00","description":"El Marqu\u00e9s de Santillana","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/#primaryimage","url":"https:\/\/natureduca.com\/images_culturblog\/marques_santillana.jpg","contentUrl":"https:\/\/natureduca.com\/images_culturblog\/marques_santillana.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/el-marques-de-santillana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"El Marqu\u00e9s de Santillana"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":1,"uagb_excerpt":"\u00a0\u00a0 El Marqu\u00e9s de Santillana (1398-1458), cuyo nombre era \u00cd\u00f1igo L\u00f3pez de Mendoza, fue un t\u00edpico representante del primer Renacimiento espa\u00f1ol y hombre de extensa cultura, gran adversario de don \u00c1lvaro de Luna. \u00a0\u00a0 Pertenec\u00eda a una ilustre familia de gran influencia en los asuntos pol\u00edticos; su padre era almirante\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/21\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=21"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=21"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}