{"id":169,"date":"2009-01-02T02:58:27","date_gmt":"2009-01-02T00:58:27","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=169"},"modified":"2015-12-29T21:08:53","modified_gmt":"2015-12-29T19:08:53","slug":"historia-militar-1945-1","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/","title":{"rendered":"Historia militar: 1945 (1)"},"content":{"rendered":"<p align=\"left\"><font face=\"arial,helvetica,sans-serif\">En agosto de 1945, con el lanzamiento de bombas at\u00f3micas sobre Hiroshima y Nagasaki, el mundo entr\u00f3 en la era nuclear. El alto grado de destrucci\u00f3n de la nueva arma ha estado presente como amenaza permanente a lo largo de todos los conflictos b\u00e9licos sucedidos desde la conclusi\u00f3n de la Segunda Guerra Mundial.<\/font><\/p>\n<blockquote>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" width=\"280\" src=\"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/e\/e0\/Nagasakibomb.jpg\/280px-Nagasakibomb.jpg\" height=\"335\" class=\"thumbimage\" \/><br \/>\n<font size=\"2\" face=\"arial,helvetica,sans-serif\">Nube provocada por la bomba at\u00f3mica lanzada sobre Nagasaki<br \/>\nFoto <\/font><a target=\"_blank\" href=\"http:\/\/commons.wikimedia.org\/wiki\/Portada\" title=\"Bomba Nagasaki\" class=\"extiw\"><font size=\"2\" face=\"arial,helvetica,sans-serif\">Wikimedia Commons<\/font><\/a><\/div>\n<\/blockquote>\n<p><font face=\"arial,helvetica,sans-serif\">Dos bloques hostiles se crearon tras el fin de la Guerra, encabezados una parte por la extinta Uni\u00f3n de Rep\u00fablicas Socialistas Sovi\u00e9ticas (URSS), y la otra por los Estados Unidos de Am\u00e9rica; ambos poseedores de armamento nuclear. No obstante, a pesar de la amenaza, las armas nucleares no volvieron a utilizarse desde entonces.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">Pero, la guerra convencional mantuvo su desarrollo sin interrupci\u00f3n. Cierto es que, aunque existi\u00f3 una paz dificil entre las superpotencias, \u00e9sta se mantuvo al fin y al cabo, pero en el resto del mundo, en alguna parte, no se dej\u00f3 de combatir d\u00eda tras d\u00eda. Cientos de conflictos armados acaecieron desde el final de la Segunda Guerra Mundial, algunos a gran escala y otros de menor intensidad. As\u00ed, se luch\u00f3 desde niveles de peque\u00f1os grupos guerrilleros, incluso de forma individual y sin direcci\u00f3n ni estrategia, hasta los de despliegue de alta tecnolog\u00eda terrestre y a\u00e9rea, con cazas que volaban a velocidades supers\u00f3nicas, sofisticado instrumental electr\u00f3nico y costoso armamento.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">La \u00abdisuasi\u00f3n\u00bb que provoc\u00f3 el arma nuclear ha sido el paraguas bajo el cual se han desarrollado las guerras convencionales desde la Segunda Guerra Mundial; las consecuencias de su utilizaci\u00f3n constitu\u00edan, sin duda, un coste demasiado elevado para aquellos pa\u00edses que tuvieran la tentaci\u00f3n de tomar esa v\u00eda. En el an\u00e1lisis coincidieron las potencias que pose\u00edan armamento nuclear: los resultados finales ser\u00edan catastr\u00f3ficos para dos partes que se enfrentasen.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">Los estrategas militares han tenido desde entonces constantes problemas de situaci\u00f3n, ante la forma de enfocar la relaci\u00f3n entre los dos tipos de poder militar, el nuclear y el convencional. Ambos poderes han convivido a lo largo de todos estos a\u00f1os, y una posible consecuencia de la existencia del arma nuclear ha sido, el aumento progresivo del poder destructivo de las armas convencionales, las cuales recibieron un impulso notable. Pero, el armamento nuclear no dej\u00f3 de desarrollarse y tambi\u00e9n fue investigado sin pausa, aumentando notablemente su poder destructivo, manteni\u00e9ndose, de esta forma, la vigencia de la \u00abdisuasi\u00f3n\u00bb.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">El poder militar tambi\u00e9n increment\u00f3 su capacidad de uso selectivo. As\u00ed, las nuevas armas, como los misiles filoguidados contracarro, o los de crucero capaces de volar haciendo un seguimiento del terreno para evitar los radares enemigos, adquirieron gran precisi\u00f3n en la selecci\u00f3n y alcance de sus objetivos, con errores de pocos metros. Estas caracter\u00edsticas, permitieron planear los ataques reduciendo notablemente las p\u00e9rdidas humanas, y los de tipo indiscriminado sobre objetivos civiles.La precisi\u00f3n en la localizaci\u00f3n de los objetivos tambi\u00e9n recibi\u00f3 un impulso con nuevos m\u00e9todos de reconocimiento y vigilancia.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">La tendencia de las primeras d\u00e9cadas del siglo XX en la multiplicaci\u00f3n del poder destructivo de las armas, cambi\u00f3 en cierta medida con el panorama creado a partir de 1945. Aunque los conflictos no dejaron de ser crueles como anta\u00f1o, se apreciaron voluntades por evitar o limitar su escalada. El presidente Truman, por ejemplo, no permiti\u00f3 que el general MacArthur atacase la China continental en 1950, durante la guerra de Corea; tambi\u00e9n se evit\u00f3 atacar en los a\u00f1os sesenta Vietnam del Norte. La opci\u00f3n nuclear exist\u00eda, pero su aplicaci\u00f3n nunca se llev\u00f3 a cabo en estos casos.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">El ejemplo de renuncia a la opci\u00f3n nuclear, lo podemos observar en la guerra de Vietnam, donde una potencia notable como era EEUU, fue incapaz de vencer a un enemigo cuyos recursos en material militar era \u00ednfimo. EEUU mantuvo esa guerra y sufri\u00f3 muchas bajas porque renunci\u00f3 al empleo de armas con mayor poder destructor, como eran los ingenios nucleares. A\u00fan as\u00ed, los m\u00e9todos empleados fueron muy devastadores, especialmente para las poblaciones civiles vietnamitas.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">En los a\u00f1os cuarenta y cincuenta, la Guerra Fr\u00eda entre la URSS y el bloque occidental constituy\u00f3 un conflicto que nunca alcanz\u00f3 una confrontaci\u00f3n directa, pero que result\u00f3 un elemento importante en numerosas luchas anticolonialistas que sucedieron en ese periodo.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">La estrategia y defensa antinuclear<\/font><font face=\"arial,helvetica,sans-serif\">Estrat\u00e9gicamente hablando, para los pensadores militares de la \u00e9poca, lo sucedido antes y poco despu\u00e9s del lanzamiento de las bombas at\u00f3micas sobre Jap\u00f3n, se ofrec\u00eda como un panorama de futuro muy sombr\u00edo. Hoy en d\u00eda, el mundo que conocemos es muy diferente al de 1945, pero en aquellos momentos, tras conocerse el poder de devastaci\u00f3n del nuevo ingenio militar, la imaginaci\u00f3n de los estrategas militares sobre las posibilidades de destrucci\u00f3n a gran escala se desbordaron. As\u00ed, pensaron que si un \u00fanica aeronave pod\u00eda transportar una sola bomba capaz de destruir una ciudad entera, se tornaba casi imposible una defensa a\u00e9rea efectiva, o la limitaci\u00f3n de los efectos destructivos. En consecuencia, la conclusi\u00f3n fue que s\u00f3lo podr\u00eda garantizarse la defensa contra un ataque nuclear, ofreciendo una respuesta de similar intensidad. Tal respuesta vendr\u00eda a definir lo que hoy conocemos como \u00abdisuasi\u00f3n militar\u00bb, por la cual, un potencial atacante se abstendr\u00eda de lanzar un ataque nuclear sabiendo que la respuesta ser\u00eda de igual magnitud, y donde el concepto de \u00abganar la batalla\u00bb no podr\u00eda valorarse, en tanto que ambos contendientes sufrir\u00edan alt\u00edsimos costes en vidas humanas y materiales; ambos \u00abperder\u00edan\u00bb.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">No obstante, durante los primeros a\u00f1os de la posguerra no se puso en pr\u00e1ctica la estrategia de la disuasi\u00f3n nuclear, sino que ambas potencias dispusieron el mantenimiento del armamento convencional y el \u00e9nfasis en el n\u00famero de efectivos de los ej\u00e9rcitos, as\u00ed como en el poder industrial y la capacidad de resoluci\u00f3n militar. Particularmente, la URSS lo hizo por necesidad, al no disponer a\u00fan del arma nuclear, pero puso sin embargo todas sus energ\u00edas en conseguirla. Por su parte, EEUU, a pesar de disponer de armamento nuclear, ante la disposici\u00f3n de la URSS se vio forzada a continuar prepar\u00e1ndose para la guerra convencional.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">Con el comienzo de la Guerra Fr\u00eda a finales de la d\u00e9cada de 1940, tras romperse la coalici\u00f3n antifascista que se formara en el transcurso de la II Guerra Mundial, a\u00fan no se vislumbraba en el horizonte futuro una imagen de conflictos muy diferente a los anteriores. El miedo a la detrucci\u00f3n total a\u00fan no dominaba, y las guerras se imaginaban a base de grandes movilizaciones de efectivos y eficacia del armamento convencional. El motivo era que las bombas at\u00f3micas eran de fisi\u00f3n (todav\u00eda no se hab\u00eda experimentado con la bomba H) y escasas, y los medios de transporte a\u00e9reos a\u00fan requer\u00edan de aviones de h\u00e9lice; no se hac\u00eda una hip\u00f3tesis de cambio de estos par\u00e1metros, o en todo caso se pensaba que durar\u00edan mucho tiempo.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">La situaci\u00f3n dio un vuelco a principios de la d\u00e9cada de 1950: la URSS realiz\u00f3 sus propias pruebas nucleares y consigui\u00f3 hacer estallar una bomba nuclear. En teor\u00eda, el equilibrio se hab\u00eda conseguido, y la disuasi\u00f3n, a base de anunciar el terror por ambas partes, deber\u00eda dar sus resultados pr\u00e1cticos en forma de prudencia mutua. Pero, en 1952 tanto EEUU como la URSS inauguraron la era termonuclear al ensayar con \u00e9xito bombas de hidr\u00f3geno. Ahora, para el poseedor de estos ingenios, el poder de devastaci\u00f3n ser\u00eda ilimitado.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">El presidente americano Truman, tras el ensayo termonuclear de la URSS, fue informado de unos estudios solicitados a instancia suya, que concluyeron en la necesidad de mantener y potenciar el armamento convencional con objeto de igualar el poder del ej\u00e9rcito sovi\u00e9tico, al ir avanzando el nuclear hacia una situaci\u00f3n de equilibrio. La Guerra de Corea de 1950-53 vino a confirmar esa necesidad, y el reame occidental se realiz\u00f3 r\u00e1pidamente.<\/font><font face=\"arial,helvetica,sans-serif\">\u00a0<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">Este conflicto de tipo convencional se realiz\u00f3 a gran escala, y trajo consigo m\u00e1s de un mill\u00f3n de v\u00edctimas con el enfrentamiento de China y Corea del Norte contra las fuerzas occidentales, que al poseer una experiencia t\u00e9cnica superior consiguieron estabilizar la situaci\u00f3n. No obstante, el resultado frustr\u00f3 sobremanera y cre\u00f3 un estado de opini\u00f3n muy cr\u00edtico entre los estadounidenses. Adem\u00e1s, todo ese esfuerzo militar de tipo convencional supuso un desembolso econ\u00f3mico muy importante tanto para EEUU como los aliados europeos, convirti\u00e9ndose en un lastre insostenible.<\/font><\/p>\n<blockquote>\n<p align=\"center\">\n<font size=\"2\" face=\"Arial\">Fuerzas aliadas abandonando Corea del Norte. S\u00f3lo EEUU perdi\u00f3 m\u00e1s de 44.000 soldados, menos que en Vietnam pero en un periodo m\u00e1s corto<br \/>\nFoto <\/font><a target=\"_blank\" href=\"http:\/\/commons.wikimedia.org\/wiki\/Portada\" title=\"Bomba Nagasaki\" class=\"extiw\"><font size=\"2\" face=\"Arial\">Wikimedia Commons<\/font><\/a><\/p>\n<\/blockquote>\n<p><font face=\"arial,helvetica,sans-serif\">Como consecuencia de la experiencia de Corea, los estrategas norteamericanos cambiaron su orientaci\u00f3n en la d\u00e9cada de 1950 ya bajo la presidencia de Eisenhower, y lo hicieron en sentido totalmente contrario a la llevada a cabo por Truman. As\u00ed, en vez de incrementar las fuerzas convencionales y dejar a un lado las nucleares, EEUU adopt\u00f3 la doctrina de la \u00abrepresalia masiva\u00bb (en referencia a cubrirse mediante la disuasi\u00f3n nuclear) como estrategia para defender todos aquellos puntos que consideraba vitales para su seguridad. En consecuencia, durante toda la d\u00e9cada EEUU y los aliados europeos redujeron dr\u00e1sticamente los gastos en armamento convencional.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">La supuesta respuesta nuclear por parte de los aliados ante una agresi\u00f3n menor suscitaba inquietud. Para muchos tal amenaza no era creible, al considerar que la URSS responder\u00eda con un ataque de represalia sobre ciudades americanas. Esta pol\u00edtica no constitu\u00eda, pues, una disuasi\u00f3n efectiva. Tras suavizarse la tensi\u00f3n Este-Oeste a partir de 1953, con la finalizaci\u00f3n de la Guerra de Corea y la muerte de Stalin, surgi\u00f3 de nuevo un m\u00e1ximo en la fricci\u00f3n URSS-EEUU, cuyo punto \u00e1lgido se sit\u00faa en noviembre de 1958 con la \u00abCuesti\u00f3n de Berl\u00edn\u00bb nuevamente suscitada por Jruschov, y en la cual el primer ministro defend\u00eda la tesis de incorporar la ciudad de Berl\u00edn a la Alemania del Este, denunciando el estatuto de ocupaci\u00f3n del cuatripartito.<\/font><\/p>\n<p><font face=\"arial,helvetica,sans-serif\">La II Guerra Mundial infligi\u00f3 un duro golpe al poder de las naciones occidentales, manifest\u00e1ndose un proceso de descolonizaci\u00f3n muy sangriento, y donde brit\u00e1nicos, franceses, portugueses o neerlandeses lucharon duramente por el mantenimiento de sus \u00faltimas posesiones. En esas luchas, muchos movimientos nacionalistas revolucionarios fueron combatidos por reg\u00edmenes no democr\u00e1ticos que eran apoyados a menudo por los norteamericanos, alargando dolorosamente los conflictos.<\/font><\/p>\n<p><font size=\"2\" face=\"Arial\"><em>Continuar\u00e1&#8230;<\/em><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En agosto de 1945, con el lanzamiento de bombas at\u00f3micas sobre Hiroshima y Nagasaki, el mundo entr\u00f3 en la era nuclear. El alto grado de destrucci\u00f3n de la nueva arma ha estado presente como amenaza permanente a lo largo de todos los conflictos b\u00e9licos sucedidos desde la conclusi\u00f3n de la\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":-1,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[6],"tags":[1016,1012,1034,1017,1054,1027,1036,1025,1063,1033],"class_list":["post-169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-militar","tag-arte","tag-ave","tag-guerra","tag-historia","tag-industria","tag-militar","tag-norteamerica","tag-rosa","tag-transporte","tag-vino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Historia militar: 1945 (1) - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"Historia militar: 1945 (1) - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historia militar: 1945 (1) - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"Historia militar: 1945 (1) - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-01-02T00:58:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-29T19:08:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"Historia militar: 1945 (1)\",\"datePublished\":\"2009-01-02T00:58:27+00:00\",\"dateModified\":\"2015-12-29T19:08:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/\"},\"wordCount\":1819,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/upload.wikimedia.org\\\/wikipedia\\\/commons\\\/thumb\\\/e\\\/e0\\\/Nagasakibomb.jpg\\\/280px-Nagasakibomb.jpg\",\"keywords\":[\"arte\",\"ave\",\"guerra\",\"historia\",\"industria\",\"militar\",\"norteamerica\",\"rosa\",\"transporte\",\"vino\"],\"articleSection\":[\"Historia militar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/\",\"name\":\"Historia militar: 1945 (1) - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/upload.wikimedia.org\\\/wikipedia\\\/commons\\\/thumb\\\/e\\\/e0\\\/Nagasakibomb.jpg\\\/280px-Nagasakibomb.jpg\",\"datePublished\":\"2009-01-02T00:58:27+00:00\",\"dateModified\":\"2015-12-29T19:08:53+00:00\",\"description\":\"Historia militar: 1945 (1) - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/#primaryimage\",\"url\":\"http:\\\/\\\/upload.wikimedia.org\\\/wikipedia\\\/commons\\\/thumb\\\/e\\\/e0\\\/Nagasakibomb.jpg\\\/280px-Nagasakibomb.jpg\",\"contentUrl\":\"http:\\\/\\\/upload.wikimedia.org\\\/wikipedia\\\/commons\\\/thumb\\\/e\\\/e0\\\/Nagasakibomb.jpg\\\/280px-Nagasakibomb.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/historia-militar-1945-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Historia militar: 1945 (1)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historia militar: 1945 (1) - Blog Cultureduca educativa","description":"Historia militar: 1945 (1) - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/","og_locale":"es_ES","og_type":"article","og_title":"Historia militar: 1945 (1) - Blog Cultureduca educativa","og_description":"Historia militar: 1945 (1) - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2009-01-02T00:58:27+00:00","article_modified_time":"2015-12-29T19:08:53+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"Historia militar: 1945 (1)","datePublished":"2009-01-02T00:58:27+00:00","dateModified":"2015-12-29T19:08:53+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/"},"wordCount":1819,"commentCount":1,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/#primaryimage"},"thumbnailUrl":"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/e\/e0\/Nagasakibomb.jpg\/280px-Nagasakibomb.jpg","keywords":["arte","ave","guerra","historia","industria","militar","norteamerica","rosa","transporte","vino"],"articleSection":["Historia militar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/","url":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/","name":"Historia militar: 1945 (1) - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/#primaryimage"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/#primaryimage"},"thumbnailUrl":"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/e\/e0\/Nagasakibomb.jpg\/280px-Nagasakibomb.jpg","datePublished":"2009-01-02T00:58:27+00:00","dateModified":"2015-12-29T19:08:53+00:00","description":"Historia militar: 1945 (1) - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/#primaryimage","url":"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/e\/e0\/Nagasakibomb.jpg\/280px-Nagasakibomb.jpg","contentUrl":"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/e\/e0\/Nagasakibomb.jpg\/280px-Nagasakibomb.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/historia-militar-1945-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"Historia militar: 1945 (1)"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":1,"uagb_excerpt":"En agosto de 1945, con el lanzamiento de bombas at\u00f3micas sobre Hiroshima y Nagasaki, el mundo entr\u00f3 en la era nuclear. El alto grado de destrucci\u00f3n de la nueva arma ha estado presente como amenaza permanente a lo largo de todos los conflictos b\u00e9licos sucedidos desde la conclusi\u00f3n de la\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=169"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}