{"id":1264,"date":"2011-02-22T18:17:13","date_gmt":"2011-02-22T16:17:13","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=1264"},"modified":"2018-12-22T03:12:33","modified_gmt":"2018-12-22T01:12:33","slug":"don-juan-tenorio-i-iii-jose-zorrilla","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/","title":{"rendered":"\u00abDon Juan Tenorio\u00bb (I-III) [Jos\u00e9 Zorrilla]"},"content":{"rendered":"<p><strong>PRIMERA PARTE<br \/>\nACTO TERCERO<\/strong><\/p>\n<p>Profanaci\u00f3n<\/p>\n<p>Celda de DO\u00d1A IN\u00c9S. Puerta en el fondo y a la izquierda<\/p>\n<p>Escena primera<\/p>\n<p>DO\u00d1A IN\u00c9S, la ABADESA<\/p>\n<p>IN\u00c9S. \u00bfConque me hab\u00e9is entendido?<\/p>\n<p>ABADESA S\u00ed, se\u00f1ora.<\/p>\n<p>IN\u00c9S. Est\u00e1 muy bien;<\/p>\n<p>ABADESA la voluntad decisiva<br \/>\nde vuestro padre tal es.<br \/>\nSois joven, c\u00e1ndida y buena;<br \/>\nvivido en el claustro hab\u00e9is<br \/>\ncasi desde que nacisteis;<br \/>\ny para quedar en \u00e9l<br \/>\natada con santos votos<br \/>\npara siempre, ni a\u00fan ten\u00e9is,<br \/>\ncomo otras, pruebas dif\u00edciles<br \/>\nni penitencias que hacer.<br \/>\n\u00a1Dichosa mil veces vos!<br \/>\nDichosa, s\u00ed, do\u00f1a In\u00e9s,<br \/>\nque no conociendo el mundo,<br \/>\nno le deb\u00e9is de temer.<br \/>\n\u00a1Dichosa vos, que del claustro<br \/>\nal pisar en el dintel,<br \/>\nno os volver\u00e9is a mirar<br \/>\nlo que tras vos dejar\u00e9is!<br \/>\nY los mundanos recuerdos<br \/>\ndel bullicio y del placer<br \/>\nno os turbar\u00e1n tentadores<br \/>\ndel ara santa a los pies;<br \/>\npues ignorando lo que hay<br \/>\ntras esa santa pared,<br \/>\nlo que tras ella se queda<br \/>\njam\u00e1s apetecer\u00e9is.<br \/>\nMansa paloma ense\u00f1ada<br \/>\nen las palmas a comer<br \/>\ndel due\u00f1o que la ha criado<br \/>\nen dom\u00e9stico vergel,<br \/>\nno habiendo salido nunca<br \/>\nde la protectora red,<br \/>\nno ansiareis nunca las alas<br \/>\npor el espacio tender.<br \/>\nLirio gentil, cuyo tallo<br \/>\nmecieron s\u00f3lo tal vez<br \/>\nlas embalsamadas brisas<br \/>\ndel m\u00e1s florecido mes,<br \/>\naqu\u00ed a los besos del aura<br \/>\nvuestro c\u00e1liz abrir\u00e9is,<br \/>\ny aqu\u00ed vendr\u00e1n vuestras hojas<br \/>\ntranquilamente a caer.<br \/>\nY en el pedazo de tierra<br \/>\nque abarca nuestra estrechez,<br \/>\ny en el pedazo de cielo<br \/>\nque por las rejas se ve,<br \/>\nvos no ver\u00e9is m\u00e1s que un lecho<br \/>\ndo en dulce sue\u00f1o yacer,<br \/>\ny un velo azul suspendido<br \/>\na las puertas del Ed\u00e9n.<br \/>\n\u00a1Ay! En verdad que os envidio,<br \/>\nventurosa do\u00f1a In\u00e9s,<br \/>\ncon vuestra inocente vida,<br \/>\nla virtud del no saber.<br \/>\n\u00bfMas por qu\u00e9 est\u00e1is cabizbaja?<br \/>\n\u00bfPor qu\u00e9 no me respond\u00e9is<br \/>\ncomo otras veces, alegre,<br \/>\ncuando en lo mismo os habl\u00e9?<br \/>\n\u00bfSuspir\u00e1is?&#8230; \u00a1Oh!, ya comprendo:<br \/>\nde vuelta aqu\u00ed hasta no ver<br \/>\na vuestra aya, est\u00e1is inquieta;<br \/>\npero nada recel\u00e9is.<br \/>\nA casa de vuestro padre<br \/>\nfue casi al anochecer,<br \/>\ny abajo en la porter\u00eda<br \/>\nestar\u00e1: yo os la enviar\u00e9,<br \/>\nque estoy de vela esta noche.<br \/>\nConque, vamos, do\u00f1a In\u00e9s,<br \/>\nrecogeos, que ya es hora:<br \/>\nmal ejemplo no me deis<br \/>\na las novicias, que ha tiempo<br \/>\nque duermen ya: hasta despu\u00e9s.<\/p>\n<p>IN\u00c9S. Id con Dios, madre abadesa.<\/p>\n<p>ABADESA Adi\u00f3s, hija.<\/p>\n<p>Escena II<\/p>\n<p>DO\u00d1A IN\u00c9S Ya se fue.<br \/>\nNo s\u00e9 qu\u00e9 tengo, \u00a1ay de m\u00ed!,<br \/>\nque en tumultuoso tropel<br \/>\nmil encontradas ideas<br \/>\nme combaten a la vez.<br \/>\nOtras noches complacida<br \/>\nsus palabras escuch\u00e9;<br \/>\ny de esos cuadros tranquilos<br \/>\nque sabe pintar tan bien,<br \/>\nde esos placeres dom\u00e9sticos<br \/>\nla dichosa sencillez<br \/>\ny la calma venturosa,<br \/>\nme hicieron apetecer<br \/>\nla soledad de los claustros<br \/>\ny su santa rigidez.<br \/>\nMas hoy la o\u00ed distra\u00edda,<br \/>\ny en sus pl\u00e1ticas hall\u00e9,<br \/>\nsi no enojosos discursos<br \/>\na lo menos aridez.<br \/>\nY no s\u00e9 por qu\u00e9 al decirme<br \/>\nque podr\u00eda acontecer<br \/>\nque se acelerase el d\u00eda<br \/>\nde mi profesi\u00f3n, tembl\u00e9;<br \/>\ny sent\u00ed del coraz\u00f3n<br \/>\nacelerarse el vaiv\u00e9n,<br \/>\ny te\u00f1\u00edrseme el semblante<br \/>\nde amarilla palidez.<br \/>\n\u00a1Ay de m\u00ed&#8230;! \u00a1Pero mi due\u00f1a,<br \/>\nd\u00f3nde estar\u00e1&#8230;! Esa mujer<br \/>\ncon sus pl\u00e1ticas al cabo<br \/>\nme entretiene alguna vez.<br \/>\nY hoy la echo menos&#8230; acaso<br \/>\nporque la voy a perder,<br \/>\nque en profesando es preciso<br \/>\nrenunciar a cuanto am\u00e9.<br \/>\nMas pasos siento en el claustro;<br \/>\n\u00a1oh!, reconozco muy bien<br \/>\nsus pisadas&#8230; Ya est\u00e1 aqu\u00ed.<\/p>\n<p>Escena III<\/p>\n<p>DO\u00d1A IN\u00c9S, BR\u00cdGIDA<\/p>\n<p>BR\u00cdGIDA.\u00a0 Buenas noches, do\u00f1a In\u00e9s.<\/p>\n<p>IN\u00c9S. \u00bfC\u00f3mo hab\u00e9is tardado tanto?<\/p>\n<p>BR\u00cdGIDA.\u00a0 Voy a cerrar esta puerta.<\/p>\n<p>IN\u00c9S. Hay orden de que est\u00e9 abierta.<\/p>\n<p>BR\u00cdGIDA.\u00a0 Eso es muy bueno y muy santo<br \/>\npara las otras novicias<br \/>\nque han de consagrarse a Dios,<br \/>\nno, do\u00f1a In\u00e9s, para vos.<\/p>\n<p>IN\u00c9S. Br\u00edgida, \u00bfno ves que vicias<br \/>\nlas reglas del monasterio<br \/>\nque no permiten&#8230;?<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Bah!, \u00a1bah!<br \/>\nM\u00e1s seguro as\u00ed se est\u00e1,<br \/>\ny as\u00ed se habla sin misterio<br \/>\nni estorbos: \u00bfhab\u00e9is mirado<br \/>\nel libro que os he tra\u00eddo?<\/p>\n<p>IN\u00c9S. \u00a1Ay!, se me hab\u00eda olvidado.<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Pues me hace gracia el olvido!<\/p>\n<p>IN\u00c9S. \u00a1Como la madre abadesa<br \/>\nse entr\u00f3 aqu\u00ed inmediatamente!<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Vieja m\u00e1s impertinente!<\/p>\n<p>IN\u00c9S. \u00bfPues tanto el libro interesa?<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Vaya si interesa! Mucho.<br \/>\n\u00bfPues qued\u00f3 con poco af\u00e1n<br \/>\nel infeliz!<\/p>\n<p>IN\u00c9S. \u00bfQui\u00e9n?<\/p>\n<p>BR\u00cdGIDA.\u00a0 Don Juan.<\/p>\n<p>IN\u00c9S. \u00a1V\u00e1lgame el cielo! \u00a1Qu\u00e9 escucho!<br \/>\n\u00bfEs don Juan quien me le env\u00eda?<\/p>\n<p>BR\u00cdGIDA.\u00a0 Por supuesto.<\/p>\n<p>IN\u00c9S. \u00a1Oh! Yo no debo<br \/>\nTomarle.<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Pobre mancebo!<br \/>\nDesairarle as\u00ed, ser\u00eda<br \/>\nMatarle.<\/p>\n<p>IN\u00c9S. \u00bfQu\u00e9 est\u00e1s diciendo?<\/p>\n<p>BR\u00cdGIDA.\u00a0 Si ese horario no tom\u00e1is,<br \/>\ntal pesadumbre le dais<br \/>\nque va a enfermar; lo estoy<br \/>\nviendo.<\/p>\n<p>IN\u00c9S. \u00a1Ah! No, no: de esa manera,<br \/>\nle tomar\u00e9.<\/p>\n<p>BR\u00cdGIDA.\u00a0 Bien har\u00e9is.<\/p>\n<p>IN\u00c9S. \u00a1Y qu\u00e9 bonito es!<\/p>\n<p>BR\u00cdGIDA.\u00a0 Ya veis;<br \/>\nquien quiere agradar, se esmera.<\/p>\n<p>IN\u00c9S. Con sus manecillas de oro.<br \/>\n\u00a1Y cuidado que est\u00e1 prieto!<br \/>\nA ver, a ver si completo<br \/>\nContiene el rezo del coro.<br \/>\n(Le abre, y cae una carta de entre sus hojas.)<br \/>\nMas, \u00bfqu\u00e9 cay\u00f3?<\/p>\n<p>BR\u00cdGIDA.\u00a0 Un papelito.<\/p>\n<p>IN\u00c9S. Una carta!<\/p>\n<p>BR\u00cdGIDA.\u00a0 Claro est\u00e1;<br \/>\nen esa carta os vendr\u00e1<br \/>\nofreciendo el regalito.<\/p>\n<p>IN\u00c9S. \u00a1Qu\u00e9! \u00bfSer\u00e1 suyo el papel?<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Vaya, que sois inocente!<br \/>\nPues que os feria, es<br \/>\nconsiguiente<br \/>\nque la carta ser\u00e1 de \u00e9l.<\/p>\n<p>IN\u00c9S. \u00a1Ay, Jes\u00fas!<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00bfQu\u00e9 es lo que os da?<\/p>\n<p>IN\u00c9S. Nada, Br\u00edgida, no es nada.<\/p>\n<p>BR\u00cdGIDA.\u00a0 No, no; si est\u00e1is inmutada.<br \/>\n(Ya presa en la red est\u00e1.)<br \/>\n\u00bfSe os pasa?<\/p>\n<p>IN\u00c9S. S\u00ed.<\/p>\n<p>BR\u00cdGIDA.\u00a0 Eso habr\u00e1 sido<br \/>\ncualquier mare\u00edllo vano.<\/p>\n<p>IN\u00c9S. \u00a1Ay! Se me abrasa la mano<br \/>\ncon que el papel he cogido.<\/p>\n<p>BR\u00cdGIDA.\u00a0 Do\u00f1a In\u00e9s, \u00a1v\u00e1lgame Dios!<br \/>\nJam\u00e1s os he visto as\u00ed:<br \/>\nest\u00e1is tr\u00e9mula.<\/p>\n<p>IN\u00c9S. \u00a1Ay de m\u00ed!<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00bfQu\u00e9 es lo que pasa por vos?<\/p>\n<p>IN\u00c9S. No s\u00e9&#8230; El campo de mi mente<br \/>\nSiento que cruzan perdidas<br \/>\nmil sombras desconocidas<br \/>\nque me inquietan vagamente;<br \/>\ny ha tiempo al alma me dan<br \/>\ncon su agitaci\u00f3n tortura.<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00bfTiene alguna, por ventura,<br \/>\nel semblante de don Juan?<\/p>\n<p>IN\u00c9S. No s\u00e9: desde que le vi,<br \/>\nBr\u00edgida m\u00eda, y su nombre<br \/>\nme dijiste, tengo a ese hombre<br \/>\nSiempre delante de m\u00ed.<br \/>\nPor doquiera me distraigo<br \/>\ncon su agradable recuerdo,<br \/>\ny si un instante le pierdo,<br \/>\nen su recuerdo recaigo.<br \/>\nNo s\u00e9 qu\u00e9 fascinaci\u00f3n<br \/>\nen mis sentidos ejerce,<br \/>\nque siempre hacia \u00e9l se me<br \/>\ntuerce<br \/>\nla mente y el coraz\u00f3n:<br \/>\ny aqu\u00ed y en el oratorio,<br \/>\ny en todas partes, advierto<br \/>\nque el pensamiento divierto<br \/>\ncon la imagen de Tenorio.<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1V\u00e1lgame Dios! Do\u00f1a In\u00e9s,<br \/>\nseg\u00fan lo vais explicando,<br \/>\ntentaciones me van dando<br \/>\nde creer que eso amor es.<\/p>\n<p>IN\u00c9S. \u00a1Amor has dicho!<\/p>\n<p>BR\u00cdGIDA.\u00a0 S\u00ed, amor.<\/p>\n<p>IN\u00c9S. No, de ninguna manera.<\/p>\n<p>BR\u00cdGIDA.\u00a0 Pues por amor lo entendiera<br \/>\nel menos entendedor;<br \/>\nmas vamos la carta a ver:<br \/>\n\u00bfen qu\u00e9 os par\u00e1is? \u00bfUn suspiro?<\/p>\n<p>IN\u00c9S. \u00a1Ay!, que cuanto m\u00e1s la miro,<br \/>\nmenos me atrevo a leer.<br \/>\n(Lee.)<br \/>\n\u00abDo\u00f1a In\u00e9s del alma m\u00eda.\u00bb<br \/>\n\u00a1Virgen Santa, qu\u00e9 principio!<\/p>\n<p>BR\u00cdGIDA.\u00a0 Vendr\u00e1 en verso, y ser\u00e1 un ripio<br \/>\nque traer\u00e1 la poes\u00eda.<br \/>\nVamos, seguid adelante.<\/p>\n<p>IN\u00c9S. (Lee.) \u00abLuz de donde el sol la toma,<br \/>\nhermos\u00edsima paloma<br \/>\nprivada de libertad,<br \/>\nsi os dign\u00e1is por estas letras<br \/>\npasar vuestros lindos ojos,<br \/>\nno los torn\u00e9is con enojos<br \/>\nsin concluir, acabad.\u00bb<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Qu\u00e9 humildad! \u00a1Y que finura!<br \/>\n\u00bfD\u00f3nde hay mayor<br \/>\nrendimiento?<\/p>\n<p>IN\u00c9S. Br\u00edgida, no s\u00e9 qu\u00e9 siento.<\/p>\n<p>BRIGIDA. Seguid, seguid la lectura.<\/p>\n<p>IN\u00c9S. (Lee.)<\/p>\n<p>\u00abNuestros padres de consuno<br \/>\nnuestras bodas acordaron,<br \/>\nporque los cielos juntaron<br \/>\nlos destinos de los dos.<br \/>\nY halagado desde entonces<br \/>\ncon tan risue\u00f1a esperanza,<br \/>\nmi alma, do\u00f1a In\u00e9s, no alcanza<br \/>\notro porvenir que vos.<br \/>\nDe amor con ella en mi pecho<br \/>\nbrot\u00f3 una chispa ligera,<br \/>\nque han convertido en hoguera<br \/>\ntiempo y afici\u00f3n tenaz:<br \/>\ny esta llama que en m\u00ed mismo<br \/>\nse alimenta inextinguible,<br \/>\ncada d\u00eda m\u00e1s terrible<br \/>\nva creciendo y m\u00e1s voraz.\u00bb<\/p>\n<p>BR\u00cdGIDA.\u00a0 Es claro; esperar le hicieron<br \/>\nen vuestro amor alg\u00fan d\u00eda,<br \/>\ny hondas ra\u00edces ten\u00eda<br \/>\ncuando a arranc\u00e1rsele fueron.<br \/>\nSeguid.<\/p>\n<p>IN\u00c9S. (Lee.) \u00abEn vano a apagarla<br \/>\nconcurren tiempo y ausencia,<br \/>\nque doblando su violencia,<br \/>\nno hoguera ya, volc\u00e1n es.<br \/>\nY yo, que en medio del cr\u00e1ter<br \/>\ndesamparado batallo,<br \/>\nsuspendido en \u00e9l me hallo<br \/>\nentre mi tumba y mi In\u00e9s.\u00bb<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00bfLo veis, In\u00e9s? Si ese horario<br \/>\nle despreci\u00e1is, al instante<br \/>\nle preparan el sudario.<\/p>\n<p>IN\u00c9S. Yo desfallezco.<\/p>\n<p>BR\u00cdGIDA.\u00a0 Adelante.<\/p>\n<p>IN\u00c9S. (Lee.)<br \/>\n\u00abIn\u00e9s, alma de mi alma,<br \/>\nperpetuo im\u00e1n de mi vida,<br \/>\nperla sin concha escondida<br \/>\nentre las algas del mar;<br \/>\ngarza que nunca del nido<br \/>\ntender osaste el vuelo,<br \/>\nel di\u00e1fano azul del cielo<br \/>\npara aprender a cruzar:<br \/>\nsi es que a trav\u00e9s de esos muros<br \/>\nel mundo apenada miras,<br \/>\ny por el mundo suspiras<br \/>\nde libertad con af\u00e1n,<br \/>\nacu\u00e9rdate que al pie mismo<br \/>\nde esos muros que te guardan,<br \/>\npara salvarte te aguardan<br \/>\nlos brazos de tu don Juan.\u00bb<\/p>\n<p>(Representa.)<\/p>\n<p>\u00bfQu\u00e9 es lo que me pasa, \u00a1cielo!<br \/>\nque me estoy viendo morir?<\/p>\n<p>BR\u00cdGIDA.\u00a0 (Ya trag\u00f3 todo el anzuelo.)<br \/>\nVamos, que est\u00e1 al concluir.<\/p>\n<p>IN\u00c9S. (Lee.)<br \/>\n\u00abAcu\u00e9rdate de quien llora<br \/>\nal pie de tu celos\u00eda<br \/>\ny all\u00ed le sorprende el d\u00eda<br \/>\ny le halla la noche all\u00ed;<br \/>\nacu\u00e9rdate de quien vive<br \/>\ns\u00f3lo por ti, \u00a1vida m\u00eda!<br \/>\ny que a tus pies volar\u00eda<br \/>\nsi le llamaras a ti.\u00bb<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00bfLo veis? Vendr\u00eda.<\/p>\n<p>IN\u00c9S. \u00a1Vendr\u00eda!<\/p>\n<p>BR\u00cdGIDA.\u00a0 A postrarse a vuestros pies.<\/p>\n<p>IN\u00c9S. \u00bfPuede?<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Oh!, s\u00ed.<\/p>\n<p>IN\u00c9S. \u00a1Virgen Mar\u00eda!<\/p>\n<p>BR\u00cdGIDA.\u00a0 Pero acabad, do\u00f1a In\u00e9s.<\/p>\n<p>IN\u00c9S. (Lee.)<br \/>\n\u00abAdi\u00f3s, \u00a1oh luz de mis ojos!<br \/>\nAdi\u00f3s, In\u00e9s de mi alma:<br \/>\nmedita, por Dios, en calma<br \/>\nlas palabras que aqu\u00ed van:<br \/>\ny si odias esa clausura,<br \/>\nque ser tu sepulcro debe,<br \/>\nmanda, que a todo se atreve<br \/>\npor tu hermosura don Juan.\u00bb<\/p>\n<p>(Representa DO\u00d1A IN\u00c9S.)<br \/>\n\u00a1Ay! \u00bfQu\u00e9 filtro envenenado<br \/>\nme dan en este papel,<br \/>\nque el coraz\u00f3n desgarrado<br \/>\nme estoy sintiendo con \u00e9l?<br \/>\n\u00bfQu\u00e9 sentimientos dormidos<br \/>\nson los que revela en m\u00ed?<br \/>\n\u00bfQu\u00e9 impulsos jam\u00e1s sentidos?<br \/>\n\u00bfQu\u00e9 luz, que hasta hoy nunca<br \/>\nvi?<br \/>\n\u00bfQu\u00e9 es lo que engendra en mi<br \/>\nalma<br \/>\ntan nuevo y profundo af\u00e1n?<br \/>\n\u00bfQui\u00e9n roba la dulce calma<br \/>\nde mi coraz\u00f3n?<\/p>\n<p>BR\u00cdGIDA.\u00a0 Don Juan.<\/p>\n<p>IN\u00c9S.<br \/>\n\u00a1Don Juan dices&#8230;! \u00bfConque ese<br \/>\nhombre<br \/>\nme ha de seguir por doquier?<br \/>\n\u00bfS\u00f3lo he de escuchar su<br \/>\nnombre?<br \/>\n\u00bfS\u00f3lo su sombra he de ver?<br \/>\n\u00a1Ah! Bien dice: junt\u00f3 el cielo<br \/>\nlos destinos de los dos,<br \/>\ny en mi alma engendr\u00f3 este<br \/>\nanhelo fatal.<\/p>\n<p>(Se oyen dar las \u00e1nimas.)<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Silencio, por Dios!<\/p>\n<p>IN\u00c9S. \u00bfQu\u00e9?<\/p>\n<p>BR\u00cdGIDA.\u00a0 Silencio!<\/p>\n<p>IN\u00c9S. Me estremeces.<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00bfO\u00eds, do\u00f1a In\u00e9s, tocar?<\/p>\n<p>IN\u00c9S. S\u00ed, lo mismo que otras veces<br \/>\nlas \u00e1nimas oigo dar.<\/p>\n<p>BR\u00cdGIDA.\u00a0 Pues no habl\u00e9is de \u00e9l.<\/p>\n<p>IN\u00c9S. \u00a1Cielo santo!<br \/>\n\u00bfDe qui\u00e9n?<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00bfDe qui\u00e9n ha de ser?<br \/>\nDe ese don Juan que am\u00e1is<br \/>\ntanto,<br \/>\nPorque puede aparecer.<\/p>\n<p>IN\u00c9S.<\/p>\n<p>\u00a1Me amedrentas! \u00bfPuede ese<br \/>\nhombre<br \/>\nllegar hasta aqu\u00ed?<\/p>\n<p>BR\u00cdGIDA.\u00a0 Quiz\u00e1.<br \/>\nPorque el eco de su nombre<br \/>\ntal vez llega adonde est\u00e1.<\/p>\n<p>IN\u00c9S. \u00a1Cielos! \u00bfY podr\u00e1?&#8230;<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00bfQui\u00e9n sabe?<\/p>\n<p>IN\u00c9S. \u00bfEs un esp\u00edritu, pues?<\/p>\n<p>BR\u00cdGIDA.\u00a0 No, mas si tiene una llave&#8230;<\/p>\n<p>IN\u00c9S. \u00a1Dios!<\/p>\n<p>BR\u00cdGIDA.\u00a0 Silencio, do\u00f1a In\u00e9s:<br \/>\n\u00bfno o\u00eds pasos?<\/p>\n<p>IN\u00c9S. \u00a1Ay! Ahora<br \/>\nnada oigo.<\/p>\n<p>BR\u00cdGIDA.\u00a0 Las nueve dan.<br \/>\nSuben&#8230;,se acercan&#8230; Se\u00f1ora&#8230;<br \/>\nYa est\u00e1 aqu\u00ed.<\/p>\n<p>IN\u00c9S. \u00bfQui\u00e9n?<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00c9l.<\/p>\n<p>IN\u00c9S. \u00a1Don Juan!<\/p>\n<p>Escena IV<\/p>\n<p>DO\u00d1A IN\u00c9S, DON JUAN, BR\u00cdGIDA<\/p>\n<p>IN\u00c9S. \u00bfQu\u00e9 es esto? Sue\u00f1o&#8230;, deliro.<\/p>\n<p>JUAN. \u00a1In\u00e9s de mi coraz\u00f3n!<\/p>\n<p>IN\u00c9S. \u00bfEs realidad lo que miro,<br \/>\no es una fascinaci\u00f3n&#8230;?<br \/>\nTenedme&#8230;. apenas respiro&#8230;<br \/>\nSombra&#8230;. huye por compasi\u00f3n.<br \/>\n\u00a1Ay de m\u00ed&#8230;!<\/p>\n<p>(Desm\u00e1yase DO\u00d1A IN\u00c9S y DON JUAN la sostiene. La carta de DON JUAN queda en el suelo abandonada por DO\u00d1A IN\u00c9S al desmayarse.)<\/p>\n<p>BR\u00cdGIDA.\u00a0 La ha fascinado<br \/>\nvuestra repentina entrada,<br \/>\ny el pavor la ha trastornado.<\/p>\n<p>JUAN. Mejor: as\u00ed nos ha ahorrado<br \/>\nla mitad de la jornada.<br \/>\n\u00a1Ea! No desperdiciemos<br \/>\nel tiempo aqu\u00ed en contemplarla,<br \/>\nsi perdernos no queremos.<br \/>\nEn los brazos a tomarla<br \/>\nvoy, y cuanto antes, ganemos<br \/>\nese claustro solitario.<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Oh, vais a sacarla as\u00ed!<\/p>\n<p>JUAN. Necia, \u00bfpiensas que romp\u00ed<br \/>\nla clausura, temerario,<br \/>\npara dej\u00e1rmela aqu\u00ed?<br \/>\nMi gente abajo me espera:<br \/>\ns\u00edgueme.<\/p>\n<p>BR\u00cdGIDA.\u00a0 \u00a1Sin alma estoy!<br \/>\n\u00a1Ay! Este hombre es una fiera;<br \/>\nnada le ataja ni altera&#8230;<br \/>\nS\u00ed, s\u00ed; a su sombra me voy.<\/p>\n<p>Escena V<\/p>\n<p>LA ABADESA<\/p>\n<p>Jurara que hab\u00eda o\u00eddo<br \/>\npor estos claustros andar:<br \/>\nhoy a do\u00f1a In\u00e9s velar<br \/>\nalgo m\u00e1s la he permitido.<br \/>\nY me temo&#8230; Mas no est\u00e1n<br \/>\naqu\u00ed. \u00bfQu\u00e9 pudo ocurrir<br \/>\na las dos, para salir<br \/>\nde la celda? \u00bfD\u00f3nde ir\u00e1n?<br \/>\n\u00a1Hola! Yo las atar\u00e9<br \/>\ncorto para que no vuelvan<br \/>\na enredar, y me revuelvan<br \/>\na las novicias&#8230;, s\u00ed a fe.<br \/>\nMas siento por all\u00e1 fuera<br \/>\npasos. \u00bfQui\u00e9n es?<\/p>\n<p>Escena VI<\/p>\n<p>LA ABADESA, LA TORNERA<\/p>\n<p>TORNERA.\u00a0 Yo, se\u00f1ora.<\/p>\n<p>ABADESA \u00a1Vos en el claustro a esta hora!<br \/>\n\u00bfQu\u00e9 es esto, hermana tornera?<\/p>\n<p>TORNERA.\u00a0 Madre abadesa, os buscaba.<\/p>\n<p>ABADESA \u00bfQu\u00e9 hay? Decid.<\/p>\n<p>TORNERA. Un noble<br \/>\nanciano<br \/>\nquiere hablaros.<\/p>\n<p>ABADESA Es en vano.<\/p>\n<p>TORNERA.\u00a0 Dice que es de Calatrava<br \/>\ncaballero; que sus fueros<br \/>\nle autorizan a este paso,<br \/>\ny que la urgencia del caso<br \/>\nle obliga al instante a veros.<\/p>\n<p>ABADESA \u00bfDijo su nombre?<\/p>\n<p>TORNERA.\u00a0 El se\u00f1or<br \/>\ndon Gonzalo de Ulloa.<\/p>\n<p>ABADESA \u00bfQu\u00e9<br \/>\npuede querer&#8230;? Abrale,<br \/>\nhermana: es comendador<br \/>\nde la Orden, y derecho<br \/>\ntiene en el claustro de entrada.<\/p>\n<p>Escena VII<\/p>\n<p>LA ABADESA. \u00bfA una hora tan avanzada<br \/>\nvenir as\u00ed&#8230;? No sospecho<br \/>\nqu\u00e9 pueda ser&#8230;, mas me place,<br \/>\npues no hallando a su hija aqu\u00ed,<br \/>\nla reprender\u00e1, y as\u00ed<br \/>\nmirar\u00e1 otra vez lo que hace.<\/p>\n<p>Escena VIII<\/p>\n<p>LA ABADESA, DON GONZALO, LA TORNERA, a la puerta<\/p>\n<p>DON GONZALO.\u00a0 Perdonad, madre abadesa,<br \/>\nque en hora tal os moleste;<br \/>\nmas para m\u00ed, asunto es \u00e9ste<br \/>\nque honra y vida me interesa.<\/p>\n<p>ABADESA \u00a1Jes\u00fas!<\/p>\n<p>DON GONZALO.\u00a0 O\u00edd.<\/p>\n<p>ABADESA Hablad, pues.<\/p>\n<p>DON GONZALO.\u00a0 Yo guard\u00e9 hasta hoy un tesoro<br \/>\nde m\u00e1s quilates que el oro,<br \/>\ny ese tesoro es mi In\u00e9s.<\/p>\n<p>ABADESA A prop\u00f3sito.<\/p>\n<p>DON GONZALO.\u00a0 Escuchad.<br \/>\nSe me acaba de decir<br \/>\nque han visto a su due\u00f1a ir<br \/>\nha poco por la ciudad<br \/>\nhablando con un criado<br \/>\nque un don Juan, de tal<br \/>\nrenombre,<br \/>\nque no hay en la tierra otro<br \/>\nhombre<br \/>\ntan audaz y tan malvado.<br \/>\nEn tiempo atr\u00e1s se pens\u00f3<br \/>\ncon \u00e9l a mi hija casar,<br \/>\ny hoy, que se la fui a negar,<br \/>\nrob\u00e1rmela me jur\u00f3.<br \/>\nQue por el torpe doncel<br \/>\nganada la due\u00f1a est\u00e1,<br \/>\nno puedo dudarlo ya:<br \/>\ndebo, pues, guardarme de \u00e9l.<br \/>\nY un d\u00eda, una hora quiz\u00e1s<br \/>\nde imprevisi\u00f3n, le bastara<br \/>\npara que mi honor manchara<br \/>\na ese hijo de Satan\u00e1s.<br \/>\nHe aqu\u00ed mi inquietud cu\u00e1l es:<br \/>\npor la due\u00f1a, en conclusi\u00f3n,<br \/>\nvengo: vos la profesi\u00f3n<br \/>\nabreviad de do\u00f1a In\u00e9s.<\/p>\n<p>ABADESA Sois padre, y es vuestro af\u00e1n<br \/>\nmuy justo, comendador;<br \/>\nmas ved que ofende a mi honor.<\/p>\n<p>DON GONZALO.\u00a0 No sab\u00e9is qui\u00e9n es don Juan.<\/p>\n<p>ABADESA Aunque le pint\u00e1is tan malo,<br \/>\nyo os puedo decir de m\u00ed,<br \/>\nque mientras In\u00e9s est\u00e9 aqu\u00ed,<br \/>\nsegura est\u00e1, don Gonzalo.<\/p>\n<p>DON GONZALO.\u00a0 Lo creo; mas las razones<br \/>\nabreviemos: entregadme<br \/>\na esa due\u00f1a, y perdonadme<br \/>\nmis mundanas opiniones.<br \/>\nSi vos de vuestra virtud<br \/>\nme respond\u00e9is, yo me fundo<br \/>\nen que conozco del mundo<br \/>\nla insensata juventud.<\/p>\n<p>ABADESA Se har\u00e1 como lo exig\u00eds.<br \/>\nHermana tornera, id, pues,<br \/>\na buscar a do\u00f1a In\u00e9s<br \/>\ny a su due\u00f1a. (Vase LA TORNERA.)<\/p>\n<p>DON GONZALO.\u00a0 \u00bfQu\u00e9 dec\u00eds,<br \/>\nse\u00f1ora? O traici\u00f3n me ha hecho<br \/>\nmi memoria, o yo s\u00e9 bien<br \/>\nque \u00e9sta es hora de que est\u00e9n<br \/>\nambas a dos en su lecho.<\/p>\n<p>ABADESA Ha un punto sent\u00ed a las dos<br \/>\nsalir de aqu\u00ed, no s\u00e9 a qu\u00e9.<\/p>\n<p>DON GONZALO.\u00a0 \u00a1Ay! Por qu\u00e9 tiemblo no s\u00e9.<br \/>\n\u00a1Mas qu\u00e9 veo, santo Dios!<br \/>\nUn papel&#8230;, me lo dec\u00eda<br \/>\na voces mi mismo af\u00e1n.<br \/>\n(Leyendo.)<br \/>\n\u00abDo\u00f1aIn\u00e9s del alma m\u00eda&#8230;\u00bb<br \/>\nY la firma de don Juan.<br \/>\nVed&#8230;, ved&#8230;, esa prueba escrita.<br \/>\nLeed ah\u00ed&#8230; \u00a1Oh! Mientras que<br \/>\nvos<br \/>\npor ella rog\u00e1is a Dios<br \/>\nviene el diablo y os la quita.<\/p>\n<p>Escena IX<\/p>\n<p>LA ABADESA, DON GONZALO, LA TORNERA<\/p>\n<p>TORNERA.\u00a0 Se\u00f1ora&#8230;<\/p>\n<p>ABADESA \u00bfQu\u00e9 es?<\/p>\n<p>TORNERA.\u00a0 Vengo muerta.<\/p>\n<p>DON GONZALO.\u00a0 Concluid.<\/p>\n<p>TORNERA.\u00a0 No acierto a hablar&#8230;<br \/>\nHe visto a un hombre saltar<br \/>\npor las tapias de la huerta.<\/p>\n<p>DON GONZALO.\u00a0 \u00bfVeis? Corramos: \u00a1ay de m\u00ed!<\/p>\n<p>ABADESA \u00bfD\u00f3nde vais, comendador?<\/p>\n<p>DON GONZALO.\u00a0 \u00a1Imb\u00e9cil!, tras de mi honor,<br \/>\nque os roban a vos de aqu\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRIMERA PARTE ACTO TERCERO Profanaci\u00f3n Celda de DO\u00d1A IN\u00c9S. Puerta en el fondo y a la izquierda Escena primera DO\u00d1A IN\u00c9S, la ABADESA IN\u00c9S. \u00bfConque me hab\u00e9is entendido? ABADESA S\u00ed, se\u00f1ora. IN\u00c9S. Est\u00e1 muy bien; ABADESA la voluntad decisiva de vuestro padre tal es. Sois joven, c\u00e1ndida y buena; vivido\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[5,1109],"tags":[1010,1016,1012,1140,1015,1145,1057,1025,2743,1020],"class_list":["post-1264","post","type-post","status-publish","format-standard","hentry","category-literatura","category-textos-literarios","tag-amor","tag-arte","tag-ave","tag-escena","tag-flor","tag-libro","tag-pensamiento","tag-rosa","tag-tenorio","tag-violencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Don Juan Tenorio&quot; (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"&quot;Don Juan Tenorio&quot; (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Don Juan Tenorio&quot; (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"&quot;Don Juan Tenorio&quot; (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-22T16:17:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-22T01:12:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/don-juan-tenorio-i-iii-jose-zorrilla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/don-juan-tenorio-i-iii-jose-zorrilla\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"\u00abDon Juan Tenorio\u00bb (I-III) [Jos\u00e9 Zorrilla]\",\"datePublished\":\"2011-02-22T16:17:13+00:00\",\"dateModified\":\"2018-12-22T01:12:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/don-juan-tenorio-i-iii-jose-zorrilla\\\/\"},\"wordCount\":2949,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"keywords\":[\"amor\",\"arte\",\"ave\",\"escena\",\"flor\",\"libro\",\"pensamiento\",\"rosa\",\"tenorio\",\"violencia\"],\"articleSection\":[\"Literatura \\\/ Po\u00e9tica\",\"Textos literarios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/don-juan-tenorio-i-iii-jose-zorrilla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/don-juan-tenorio-i-iii-jose-zorrilla\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/don-juan-tenorio-i-iii-jose-zorrilla\\\/\",\"name\":\"\\\"Don Juan Tenorio\\\" (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"datePublished\":\"2011-02-22T16:17:13+00:00\",\"dateModified\":\"2018-12-22T01:12:33+00:00\",\"description\":\"\\\"Don Juan Tenorio\\\" (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/don-juan-tenorio-i-iii-jose-zorrilla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/don-juan-tenorio-i-iii-jose-zorrilla\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/don-juan-tenorio-i-iii-jose-zorrilla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abDon Juan Tenorio\u00bb (I-III) [Jos\u00e9 Zorrilla]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Don Juan Tenorio\" (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa","description":"\"Don Juan Tenorio\" (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/","og_locale":"es_ES","og_type":"article","og_title":"\"Don Juan Tenorio\" (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa","og_description":"\"Don Juan Tenorio\" (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2011-02-22T16:17:13+00:00","article_modified_time":"2018-12-22T01:12:33+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"\u00abDon Juan Tenorio\u00bb (I-III) [Jos\u00e9 Zorrilla]","datePublished":"2011-02-22T16:17:13+00:00","dateModified":"2018-12-22T01:12:33+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/"},"wordCount":2949,"commentCount":0,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"keywords":["amor","arte","ave","escena","flor","libro","pensamiento","rosa","tenorio","violencia"],"articleSection":["Literatura \/ Po\u00e9tica","Textos literarios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/","url":"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/","name":"\"Don Juan Tenorio\" (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"datePublished":"2011-02-22T16:17:13+00:00","dateModified":"2018-12-22T01:12:33+00:00","description":"\"Don Juan Tenorio\" (I-III) [Jos\u00e9 Zorrilla] - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/don-juan-tenorio-i-iii-jose-zorrilla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"\u00abDon Juan Tenorio\u00bb (I-III) [Jos\u00e9 Zorrilla]"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":0,"uagb_excerpt":"PRIMERA PARTE ACTO TERCERO Profanaci\u00f3n Celda de DO\u00d1A IN\u00c9S. Puerta en el fondo y a la izquierda Escena primera DO\u00d1A IN\u00c9S, la ABADESA IN\u00c9S. \u00bfConque me hab\u00e9is entendido? ABADESA S\u00ed, se\u00f1ora. IN\u00c9S. Est\u00e1 muy bien; ABADESA la voluntad decisiva de vuestro padre tal es. Sois joven, c\u00e1ndida y buena; vivido\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/1264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=1264"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/1264\/revisions"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=1264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=1264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=1264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}