{"id":1234,"date":"2011-02-22T12:36:43","date_gmt":"2011-02-22T10:36:43","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=1234"},"modified":"2018-12-22T03:13:00","modified_gmt":"2018-12-22T01:13:00","slug":"cartas-de-relacion-de-hernan-cortes-iii-ii","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/","title":{"rendered":"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II)"},"content":{"rendered":"<p>TERCERA RELACI\u00d3N &#8211; Parte 2<\/p>\n<p>Y yo me part\u00ed y a las diez del d\u00eda llegamos a Guastepeque, de que arriba he fecho menci\u00f3n, y en la casa de una huerta del se\u00f1or de all\u00ed nos aposentamos todos, la cual huerta es la mayor y m\u00e1s fermosa y fresca que nunca se vio, porque tiene dos leguas de circuito y por medio della va una muy gentil ribera de agua, y de trecho a trecho, cantidad de dos tiros de ballesta, hay aposentamientos y jardines muy frescos e infinitos \u00e1rboles de diversas frutas y muchas yerbas y flores olorosas, que cierto es cosa de admiraci\u00f3n ver la gentileza y grandeza de toda esta huerta. Y aquel d\u00eda reposamos en ella, donde los naturales nos hicieron el placer y servicio que pudieron. Y otro d\u00eda nos partimos, y a las ocho horas del d\u00eda llegamos a una buena poblaci\u00f3n que se dice Yautepeque, en la cual estaban esper\u00e1ndonos mucha gente de guerra de los enemigos. Y como llegamos, paresci\u00f3 que quisieron hacernos alguna se\u00f1al de paz o por el temor que tuvieron o por nos enga\u00f1ar, pero luego incontinente sin m\u00e1s acuerdo comenzaron a huir desamparando su pueblo. Y yo no cur\u00e9 de deternerme en \u00e9l, y con los treinta de caballo dimos tras ellos bien dos leguas fasta los encerrar en otro pueblo que se dice Gilutepeque, donde alanceamos y matamos muchos. Y en este pueblo hallamos la gente muy descuidada porque llegamos primero que sus esp\u00edas, y murieron algunos y tom\u00e1ronse muchas mujeres y mochachos, y todos los dem\u00e1s huyeron. Y yo estuve dos d\u00edas en este pueblo creyendo que el se\u00f1or d\u00e9l se viniera a dar por vasallo de Vuestra Majestad, y como nunca vino, cuando part\u00ed fice poner fuego al pueblo. Y antes que d\u00e9l saliese vinieron ciertas personas del pueblo antes, que se dice Yactepeque, y rog\u00e1ronme que les perdonase y que ellos se quer\u00edan dar por vasallos de Vuestra Majestad. Yo los resceb\u00ed de buena voluntad porque en ellos se hab\u00edan hecho ya buen castigo. Aquel d\u00eda que me part\u00ed a las nueve del d\u00eda llegu\u00e9 a vista de un pueblo muy fuerte que se llama Coadnabaced, y dentro d\u00e9l hab\u00eda mucha gente de guerra y era tan fuerte el pueblo y cercado de tantos cerros y barrancas que algunas hab\u00eda de diez estados de hondura. Y no pod\u00eda entrar ninguna gente de caballo salvo por dos partes y \u00e9stas entonces no las sab\u00edamos, y aun para entrar por aqu\u00e9llas hab\u00edamos de rodear m\u00e1s de legua y media. Y tambi\u00e9n se pod\u00eda entrar por puentes de madera, pero ten\u00edanlas alzadas y estaban tan fuertes y tan a su salvo que aunque fu\u00e9ramos diez veces m\u00e1s no nos tuvieran en nada. Y lleg\u00e1ndonos hacia ellos, tir\u00e1bannos a su placer muchas varas y flechas y piedras. Y estando as\u00ed muy revueltos con nosotros, un indio de Tascaltecal pas\u00f3 de tal manera que no le vieron por un paso muy peligroso, y como los enemigos le vieron ans\u00ed de s\u00fapito creyeron que los espa\u00f1oles les entraban por all\u00ed. Y as\u00ed, ciegos y espantados, comienzan a ponerse en huida y el indio tras ellos. Y tres o cuatro criados m\u00edos y otros dos de una capitan\u00eda, como vieron pasar al indio, sigui\u00e9ronle y pasaron de la otra parte, y yo con los de caballo comenc\u00e9 a guiar hacia la sierra para buscar entrada al pueblo. Y los indios nuestros enemigos no hac\u00edan sino tirarnos varas y flechas porque entre ellos y nosotros no hab\u00eda m\u00e1s de una barranca como cava, y como esta ban embebecidos en pelear con nosotros y \u00e9stos no hab\u00edan visto los cinco espa\u00f1oles, llegan de improviso por las espaldas y comienzan a darles de cochilladas. Y como los tomaron de tan sobresalto y sin pensamiento que por las espaldas se les hab\u00eda de facer alguna ofensa, porque ellos no sab\u00edan que los suyos hab\u00edan desamparado el paso por donde los espa\u00f1oles y el indio hab\u00edan pasado, estaban espantados y no osaban pelear, y los espa\u00f1oles mataban en ellos. Y desque cayeron en la burla comenzaron a huir, y ya nuestra gente de pie estaba dentro en el pueblo y le comenzaban a quemar y los enemigos todos a le desamparar. Y as\u00ed huyendo se acogieron a la sierra, aunque murieron muchos dellos y los de caballo siguieron y mataron muchos. Y despu\u00e9s que hallamos por d\u00f3nde entrar al pueblo, que ser\u00eda mediod\u00eda, aposent\u00e1mosnos en las casas de una huerta porque lo hallamos ya casi quemado todo. Y ya bien tarde, el se\u00f1or d\u00e9l y algunos otros prencipales, viendo que en cosa tan fuerte como su pueblo no se hab\u00edan podido defender, temiendo que all\u00e1 en la sierra los hab\u00edamos de ir a matar, acordaron de se venir a ofrescer por vasallos de Vuestra Majestad despu\u00e9s de les haber quemado, y yo los resceb\u00ed por tales y prometi\u00e9ronme de ah\u00ed adelante ser siempre nuestros amigos. Estos indios y los otros que ven\u00edan a se dar por vasallos de Vuestra Majestad despu\u00e9s de los haber quemado y destruido sus casas y haciendas nos dijeron que la causa por que ven\u00edan tarde a nuestra amistad era porque pensaban que satisfac\u00edan sus culpas con consentir primero hacerles da\u00f1o, creyendo que hecho, no tern\u00edamos despu\u00e9s tanto enojo dellos. Aquella noche dormimos en aquel pueblo, y por la ma\u00f1ana seguimos nuestro camino por una tierra de pinares despoblada y sin ninguna agua, la cual y un puerto pasamos con grand\u00edsimo trabajo y sin beber, tanto que muchos de los indios que iban con nosotros perescieron de sed. Y a siete leguas de aquel pueblo en unas estancias paramos aquella noche. Y en amanesciendo tomamos nuestro camino y llegamos a vista de una gentil cibdad que se dice Suchimilco, que est\u00e1 edificada en la la guna dulce. Y como los naturales della estaban avisados de nuestra venida ten\u00edan hechas muchas albarradas y acequias, y alzadas las puentes de todas las entradas de la cibdad, la cual est\u00e1 de Timixtit\u00e1n tres o cuatro leguas, y estaba dentro mucha y muy lucida gente y muy determinados de se defender o morir. Y llegados y recogida toda la gente y puesta en mucha orden y concierto, yo me ape\u00e9 de mi caballo y segu\u00ed con ciertos peones hacia una albarrada que ten\u00edan hecha, y detr\u00e1s estaba infinita gente de guerra. Y como comenzamos a combatir el albarrada y los ballesteros y escopeteros les hac\u00edan da\u00f1o, desampar\u00e1ronla, y los espa\u00f1oles se echaron al agua y pasaron adelante por donde hallaban tierra firme, y en media hora que peleamos con ellos les ganamos la prencipal parte de la cibdad. Y retra\u00eddos los contrarios, por las calles del agua y en sus canoas pelearon hasta la noche. Y unos mov\u00edan paces y otros por eso no dejaban de pelear, y movi\u00e9ronlas tantas veces sin ponerlas por obra hasta que ca\u00edmos en la cuenta, porque ellos lo hac\u00edan para dos efetos: el uno, para alzar sus haciendas en tanto que nos deten\u00edan con la paz; el otro, por dilatar tiempo en tanto que les ven\u00eda socorro de M\u00e9xico y Temixtit\u00e1n. Y este d\u00eda nos mataron dos espa\u00f1oles porque se desmandaron de los otros a robar y vi\u00e9ronse con tanta nescesidad que nunca pudieron ser socorridos. Y en la tarde pensaron los enemigos c\u00f3mo nos podr\u00edan atajar de manera que no pudi\u00e9semos salir de su cibdad con las vidas y juntos mucha copia dellos, determinaron de venir por la parte que nosotros hab\u00edamos entrado. Y como los vimos venir tan de s\u00fapito, espant\u00e1monos de ver su ardid y presteza, y seis de caballo y yo que est\u00e1bamos m\u00e1s a punto que los otros arremetimos por medio dellos. Y ellos de temor de los caballos pusi\u00e9ronse en huida, y ans\u00ed salimos de la cibdad tras ellos matando muchos, aunque nos vimos en harto aprieto, porque como eran tan valientes hombres, muchos dellos osaban esperar a los de caballo con sus espadas y rodelas. Y como and\u00e1bamos revueltos con ellos y hab\u00eda muy grand pieza, el caballo en que yo iba se dej\u00f3 caer de cansado. Y como algunos de los contrarios me vieron a pie revolvieron contra m\u00ed, y yo con la lanza empec\u00e9me a defender dellos. Y un indio de los de Tascaltecal, como me vio en necesidad lleg\u00f3se a me ayudar, y \u00e9l y un mozo m\u00edo que luego lleg\u00f3 levantamos el caballo. Y ya en esto llegaron los espa\u00f1oles y los enemigos desampararon todo el campo, y yo con los otros de caballo que entonces hab\u00edan llegado, como est\u00e1bamos muy cansados nos volvimos a la cibdad. Y aunque era ya casi noche y saz\u00f3n de reposar mand\u00e9 que todas las puentes alzadas por do iba el agua se cegasen con piedra y adobes que hab\u00eda all\u00ed porque los de caballo pudiesen entrar y salir sin estorbo ninguno en la cibdad, y no me part\u00ed de all\u00ed fasta que todos aquellos pasos malos quedaron muy bien adreszados. Y con mucho aviso y recaudo de velas pasamos aquella noche. Otro d\u00eda, como todos los naturales de la provincia de M\u00e9xico y Temixtit\u00e1n sab\u00edan ya que est\u00e1bamos en Suchimilco, acordaron de venir con grand poder por el agua y por la tierra a nos cercar, porque cre\u00edan que no pod\u00edamos ya escapar de sus manos. Y yo me sub\u00ed a una torre de sus \u00eddolos para ver c\u00f3mo ven\u00eda la gente y por d\u00f3nde nos pod\u00edan acometer, para proveer en ello lo que nos conveniese, y ya que en todo hab\u00eda dado orden llega por el agua una muy grande flota de canoas, que creo que pasaban de dos mill, y en ellas ven\u00edan m\u00e1s de doce mill hombres de guerra. Y por la tierra llega tanta multitud de gente que todos los campos cubr\u00edan, y los capitanes dellos que ven\u00edan delante tra\u00edan sus espadas de las nuestras en las manos, y apellidando sus provincias dec\u00edan: \u00a1M\u00e9xico, M\u00e9xico! \u00a1Temixtit\u00e1n, Temixtit\u00e1n!\u00bb, y dec\u00edannos muchas enjurias y amenaz\u00e1ndonos que nos hab\u00edan de matar con aquellas espadas que nos habian tomado la otra vez en la cibdad de Temixtit\u00e1n. Y como ya hab\u00eda prove\u00eddo ad\u00f3nde hab\u00eda de acudir cada capit\u00e1n, y porque hacia la tierra firme hab\u00eda mucha copia de enemigos, sal\u00ed a ellos con veinte de caballo y con quinientos indios de Tascaltecal y repart\u00edmonos en tres partes. Y mand\u00e9les que desque hobiesen rompido, que se recogiesen al pie de un cerro que estaba media legua de all\u00ed, porque tambi\u00e9n hab\u00eda all\u00ed mucha gente de los enemigos. Y como nos dividimos cada escuadr\u00f3n sigui\u00f3 a los enemigos por su cabo, y despu\u00e9s de desbaratados y alanceados y muertos muchos, recog\u00edmonos al pie del cerro. Y yo mand\u00e9 a ciertos peones criados m\u00edos que me hab\u00edan servido y eran bien sueltos que por lo m\u00e1s agro del cerro trabajasen de lo subir, y que yo con los de caballo rodear\u00eda por detr\u00e1s, que era m\u00e1s llano, y los tomar\u00edamos en medio. Y ans\u00ed fue, que como los enemigos vieron que los espa\u00f1oles les subian por el cerro, volvieron las espaldas, creyendo que hu\u00edan a su salvo, y topan con nosotros, que ser\u00edamos quince de caballo. Y comenzamos a dar en ellos y los de Tascaltecal ansimesmo, por manera que en poco espacio murieron m\u00e1s de quinientos de los enemigos, y todos los otros se salvaron y fuyeron a las sierras. Y los otros seis de caballo acertaron a ir por un camino muy ancho y muy llano alanceando en los enemigos, y a media legua de Suchimilco dan sobre un escuadr\u00f3n de gente muy lucida que ven\u00eda en su socorro, y desbarat\u00e1ronlos y alancearon algunos. Y ya que nos hobimos juntado todos los de caballo, que ser\u00edan las diez del d\u00eda, volvimos a Suchimilco. Y a la entrada hall\u00e9 muchos espa\u00f1oles que deseaban mucho nuestra venida y saber lo que nos hab\u00eda acontecido, y cont\u00e1ronme c\u00f3mo se hab\u00edan visto en mucho aprieto y hab\u00edan trabajado todo lo posible por echar fuera los enemigos, de los cuales hab\u00edan muerto mucha cantidad, y di\u00e9ronme dos espadas de las nuestras que les hab\u00edan tomado y dij\u00e9ronme c\u00f3mo los ballesteros no ten\u00edan saetas ni almac\u00e9n alguno. Y estando en esto, antes que nos ape\u00e1semos asomaron por una calzada muy ancha un grand escuadr\u00f3n de los enemigos con muy grandes alaridos y de presto arremetimos a ellos, y como de la una parte y de la otra de la calzada era todo agua lanz\u00e1ronse en ella, y as\u00ed los desbaratamos. Y recogida la gente, volvimos a la cibdad bien cansados y mand\u00e9la quemar toda expceto aquello donde est\u00e1bamos aposentados. Y as\u00ed estuvimos en esta cibdad tres d\u00edas que en ninguno dellos dejamos de pelear, y al cabo, dej\u00e1ndola toda quemada y asolada, nos partimos. Y cierto era mucho para ver, porque ten\u00eda muchas casas y torres de sus \u00eddolos de cal y canto. Y por no me alargar dejo de particularizar otras cosas bien notables desta cibdad. El d\u00eda que me part\u00ed me sal\u00ed fuera a una plaza que est\u00e1 en la tierra firme junto a esta cibdad que es donde los naturales hacen sus mercados. Y estaba dando orden c\u00f3mo diez de caballo fuesen en la delantera y otros diez en medio de la gente de pie y yo con otros diez en la rezaga, y los de Suchimilco, como vieron que nos encomenz\u00e1bamos a ir, creyendo que de temor suyo era, llegan por nuestras espaldas con mucha grita. Y los diez de caballo y yo volvimos a ellos y segu\u00edmoslos hasta meterlos en el agua en tal manera que no curaron m\u00e1s de nosotros, y as\u00ed nos volvimos nuestro camino. Y a las diez del d\u00eda llegamos a la cibdad de Cuyoacan, que est\u00e1 de Suchimilco dos leguas, y de las cibdades de Temixtit\u00e1n y Culuacan y Uchilubuzco e Yztapalapa y Cuytaguapa y Mizqueque, que todas est\u00e1n en el agua &#8211; la m\u00e1s lejos d\u00e9stas est\u00e1 una legua y media &#8211; , y hall\u00e1mosla despoblada. Y aposent\u00e1mosnos en la casa del se\u00f1or y aqu\u00ed estuvimos el d\u00eda que llegamos y otro. Y porque en siendo acabados los bergantines hab\u00eda de poner cerco a Temixtit\u00e1n, quise primero ver la disposici\u00f3n desta cibdad y las entradas y salidas y por d\u00f3nde los espa\u00f1oles pod\u00edan ofender o ser ofendidos, y otro d\u00eda que llegu\u00e9 tom\u00e9 cinco de caballo y ducientos peones y fuime hasta la laguna, que estaba muy cerca, por una calzada que entra a la cibdad de Temixtit\u00e1n. Y vimos tanto n\u00famero de canoas por el agua y en ellas gente de guerra que era infinito, y llegamos a una albarrada que ten\u00edan fecha en la calzada y los peones comenz\u00e1ronla a combatir. Y aunque fue muy recia y hobo mucho resistencia e hirieron diez espa\u00f1oles, al fin se la ganaron y mataron muchos de los enemigos, aunque los ballesteros y escopeteros quedaron sin p\u00f3lvora y sin saetas. Y dende alli vimos c\u00f3mo iba la calzada derecha por el agua hasta dar en Temixtit\u00e1n bien legua y media, y ella y la otra que va a dar a Yztapalapa llenas de gente sin cuento. Y como yo hobe considerado bien lo que conven\u00eda verse, porque aqu\u00ed en esta cibdad hab\u00eda de estar una guarnici\u00f3n de gente de pie y de caballo, hice recoger los nuestros, y as\u00ed nos volvimos quemando las casas y torres de sus \u00eddolos. Y otro d\u00eda nos partimos desta cibdad a la de Tacuba, que est\u00e1 dos leguas, y llegamos a las nueve del d\u00eda alanceando por unas partes y por otras porque los enemigos sal\u00edan de la laguna por dar en los indios que nos tra\u00edan el fardaje, y hall\u00e1banse burlados y ans\u00ed nos dejaban ir en paz. Y porque, como he dicho, mi intenci\u00f3n prencipal hab\u00eda sido procurar de dar vuelta a todas las lagunas por calar y saber mejor la tierra y tambi\u00e9n por socorrer aquellos nuestros amigos, no cur\u00e9 de pararme en Tacuba. Y como los de Temixtit\u00e1n &#8211; que est\u00e1 all\u00ed muy cerca, que casi se estiende la cibdad tanto que llega cerca de la tierra firme de Tacuba &#8211; como vieron que pas\u00e1bamos adelante cobraron mucho esfuerzo, y con gran denuedo acometieron a dar en medio de nuestro fardaje. Y como los de caballo ven\u00edamos bien repartidos y todo por all\u00ed era llano aprovech\u00e1bamosnos bien de los contrarios sin rescebir los nuestros ning\u00fand peligro, y como corr\u00edamos a unas partes y a otras y unos mancebos cr\u00edados m\u00edos me sigu\u00edan algunas veces, aquella vez dos d\u00e9llos no lo hicieron y hall\u00e1ronse en parte donde los enemigos los llevaron, donde creemos que les dar\u00edan muy cruel muerte como acostumbran, de que sabe Dios el sentimiento que hobe, ans\u00ed por ser cristianos como porque eran valientes hombres y le hab\u00edan servido muy bien en esta guerra a Vuestra Majestad. Y salidos desta cibdad, comenzamos a seguir nuestro camino por entre otras poblaciones cerca de all\u00ed y alcanzamos a la gente. Y all\u00ed supe entonces c\u00f3mo los indios hab\u00edan llevado aquellos mancebos, y por vengar su muerte y porque los enemigos nos segu\u00edan con el mayor orgullo de mundo, yo con veinte de caballo me puse detr\u00e1s de unas casas en celada. Y como los indios v\u00edan a los otros diez con toda la gente y fardaje ir adelante, no hac\u00edan sino seguillos por un camino adelante que era muy ancho y muy llano, no se temiendo de cosa ninguna. Y como vimos pasar ya algunos, yo apellid\u00e9 en nombre del ap\u00f3stol Santiago y dimos en ellos muy reciamente, y antes que se nos metiesen en las acequias que hab\u00eda cerca hab\u00edamos muerto dellos m\u00e1s de cient prencipales y muy lucidos, y no curaron de m\u00e1s nos seguir. Este d\u00eda fuimos a dormir dos leguas adelante a la cibdad de Coatinchan bien cansados y mojados, porque hab\u00eda llovido mucho aquella tarde, y hall\u00e1mosla despoblada. Y otro d\u00eda comenzamos de caminar alanceando de cuando en cuando a algunos indios que nos sal\u00edan a gritar, y fuemos a dormir a una poblaci\u00f3n que se dice Gilotepeque, y hall\u00e1mosla despoblada. Y otro d\u00eda llegamos a las doce horas del d\u00eda una cibdad que se dice Aculman, que es del se\u00f1or\u00edo de la cibdad de Tesuico, a donde fuemos aquella noche a dormir. Y fuemos de los espa\u00f1oles bien rescebidos y se holgaron con nuestra venida como a la salvaci\u00f3n, porque despu\u00e9s que yo me hab\u00eda partido dellos no hab\u00edan sabido de m\u00ed fasta aquel d\u00eda que llegamos, y hab\u00edan tenido muchos rebatos en la cibdad, y los naturales della les dec\u00edan cada d\u00eda que los de M\u00e9xico y Temixtit\u00e1n hab\u00edan de venir sobre ellos en tanto que yo por all\u00e1 andaba. Y as\u00ed se concluy\u00f3 con la ayuda de Dios esta jornada, y fue muy grand cosa y en que Vuestra Majestad rescibi\u00f3 mucho servicio por muchas causas que adelante se dir\u00e1n. Al tiempo que yo, Muy Poderoso e Invit\u00edsimo Se\u00f1or, estaba en la cibdad de Temixtit\u00e1n, luego a la primera vez que a ella vine, prove\u00ed, como en la otra relaci\u00f3n hice saber a Vuestra Majestad, que en dos o tres provincias aparejadas para ello se hiciesen para Vuestra Majestad ciertas casas de granjer\u00edas en que hobiese labranzas y otras cosas conforme a la calidad de aquellas provincias. Y a una dellas que se dice Chinanta invi\u00e9 para ello dos espa\u00f1oles. Y esta provincia no es subjeta a los naturales de Cul\u00faa, y en las otras que lo eran al tiempo que me daban guerra en la cibdad de Temixtit\u00e1n mataron a los que estaban en aquellas granjer\u00edas y tomaron lo que en ellas hab\u00eda, que era cosa muy gruesa seg\u00fand la manera de la tierra. Y destos espa\u00f1oles que estaban en Chinanta se pas\u00f3 casi un a\u00f1o que no supe dellos, porque como todas aquellas provincias estaban rebeladas ni ellos pod\u00edan saber de nosotros ni nosotros dellos. Y estos naturales de la provincia de Chinanta, como eran vasallos de Vuestra Majestad y enemigos de los de Cul\u00faa, dijeron a aquellos cristianos que en ninguna manera saliesen de su tierra, porque nos hab\u00edan dado los de Cul\u00faa mucha guerra y cre\u00edan que pocos o ningunos de nosotros hab\u00eda vivos, y as\u00ed se estuvieron estos dos espa\u00f1oles en aquella tierra. Y el uno dellos, que era mancebo y hombre para guerra, hici\u00e9ronle su capit\u00e1n, y en este tiempo sal\u00eda con ellos a dar guerra a sus enemigos y las m\u00e1s veces \u00e9l y los de Chinanta eran vencidores. Y como despu\u00e9s plugo a Dios que nosotros volvimos a nos rehacer y haber alguna vitoria contra los enemigos que nos hab\u00edan desbaratado y echado de Temixtit\u00e1n, \u00e9stos de Chinanta dijeron a aquellos cristianos que hab\u00edan sabido que en la provincia de Tepeaca hab\u00eda espa\u00f1oles, y que si quer\u00edan saber la verdad, que ellos quer\u00edan aventurar dos indios, aunque hab\u00edan de pasar por mucha tierra de sus enemigos, pero que andar\u00edan de noche y fuera del camino hasta llegar a Tepeaca. Y con aquellos dos indios el uno de aquellos espa\u00f1oles, que era el m\u00e1s hombre de bien, escr\u00edbi\u00f3 una carta cuyo tenor es el siguiente: Nobles se\u00f1ores: Dos o tres cartas he escr\u00edpto a vuestras mercedes, y no s\u00e9 si han aportado all\u00e1 o no. Y pues de aqu\u00e9llas no he habido respuesta, tambi\u00e9n pongo en duda habella d\u00e9sta. H\u00e1goos, se\u00f1ores, saber c\u00f3mo todos los naturales desta tierra de Cul\u00faa andan levantados y de guerra. Y muchas veces nos han acometido, pero siempre, loores a Nuestro Se\u00f1or, hemos sido vencidores. Y con los de Tuxtepeque y su parcialidad de Cul\u00faa cada d\u00eda tenemos guerra. Los que est\u00e1n en servicio de Sus Altezas y por sus vasallos son siete villas de los Tenez. Y yo y Nicol\u00e1s siempre estamos en Chinanta, que es la cabecera. Mucho quisiera saber ad\u00f3nde est\u00e1 el capit\u00e1n para le poder escrebir y hacer saber las cosas de ac\u00e1. Y si por ventura me escribi\u00e9redes de d\u00f3nde \u00e9l est\u00e1 e invi\u00e1redes veinte o treinta espa\u00f1oles, irme \u00eda con dos naturales prencipales de aqu\u00ed que tienen deseo de ver y fablar al capit\u00e1n. Y ser\u00eda bien que viniesen, porque como es tiempo agora de coger el cacao, est\u00f3rbanlo los de Cul\u00faa con las guerras. Nuestro Se\u00f1or guarde las nobles personas de vuestras mercedes como desean. &#8211; De Chinantla, a no s\u00e9 cu\u00e1ntos del mes de abr\u00edl de mill y quinientos y veinte y uno a\u00f1os. A servicio de vuestras mercedes. &#8211; Fernando de Barrientos. Y como los dos indios llegaron con esta carta a la dicha provincia de Tepeaca, el capit\u00e1n que yo all\u00ed hab\u00eda dejado con ciertos espa\u00f1oles invi\u00f3mela luego a Tesuico. Y rescebida, todos rescebimos muy grand placer, porque aunque siempre hab\u00edamos confiado en la amistad de los de Chinanta, ten\u00edamos pensamiento que si se confederaban con los de Cul\u00faa, que habr\u00edan muerto aquellos dos espa\u00f1oles. A los cuales yo luego escrib\u00ed d\u00e1ndoles cuenta de lo pasado y que tuviesen esperanza, que aunque estaban cercados de todas partes de los enemigos, presto, placiendo a Dios, se ver\u00edan libres y podr\u00edan salir y entrar seguros. Despu\u00e9s de haber dado vuelta a las lagunas, en que tomamos muchos avisos para poner el cerco a Temixtit\u00e1n por la tierra y por el agua, yo estuve en Tesuico fornesci\u00e9ndome lo mejor que pude de gente y de armas y dando priesa en que se acabasen los bergantines y una zanja que se hac\u00eda para los llevar por ella fasta la laguna, la cual zanja se comenz\u00f3 a facer luego que la ligaz\u00f3n y tablaz\u00f3n de los bergantines se trujeron en una acequia de agua que iba por cabe los aposentamientos fasta dar en la laguna. Y desde donde los bergantines se ligaron y la zanja se comenz\u00f3 a hacer hay bien media legua fasta la laguna, y en esta obra anduvieron cincuenta d\u00edas m\u00e1s de ocho mill personas cada d\u00eda de los naturales de la provincia de Aculuacan y Tesuico, porque la zanja ten\u00eda m\u00e1s de dos estados de hondura y otros tantos de anchura e iba toda chapada y estacada , por manera que el agua que por ella iba la pusieron en el peso de la laguna, de forma que las fustas se pod\u00edan llevar sin peligro y sin trabajo fasta el agua, que cierto que fue obra grand\u00edsima y mucho para ver. Y acabados los bergantines y puestos en esta zanja, a veinte y ocho de abril del dicho a\u00f1o fice alarde de toda la gente y hall\u00e9 ochenta y seis de caballo, y ciento y diez y ocho ballesteros y escopeteros, y setecientos y tantos peones de espadas y rodela, y tres tiros gruesos de hierro, y quince tiros peque\u00f1os de bronce y diez quintales de p\u00f3lvora. Acabado de hacer el dicho alarde, yo encargu\u00e9 y encomend\u00e9 mucho a todos los espa\u00f1oles que guardasen y cumpliesen las ordenanzas que yo hab\u00eda hecho para las cosas de la guerra en todo cuanto les fuese posible, y que se alegrasen y esforzasen mucho, pues que v\u00edan que Nuestro Se\u00f1or nos encaminaba para haber vitoria de nuestros enemigos, porque bien sab\u00edan que cuando hab\u00edamos entrado en Tesuico no hab\u00edamos tra\u00eddo m\u00e1s de cuarenta de caballo, y que Dios nos hab\u00eda socorrido mejor que lo hab\u00edamos pensado y hab\u00edan venido nav\u00edos con los caballos y gente y armas que hab\u00edan visto; y que esto y prencipalmente ver que pele\u00e1bamos en favor y augmento de nuestra fee y por reducir al servicio de Vuestra Majestad tantas tierras y provincias como se le hab\u00edan rebelado les hab\u00eda de poner mucho \u00e1nimo y esfuerzo para vencer o morir. Y todos respondieron y mostraron tener para ello muy entera voluntad y deseo. Y aquel d\u00eda del alarde pasamos con mucho placer y deseo de nos ver ya sobre el cerco y dar conclusi\u00f3n a esta guerra, de que depend\u00eda toda la paz o desasosiego destas partes. Otro d\u00eda siguiente fice mensajeros a las provincias de Tascaltecal, Guaxocingo y Churultecal a les facer saber c\u00f3mo los bergantines eran acabados y que yo y toda la gente est\u00e1bamos apercebidos y de camino para ir a cercar la grand cibdad de Temixtit\u00e1n; por tanto, que les rogaba, pues que ya por m\u00ed estaban avisados y ten\u00edan su gente apercebida, que con toda la m\u00e1s y bien armada [gente] que pudiesen, se partiesen y se viniesen all\u00ed a Tesuico donde yo les esperar\u00eda diez d\u00edas, y que en ninguna manera excediesen desto, porque ser\u00eda grande desv\u00edo para lo que estaba concertado. Y como llegaron los mensajeros y los naturales de aquellas provincias estaban apercebidos y con mucho deseo de se ver con los de Cul\u00faa, los de Guaxocingo y Chorultecal se vinieron a Calco porque yo se lo hab\u00eda ans\u00ed mandado, porque junto por all\u00ed hab\u00eda de entrar a poner el cerco. Y los capitanes de Tascaltecal con toda su gente muy lucida y bien armada llegaron a Tesuico cinco o seis d\u00edas antes de Pascua de Esp\u00edritu Santo, que fue el tiempo que yo les asign\u00e9. Y como aquel d\u00eda supe que ven\u00edan cerca, sal\u00edlos a rescebir con mucho placer. Y ellos ven\u00edan tan alegres y bien ordenados que no pod\u00eda ser mejor, y seg\u00fand la cuenta que los capitanes nos dieron pasaban de cincuenta mill hombres de guerra, los cuales fueron por nosotros muy bien rescebidos y aposentados. El segundo d\u00eda de Pascua mand\u00e9 salir a toda la gente de pie y de caballo a la plaza desta cibdad de Tesuico para la ordenar y dar a los capitanes la que hab\u00edan de llevar para tres guarniciones de gente que se hab\u00edan de poner en tres cibdades que est\u00e1n en torno de Temixtit\u00e1n. Y de la una guarnici\u00f3n hice capit\u00e1n a Pedro de Alvarado, y dile treinta de caballo, y diez y ocho ballesteros y escopeteros, y ciento y cincuenta peones de espada y rodela y m\u00e1s de veinte y cinco mill hombres de guerra de los de Tascaltecal. Y \u00e9stos hab\u00edan de asentar su real en la cibdad de Tacuba. De la otra guarnici\u00f3n fice capit\u00e1n a Crist\u00f3bal de Olid, al cual di treinta y tres de caballo, y diez y ocho ballesteros y escopeteros, y ciento y sesenta peones de espada y rodela y m\u00e1s de veinte mill hombres de guerra de nuestros amigos. Y \u00e9stos hab\u00edan de asentar su real en la cibdad de Cuyoacan. De la otra tercera guarnici\u00f3n fice capit\u00e1n a Gon\u00e7alo de Sandoval, alguacil mayor, y d\u00edle veinte y cuatro de caballo, y cuatro escopeteros, y trece ballesteros y ciento y cincuenta peones de espada y rodela &#8211; los cincuenta dellos mancebos escogidos que yo tra\u00eda en mi compa\u00f1\u00eda &#8211; y toda la gente de Guaxocingo y Chururtecal y Calco, que hab\u00eda m\u00e1s de treinta mill hombres. Y \u00e9stos hab\u00edan de ir por la cibdad de Yztapalapa a destruirla y pasar adelante por una calzada de la laguna con favor y espaldas de los bergantines, y juntarse con la guarnici\u00f3n de Cuyoacan, para que despu\u00e9s que yo entrase con los bergantines por la laguna el dicho alguacil mayor asentase su real donde le paresciese que m\u00e1s conven\u00eda. Para los trece bergantines con que yo hab\u00eda de entrar por la laguna dej\u00e9 trecientos hombres, todos los m\u00e1s gente de la mar y bien diestra, de manera que en cada bergant\u00edn iban veinte y cinco espa\u00f1oles y cada fusta llevaba su capit\u00e1n y veedor y seis ballesteros y [seis] escopeteros. Dada la orden susodicha, los dos capitanes que hab\u00edan de estar con la gente en las cibdades de Tacuba y Cuyoacan, despu\u00e9s de haber rescebido las instruciones de lo que hab\u00edan de hacer, se partieron de Tesuico a diez d\u00edas de mayo, y fueron a dormir dos leguas y media de all\u00ed a una poblaci\u00f3n buena que se dice Aculman. Y aquel d\u00eda supe c\u00f3mo entre los capitanes hab\u00eda habido cierta diferencia sobre el aposentamiento, y prove\u00ed luego esa noche para lo remediar y poner en paz y yo invi\u00e9 una persona para ello que los reprehendi\u00f3 y apacigu\u00f3. Y otro d\u00eda de ma\u00f1ana se partieron de all\u00ed y fueron a dormir a otra poblaci\u00f3n que se dice Gilotepeque, la cual hallaron despoblada porque era ya tierra de los enemigos. Y otro d\u00eda siguiente siguieron su camino en su ordenanza y fueron a dormir a una cibdad que se dice Guatitlan de que antes desto he fecho relaci\u00f3n a Vuestra Majestad, la cual ansimesmo hallaron despoblada. Y aquel d\u00eda pasaron por otras dos cibdades y poblaciones que tampoco hallaron gente en ellas. Y a hora de v\u00edsperas entraron en Tacuba, que tambi\u00e9n estaba despoblada, y aposent\u00e1ronse en las casas del se\u00f1or de all\u00ed, que son muy hermosas y grandes. Y aunque era ya tarde, los naturales de Tascaltecal dieron una vista por la entrada de dos calzadas de la cibdad de Temixtit\u00e1n y pelearon dos o tres horas valientemente con los de la cibdad. Y como la noche los desparti\u00f3, volvi\u00e9ronse sin ning\u00fand peligro a Tacuba. Otro d\u00eda de ma\u00f1ana los dos capitanes acordaron, como yo les hab\u00eda mandado, de ir a quitar el agua dulce que por ca\u00f1os entraba a la cibdad de Temextit\u00e1n. Y el uno dellos con veinte de caballo y ciertos ballesteros y escopeteros fue al nascimiento de la fuente, que estaba un cuarto de legua de all\u00ed, y cort\u00f3 y quebr\u00f3 los ca\u00f1os, que eran de madera y de cal y canto. Y pele\u00f3 reciamente con los de la cibdad que se lo defend\u00edan por la mar y por la tierra, y al fin los desbarat\u00f3 y dio conclusi\u00f3n a lo que iba, que era quitarles el agua dulce que entraba a la cibdad, que fue muy grande ardid. Este mismo d\u00eda los capitanes ficieron adreszar algunos malos pasos y puentes y acequias que estaban por all\u00ed alderredor de la laguna porque los de caballo pudiesen libremente correr por una parte y por otra. Y hecho esto, en que se tardar\u00eda tres o cuatro d\u00edas en los cuales se hobieron muchos recuentros con los de la cibdad en que fueron heridos algunos espa\u00f1oles y muertos hartos de los enemigos y les ganaron muchas albarradas y puentes y hobo hablas y desaf\u00edos entre los de la cibdad y los naturales de Tascaltecal que eran cosas bien notables y para ver, el capit\u00e1n Crist\u00f3bal de Olid con la gente que hab\u00eda de estar en guarnici\u00f3n en la cibdad de Cuyoacan, que est\u00e1 dos leguas de Tacuba, se parti\u00f3. Y el capit\u00e1n Pedro de Alvarado se qued\u00f3 en guarnici\u00f3n con su gente en Tacuba, donde cada d\u00eda ten\u00eda escaramuzas y peleas con los in dios. Y aquel d\u00eda que Crist\u00f3bal de Olid se parti\u00f3 para Cuyoacan \u00e9l y la gente llegaron a las diez del d\u00eda y aposent\u00e1ronse en las casas del se\u00f1or de all\u00ed y hallaron despoblada la cibdad. Y otro d\u00eda de ma\u00f1ana fueron a dar una vista a la calzada que entra en Temixtit\u00e1n con hasta veinte de caballo y algunos ballesteros y con seis o siete mill indios de Tascaltecal, y hallaron muy apercebidos los contrarios y rota la calzada y hechas muchas albarradas, y pelearon con ellos y los ballesteros hirieron y mataron algunos. Y esto continuaron seis o siete d\u00edas que en cada uno dellos hobo muchos recuentros y escaramuzas. Y una noche a media noche llegaron ciertas velas de los de la cibdad a gritar cerca del real y las velas de los espa\u00f1oles apellidaron alarma, y sali\u00f3 la gente y no hallaron ninguno de los enemigos porque dende muy lejos del real hab\u00edan dado la grita, la cual les hab\u00eda puesto alg\u00fand temor. Y como la gente de los nuestros estaba dividida en tantas partes, los de las dos guarniciones deseaban mi llegada con los bergantines como la salvaci\u00f3n, y con esta esperanza estuvieron aquellos pocos d\u00edas hasta que yo llegu\u00e9, como adelante dir\u00e9. Y en estos seis d\u00edas los del un real y del otro se juntaban cada d\u00eda y los de caballo corr\u00edan la tierra como estaban cerca los unos de los otros, y siempre alanceaban muchos de los enemigos y de la sierra cog\u00edan mucho ma\u00edz para sus reales, que es el pan y mantenimiento destas partes y hace mucha ventaja a lo de las Islas. En los cap\u00edtulos precedentes dije c\u00f3mo yo me quedaba en Tesuico con trecientos hombres y los trece bergantines porque, en sabiendo que las guarniciones estaban en los lugares donde hab\u00edan de asentar sus reales, yo me embarcase y diese una vista a la cibdad e ficiese algun da\u00f1o en las canoas. Y aunque yo deseaba mucho irme por la tierra por dar orden en los reales, como los capitanes eran personas de quien se pod\u00eda muy bien fiar lo que ten\u00edan entre manos y lo de los bergantines importaba mucha importancia y se requer\u00eda grand concierto y cuidado, determin\u00e9 de me meter en ellos porque la m\u00e1s aventura y ries go era la que se esperaba por el agua, y aunque por las personas prencipales de mi compa\u00f1\u00eda me fue requerido en forma que me fuese con las guarniciones, porque ellos pensaban que ellas llevaban lo m\u00e1s peligroso. Y otro d\u00eda despu\u00e9s de la fiesta de Corpus Christi, viernes, al cuarto del alba fice salir de Tesuico a Gonzalo de Sandoval, alguacil mayor, con su gente y que se fuese derecho a la cibdad de Yztapalapa, que estaba de all\u00ed seis leguas peque\u00f1as. Y a poco m\u00e1s de mediod\u00eda llegaron a ella y comenzaron a quemarla y a pelear con la gente della, y como vieron el grand poder que el alguacil mayor llevaba, porque iban con \u00e9l m\u00e1s de treinta y cinco o cuarenta mill hombres nuestros amigos, acog\u00e9ronse al agua en sus canoas. Y el alguacil mayor con toda la gente que llevaba se aposent\u00f3 en aquella cibdad y estuvo en ella aquel d\u00eda esperando lo que yo le hab\u00eda de mandar y me susced\u00eda. Como hobe despachado al alguacil mayor luego me met\u00ed en los bergantines y nos hecimos a la vela y al remo, y al tiempo que el alguacil mayor combat\u00eda y quemaba la cibdad de Yztapalapa llegamos a vista de un cerro grande y fuerte que est\u00e1 cerca de la dicha cibdad y todo en el agua. Conoscieron que yo entraba ya por la laguna, y el dicho cerro estaba muy fuerte y hab\u00eda mucha gente en \u00e9l ans\u00ed de los pueblos de alderredor del agua como de Temixtit\u00e1n, porque ya ellos sab\u00edan que el primer recuentro hab\u00eda de ser con los de Yztapalapa y estaban all\u00ed para defensa suya y para nos ofender si pudiesen. Y como vieron llegar la flota comenzaron a apellidar y a hacer grandes ahumadas, porque todas las cibdades de las lagunas lo supiesen y estuviesen apercebidas. Y aunque mi motivo era ir a combatir la parte de la cibdad de Yztapalapa que est\u00e1 en el agua, revolvimos sobre aquel cerro y pe\u00f1ol y salt\u00e9 en \u00e9l con ciento y cincuenta hombres, y aunque era muy agro y alto con mucha dificultad le comenzamos a subir y por fuerza les ganamos las albarradas que en lo alto ten\u00edan hechas para su defensa, y entr\u00e1 moslos de tal manera que ninguno dellos se escap\u00f3 expceto las mujeres y ni\u00f1os. Y en este combate me hirieron veinte y cinco espa\u00f1oles, pero fue muy hermosa vitoria. Como los de Yztapalapa hab\u00edan hecho ahumadas desde unas torres de \u00eddolos que estaban en un cerro muy alto junto a su cibdad, los de Temixtit\u00e1n y de las otras cibdades que est\u00e1n en el agua conoscieron que yo entraba ya por la laguna con los bergantines, y de improviso junt\u00f3se tan grand flota de canoas para nos venir acometer y a tentar qu\u00e9 cosa eran los bergantines, y a lo que pudimos juzgar pasaban de quinientas canoas. Y como yo vi que tra\u00edan su derrota derecha a nosotros, yo y la gente que hab\u00edamos saltado en aquel cerro grande nos embarcamos a mucha priesa y mand\u00e9 a los capitanes de los bergantines que en ninguna manera se moviesen, porque los de las canoas se determinasen a nos acometer y creyesen que nosotros de temor no os\u00e1bamos salir a ellos. Y as\u00ed comenzaron con mucho \u00edmpetu de caminar su flota hacia nosotros, pero a obra de dos tiros de ballesta repar\u00e1ronse y estuvieron quedos. Y como yo deseaba mucho que el primer recuentro que con ellos hobi\u00e9semos fuese de mucha vitoria y se hiciese de manera que ellos cobrasen mucho temor de los bergantines, porque la llave de toda la guerra estaba en ellos y donde ellos pod\u00edan rescebir m\u00e1s da\u00f1o y aun nosotros tambi\u00e9n era por el agua, plugo a Nuestro Se\u00f1or que, est\u00e1ndonos mirando los unos a los otros, vino un viento de la tierra muy favorable para embestir con ellos, y luego mand\u00e9 a los capitanes que rompiesen por la flota de las canoas y siguiesen tras ellos fasta los encerrar en la cibdad de Temixtit\u00e1n. Y como el viento era muy bueno, aunque ellos hu\u00edan cuanto pod\u00edan, embestimos por medio dellos y quebramos infinitas canoas y matamos y ahogamos muchos de los enemigos, que era la cosa del mundo m\u00e1s para ver. Y en este alcance los seguimos bien tres leguas grandes fasta los encerrar en las casas de la cibdad, y as\u00ed plugo a Nuestro Se\u00f1or de nos dar mayor y mejor victoria que nosotros hab\u00edamos pedido y deseado. Los de la guarnici\u00f3n de Cuyoacan, que pod\u00edan mejor que los de la cibdad de Tacuba ver c\u00f3mo ven\u00edamos con los bergantines, como vieron todas las trece velas por el agua y que tra\u00edamos tan buen tiempo y que desbarat\u00e1bamos todas las canoas de los enemigos, seg\u00fand despu\u00e9s me certificaron, fue la cosa del mundo de que m\u00e1s placer hobieron y que m\u00e1s ellos deseaban. Porque, como he dicho, ellos y los de Tacuba ten\u00edan muy grand deseo de mi venida y con mucha raz\u00f3n, porque estaba la una guarnici\u00f3n y la otra entre tanta multitud de enemigos que milagrosamente los animaba nuestro Se\u00f1or y enflaquec\u00eda los \u00e1nimos de los enemigos para que no se determinasen a los salir acometer a su real, lo cual si fuera, no pudiera ser menos de rescebir los espa\u00f1oles mucho da\u00f1o, aunque siempre estaban muy apercebidos y determinados de morir o ser vencedores como aqu\u00e9llos que se hallan apartados de toda manera de socorro salvo de aqu\u00e9l que de Dios esperaban. As\u00ed como los de las guarniciones de Cuyoacan nos vieron seguir, las canoas tomaron su camino y los m\u00e1s de caballo y de pie que all\u00ed estaban para la cibdad de Temixtit\u00e1n, y pelearon muy reciamente con los indios que estaban en la calzada y les ganaron las albarradas que ten\u00edan hechas y les tomaron y pasaron a pie y a caballo muchas puentes que ten\u00edan quitadas. Y con el favor de los bergantines que iban cerca de la calzada los indios de Tascaltecal nuestros amigos y los espa\u00f1oles segu\u00edan a los enemigos, y dellos mataban y dellos se echaron al agua de la otra parte de la calzada por do no iban los bergantines. As\u00ed fueron con esta vitoria m\u00e1s de una grand legua por la calzada hasta llegar donde yo hab\u00eda parado con los bergantines, como abajo har\u00e9 relaci\u00f3n. Como los bergantines fuimos bien tres leguas dando caza a las canoas, las que se nos escaparon alleg\u00e1ronse entre las casas de la cibdad, y como era ya despu\u00e9s de v\u00edsperas mand\u00e9 recoger los bergantines y llegamos con ellos a la calzada. Y all\u00ed determin\u00e9 de saltar en tierra con treinta hombres por les ganar unas dos torres de sus \u00eddolos peque\u00f1as que estaban cercadas con su cerca baja de cal y canto. Y como saltamos all\u00ed pelearon con nosotros muy reciamente por nos las defender, y al fin con harto peligro y trabajo gan\u00e1moselas. Y luego hice sacar en tierra tres tiros de hierro gruesos que yo tra\u00eda, y porque lo que restaba de la calzada desde all\u00ed a la cibdad, que era media legua, estaba todo lleno de los enemigos y de la una parte y de la otra de la calzada que era agua todo lleno de canoas con gente de guerra, fice asentar el un tiro de aqu\u00e9llos y tir\u00f3 por la calzada adelante y fizo mucho da\u00f1o en los enemigos, y por descuido del artillero en aquel mismo punto que tir\u00f3 se nos quem\u00f3 la p\u00f3lvora que all\u00ed ten\u00edamos, aunque era poca. Y luego esa noche prove\u00ed un bergantin que fuese a Yztapalapa adonde estaba el alguacil mayor, que ser\u00eda dos leguas de all\u00ed, y que trujese toda la p\u00f3lvora que hab\u00eda. Y aunque al principio mi intenci\u00f3n era luego que entrase con los bergantines irme a Cuyoacan y dejar prove\u00eddo c\u00f3mo anduviesen a mucho recaudo haciendo todo el m\u00e1s da\u00f1o que pudiesen, como aquel d\u00eda salt\u00e9 all\u00ed en la calzada y les gan\u00e9 aquellas dos torres, determin\u00e9 de asentar all\u00ed real y que los bergantines se estuviesen all\u00ed junto a las torres, y que la mitad de la gente de la guarnici\u00f3n de Cuyoacan y otros cincuenta peones de los del alguacil mayor se viniesen all\u00ed otro d\u00eda. Y prove\u00eddo esto, aquella noche estuvimos a mucho recaudo porque est\u00e1bamos en grand peligro y toda la gente de la cibdad acud\u00eda all\u00ed por la calzada y por el agua. Y a media noche llega mucha multitud de gente en canoas y por la calzada a dar sobre nuestro real, y cierto nos pusieron en grand temor y rebato, en especial porque era de noche y nunca ellos a tal tiempo suelen acometer ni se ha visto que de noche hayan peleado, salvo con mucha sobra de vitoria. Y como nosotros est\u00e1bamos muy apercebidos comenzamos a pelear con ellos, y dende los bergantines, porque cada uno tra\u00eda un tiro peque\u00f1o de campo, comenzaron a soltarlos y los ballesteros y escopeteros a hacer lo mismo, y desta manera no osaron llegar m\u00e1s adelante ni llegaron tanto que nos hiciesen ning\u00fand da\u00f1o, y as\u00ed nos dejaron lo que qued\u00f3 de la noche sin nos acometer m\u00e1s. Otro d\u00eda en amaneciendo llegaron al real de la calzada donde yo estaba quince ballesteros y escopeteros y cincuenta hombres de espada y rodela y siete u ocho de caballo de la guarnici\u00f3n de Cuyoacan. Y ya cuando ellos llegaron los de la cibdad en canoas y por la calzada peleaban con nosotros, y era tanta la multitud que por el agua y por la tierra no v\u00edamos sino gente, y daban tantas gritas y alaridos que paresc\u00eda que se hund\u00eda el mundo. Y nosotros comenzamos a pelear con ellos por la calzada adelante y gan\u00e1mosles una puente que ten\u00edan quitada y una albarrada que ten\u00edan hecha a la entrada, y con los tiros y con los de caballo hecimos tanto da\u00f1o en ellos que casi los encerramos hasta las primeras casas de la cibdad. Y porque de la otra parte de la calzada como los bergantines no pod\u00edan pasar andaban muchas canoas y nos fac\u00edan da\u00f1o con flechas y varas que nos tiraban a la calzada, hice romper un pedazo della junto a nuestro real e hice pasar de la otra parte cuatro bergantines, los cuales como pasaron, encerraron las canoas todas entre las casas de la cibdad en tal manera que no osaban por ninguna v\u00eda salir a lo largo. Y por la otra parte de la calzada los otros ocho bergantines peleaban con las canoas, y las encerraron entre las casas y entraron por entre ellas aunque hasta entonces no lo hab\u00edan osado hacer porque hab\u00eda muchos bajos y estacas que les estorbaban. Y como hallaron canales por donde entrar seguros, peleaban con los de las canoas, y tomaron algunas dellas y quemaron muchas casas del arrabal. Y aquel d\u00eda todo despendimos en pelear de la manera ya dicha. Otro d\u00eda siguiente el alguacil mayor con la gente que ten\u00eda en Yztapalapa, as\u00ed espa\u00f1oles como nuestros amigos, se parti\u00f3 para Cuyoacan. Y dende all\u00ed para tierra firme viene una calzada que tura obra de legua y media, y como el alguacil mayor comenz\u00f3 a caminar, a obra de un cuarto de legua lleg\u00f3 a una cibdad peque\u00f1a que tambien est\u00e1 en el agua y por muchas partes della se puede andar a caballo. Y los naturales de all\u00ed comenzaron a pelear con \u00e9l, y \u00e9l los desbarat\u00f3 y mat\u00f3 muchos y les destruy\u00f3 y quem\u00f3 toda la cibdad. Y porque yo hab\u00eda sabido que los indios hab\u00edan rompido mucho de la calzada y la gente no pod\u00eda pasar bien, invi\u00e9les dos bergantines para que les ayudasen a pasar, de los cuales hicieron puente por donde los peones pasaron, y desque hobieron pasado se fueron a aposentar a Cuyoacan. Y el alguacil mayor con diez de caballo tom\u00f3 el camino de la calzada donde ten\u00edamos nuestro real, y cuando lleg\u00f3 hall\u00f3nos peleando, y \u00e9l y los que ven\u00edan con \u00e9l se apearon y comenzaron a pelear con los de la calzada con quien nosotros and\u00e1bamos revueltos. Y como el dicho alguacil mayor comenz\u00f3 a pelear los contrarios le atravesaron un pie con una vara, y aunque a \u00e9l y a otros algunos nos hirieron aquel d\u00eda, con los tiros gruesos y con las ballestas y escopetas hecimos mucho da\u00f1o en ellos, en tal manera que ni los de las canoas ni los de la calzada no osaban llegarse tanto a nosotros y mostraban m\u00e1s temor y menos orgullo que sol\u00edan. Y desta manera estuvimos seis d\u00edas en que cada d\u00eda ten\u00edamos combate con ellos y los bergantines iban quemando alderredor de la cibdad todas las casas que pod\u00edan. Y descubrieron canal por donde pod\u00edan entrar alderredor y por los arrabales de la cibdad y llegar a lo grueso della, que fue cosa muy provechosa e hizo cesar la venida de las canoas, que ya no osaba asomar ninguna con un cuarto de legua a nuestro real. Otro d\u00eda Pedro de Alvarado, que estaba por capit\u00e1n de la gente que estaba en guarnici\u00f3n en Tacuba, me hizo saber c\u00f3mo por la otra parte de la cibdad, por una calzada que va a unas poblaciones de la tierra firme y por otra peque\u00f1a que estaba junto a ella, los de Temixtit\u00e1n entraban y sal\u00edan cuando quer\u00edan, y que cre\u00eda que vi\u00e9ndose en aprieto, se hab\u00edan de salir todos por all\u00ed. Aunque yo deseaba m\u00e1s su salida que no ellos, porque muy mejor nos pudi\u00e9ramos aprovechar dellos en la tierra firme que no en la fortaleza grande que ten\u00edan en el agua, pero porque estuviesen todos cercados y no se pudiesen aprovechar en cosa ninguna de la tierra firme, aunque el alguacil mayor estaba herido le mand\u00e9 que fuese a asentar su real a un pueblo peque\u00f1o a do iba a salir la una de aquellas dos calzadas, el cual se parti\u00f3 con veinte y tres de caballo y cient peones y diez y ocho ballesteros y escopeteros y me dej\u00f3 otros cincuenta peones de los que yo tra\u00eda en mi compa\u00f1\u00eda. Y en llegando, que fue otro d\u00eda, asent\u00f3 su real adonde yo le mand\u00e9, y dende all\u00ed en delante la cibdad de Temixtit\u00e1n qued\u00f3 cercada por todas las partes que por calzadas pod\u00edan salir a la tierra firme. Yo ten\u00eda, Muy Poderoso Se\u00f1or, en el real de la calzada ducientos peones espa\u00f1oles en que hab\u00eda veinte y cinco ballesteros y escopeteros, \u00e9stos sin la gente de los bergantines, que eran m\u00e1s de ducientos y cincuenta. Y como ten\u00edamos algo encerrados a los enemigos y ten\u00edamos mucha gente de guerra de nuestros amigos, determin\u00e9 de entrar por la calzada a la cibdad todo lo m\u00e1s que pudiese y que los bergantines al fin de la una parte y de la otra se estuviesen para hacrnos espaldas. Y mand\u00e9 que algunos de caballo y peones de los que estaban en Cuyoacan se viniesen al real para que entrasen con nosotros, y que diez de caballo se quedasen a la entrada de la calzada haciendo espaldas a nosotros y a algunos que quedaban en Cuyoacan, porque los naturales de las cibdades de Suchimilco y Culuacan e Yztapalapa y Chilobusco y Mixicalcingo y Cuitaguacad y Mizque, que est\u00e1n en el agua, estaban rebellados y eran en favor de los de la cibdad. Y queriendo \u00e9stos tomarnos las espaldas, est\u00e1bamos seguros con los diez o doce de caballo que yo mandaba andar por la calzada y otros tantos que siempre estaban en Cuyoacan y m\u00e1s de diez mill indios nuestros amigos. Ansimesmo mand\u00e9 al alguacil mayor y a Pedro de Alvarado que por sus estancias acometiesen aquel d\u00eda a los de la cibdad, porque yo quer\u00eda por mi parte ganalles todo lo que m\u00e1s pudiese. Y ans\u00ed sal\u00ed por la ma\u00f1ana del real y seguimos a pie por la calzada adelante y luego hallamos los enemigos en defensa de una quebradura que ten\u00edan hecha en ella tan ancha como una lanza y otro tanto de hondura, y en ella ten\u00edan hecha una albarrada. Y peleamos con ellos y ellos con nosotros muy valientemente y al fin se la ganamos, y seguimos por la calzada adelante hasta llegar a la entrada de la cibdad donde estaba una torre de sus \u00eddolos y al pie della una puente muy grande alzada y por ella atravesaba una calle de agua muy ancha con otra muy fuerte albarrada. Y como llegamos comenzaron a pelear con nosotros, pero como los bergantines estaban de la una parte y de la otra gan\u00e1mosela sin peligro, lo cual fuera imposible sin ayuda dellos. Y como comenzaron a desamparar el albarrada, los de los bergantines saltaron en tierra y nosotros pasamos el agua y tambi\u00e9n los de Tascaltecal y Guaxocingo y Calco y Tesuico, que eran m\u00e1s de ochenta mill hombres. Y entretanto que ceg\u00e1bamos con piedra y adobes aquella puente los espa\u00f1oles ganaron otra albarrada que estaba en la calle que es la prencipal y m\u00e1s ancha de toda la cibdad, y como aqu\u00e9lla no ten\u00eda agua fue muy facil de ganar. Y siguieron el alcance tras los enemigos por la calle adelante hasta llegar a otra puente que ten\u00edan alzada salvo una viga ancha por donde pasaban, y puestos por ella y por el agua en salvo, quit\u00e1ronla de presto. Y de la otra parte de la puente ten\u00edan hecha otra grande albarrada de barro y adobes, y como llegamos a ella y no podimos pasar sin echarnos al agua y esto era muy peligroso los enemigos peleaban muy valientemente, y de la una parte y de la otra de la calle hab\u00eda infinitos dellos peleando con mucho coraz\u00f3n desde las azoteas. Y como se llegaron copias de ballesteros y esco peteros y tir\u00e1bamos con dos tiros por la calle adelante hac\u00edamosles mucho da\u00f1o, y como lo conoscimos ciertos espa\u00f1oles se lanzaron al agua y pasaron de la otra parte, y tur\u00f3 en ganarse m\u00e1s de dos horas. Y como los enemigos los vieron pasar, desampararon el albarrada y las azoteas y p\u00f3nense en huida por la calle adelante, y as\u00ed pas\u00f3 toda la gente. Y yo hice luego comenzar a cegar aquella puente y desfacer el albarrada, y entretanto los espa\u00f1oles y los indios nuestros amigos siguieron el alcance por la calle adelante bien dos tiros de ballesta hasta otra puente que est\u00e1 junto a la plaza de los prencipales aposentamientos de la cibdad. Y esta puente no la ten\u00edan quitada ni ten\u00edan hecha albarrada en ella porque ellos no pensaron que aquel d\u00eda se les ganara ninguna cosa de lo que se les gan\u00f3 ni aun nosotros pensamos que fuera la mitad. Y a la entrada de la plaza asest\u00f3se un tiro y con \u00e9l resceb\u00edan mucho da\u00f1o los enemigos, que eran tantos que no cab\u00edan en ella. Y los espa\u00f1oles como vieron que all\u00ed no hab\u00eda agua, de donde se suele rescebir peligro, determinaron de les entrar la plaza, y como los de la cibdad vieron su determinaci\u00f3n puesta en obra y vieron mucha multitud de nuestros amigos y aunque dellos sin nosotros no ten\u00edan ning\u00fand temor, vuelven las espaldas, y los espa\u00f1oles y nuestros amigos dan en pos dellos hasta los encerrar en el circuito de sus \u00eddolos, el cual es cercado de cal y canto. Y como en la otra relaci\u00f3n se habr\u00e1 visto, tiene tan grand circuito como una villa de cuatrocientos vecinos. Y este fue luego desamparado dellos, y los espa\u00f1oles y nuestros amigos se lo ganaron y estuvieron en \u00e9l y en las torres un buen rato. Y como los de la cibdad vieron que no hab\u00eda gente de caballo, volvieron sobre los espa\u00f1oles y por fuerza los echaron de las torres y del patio y circuito, en que se vieron en muy grande aprieto y peligro. Y como iban m\u00e1s que retray\u00e9ndose, hicieron rostro debajo de los portales del patio, y como los aquejaban tan reciamente, los desampararon y se retrujeron a la plaza y de all\u00ed los echaron por fuerza hasta los meter por la calle adelante, en tal manera que el tiro que all\u00ed estaba lo desampararon. Y los espa\u00f1oles como no pod\u00edan sufrir la fuerza de los enemigos se retrajeron con mucho peligro, el cual de hecho rescebieran, sino que plugo a Dios que en aquel punto llegaron tres de caballo y entran por la plaza adelante, y como los enemigos los vieron creyeron que eran m\u00e1s y comienzan a huir, y mataron algunos dellos y gan\u00e1ronles el patio y circuito que arriba dije. Y en la torre m\u00e1s prencipal y alta d\u00e9l, que tiene ciento y tantas gradas hasta llegar a lo alto, fici\u00e9ronse fuertes all\u00ed diez o doce indios prencipales de los de la cibdad, y cuatro o cinco espa\u00f1oles subi\u00e9rongela por fuerza, y aunque ellos se defend\u00edan bien gela ganaron y los mataron a todos. Y despu\u00e9s vinieron otros cinco o seis de caballo, y ellos y los otros echaron una celada en que mataron m\u00e1s de treinta de los enemigos. Y como ya era tarde yo mand\u00e9 recoger la gente y que se retrujesen, y al retraer cargaba tanta multitud de los enemigos que si no fuera por los de caballo fuera imposible no rescebir mucho da\u00f1o los espa\u00f1oles, pero como todos aquellos malos pasos de la calle y calzada donde se esperaba el peligro al tiempo del retraer yo los ten\u00eda muy bien adreszados y adobados y los de caballo pod\u00edan por ellos muy bien entrar y salir; y como los enemigos ven\u00edan dando en nuestra retroguarda los de caballo revolv\u00edan sobre ellos, que siempre alanceaban o mataban algunos; y como la calle era muy larga, hobo lugar de facerse esto cuatro o cinco veces. Y aunque los enemigos v\u00edan que resceb\u00edan da\u00f1o ven\u00edan los perros tan rabiosos que en ninguna manera los pod\u00edamos detener ni que nos dejasen de seguir, y todo el d\u00eda se gastara en esto, sino que ya ellos ten\u00edan tomadas muchas azoteas que salen a la calle y los de caballo resceb\u00edan a esta causa mucho peligro, y ans\u00ed nos fuemos por la calzada adelante a nuestro real sin peligrar ning\u00fand espa\u00f1ol, aunque hobo algunos heridos. Y dejamos puesto fuego a las m\u00e1s y mejores casas de aquella calle, porque cuando otra vez entr\u00e1semos dende las azoteas no nos hiciesen da\u00f1o. Este mismo d\u00eda el alguacil mayor y Pedro de Alvarado pelearon cada uno por su estancia muy reciamente con los de la cibdad, y al tiempo del combate estar\u00edamos los unos de los otros a legua y media y a una legua, porque se estiende tanto la poblaci\u00f3n de la cibdad que aun diminuyo la distancia que hay. Y nuestros amigos que estaban con ellos, que eran infinitos, pelearon muy bien y se retrujeron aquel d\u00eda sin rescebir ning\u00fand da\u00f1o. En este comedio don Hernando, se\u00f1or de la cibdad de Tesuico y provincia de Aculuacan de que arr\u00edba he hecho relaci\u00f3n a Vuestra Majestad, procuraba de traer a todos los naturales de su provincia y cibdad, especialmente los prencipales, a nuestra amistad, porque a\u00fan no estaban tan confirmados en ella como despu\u00e9s lo estuvieron. Y cada d\u00eda ven\u00edan al dicho don Fernando muchos se\u00f1ores y hermanos suyos con determinaci\u00f3n de ser en nuestro favor y pelear con los de M\u00e9sico y Temixtit\u00e1n. Y como don Hernando era mochacho y ten\u00eda mucho amor a los espa\u00f1oles y conosc\u00eda la merced que en nombre de Vuestra Majestad se le hab\u00eda hecho en darle tan grande se\u00f1or\u00edo, habiendo otros que le preced\u00edan en el derecho d\u00e9l, trabajaba cuanto le era posible c\u00f3mo todos sus vasallos viniesen a pelear con los de la cibdad y ponerse en los peligros y trabajos que nosotros. Y habl\u00f3 con sus hermanos, que eran seis o siete, todos mancebos bien dispuestos, y d\u00edjoles que les rogaba que con toda la gente de su se\u00f1or\u00edo viniesen a me ayudar. Y a uno dellos, que se llama Ystrisuchil, que es de edad de veinte y tres o veinte y cuatro a\u00f1os, muy esforzado, amado y temido de todos, invi\u00f3le por capit\u00e1n. Y lleg\u00f3 al real de la calzada con m\u00e1s de treinta mill hombres de guerra muy bien adrezados a su manera, y a los otros dos reales ir\u00edan otros veinte mill. Y yo los resceb\u00ed alegremente agradeci\u00e9ndoles su voluntad y obra. Bien podr\u00e1 Vuestra Ces\u00e1rea Majestad considerar si era buen socorro y buena amistad la de don Fernando y lo que sinter\u00edan los de Temixtit\u00e1n en ver venir contra ellos a los que ellos ten\u00edan por vasallos y por amigos y parientes y hermanos y aun padres e hijos. Dende a dos d\u00edas el combate de la cibdad se dio, como arriba he dicho. Y venida ya esta gente en nuestro socorro, los naturales de la cibdad de Suchimilco, que est\u00e1 en el agua, y ciertos pueblos de utum\u00edes, que es gente serrana y de m\u00e1s copia que los de Suchimilco y eran esclavos del se\u00f1or de Timistit\u00e1n, se vinieron a ofrescer y dar por vasallos de Vuestra Majestad rog\u00e1ndome que les perdonase la tardanza. Y yo los resceb\u00ed muy bien y folgu\u00e9 mucho con su venida, porque si alg\u00fand da\u00f1o pod\u00edan rescebir los de Cuyoacan era de aqu\u00e9llos. Como por el real de la calzada donde yo estaba hab\u00edamos quemado con los bergantines muchas casas de los arrabales de la cibdad y no osaba asomar canoa ninguna por todo aquello, paresci\u00f3me que para nuestra seguridad bastaba tener en torno de nuestro real siete bergantines, y por eso acord\u00e9 de inviar al real del alguacil mayor y al de Pedro de Alvarado cada tres bergantines. Y encomend\u00e9 mucho a los capitanes dellos que porque por la parte de aquellos dos reales los de la cibdad se aprovechaban mucho de la tierra en sus canoas y met\u00edan agua y frutas y ma\u00edz y otras vituallas, que corriesen de noche y de d\u00eda los unos y los otros del un real al otro, y que dem\u00e1s desto aprovechar\u00edan mucho para hacer espaldas a la gente de los reales todas las veces que quisiesen entrar a combatir la cibdad. Y as\u00ed se fueron estos seis bergantines a los otros reales, que fue cosa nescesaria y provechosa, porque cada d\u00eda y cada noche hac\u00edan con ellos saltos maravillosos y tomaban muchas canoas y gente de los enemigos. Prove\u00eddo esto y venida en nuestro socorro y de paz la gente de que arriba he fecho menci\u00f3n, habl\u00e9les a todos y d\u00edjeles c\u00f3mo yo determinaba de entrar a combatir la cibdad dende a dos d\u00edas, por tanto, que todos viniesen para entonces muy a punto de guerra y que en aquello conoscer\u00eda si eran nuestros amigos, y ellos prometieron de lo complir ans\u00ed. Y otro d\u00eda fice adreszar y apercebir la gente y escrib\u00ed a los reales y bergantines lo que ten\u00eda acordado y lo que hab\u00edan de hacer. Otro d\u00eda por la ma\u00f1ana, despu\u00e9s de haber o\u00eddo misa e informados los capitanes de lo que hab\u00edan de facer, yo sal\u00ed de nuestro real con quince o veinte de caballo y trecientos espa\u00f1oles y con todos nuestros amigos, que era infinita gente. Y yendo por la calzada adelante, a tres tiros de ballesta de real estaban ya los enemigos esper\u00e1ndonos con muchos alaridos, y como en los tres d\u00edas antes no se les hab\u00eda dado combate hab\u00edan desfecho cuanto hab\u00edamos cegado del agua, y ten\u00edanlo muy m\u00e1s fuerte y peligroso de ganar que de antes. Y los bergantines llegaron por la una parte y por la otra de la calzada, y como con ellos se pod\u00edan llegar muy cerca de los enemigos con los tiros y escopetas y ballestas hac\u00edanles mucho da\u00f1o, y conosci\u00e9ndolo, saltan en tierra y ganan el albarrada y puente. Y comenzamos a pasar de la otra parte y dar en pos de los enemigos, los cuales luego se fortalec\u00edan en las otras puentes y albarradas que ten\u00edan hechas, las cuales aunque con m\u00e1s trabajo y peligro que la otra vez les ganamos, y les echamos de toda la calle y de la plaza de los aposentamientos grandes de la cibdad. Y de all\u00ed mand\u00e9 que no pasasen los espa\u00f1oles, porque yo con la gente de nuestros amigos andaba cegando con piedra y adobes toda el agua, que era tanto de hacer que aunque para ello ayudaban m\u00e1s de diez mill indios, cuando se acab\u00f3 de adreszar era ya hora de v\u00edsperas. Y en todo este tiempo siempre los espa\u00f1oles y nuestros amigos andaban peleando y escaramuzando con los de la cibdad y ech\u00e1ndoles celadas en que murieron muchos dellos. Y yo con los de caballo anduve un rato por la cibdad y alance\u00e1bamos por las calles do no hab\u00eda agua los que alcanz\u00e1bamos, de manera que los ten\u00edamos retra\u00eddos y no osaban llegar a lo firme. Viendo que \u00e9stos de la cibdad estaban rebeldes y mostraban tanta determinaci\u00f3n de morir o defenderse, coleg\u00ed dello dos cosas: la una, que hab\u00edamos de haber poca o ninguna de la riqueza que nos hab\u00edan tomado; y la otra, que daban ocasi\u00f3n y nos forzaban a que totalmente los destruy\u00e9semos. Y desta postrera ten\u00eda m\u00e1s sentimiento y me pesaba en el alma, y pensaba qu\u00e9 forma tern\u00eda para los atemorizar de manera que viniesen en conoscimiento de su yerro y del da\u00f1o que pod\u00edan rescebir de nosotros. Y no hac\u00eda sino quemalles y derrocalles las torres de sus \u00eddolos y sus casas, y porque lo sintiesen m\u00e1s este d\u00eda fice poner fuego a estas casas grandes de la plaza donde la otra vez que nos echaron de la cibdad los espa\u00f1oles y yo est\u00e1bamos aposentados &#8211; que eran tan grandes que un pr\u00edncipe con m\u00e1s de seiscientas personas de su casa y servicio se pod\u00eda aposentar en ellas &#8211; y otras que estaban junto a ellas, que aunque algo menores eran muy m\u00e1s frescas y gentiles y ten\u00eda en ellas Muteezuma todos los linajes de aves que en estas partes hab\u00eda. Y aunque a m\u00ed me pes\u00f3 mucho dello, porque a ellos les pesaba mucho m\u00e1s determin\u00e9 de las quemar, de que los enemigos mostraron harto pesar y tambi\u00e9n los otros sus aliados de las cibdades de la laguna, porque \u00e9stos ni otros nunca pensaron que nuestra fuerza bastara a les entrar tanto en la cibdad, y esto les puso harto desmayo. Puesto fuego a estas casas, porque ya era tarde recog\u00ed la gente para nos volver a nuestro real. Y como los de la cibdad ve\u00edan que nos retra\u00edamos cargaban infenitos dellos y ven\u00edan con mucho \u00edmpitu d\u00e1ndonos en la retroguarda, y como toda la calle estaba buena para correr los caballos volv\u00edamos sobre ellos y alance\u00e1bamos de cada vuelta muchos dellos, y por eso no nos dejaban de nos venir dando grita a las espaldas. Este d\u00eda sintieron y mostraron mucho desmayo, especialmente viendo entrar por su cibdad quem\u00e1ndola y destruy\u00e9ndola y peleando con ellos los de Tesuico y Calco y de Suchimilco y los otum\u00edes, y nombr\u00e1ndose cada uno de d\u00f3nde era; y por otra parte los de Tascaltecal, que ellos y los otros les mostraban los de su cibdad hechos pedazos, dici\u00e9ndoles que los hab\u00edan de cenar aquella noche y almorzar otro d\u00eda, como de hecho lo hac\u00edan. Y as\u00ed nos venimos a nuestro real a descansar, porque aquel d\u00eda hab\u00edamos trabajado mucho. Y los siete bergantines que yo ten\u00eda entraron aquel d\u00eda por las calles del agua de la cibdad y quemaron mucha parte della. Los capitanes de los otros reales y los seis bergantines pelearon muy bien aquel d\u00eda, y de lo que les acaesci\u00f3 me pudiera muy bien alargar, y por evitar prolejidad lo dejo, m\u00e1s de que con vitoria se retrujeron a sus reales sin rescebir peligro ninguno. Otro d\u00eda siguiente luego por la ma\u00f1ana, despu\u00e9s de haber o\u00eddo misa, torn\u00e9 a la cibdad por la misma orden con toda la gente, porque los contrarios no tuviesen lugar de descegar las puentes y hacer las albarradas. Y por bien que madrugamos, de las tres partes y calles de agua que atraviesan la calle que va del real fasta las casas grandes de la plaza las dos dellas estaban como los d\u00edas antes, que fueron muy recias de ganar, y tanto que dur\u00f3 el combate desde las ocho horas fasta la una despu\u00e9s de mediod\u00eda, en que se gastaron casi todas las saetas, almac\u00e9n y pelotas que los ballesteros y escopeteros llevaban. Y crea Vuestra Majestad que era sin comparaci\u00f3n el peligro en que nos v\u00edamos todas las veces que les gan\u00e1bamos estas puentes, porque para ganarlas era forzado echarse a nado los espa\u00f1oles y pasar de la otra parte, y esto no pod\u00edan ni osaban facer muchos porque a cuchilladas y a botes de lanza resist\u00edan los enemigos que no saliesen a la otra parte. Pero como ya por los lados no ten\u00edan azoteas de donde nos hiciesen da\u00f1o y desta otra parte los asaete\u00e1bamos \u2013 porque est\u00e1bamos los unos de los otros un tiro de herradura \u2013 y los espa\u00f1oles tomaban de cada d\u00eda mucho m\u00e1s \u00e1nimo y determinaban de pasar, y tambi\u00e9n porque v\u00edan que mi determinaci\u00f3n era aqu\u00e9lla y que cayendo o levantando no se hab\u00eda de hacer otra cosa, parescer\u00e1 a Vuestra Majestad que pues tanto peligro resceb\u00edamos en el ganar destas puentes y albarradas, que \u00e9ramos negligentes, ya que las gan\u00e1bamos, [en] no las sostener, por no tornar cada d\u00eda de nuevo a nos ver en tanto peligro y trabajo, que sin duda era grande. Y cierto as\u00ed parescer\u00e1 a los absentes, pero sabr\u00e1 Vuestra Majestad que en ninguna manera se pod\u00eda facer,porque para ponerse as\u00ed en efeto se requer\u00eda dos cosas: o que el real pas\u00e1ramos all\u00ed a la plaza y circuito de las torres de los \u00eddolos, o que gente guardaran las puentes de noche. Y de lo uno y de lo otro se rescibiera grand peligro y hab\u00eda posibilidad para ello, porque teniendo el real en la cibdad cada noche y cada hora, como ellos eran muchos y nosotros pocos nos dieran mill rebatos y pelearan con nosotros y fuera el trabajo incomportable y pod\u00edan darnos por muchas partes. Pues guardar las puentes gente de noche, quedaban los espa\u00f1oles tan cansados de pelear el d\u00eda que no se pod\u00eda sufrir poner gente en guarda dellos, y a esta causa nos era forzado ganarlas de nuevo cada d\u00eda que entr\u00e1bamos en la cibdad. Aquel d\u00eda, como se tard\u00f3 mucho en ganar aquellas puentes y en las tornar a cegar no hobo lugar de hacer m\u00e1s, slavo que por otra calle prencipal que va a dar a la cibdad de Tacuba se ganaron otras dos puentes y se cegaron y se quemaron muchas y buenas casas de aquella calle. Y con esto se lleg\u00f3 la tarde y hora de retraernos, donde receb\u00edamos siempre poco menos peligro que en el ganar de las puentes, porque en vi\u00e9ndonos retraer era tan cierto cobrar los de la cibdad tanto esfuerzo que no paresc\u00eda sino que hab\u00edan habido toda la vitoria del mundo y que nosotros \u00edbamos huyendo. Y para este retraer era nescesario estar las puentes bien cegadas y lo cegado igual al suelo de las calles, de maners que los de caballo pudiesen li bremente correr a una parte y a otra. Y as\u00ed en el retraer, como ellos ven\u00edan tan golosos tras nosotros algunas veces fing\u00edamos ir huyendo y revolv\u00edamos los de caballo sobre ellos y siempre tom\u00e1bamos doce o trece de aquellos m\u00e1s esforzados, y con esto y con algunas celadas que siempre les ech\u00e1bamos continuo llevaban lo peor. Y cierto verlo era cosa de admiraci\u00f3n, porque por m\u00e1s notorio que les era el mal y da\u00f1o que al retraer de nosotros resceb\u00edan, no dejaban de nos seguir hasta nos ver salidos de la cibdad. Y con esto nos volvimos a nuestro real. Y los capitanes de los otros reales nos hicieron saber c\u00f3mo aquel d\u00eda les hab\u00eda suscedido muy bien y hab\u00edan muerto mucha gente por la mar y por la tierra. Y el capit\u00e1n Pedro de Alvarado, que estaba en Tacuba, me escribi\u00f3 que hab\u00eda ganado dos o tres puentes, porque como era en la calzada que sale del mercado de Temixtit\u00e1n a Tacuba y los tres bergantines que yo le hab\u00eda dado pod\u00edan llegar por la una parte a zabordar en la mesma calzada, no hab\u00eda tenido tanto peligro como los d\u00edas pasados. Y por aquella parte de Pedro de Alvarado hab\u00eda m\u00e1s puentes y m\u00e1s quebradas en la calzada, aunque hab\u00eda menos azoteas que por las otras partes. En todo este tiempo los naturales de Yztapalapa y Oichilobuzco y Mexicacingo y Culuacan y Mezquique y Cuitaguaca, que, como he fecho relaci\u00f3n, est\u00e1n en la laguna dulce, nunca hab\u00edan querido venir de paz ni tampoco en todo este tiempo hab\u00edamos rescebido ning\u00fand da\u00f1o dellos. Y como los de Calco eran muy leales vasallos de Vuestra Majestad y v\u00edan que nosotros ten\u00edamos bien que hacer con los de la grand cibdad, junt\u00e1ronse con otras poblaciones que est\u00e1n alrededor de las lagunas y hac\u00edan todo el da\u00f1o que pod\u00edan a aqu\u00e9llos del agua. Y ellos viendo c\u00f3mo de cada d\u00eda hab\u00edamos vitoria contra los de Temixtit\u00e1n y por el da\u00f1o que resceb\u00edan y podr\u00edan rescebir de nuestros amigos acordaron de venir, y llegaron a nuestro real y rog\u00e1ronme que les perdonase lo pasado y que mandase a los de Calco y a los otros sus vecinos que no les hiciesen mas da\u00f1o. Y yo les dije que me plac\u00eda y que no ten\u00eda enojo dellos salvo de los de la cibdad, y que para que creyese que su amistad era verdadera, que les rogaba que porque mi determinaci\u00f3n era de no levantar el real hasta tomar por paz o por guerra a los de la cibdad y ellos ten\u00edan muchas canoas para me ayudar, que hiciesen apercebir todas las que pudiesen con toda la m\u00e1s gente de guerra que en sus poblaciones hab\u00eda para que por el agua viniesen en nuestra ayuda de ah\u00ed en delante. Y tambi\u00e9n les rogaba que porque los espa\u00f1oles ten\u00edan pocas y ruines chozas y era tiempo de muchas aguas, que hiciesen en el real todas las m\u00e1s casas que pudiesen y que trujesen canoas para traer adobes y madera de las casas de la cibdad que estaban m\u00e1s cercanas al real. Y ellos dijeron que las canoas y gente de guerra estaban apercebidas para cada d\u00eda. Y en el facer de las casas sirvieron tan bien que de una parte y de la otra de las dos torres de la calzada donde yo estaba aposentado hicieron tantas que dende la primera casa hasta la postrera hab\u00eda m\u00e1s de tres o cuatro tiros de ballesta. Y vea Vuestra Majestad qu\u00e9 tan ancha puede ser la calzada que va por lo m\u00e1s hondo de la laguna que de la una parte y de la otra iban estas casas y quedaba en medio hecha calle, que muy a placer a pie y a caballo \u00edbamos y ven\u00edamos por ella. Y hab\u00eda a la continua en el real con espa\u00f1oles e indios que les serv\u00edan m\u00e1s de dos mill personas, porque toda la otra gente de guerra nuestros amigos se aposentaban en Cuyoacan, que est\u00e1 legua y media del real. Y tambi\u00e9n \u00e9stos destas poblaciones nos prove\u00edan de algunos mantenimientos de que ten\u00edamos harta nescesidad, especialmente de pescado y de cerezas, que hay tantas que pueden bastecer en cinco o seis meses del a\u00f1o que turan a doblada gente de la que en esta tierra hay. Como dos o tres d\u00edas arreo hab\u00edamos entrado por la parte de nuestro real en la cibdad &#8211; sin otras tres o cuatro que hab\u00edamos entrado &#8211; y siempre hab\u00edamos vitoria contra los enemigos y con los tiros y ballestas y escopetas mat\u00e1bamos infinitos, pens\u00e1bamos que de cada hora se movieran a nos acometer con la paz, la cual dese\u00e1bamos como a la salvaci\u00f3n. Y ninguna cosa nos aprovechaba para los atraer a este prop\u00f3sito, y por los poner en m\u00e1s nescesidad y ver si los podr\u00eda constre\u00f1ir de venir a la paz propuse de entrar en la cibdad cada d\u00eda y combat\u00edles con la gente que llevaba por tres o cuatro partes. Y fice venir toda la gente de aquellas cibdades del agua en sus canoas y aquel d\u00eda por la ma\u00f1ana hab\u00eda en nuestro real m\u00e1s de cient mill hombres nuestros amigos, y mand\u00e9 que los cuatro bergantines con la mitad de canoas, que ser\u00edan fasta mill y quinientas, fuesen por la una parte y que los tres con otras tantas que fuesen por otra y corriesen todo lo m\u00e1s de la cibdad en torno y quemasen y ficiesen todo el m\u00e1s da\u00f1o que pudiesen. Y yo entr\u00e9 por la calle prencipal adelante y fall\u00e1mosla toda desembarazada fasta las casas grandes de la plaza, que ninguna de las puentes estaba abierta, y pas\u00e9 adelante a la calle que va a salir a Tacuba en que hab\u00eda otras seis o siete puentes. Y de all\u00ed prove\u00ed que un capit\u00e1n entrase por otra calle con sesenta o setenta hombres y seis de caballo fuesen a las espaldas para los asegurar, y con ellos iban m\u00e1s de diez o doce mill indios nuestros amigos, y mand\u00e9 a otro capit\u00e1n que por otra calle ficiese lo mismo. Y yo con la gente que me quedaba segu\u00ed por la calle de Tacuba adelante y ganamos tres puentes, las cuales se cegaron, y dejamos para otro d\u00eda las otras porque era tarde y se pudiesen mejor ganar , porque yo deseaba mucho que toda aquella calle se ganase porque la gente del real de Pedro de Alvarado se comunicase con la nuestra y pasasen del un real al otro y los bergantines ficiesen lo mesmo. Y este d\u00eda fue de mucha vitoria as\u00ed por el agua como por la tierra, y h\u00f3bose mucho despojo de los de la cibdad. En los reales del alguacil mayor y Pedro de Alvarado se hobo tambi\u00e9n mucha vitoria. Otro d\u00eda siguiente volv\u00ed a entrar en la cibdad por la orden que el d\u00eda pasado, y di\u00f3nos Dios tanta vitoria que por las partes donde yo entraba con la gente no paresc\u00eda que hab\u00eda ninguna resistencia, y los enemigos se retra\u00edan tan reciamente que paresc\u00eda que les ten\u00edamos ganado las tres cuartas partes de la cibdad. Y tambi\u00e9n por el real de Pedro de [Al]varado les daban mucha priesa, y sin duda el d\u00eda pasado y aqu\u00e9ste yo ten\u00eda por cierto que vinieran de paz, de la cual yo siempre con vitoria y sin ella hac\u00eda todas las muestras que pod\u00eda, y nunca por esto en ellos hall\u00e1bamos ninguna se\u00f1al de paz. Y aquel d\u00eda nos volvimos al real con mucho placer, aunque no nos dejaba de pesar en el alma por ver tan determinados de morir a los de la c\u00edbdad. En estos d\u00edas pasados Pedro de Alvarado hab\u00eda ganado muchas puentes, y por las sustentar y guardar pon\u00eda velas de pie y de caballo de noche en ellas, y la otra gente \u00edbase al real que estaba tres cuartos de legua de all\u00ed. Y porque este trabajo era incomportable acord\u00f3 de pasar el real al cabo de la calzada que va a dar al mercado de Temixtit\u00e1n, que es una plaza harto mayor que la de Salamanca y toda cercada de portales a la redonda. Y para llegar a ella no le faltaban de ganar sino otras dos o tres puentes, pero eran muy anchas y pel\u00edgrosas de ganar, y as\u00ed estuvo algunos d\u00edas que siempre peleaba y hab\u00eda vitoria. Y aquel d\u00eda que digo en el cap\u00edtulo antes d\u00e9ste, como v\u00eda que los enemigos mostraban flaqueza y que por donde yo estaba les daba muy continuos y recios combates, ceb\u00f3se tanto en el sabor de la vitoria y de las muchas puentes y albarradas que les hab\u00eda ganado que determin\u00f3 de les pasar y ganar una puente en que hab\u00eda m\u00e1s de sesenta pasos desfechos de la calzada, todo de agua de hondura de estado y medio y dos. Y como acometieron aquel mesmo d\u00eda y los bergantines ayudaron mucho pasaron el agua y ganaron la puente y siguen tras los enemigos que iban puestos en huida. Y Pedro de Alvarado daba mucha priesa en que se cegase aquel paso porque pasasen los de caballo y tambi\u00e9n porque cada d\u00eda por escrito y por palabra le amonestaba que no ganase un palmo de tierra sin que quedase muy seguro para entrar y salir los de caballo, porque \u00e9stos fac\u00edan la guerra. Y como los de la cibdad vieron que no hab\u00eda m\u00e1s de cuarenta o cincuenta espa\u00f1oles de la otra parte y algunos amigos nuestros y que los de caballo no pod\u00edan pasar, revuelven sobre ellos tan de s\u00fapito que los ficieron volver las espaldas y echar al agua, y tomaron vivos tres o cuatro espa\u00f1oles que luego fueron a sacrificar y mataron algunos amigos nuestros. Y al fin Pedro de Alvarado se retrajo a su real. Y como aquel d\u00eda yo llegu\u00e9 al nuestro y supe lo que le hab\u00eda acaescido fue la cosa del mundo que m\u00e1s me pes\u00f3, porque era ocasi\u00f3n de dar esfuerzo a los enemigos y creer que en ninguna manera les osar\u00edamos entrar. La cabsa porque Pedro de Alvarado quiso tomar aquel mal paso fue, como digo, ver que hab\u00eda ganado mucha parte de la fuerza de los indios y que ellos mostraban alguna flaqueza, y prencipalmente porque la gente de su real importunaban que ganasen el mercado, porque aqu\u00e9l ganado, era toda la cibdad casi tomada, y toda su fuerza y esperanza de los indios ten\u00edan all\u00ed. Y como los del dicho real de Alvarado v\u00edan que yo continuaba mucho los combates de la cibdad, cre\u00edan que yo hab\u00eda de ganar primero que ellos el dicho mercado, y como estaban m\u00e1s cerca d\u00e9l que nosotros ten\u00edan por caso de honra no le ganar primero, y por esto el dicho Pedro de Alvarado era muy importunado. Y lo mesmo me acaesc\u00eda a m\u00ed en nuestro real, porque todos los espa\u00f1oles me ahincaban muy recio que por una de tres calles que iban a dar al dicho mercado entr\u00e1semos, porque no ten\u00edamos resistencia y ganado aqu\u00e9l, tem\u00edamos menos trabajo. Y yo desimulaba por todas las v\u00edas que pod\u00eda por no lo hacer aunque les encubr\u00eda la causa, y esto era por los inconvinientes y peligros que se me representaban, porque para entrar en el mercado hab\u00eda infinitas azoteas y puentes y calzadas rompidas, y en tal manera que cada casa por donde hab\u00edamos de ir estaba hecha como isla en medio del agua. Como aquella tarde que llegu\u00e9 al real supe del desbarato de Pedro de Alvarado, otro d\u00eda de ma\u00f1ana acord\u00e9 de ir a su real para le reprehender lo pasado y para ver lo que hab\u00eda ganado y en qu\u00e9 parte hab\u00eda pasado el real, y para le avisar de lo que fuese m\u00e1s nescesario para su seguridad y ofensa de los enemigos. Y como yo llegu\u00e9 a su real sin duda me espant\u00e9 de lo mucho que estaba metido en la cibdad y de los malos pasos y puentes que les hab\u00eda ganado. Y visto, no le imput\u00e9 tanta culpa como antes paresc\u00eda tener, y platicado cerca de lo que hab\u00eda de hacer, yo me volv\u00ed a nuestro real aquel d\u00eda. Pasado esto, yo fice algunas entradas en la cibdad por las partes que sol\u00eda. Y combat\u00edan los bergantines y canoas por dos partes y yo por la cibdad por otras cuatro, y siempre hab\u00edamos vitoria y se mataba mucha gente de los contrarios, porque cada d\u00eda ven\u00eda gente sin n\u00famero en nuestro favor. Y yo dilataba de me meter m\u00e1s adentro en la cibdad, lo uno por ver si revocar\u00edan el prop\u00f3sito y dureza que los contrarios ten\u00edan; y lo otro porque nuestra entrada no pod\u00eda ser sin mucho peligro, porque ellos estaban muy juntos y fuertes y muy determinados de morir. Y como los espa\u00f1oles ve\u00edan tanta dilaci\u00f3n en esto y que hab\u00eda m\u00e1s de veinte d\u00edas que nunca dejaban de pelear, importun\u00e1banme en gran manera, como arriba he dicho, que entr\u00e1semos y tom\u00e1semos el mercado, porque ganado, a los enemigos les quedaba poco lugar por donde se defender; y que si no se quisiesen dar, que de hambre y sed se morer\u00edan porque no ten\u00edan qu\u00e9 beber sino agua salada de la laguna. Y como yo me escusaba, el tesorero de Vuestra Majestad me dijo que todo el real afirmaba aquello y que lo deb\u00eda de hacer. Y a \u00e9l y a otras personas de bien que all\u00ed estaban les respond\u00ed que su prop\u00f3sito y deseo era muy bueno y que yo lo deseaba m\u00e1s que nadie, pero que yo lo dejaba de hacer por lo que con importunaci\u00f3n me hac\u00edan decir, que era que aunque \u00e9l y otras personas lo hiciesen como buenos, como en aquello se ofresc\u00eda mucho peligro habr\u00eda otros que no lo hiciesen. Y al fin tanto me forzaron que yo conced\u00ed que se har\u00eda en este caso lo que yo pudiese, concert\u00e1ndose primero con la gente de los otros reales. Otro d\u00eda me junt\u00e9 con algunas personas prencipales de nuestro real y acordamos de hacer saber al alguacil mayor y a Pedro de Alvarado c\u00f3mo otro d\u00eda siguiente hab\u00edamos de entrar en la cibdad y trabajar de llegar al mercado. Y escrib\u00edles lo que ellos hab\u00edan de hacer por la parte de Tacuba, y dem\u00e1s de lo escribir, para que mejor fuesen informados invi\u00e9les dos criados m\u00edos para que les avisasen de todo el negocio. Y la orden que hab\u00edan de tener era que el alguacil mayor se viniese con diez de caballo y cient peones y quince ballesteros y escopeteros al real de Pedro de Alvarado y que en el suyo quedasen otros diez de caballo; y que dejase concertado con ellos que otro d\u00eda que hab\u00eda de ser el combate se pusiesen en celada tras unas casas y que hiciesen alzar todo el fardaje como que levantaban el real, porque los de la cibdad saliesen tras dellos y la celada les diese en las espaldas; y que el dicho alguacil mayor con los tres bergantines que ten\u00eda y con los otros tres de Pedro de Alvarado ganase aquel paso malo donde desbarataron a Pedro de Alvarado y diese mucha priesa en lo cegar, y que pasasen adelante y que en ninguna manera se alejasen ni ganasen un paso sin lo dejar primero ciego y adreszado; y que si pudiesen sin mucho riesgo y peligro ganar hasta el mercado, que lo trabajasen mucho, porque yo hab\u00edan de hacer lo mesmo; que mirasen que aunque esto les inviaba a decir, no era para los obligar a ganar un paso solo de que les pudiese venir alg\u00fand desbarato o desm\u00e1n. Y esto les avisaba porque conosc\u00eda de sus personas que hab\u00edan de poner el rostro donde yo les dijese, aunque supiesen perder las vidas. Despachados aquellos dos criados m\u00edos con este recabdo, fueron al real y hallaron en \u00e9l a los dichos alguacil mayor y a Pedro de Alvarado, a los cuales significaron todo el caso seg\u00fand que ac\u00e1 en nuestro real lo ten\u00edamos concertado. Y porque ellos hab\u00edan de combatir por sola una parte y yo por muchas invi\u00e9les a decir que me inviasen setenta u ochenta hom Page 394 missing partes. Y dem\u00e1s destos tres combates que d\u00e1bamos a los de la cibdad, era tanta la gente de nuestros amigos que por las azoteas y por otras partes les entraban, que no paresc\u00eda que hab\u00eda cosa que nos pudiesen ofender. Y como les ganamos aquellas dos puentes y albarradas y la calzada los espa\u00f1oles, nuestros amigos siguieron por la calle adelante sin se les amparar cosa ninguna. Y yo me qued\u00e9 con obra de veinte espa\u00f1oles en una isleta que all\u00ed se hac\u00eda porque v\u00eda que ciertos amigos nuestros andaban envueltos con los enemigos y algunas veces los retra\u00edan hasta los echar al agua y con nuestro favor revolv\u00edan sobre ellos. Y dem\u00e1s desto guard\u00e1bamos que por ciertas traviesas de calles los de la cibdad no saliesen a tomar las espaldas a los espa\u00f1oles que hab\u00edan seguido la calle adelante, los cuales en esta saz\u00f3n me inviaron a decir que hab\u00edan ganado mucho y que no estaban muy lejos de la plaza del mercado, que en todo caso quer\u00edan pasar adelante porque ya o\u00edan el combate que el alguacil mayor y Pedro de Alvarado daban por su estancia. Y yo les invi\u00e9 a decir que en ninguna manera diesen paso adelante sin que primero las puentes quedasen muy bien ciegas, de manera que si tuviesen nescesidad de se retraer el agua no les ficiese estorbo ni embarazo alguno, pues sab\u00edan que en todo aquello estaba el peligro. Y ellos me tornaron a decir que todo lo que hab\u00edan ganado estaba bien reparado, que fuese all\u00ed y lo ver\u00eda si era as\u00ed. Y yo con recelo que no se desmandasen y dejasen ruin recabdo en el cegar de las puentes fue all\u00e1 y hall\u00e9 que hab\u00edan pasado una quebrada de la calle que era de diez o doce pasos en ancho, y el agua que por ella pasaba era de hondura de m\u00e1s de dos estados. Y al tiempo que la pasaron hab\u00edan echado en ella madera y ca\u00f1as de carrizo, y como pasaban pocos a pocos y con tiento no se hab\u00eda hundido la madera y ca\u00f1as. Y ellos con el placer de la vitor\u00eda \u00edban tan embebecidos que pensaban que quedaba muy fijo, y al punto que yo llegu\u00e9 a aquella puente de agua quitada vi que los espa\u00f1oles y muchos de nuestros amigos ven\u00edan puestos en muy grand huida y los enemigos como perros dando en ellos. Y como yo vi tan grand desm\u00e1n comenc\u00e9 a dar voces: itener, tener! Y ya que yo estaba junto al agua ha ll\u00e9la toda llena de espa\u00f1oles e indios y de manera que no paresc\u00eda que en ella hobiesen echado una paja, y los enemigos cargaron tanto que matando en los espa\u00f1oles se echaban al agua tras ellos. Y ya por la calle del agua ven\u00edan canoas de los enemigos y tomaban vivos los espa\u00f1oles, y como el negocio fue tan de s\u00fapito y vi que me mataban la gente, determin\u00e9 de que darme all\u00ed y morir peleando. Y en lo que m\u00e1s aprovech\u00e1bamos yo y los otros que all\u00ed estaban conmigo era en dar las manos a algunos tristes espa\u00f1oles que se ahogaban para que saliesen afuera, y los unos sal\u00edan heridos y los otros medio ahogados y otros sin armas, e invi\u00e1balos que se fuesen adelante. Y ya en esto cargaba tanta gente de los enemigos que a m\u00ed y a otros doce o quince que conmigo estaban nos ten\u00edan por todas partes cercados. Y como yo estaba muy metido en socorrer a los que se ahogaban, no miraba ni me acordaba del da\u00f1o que pod\u00eda rescebir, y ya me ven\u00edan a asir ciertos indios de los enemigos, y me llevaran si no fuera por un capit\u00e1n de cincuenta hombres que yo tra\u00eda siempre conmigo y por un mancebo de su compa\u00f1\u00eda, el cual despu\u00e9s de Dios me dio la vida, y por d\u00e1rmela como valiente hombre perdi\u00f3 all\u00ed la suya. En este comedio los espa\u00f1oles que sal\u00edan desbaratados \u00edbanse por aquella calzada adelante, y como era peque\u00f1a y angosta e igual a la agua -que los perros la hab\u00edan hecho ans\u00ed de industria &#8211; e iban por ella tambi\u00e9n desbaratados muchos de los nuestros amigos, iba el camino tan embarazado y tardaban tanto en andar que los enemigos ten\u00edan lugar de llegar por el agua de la una parte y de la otra y tomar y matar cuantos quer\u00edan. Y aquel capit\u00e1n que estaba conmigo, que se dice Antonio de Qui\u00f1ones, d\u00edjome: \u00abVamos de aqu\u00ed y salvemos vuestra persona, pues sab\u00e9is que sin ella ninguno de nosotros puede escapar\u00bb. Y no pod\u00eda acabar conmigo que me fuese de all\u00ed. Y como esto vio asi\u00f3me de los brazos para que di\u00e9semos la vuelta, y aunque yo holgara m\u00e1s con la muerte que con la vida, por importunaci\u00f3n de aquel capit\u00e1n y de otros compa\u00f1eros que all\u00ed estaban nos comenzamos a retraer peleando con nuestras espadas y rodelas con los enemigos que ven\u00edan heriendo en nosotros. Y en esto llega un criado m\u00edo a caballo e hizo alg\u00fand poquito de lugar, pero luego dende una azotea baja le dieron una lanzada por la garganta, que le hicieron dar la vuelta. Y estando en este tan grand conflito esperando que la gente pasase por aquella calzadilla a ponerse en salvo y nosotros deteniendo los enemigos, lleg\u00f3 un mozo m\u00edo con un caballo para que cabalgase, porque era tanto el lodo que hab\u00eda en la cazaldilla de los que entraban y sal\u00edan por el agua que no hab\u00eda persona que se pudiese tener, mayormente con los empellones que los unos y otros se daban por salvarse. Y yo cabalgu\u00e9, pero no para pelear, porque all\u00ed era imposible poderse hacer a caballo, porque si pudiera ser antes de la calzadilla en una isleta se hab\u00edan hallado los ocho de caballo que yo hab\u00eda dejado y no hab\u00edan podido hacer menos de se volver por ella, y aun la vuelta era tan peligrosa que dos yeguas en que iban dos criados m\u00edos cayeron de aquella calzadilla en el agua, y la una mataron los indios y la otra salvaron unos peones. Y otro mancebo criado m\u00edo que se dec\u00eda Crist\u00f3bal de Guzm\u00e1n cabalg\u00f3 en un caballo que all\u00ed en la isleta le dieron para me lo llevar, en que me pudiese salvar. Y a \u00e9l y al caballo antes que a m\u00ed llegase mataron los enemigos, la muerte del cual puso a todo el real en tanta tristeza que fasta hoy est\u00e1 reciente el dolor de los que lo conosc\u00edan. Y ya con todos nuestros trabajos plugo a Dios que los que quedamos salimos a la calle de Tacuba, que era bien ancha. Y recogida la gente, yo con nueve de caballo me qued\u00e9 en la retroguarda, y los enemigos ven\u00edan con tanta vitoria y orgullo que no paresc\u00eda sino que ninguno hab\u00edan de dejar a vida. Y retray\u00e9ndome lo mejor que pude, invi\u00e9 a decir al tesorero y al contador que se retrujesen a la plaza con mucho concierto. Lo mesmo invi\u00e9 a decir a los otros dos capitanes que hab\u00edan entrado por la calle que iba al mercado. Y los unos y los otros hab\u00edan peleado valientemente y ganado muchas albarradas y puentes que hab\u00edan muy bien cegado, lo cual fue causa de no rescebir da\u00f1o al retraer. Y antes que [los d]el tesorero y contador se retrujesen ya los de la cibdad por encima del albarrada donde peleaban les hab\u00edan echado dos o tres cabezas de cristianos, aunque no supieron por entonces si eran de los del real de Pedro de Alvarado o del nuestro. Y recogidos todos a la plaza, cargaba por todas partes tanta gente de los enemigos sobre nosotros que ten\u00edamos bien que hacer en los desviar, y por lugares y partes donde antes deste desbarato no osaran esperar a tres de caballo y a diez peones. E incontinente en una torre alta de sus \u00eddolos que estaba all\u00ed junto a la plaza pusieron muchos perfumes y sahumerios de unas gomas que hay en esta tierra, que paresce mucho a anime, lo cual ellos ofrescen a sus \u00eddolos en se\u00f1al de vitoria. Y aunque quisi\u00e9ramos mucho estorb\u00e1rselo no se pudo hacer, porque ya la gente a m\u00e1s andar se iban hacia el real. En este desbarato mataron los contrarios treinta y cinco o cuarenta espa\u00f1oles y m\u00e1s de mill indios nuestros amigos, e hirieron m\u00e1s de veinte cristianos y yo sal\u00ed herido en una pierna. Perdi\u00f3se el tiro peque\u00f1o de campo que hab\u00edamos llevado y muchas ballestas y escopetas y armas. Los de la cibdad, luego que hobieron la vitoria, por hacer desmayar al alguacil mayor y Pedro de Alvarado, todos los espa\u00f1oles vivos y muertos que tomaron los llevaron al Tatabulco, que es el mercado, y en unas torres altas que all\u00ed estaban desnudos los sacrificaron y abrieron por los pechos y les sacaron los corazones para ofrescer a los \u00eddolos, lo cual los espa\u00f1oles del real de Pedro de Alvarado pudieron ver bien de donde peleaban, y en los cuerpos desnudos y blancos que vieron sacrificar conoscieron que eran cristianos. Y aunque por ello hobieron grand tristeza y desmayo, se retrajeron a su real, habiendo peleando aquel d\u00eda muy bien y ganado casi hasta el dicho mercado, el cual aquel d\u00eda se acabara de ganar si Dios, por nuestros pecados, no permitiera tan gran desm\u00e1n. Nosotros fuemos a nuestro real con grand tristeza algo m\u00e1s temprano que los otros d\u00edas nos sol\u00edamos retraer, y tambi\u00e9n porque nos dec\u00edan que los bergantines eran perdidos porque los de la cibdad con las canoas nos tomaban las espaldas, aunque plugo a Dios que no fue ans\u00ed, puesto que los bergantines y las canoas de nuestros amigos se vieron en harto estrecho, y tanto que un bergant\u00edn se err\u00f3 poco de perder e hirieron al capit\u00e1n y maestre d\u00e9l. Y el capit\u00e1n muri\u00f3 dende a ocho d\u00edas. Aquel d\u00eda y la noche siguiente los de la cibdad hac\u00edan muchos regocijos de bocinas y atabales, que paresc\u00eda que se hund\u00eda el mundo, y abrieron todas las calles y puentes del agua como de antes las ten\u00edan y llegaron a poner sus fuegos y velas de noche a dos tiros de ballesta de nuestro real. Y como todos salimos tan desbaratados y heridos y sin armas, hab\u00eda nescesidad de descansar y rehacemos. En este comedio los de la cibdad tuvieron lugar de inviar sus mensajeros a muchas provincias a ellos subjetas a decir como hab\u00edan habido mucha vitoria y muerto muchos cristianos y que muy presto nos acabar\u00edan, que en ninguna manera tratasen paz con nosotros. Y la creencia que llevaban eran las dos cabezas de caballos que mataron y otras algunas de los cristianos, las cuales anduvieron mostrando por donde a ellos paresc\u00eda que conven\u00eda, que fue mucha ocasi\u00f3n de poner en m\u00e1s contumacia a los rebelados que de antes. Mas con todo, porque los de la cibdad no tomasen m\u00e1s orgullo ni sintiesen nuestra flaqueza, cada d\u00eda algunos espa\u00f1oles de pie y de caballo con muchos de nuestros amigos iban a pelear a la cibdad, aunque nunca pod\u00edan ganar m\u00e1s de algunas puentes de la primera calle antes de llegar a la plaza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TERCERA RELACI\u00d3N &#8211; Parte 2 Y yo me part\u00ed y a las diez del d\u00eda llegamos a Guastepeque, de que arriba he fecho menci\u00f3n, y en la casa de una huerta del se\u00f1or de all\u00ed nos aposentamos todos, la cual huerta es la mayor y m\u00e1s fermosa y fresca que\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[1,5,1109],"tags":[1010,1016,1012,1018,1011,1015,1034,1054,1044,1057,1025,1033],"class_list":["post-1234","post","type-post","status-publish","format-standard","hentry","category-historia","category-literatura","category-textos-literarios","tag-amor","tag-arte","tag-ave","tag-ayuda","tag-corazon","tag-flor","tag-guerra","tag-industria","tag-jardin","tag-pensamiento","tag-rosa","tag-vino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-22T10:36:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-22T01:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"88 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cartas-de-relacion-de-hernan-cortes-iii-ii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cartas-de-relacion-de-hernan-cortes-iii-ii\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II)\",\"datePublished\":\"2011-02-22T10:36:43+00:00\",\"dateModified\":\"2018-12-22T01:13:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cartas-de-relacion-de-hernan-cortes-iii-ii\\\/\"},\"wordCount\":17517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"keywords\":[\"amor\",\"arte\",\"ave\",\"ayuda\",\"corazon\",\"flor\",\"guerra\",\"industria\",\"jardin\",\"pensamiento\",\"rosa\",\"vino\"],\"articleSection\":[\"Historia\",\"Literatura \\\/ Po\u00e9tica\",\"Textos literarios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cartas-de-relacion-de-hernan-cortes-iii-ii\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cartas-de-relacion-de-hernan-cortes-iii-ii\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cartas-de-relacion-de-hernan-cortes-iii-ii\\\/\",\"name\":\"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"datePublished\":\"2011-02-22T10:36:43+00:00\",\"dateModified\":\"2018-12-22T01:13:00+00:00\",\"description\":\"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cartas-de-relacion-de-hernan-cortes-iii-ii\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cartas-de-relacion-de-hernan-cortes-iii-ii\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/cartas-de-relacion-de-hernan-cortes-iii-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa","description":"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/","og_locale":"es_ES","og_type":"article","og_title":"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa","og_description":"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2011-02-22T10:36:43+00:00","article_modified_time":"2018-12-22T01:13:00+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"88 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II)","datePublished":"2011-02-22T10:36:43+00:00","dateModified":"2018-12-22T01:13:00+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/"},"wordCount":17517,"commentCount":0,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"keywords":["amor","arte","ave","ayuda","corazon","flor","guerra","industria","jardin","pensamiento","rosa","vino"],"articleSection":["Historia","Literatura \/ Po\u00e9tica","Textos literarios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/","url":"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/","name":"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"datePublished":"2011-02-22T10:36:43+00:00","dateModified":"2018-12-22T01:13:00+00:00","description":"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II) - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/cartas-de-relacion-de-hernan-cortes-iii-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"Cartas de Relaci\u00f3n de Hern\u00e1n Cort\u00e9s (III-II)"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":0,"uagb_excerpt":"TERCERA RELACI\u00d3N &#8211; Parte 2 Y yo me part\u00ed y a las diez del d\u00eda llegamos a Guastepeque, de que arriba he fecho menci\u00f3n, y en la casa de una huerta del se\u00f1or de all\u00ed nos aposentamos todos, la cual huerta es la mayor y m\u00e1s fermosa y fresca que\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/1234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=1234"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/1234\/revisions"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=1234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=1234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=1234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}