{"id":116,"date":"2023-07-18T03:02:29","date_gmt":"2023-07-18T01:02:29","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=116"},"modified":"2023-07-18T03:02:29","modified_gmt":"2023-07-18T01:02:29","slug":"el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/","title":{"rendered":"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa"},"content":{"rendered":"<p><span class=\"subtit\" style=\"color: #993300\"><strong>\u00a0<\/strong><\/span><\/p>\n<p><span class=\"subtit\" style=\"color: #993300\"><strong>Historia del museo<\/strong><\/span><\/p>\n<p>El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa es el museo estatal m\u00e1s antiguo de nuestro pa\u00eds y se constituye en la sede del Sistema Nacional de Museos del Estado. Su importancia radica en el vasto y variado patrimonio cultural que albergan sus salas de exposici\u00f3n y dep\u00f3sitos.<\/p>\n<p>Ceramios, textiles, metales, material org\u00e1nico y l\u00edticos relacionados a invalorables restos humanos conservados con t\u00e9cnicas que a\u00fan sorprenden a los especialistas, conforman el legado de nuestro pasado prehisp\u00e1nico. Objetos de valor hist\u00f3rico-art\u00edstico y fondos documentales, fotogr\u00e1ficos y bibliogr\u00e1ficos dan cuenta de los per\u00edodos<\/p>\n<p>colonial y republicano. Todos ellos hacen de este espacio un lugar de encuentro con la historia del Per\u00fa.<\/p>\n<p>Su hist\u00f3rica arquitectura se constituye en el lugar ideal donde todos, sin importar su edad y procedencia, pueden descubrir, revivir y cuestionar las vivencias de nuestros antepasados. Invitamos a los turistas nacionales y extranjeros, ni\u00f1os y adultos, investigadores y acad\u00e9micos instituciones culturales y empresariales y al p\u00fablico en general a deleitarse y experimentar con las diversas actividades que desarrollamos y a hacer uso de los espacios que el museo ofrece.<\/p>\n<p><span class=\"subtit\" style=\"color: #993300\"><strong>Cronistas y viajeros que vieron el Per\u00fa<\/strong><\/span><\/p>\n<p>El contacto con Occidente no s\u00f3lo provoc\u00f3 una relaci\u00f3n conflictiva y desigual entre ambos mundos sino que tambi\u00e9n permiti\u00f3 reconocer las otras formas de comportamiento de gente tan diferente como los americanos.<\/p>\n<p>Estos hechos se ven reflejados en la en la descripci\u00f3n de cr\u00f3nicas e informes de viajes sobre la vida de nuestros pueblos, destacando los escritos de los primeros cronistas espa\u00f1oles como Pedro Cieza de Le\u00f3n, Juan de Betanzos. Miguel de Estete, Pedro Sancho y Crist\u00f3bal de Mena y de los cronistas \u00abind\u00edgenas\u00bb como Garcilaso de la Vega, Felipe Guaman Poma de Ayala, Joan Santa Cruz Pachacuti y Titu Cusi Yupanqui.<\/p>\n<p>Posteriormente, unos cuantos se dedicaron a constituir \u00abgabinetes\u00bb y colecciones de objetos ex\u00f3ticos y notables, tanto de plantas, animales y minerales, como de objetos de los \u00abantiguos pobladores\u00bb. Los principales coleccionistas \u00absistem\u00e1ticos\u00bb de objetos fueron el obispo Baltasar Mart\u00ednez de Compa\u00f1\u00f3n, el oidor Pedro Bravo de Lagunas y la familia Ortiz de Zevallos.<\/p>\n<p>Hacia el siglo XIX, viajeros extranjeros como Leonce Angrand, Mauricio Rugendas, George Squier y Charles Wiener, recorrieron el pa\u00eds graficando y registrando datos sobre los \u00abindios de la \u00e9poca\u00bb.<\/p>\n<p><span style=\"color: #993300\"><strong>Los Tiempos de la Norma <\/strong><\/span><\/p>\n<p>El Decreto Supremo del 2 de abril de 1822 buscaba la consolidaci\u00f3n de una conciencia nacional de base nativa, as\u00ed como la defensa del patrimonio cultural y natural. El marqu\u00e9s de Torre Tagle fue quien firm\u00f3 la norma por el General San Mart\u00edn, sin embargo fue Don Bernardo de Monteagudo el principal promotor en la constituci\u00f3n de este significativo Decreto.<\/p>\n<p><strong>El Decreto<\/strong><\/p>\n<p>\u00abEl Supremo Delegado &#8211; He acordado y decreto :<br \/>\nArt. 1 Se prohibe absolutamente la extracci\u00f3n de piedras, obras antiguas de alfarer\u00eda, tejidos y dem\u00e1s objetos que se encuentran en las huacas, sin expresa y especial licencia del Gobierno, dada con alguna mira y utilidad p\u00fablica.<\/p>\n<p>Art. 2.- El que contraviniere al art\u00edculo anterior, incurrir\u00e1 en las penas de perdimiento de la especie, sea poco o mucho su valor, lo que se aplicar\u00e1 al Museo Nacional, y m\u00e1s de mil pesos de multa aplicados a los fondos destinados a la Instrucci\u00f3n P\u00fablica.\u00bb<\/p>\n<p><strong><span style=\"color: #000000\">Los inicios del Museo Nacional<\/span><\/strong><\/p>\n<p>El primer director Don Mariano Rivero de Ustariz asumi\u00f3 la tarea de instalar el proyectado Museo Nacional en 1826.<\/p>\n<p>La primera colecci\u00f3n del Museo se form\u00f3 a instancias del gobierno, que solicit\u00f3 donaciones de objetos valiosos de tiempos de de la gentilidad y de los tres reinos.<\/p>\n<p>Rivero y Ustariz, increment\u00f3 las colecciones arqueol\u00f3gicas recorriendo las principales ruinas y recuperando materiales encontrados bajo los escombros, los que extrajo para su conservaci\u00f3n.<\/p>\n<p><strong><span class=\"negrita\" style=\"color: #993300\">De la Inquisici\u00f3n al Palacio<\/span><\/strong><\/p>\n<p>Entre 1822 y 1872, la situaci\u00f3n del Museo Nacional fue ambulante y precaria, pasando por diversos locales, no obstante de que las colecciones segu\u00edan increment\u00e1ndose.<\/p>\n<p>En mayo de 1872, gran parte de las colecciones del Museo Nacional fue trasladada al Palacio de la Exposici\u00f3n.<\/p>\n<p><strong>La Guerra y el Museo<\/strong><\/p>\n<p>Entre 1881 y 1882 , como consecuencia de la Guerra del Pac\u00edfico, la colecci\u00f3n del Museo Nacional fue llevada a Santiago de Chile como \u00abbot\u00edn\u00bb de guerra.<\/p>\n<p>Una valiosa pieza salvada del saqueo fue la Estela Raimondi y probablemente la colecci\u00f3n de \u00f3leos de los Virreyes, as\u00ed como la colecci\u00f3n Raimondi, que se encontraba en la Facultad de Medicina de Lima.<\/p>\n<p>Entre 1880 y 1905, el destino del Museo Nacional estuvo signado por el saqueo y el abandono. Fueron tiempos en que por infeliz coincidencia se formaron las principales colecciones arqueol\u00f3gicas peruanas en renombrados museos de Europa, mientras que en el Per\u00fa no exist\u00eda un Museo.<\/p>\n<p><strong>Max Hule y el Museo Nacional<\/strong><\/p>\n<p>En 1905, se instal\u00f3 en el edificio del Palacio de la Exposici\u00f3n el Museo de Historia Nacional, bajo el amparo del Instituto Hist\u00f3rico del Per\u00fa, siendo inaugurado el 29 de julio de 1906. Max Uhle, fue el encargado de la secci\u00f3n de Arqueolog\u00eda y Tribus Ind\u00edgenas del Museo, mientras que a Jos\u00e9 Augusto Izcue se le confi\u00f3 la de Historia.<\/p>\n<p>El Dr. Uhle, como director del Museo, realiz\u00f3 las primeras investigaciones de campo en sitios como la Isla San Lorenzo (Lima), Nazca (Ica) y Choquequirao (Cusco), En 1911 se deslig\u00f3 del campo y entreg\u00f3, como patrimonio nacional, el inventario de 8,675 espec\u00edmenes. Lo reemplaz\u00f3 Emilio Guti\u00e9rrez de Quintanilla como Director. D\u00e1ndole prioridad al ordenamiento administrativo.<\/p>\n<p><strong><span style=\"color: #993300\">Tello, Valc\u00e1rcel y Larco &#8211; La Universidad y los Museos Aut\u00f3nomos<\/span><\/strong><\/p>\n<p><span style=\"color: #000000\">Julio C. Tello cre\u00f3 la Secci\u00f3n de Estudios de Arqueolog\u00eda y Etnograf\u00eda del Museo de Historia Nacional . El desarrollo de la arqueolog\u00eda y antropolog\u00eda peruanas favoreci\u00f3, en 1919, la constituci\u00f3n de museos en las Universidades Nacionales de San Marcos, en Lima y de San Antonio Abad, en Cusco.<\/span><span style=\"color: #000000\">Los principales gestores de estos museos fueron Julio C. Tello y Luis E. Valc\u00e1rcel, Intelectuales respaldados por un s\u00f3lido desarrollo acad\u00e9mico. Tambi\u00e9n, por esos a\u00f1os se form\u00f3 el Museo V\u00edctor Larco Herrera, dirigido por su fundador. En 1924, este museo y su colecci\u00f3n fueron adquiridos por el gobierno.<\/span><span style=\"color: #000000\">Entre los a\u00f1os 1925 y 1945, las investigaciones en el Museo Nacional fueron intensas. Se investigaron sitios como Paracas y Wari, estudi\u00e1ndose casi toda la Costa sur, todo el valle del Rimac, la regi\u00f3n del Cusco y gran parte de los valles del Huallaga y del Mara\u00f1\u00f3n.<\/span><span style=\"color: #000000\">En el a\u00f1o 1945 se constituy\u00f3 el Consejo Superior de Museos formado por el Museo Nacional de Antropolog\u00eda y Arqueolog\u00eda, dirigido por Tello y el Museo Nacional de Historia a cargo de Valc\u00e1rcel. Entre 1955 y 1973 dirigi\u00f3 el Museo el Dr. Jorge C. Muelle.<\/span><\/p>\n<p><span style=\"color: #000000\"><strong><span style=\"color: #993300\">Transformaci\u00f3n y nuevos conceptos museol\u00f3gicos<\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #000000\">A partir de 1973, el Museo es dirigido por Luis G. Lumbreras introduciendo transformaciones en sus contenidos y recursos museogr\u00e1ficos. La investigaci\u00f3n se concentr\u00f3 en las colecciones.<\/span> <span style=\"color: #000000\">En ese per\u00edodo tambi\u00e9n se desarroll\u00f3 la idea, que desde 1963 se ten\u00eda, de proyectar la construcci\u00f3n de un nuevo Museo Nacional de Arqueolog\u00eda y Antropolog\u00eda. Situaci\u00f3n que se repite entre 1981 y 1983, cuando finalmente fue paralizada.<\/span><span style=\"color: #000000\">En 1988 se cre\u00f3 el Museo de la Naci\u00f3n, instalado en el ex Ministerio de Pesquer\u00eda y que duplicaba las funciones del Museo Nacional.<\/span><\/p>\n<p>En 1992 se fusionan el Museo Nacional de Antropolog\u00eda y Arqueolog\u00eda con su colindante el Museo Nacional de Historia, retomando en la pr\u00e1ctica el viejo proyecto del Museo de Historia Nacional.<\/p>\n<div align=\"center\">\n<table border=\"0\" width=\"500\" cellspacing=\"0\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div align=\"center\">\n<table border=\"0\" width=\"500\" cellspacing=\"0\" cellpadding=\"4\" bgcolor=\"#e9e9d1\">\n<tbody>\n<tr>\n<td><\/td>\n<td>\n<p align=\"left\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.natureduca.com\/logos\/logo_infoblog1.gif\" alt=\"\" width=\"15\" height=\"15\" align=\"absMiddle\" border=\"0\" \/><span style=\"color: #993300;font-size: small\"> Informaci\u00f3n procedente del Museo<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div align=\"center\">\n<table border=\"0\" width=\"500\" cellspacing=\"0\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Historia del museo El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa es el museo estatal m\u00e1s antiguo de nuestro pa\u00eds y se constituye en la sede del Sistema Nacional de Museos del Estado. Su importancia radica en el vasto y variado patrimonio cultural que albergan sus salas\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":-1,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[21,22],"tags":[1381,1379,1017,1056,1148,1380],"class_list":["post-116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-instituciones","category-museos","tag-antropologia","tag-arqueologia","tag-historia","tag-museo","tag-museos-2","tag-peru"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-18T01:02:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa\",\"datePublished\":\"2023-07-18T01:02:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/\"},\"wordCount\":1310,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.natureduca.com\\\/logos\\\/logo_infoblog1.gif\",\"keywords\":[\"antropolog\u00eda\",\"arqueologia\",\"historia\",\"museo\",\"museos\",\"Per\u00fa\"],\"articleSection\":[\"Instituciones\",\"Museos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/\",\"name\":\"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.natureduca.com\\\/logos\\\/logo_infoblog1.gif\",\"datePublished\":\"2023-07-18T01:02:29+00:00\",\"description\":\"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.natureduca.com\\\/logos\\\/logo_infoblog1.gif\",\"contentUrl\":\"http:\\\/\\\/www.natureduca.com\\\/logos\\\/logo_infoblog1.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa","description":"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/","og_locale":"es_ES","og_type":"article","og_title":"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa","og_description":"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2023-07-18T01:02:29+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa","datePublished":"2023-07-18T01:02:29+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/"},"wordCount":1310,"commentCount":1,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/#primaryimage"},"thumbnailUrl":"http:\/\/www.natureduca.com\/logos\/logo_infoblog1.gif","keywords":["antropolog\u00eda","arqueologia","historia","museo","museos","Per\u00fa"],"articleSection":["Instituciones","Museos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/","url":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/","name":"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/#primaryimage"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/#primaryimage"},"thumbnailUrl":"http:\/\/www.natureduca.com\/logos\/logo_infoblog1.gif","datePublished":"2023-07-18T01:02:29+00:00","description":"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/#primaryimage","url":"http:\/\/www.natureduca.com\/logos\/logo_infoblog1.gif","contentUrl":"http:\/\/www.natureduca.com\/logos\/logo_infoblog1.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/el-museo-nacional-de-arqueologia-antropologia-e-historia-del-peru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a0 Historia del museo El Museo Nacional de Arqueolog\u00eda, Antropolog\u00eda e Historia del Per\u00fa es el museo estatal m\u00e1s antiguo de nuestro pa\u00eds y se constituye en la sede del Sistema Nacional de Museos del Estado. Su importancia radica en el vasto y variado patrimonio cultural que albergan sus salas\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=116"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/116\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}