{"id":1013,"date":"2010-12-10T18:04:42","date_gmt":"2010-12-10T16:04:42","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=1013"},"modified":"2010-12-10T18:04:42","modified_gmt":"2010-12-10T16:04:42","slug":"%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/","title":{"rendered":"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer]"},"content":{"rendered":"<p><em>(Leyenda de Soria)<\/em><\/p>\n<p>Yo no s\u00e9 si esto es una historia que parece cuento o un cuento que parece historia; lo que puedo decir es que en su fondo hay una verdad, una verdad muy triste, de la que acaso yo ser\u00e9 uno de los \u00faltimos en aprovecharme, dadas mis condiciones de imaginaci\u00f3n.<\/p>\n<p>Otro, con esta idea, tal vez hubiera hecho un tomo de filosof\u00eda lacrimosa; yo he escrito esta leyenda, que, a los que nada vean en su fondo, al menos podr\u00e1 entretenerlos un rato.<\/p>\n<p>Era noble; hab\u00eda nacido entre el estruendo de las armas, y el ins\u00f3lito clamor de una trompa de guerra no le hubiera hecho levantar la cabeza un instante, ni apartar sus ojos un punto del oscuro pergamino en que le\u00eda la \u00faltima carta de un trovador.<\/p>\n<p>Los que quisieran encontrarlo no lo deb\u00edan buscar en el anchuroso patio de su castillo, donde los palafreneros domaban los potros, los pajes ense\u00f1aban a volar a los halcones y los soldados se entreten\u00edan los d\u00edas de reposo en afilar el hierro de su maza contra una piedra.<\/p>\n<p>-\u00bfD\u00f3nde est\u00e1 Manrique? \u00bfD\u00f3nde est\u00e1 vuestro se\u00f1or? -preguntaba algunas veces su madre.<\/p>\n<p>-No sabemos -respond\u00edan sus servidores-; acaso estar\u00e1 en el claustro del monasterio de la Pe\u00f1a; sentado al borde de una tumba, prestando o\u00eddo a ver si sorprende alguna palabra de la conversaci\u00f3n de los muertos; o en el puente, mirando correr una tras otra las olas del r\u00edo por debajo de sus arcos; o acurrucado en la quiebra de una roca y entretenido en contar las estrellas del cielo, en seguir una nube con la vista o contemplar los fuegos fatuos que cruzan como exhalaciones sobre el haz de las lagunas. En cualquiera parte estar\u00e1 menos en donde est\u00e9 todo el mundo.<\/p>\n<p>En efecto, Manrique amaba la soledad, y la amaba de tal modo, que algunas veces hubiera deseado no tener sombra por que su sombra no lo siguiese a todas partes.<\/p>\n<p>Amaba la soledad porque en su seno, dando rienda suelta a la imaginaci\u00f3n, forjaba un mundo fant\u00e1stico, habitado por extra\u00f1as creaciones, hijas de sus delirios y sus ensue\u00f1os de poeta, porque Manrique era poeta, \u00a1tanto, que nunca le hab\u00edan satisfecho las formas en que pudiera encerrar sus pensamientos, y nunca los hab\u00eda encerrado al escribirlos!<\/p>\n<p>Cre\u00eda que entre las rojas ascuas del hogar habitaban esp\u00edritus de fuego de mil colores, que corr\u00edan como insectos de oro a lo largo de los troncos encendidos, o danzaban en una luminosa ronda de chispas en la c\u00faspide de las llamas, y se pasaba las horas muertas sentado en un escabel, junto a la alta chimenea g\u00f3tica, inm\u00f3vil y con los ojos fijos en la lumbre.<\/p>\n<p>Cre\u00eda que en el fondo de las ondas del r\u00edo, entre los musgos de la fuente y sobre los vapores del lago viv\u00edan unas mujeres misteriosas, hadas, s\u00edlfides u ondinas, que exhalaban lamentos y suspiros o cantaban y se re\u00edan en el mon\u00f3tono rumor del agua, rumor que o\u00eda en silencio, intentando traducirlo.<\/p>\n<p>En las nubes, en el aire, en el fondo de los bosques, en las grietas de las pe\u00f1as imaginaba percibir formas o escuchar sonidos misteriosos, formas de seres sobrenaturales, palabras inteligibles que no pod\u00eda comprender.<\/p>\n<p>\u00a1Amar! Hab\u00eda nacido para so\u00f1ar el amor, no para sentirlo. Amaba a todas las mujeres un instante: a \u00e9sta porque era rubia, a aqu\u00e9lla porque ten\u00eda los labios rojos, a la otra porque se cimbreaba al andar, como un junco.<\/p>\n<p>Algunas veces llegaba su delirio hasta el punto de quedarse una noche entera mirando a la luna, que flotaba en el cielo entre un vapor de plata, o a las estrellas, que temblaban a lo lejos como los cambiantes de las piedras preciosas. En aquellas largas noches de po\u00e9tico insomnio exclamaba:<\/p>\n<p>-Si es verdad, como el prior de la Pe\u00f1a me ha dicho, que es posible que esos puntos de luz sean mundos; si es verdad que en ese globo de n\u00e1car que rueda sobre las nubes habitan gentes, \u00a1qu\u00e9 mujeres tan hermosas ser\u00e1n las mujeres de esas regiones luminosas! Y yo no podr\u00e9 verlas, y yo no podr\u00e9 amarlas&#8230; \u00bfC\u00f3mo ser\u00e1 su hermosura?&#8230; \u00bfC\u00f3mo ser\u00e1 su amor?<\/p>\n<p>Sobre el Duero, que pasa lamiendo las carcomidas y oscuras piedras de las murallas de Soria, hay un puente que conduce de la ciudad al antiguo convento de los Templarios, cuyas posesiones se extend\u00edan a lo largo de la opuesta margen del r\u00edo.<\/p>\n<p>En la \u00e9poca a que nos referimos, los caballeros de la Orden hab\u00edan ya abandonado sus hist\u00f3ricas fortalezas; pero a\u00fan quedaban en pie restos de los anchos torreones de sus muros; a\u00fan se ve\u00edan, como en parte se ven hoy, cubiertos de hiedra y campanillas blancas, los macizos arcos de su claustro, las prolongadas galer\u00edas ojivales de sus patios de armas, en las que suspiraba el viento con un gemido, agitando las altas hierbas.<\/p>\n<p>En los huertos y en los jardines cuyos senderos no hollaban hac\u00eda muchos a\u00f1os las plantas de los religiosos, la vegetaci\u00f3n, abandonada de s\u00ed misma, desplegaba todas sus galas, sin temor de que la mano del hombre la mutilase, creyendo embellecerla.<\/p>\n<p>Las plantas trepadoras sub\u00edan encaram\u00e1ndose por los a\u00f1osos troncos de los \u00e1rboles; y las sombr\u00edas calles de \u00e1lamos, cuyas copas se tocaban y se confund\u00edan entre s\u00ed, se hab\u00edan cubierto de c\u00e9sped; los cardos silvestres y las ortigas brotaban en medio de los enarenados caminos, y en los trozos de f\u00e1brica, pr\u00f3xima a desplomarse, el jaramago, flotando al viento como el penacho de una cimera, y las campanillas blancas y azules, balance\u00e1ndose como en un columpio sobre sus largos y flexibles tallos, pregonaban la victoria de la destrucci\u00f3n y la ruina.<\/p>\n<p>Era de noche; una noche de verano, templada, llena de perfumes y de rumores apacibles, y con una luna blanca y serena en mitad de un cielo azul, luminoso y transparente.<\/p>\n<p>Manrique, presa su imaginaci\u00f3n de un v\u00e9rtigo de poes\u00eda, despu\u00e9s de atravesar el puente, desde donde contempl\u00f3 un momento la negra silueta de la ciudad que se destacaba sobre el fondo de algunas nubes blanquecinas y ligeras arrolladas en el horizonte, se intern\u00f3 en las desiertas ruinas de los Templarios.<\/p>\n<p>La medianoche tocaba a su punto. La luna, que se hab\u00eda ido remontando lentamente, estaba ya en lo m\u00e1s alto del cielo, cuando al entrar en una oscura alameda que conduc\u00eda desde el derruido claustro a la margen del Duero, Manrique exhal\u00f3 un grito, un grito leve y ahogado, mezcla extra\u00f1a de sorpresa, de temor y de j\u00fabilo.<\/p>\n<p>En el fondo de la sombr\u00eda alameda hab\u00eda visto agitarse una cosa blanca que flot\u00f3 un momento y desapareci\u00f3 en la oscuridad. La orla del traje de una mujer, de una mujer que hab\u00eda cruzado el sendero y se ocultaba entre el follaje, en el mismo instante en que el loco so\u00f1ador de quimeras o imposibles penetraba en los jardines.<\/p>\n<p>-\u00a1Una mujer desconocida!&#8230; \u00a1En este sitio&#8230; \u00a1A estas horas! Esa, esa es la mujer que yo busco -exclam\u00f3 Manrique-; y se lanz\u00f3 en su seguimiento, r\u00e1pido como una saeta.<\/p>\n<p>Lleg\u00f3 al punto en que hab\u00eda visto perderse, entre la espesura de las ramas, a la mujer misteriosa. Hab\u00eda desaparecido. \u00bfPor d\u00f3nde? All\u00e1 lejos, muy lejos, crey\u00f3 divisar por entre los cruzados troncos de los \u00e1rboles como una claridad o una forma blanca que se mov\u00eda.<\/p>\n<p>-\u00a1Es ella, es ella, que lleva alas en los pies y huye como una sombra! -dijo, y se precipit\u00f3 en su busca, separando con las manos las redes de piedra que se extend\u00edan como un tapiz de unos en otros \u00e1lamos. Lleg\u00f3, rompiendo por entre la maleza y las plantas par\u00e1sitas, hasta una especie de rellano que iluminaba la claridad del cielo&#8230; \u00a1Nadie! \u00a1Ah!&#8230; Por aqu\u00ed, por aqu\u00ed va -exclam\u00f3 entonces-. Oigo sus pisadas sobre las hojas secas, y el crujido de su traje, que arrastra por el suelo y roza en los arbustos -y corr\u00eda, y corr\u00eda como un loco, de aqu\u00ed para all\u00e1, y no la ve\u00eda-. Pero siguen sonando sus pisadas -murmur\u00f3 otra vez-; creo que ha hablado; no hay duda, ha hablado&#8230; El viento, que suspira entre las ramas; las hojas, que parece que rezan en voz baja, me han impedido o\u00edr lo que ha dicho; pero no hay duda: va por ah\u00ed, ha hablado&#8230;, ha hablado&#8230; \u00bfEn qu\u00e9 idioma? No s\u00e9; pero es una lengua extranjera&#8230;<\/p>\n<p>Y torn\u00f3 a correr en su seguimiento, unas veces creyendo verla, otras pensando o\u00edrla: ya notando que las ramas por entre las cuales hab\u00eda desaparecido se mov\u00edan, ya imaginando distinguir en la arena la huella de sus breves pies; luego, firmemente persuadido de que un perfume especial, que aspiraba a intervalos, era un aroma perteneciente a aquella mujer que se burlaba de \u00e9l complaci\u00e9ndose en huirlo por entre aquellas intrincadas malezas. \u00a1Af\u00e1n in\u00fatil!<\/p>\n<p>Vag\u00f3 algunas horas de un lado a otro, fuera de s\u00ed, par\u00e1ndose para escuchar, ya desliz\u00e1ndose con las mayores precauciones sobre la hierba, ya en una carrera fren\u00e9tica y desesperada.<\/p>\n<p>Avanzando, avanzando por entre los inmensos jardines que bordeaban la margen del r\u00edo, lleg\u00f3 al fin al pie de las rocas sobre las que se eleva la ermita de San Saturio.<\/p>\n<p>-Tal vez, desde esta altura podr\u00e9 orientarme para seguir mis pesquisas a trav\u00e9s de ese confuso laberinto -exclam\u00f3, trepando de pe\u00f1a en pe\u00f1a con la ayuda de su daga.<\/p>\n<p>Lleg\u00f3 a la cima, desde la que se descubren la ciudad en lontananza y una gran parte del Duero, que se retuerce a sus pies, arrastrando una corriente impetuosa y oscura por entre las corvas m\u00e1rgenes que lo encarcelan.<\/p>\n<p>Manrique, una vez en lo alto de las rocas, tendi\u00f3 la vista a su alrededor; pero al tenderla y fijarla al cabo en un punto, no pudo contener una blasfemia. La luz de la luna rielaba chispeando en la estela que dejaba en pos de s\u00ed una barca que se dirig\u00eda a todo remo a la orilla opuesta.<\/p>\n<p>En aquella barca hab\u00eda cre\u00eddo distinguir una forma blanca y esbelta, una mujer sin duda, la mujer que hab\u00eda visto en los Templarios, la mujer de sus sue\u00f1os, la realizaci\u00f3n de sus m\u00e1s locas esperanzas. Se descolg\u00f3 de las pe\u00f1as con la agilidad de un gamo, arroj\u00f3 al suelo la gorra, cuya redonda y larga pluma pod\u00eda embarazarlo para correr, y desnud\u00e1ndose del ancho capotillo de terciopelo, parti\u00f3 como una exhalaci\u00f3n hac\u00eda el puente.<\/p>\n<p>Pensaba atravesarlo y llegar a la ciudad antes que la barca tocase en la otra orilla. \u00a1Locura! Cuando Manrique lleg\u00f3, jadeante y cubierto de sudor, a la entrada, ya los que hab\u00edan atravesado el Duero por la parte de San Saturio entraban en Soria por una de las puertas del muro, que en aquel tiempo llegaba hasta la margen del r\u00edo, en cuyas aguas se retrataban sus pardas almenas.<\/p>\n<p>Aunque desvanecida su esperanza de alcanzar a los que hab\u00edan entrado por el postigo de San Saturio, no por eso nuestro h\u00e9roe perdi\u00f3 la de saber la casa que en la ciudad pod\u00eda albergarlos. Fija en su mente esta idea, penetr\u00f3 en la poblaci\u00f3n y, dirigi\u00e9ndose hac\u00eda el barrio de San Juan, comenz\u00f3 a vagar por sus calles a la ventura.<\/p>\n<p>Las calles de Soria eran entonces, y lo son todav\u00eda, oscuras y tortuosas. Un silencio profundo reinaba en ellas, silencio que s\u00f3lo interrump\u00edan, ora el lejano ladrido de un perro, ora el rumor de una puerta al cerrarse, ora el relincho de corcel que piafando hac\u00eda sonar la cadena que lo sujetaba al pesebre en las subterr\u00e1neas caballerizas.<\/p>\n<p>Manrique, con el o\u00eddo atento a estos rumores de la noche, que unas veces le parec\u00edan los pasos de alguna persona que hab\u00eda doblado ya la \u00faltima esquina de un callej\u00f3n desierto; otras, voces confusas de gentes que hablaban a sus espaldas y que a cada momento esperaba ver a su lado, anduvo algunas horas corriendo al azar de un sitio a otro.<\/p>\n<p>Por \u00faltimo, se detuvo al pie de un caser\u00f3n de piedra; oscuro y antiqu\u00edsimo, y al detenerse brillaron sus ojos con una indescriptible expresi\u00f3n de alegr\u00eda. En una de las altas ventanas ojivales de aquel que pudi\u00e9ramos llamar palacio se ve\u00eda un rayo de luz templada y suave, que, pasando a trav\u00e9s de unas ligeras colgaduras de seda color de rosa, se reflejaba en el negruzco y agrietado pared\u00f3n de la casa de enfrente.<\/p>\n<p>-No cabe duda; aqu\u00ed vive mi desconocida -murmur\u00f3 el joven en voz baja y sin apartar un punto sus ojos de la ventana g\u00f3tica-; aqu\u00ed vive&#8230; Ella entr\u00f3 por el postigo de San Saturio&#8230; Por el postigo de San Saturio se viene a este barrio&#8230; En este barrio hay una casa donde, pasada la medianoche, a\u00fan hay gente en vela&#8230; \u00bfEn vela? \u00bfQui\u00e9n, sino ella, que vuelve de sus nocturnas excursiones, puede estarlo a esas horas?&#8230; No hay m\u00e1s; \u00e9sta es su casa.<\/p>\n<p>En esta firme persuasi\u00f3n, y revolviendo en su cabeza las m\u00e1s locas y fant\u00e1sticas imaginaciones, esper\u00f3 el alba frente a la ventana g\u00f3tica; de la que en toda la noche no falt\u00f3 la luz ni \u00e9l separ\u00f3 la vista un momento.<\/p>\n<p>Cuando lleg\u00f3 el d\u00eda, las macizas puertas del arco que daban entrada al caser\u00f3n, y sobre cuya clave se ve\u00edan esculpidos los blasones de su due\u00f1o, giraron pesadamente sobre los goznes, con un chirrido prolongado y agudo. Un escudero apareci\u00f3 en el dintel con un manojo de llaves en la mano, restreg\u00e1ndose los ojos y ense\u00f1ando al bostezar una caja de dientes capaces de dar envidia a un cocodrilo.<\/p>\n<p>Verlo Manrique y lanzarse a la puerta, todo fue obra de un instante.<\/p>\n<p>-\u00bfQui\u00e9n habita en esta casa? \u00bfC\u00f3mo se llama ella? \u00bfDe d\u00f3nde es? \u00bfA qu\u00e9 ha venido a Soria? \u00bfTiene esposo? Responde, animal -\u00e9sta fue la salutaci\u00f3n que, sacudi\u00e9ndole el brazo violentamente, dirigi\u00f3 al pobre escudero, el cual, despu\u00e9s de mirarlo un buen espacio de tiempo con los ojos espantados y est\u00fapidos, le contest\u00f3 con voz entrecortada por la sorpresa:<\/p>\n<p>-En esta casa vive el muy honrado se\u00f1or don Alonso de Valdecuellos, montero mayor de nuestro se\u00f1or el rey, que, herido en la guerra contra moros, se encuentra en esta ciudad reponi\u00e9ndose de sus fatigas.<\/p>\n<p>-Pero, \u00bfy su hija? -interrumpi\u00f3 el joven, impaciente-. \u00bfY su hija, o su hermana, o su esposa, o lo que sea?<\/p>\n<p>-No tiene ninguna mujer consigo.<\/p>\n<p>-\u00a1No tiene ninguna!&#8230; Pues, \u00bfqui\u00e9n duerme all\u00ed, en aquel aposento, donde toda la noche he visto arder una luz?<\/p>\n<p>-\u00bfAll\u00ed? All\u00ed duerme mi se\u00f1or don Alonso, que, como se halla enfermo, mantiene encendida su l\u00e1mpara hasta que amanece.<\/p>\n<p>Un rayo cayendo de improviso a sus pies no le hubiera causado m\u00e1s asombro que el que le causaron estas palabras.<\/p>\n<p>-Yo la he de encontrar, la he de encontrar; y si la encuentro, estoy casi seguro de que he de conocerla&#8230; \u00bfEn qu\u00e9? Eso es lo que no podr\u00e9 decir&#8230;; pero he de conocerla. El eco de sus pisadas o una sola palabra suya que vuelva a o\u00edr, un extremo de su traje, un solo extremo que vuelva a ver, me bastar\u00e1n para conseguirlo.<\/p>\n<p>Noche y d\u00eda estoy mirando flotar delante de mis ojos aquellos pliegues de una tela di\u00e1fana y blanqu\u00edsima; noche y d\u00eda me est\u00e1n sonando aqu\u00ed dentro, dentro de la cabeza, el crujido de su traje, el confuso rumor de sus ininteligibles palabras. \u00bfQu\u00e9 dijo?&#8230; \u00bfQu\u00e9 dijo?&#8230; \u00a1Ah!, si yo pudiera saber lo que dijo, acaso&#8230;; pero aun sin saberlo, la encontrar\u00e9&#8230;; la encontrar\u00e9; me lo da el coraz\u00f3n, y mi coraz\u00f3n no me enga\u00f1a nunca. Verdad es que ya he recorrido in\u00fatilmente todas las calles de Soria; que he pasado noches y noches al sereno, hecho poste de una esquina; que he gastado m\u00e1s de veinte doblas de oro en hacer charlar a due\u00f1as y escuderos; que he dado agua bendita en San Nicol\u00e1s a una vieja, arrebujada con tal arte en su manto de anascote, que se me figur\u00f3 una deidad; y al salir de la Colegiata, una noche de maitines, he seguido como un tonto la litera del arcediano, creyendo que el extremo de sus holapandas era el del traje de mi desconocida; pero no importa&#8230;; yo la he de encontrar, y la gloria de poseerla exceder\u00e1 seguramente al trabajo de buscarla.<\/p>\n<p>\u00bfC\u00f3mo ser\u00e1n sus ojos?&#8230; Deben de ser azules, azules y h\u00famedos como el cielo de la noche; me gustan tanto los ojos de ese color&#8230;; son tan expresivos, tan melanc\u00f3licos, tan&#8230; S\u00ed&#8230;, no hay duda: azules deben de ser, azules son seguramente, y sus cabellos, negros, muy negros y largos para que floten&#8230; Me parece que los vi flotar aquella noche, al par que su traje, y eran negros&#8230;; no me enga\u00f1o, no, eran negros.<\/p>\n<p>\u00a1Y qu\u00e9 bien hacen unos ojos azules muy rasgados y adormidos, y una cabellera suelta, flotante y oscura, a una mujer alta&#8230;; porque&#8230; ella es alta, alta y esbelta como esos \u00e1ngeles de las portadas de nuestras bas\u00edlicas, cuyos ovalados rostros envuelven en un misterioso crep\u00fasculo las sombras de sus doseles de granito!<\/p>\n<p>\u00a1Su voz!&#8230; Su voz la he o\u00eddo&#8230;; su voz es suave como el rumor del viento en las hojas de los \u00e1lamos, y su andar acompasado y majestuoso como las cadencias de una m\u00fasica. Y esa mujer, que es hermosa como el m\u00e1s hermoso de mis sue\u00f1os de adolescente, que piensa como yo pienso, que gusta de lo que yo gusto, que odia lo que yo odio, que es un esp\u00edritu hermano de mi esp\u00edritu, que es el complemento de mi ser, \u00bfno se ha de sentir conmovida al encontrarme? \u00bfNo me ha de amar como yo la amar\u00e9, como la amo ya, con todas las fuerzas de mi vida, con todas las facultades de mi alma?<\/p>\n<p>Vamos, vamos al sitio donde la vi la primera y \u00fanica vez que la he visto&#8230; \u00bfQui\u00e9n sabe si, caprichosa como yo, amiga de la soledad y el misterio, como todas las almas so\u00f1adoras, se complace en vagar por entre las ruinas en el silencio de la noche?<\/p>\n<p>Dos meses hab\u00edan transcurrido desde que el escudero de don Antonio de Valdecuellos desenga\u00f1\u00f3 al iluso Manrique; dos meses durante los cuales en cada hora hab\u00eda formado un castillo en el aire, que la realidad desvanec\u00eda con un soplo; dos meses durante los cuales hab\u00eda buscado en vano a aquella mujer desconocida, cuyo absurdo amor iba creciendo en su alma, merced a sus a\u00fan m\u00e1s absurdas imaginaciones, cuando, despu\u00e9s de atravesar, absorto en estas ideas, el puente que conduce a los Templarios, el enamorado joven se perdi\u00f3 entre las intrincadas sendas de sus jardines.<\/p>\n<p>La noche estaba serena y hermosa; la luna brillaba en toda su plenitud en lo m\u00e1s alto del cielo, y el viento suspiraba con un rumor dulc\u00edsimo entre las hojas de los \u00e1rboles.<\/p>\n<p>Manrique lleg\u00f3 al claustro, tendi\u00f3 la vista por su recinto y mir\u00f3 a trav\u00e9s de las macizas columnas de sus arcadas&#8230; Estaba desierto.<\/p>\n<p>Sali\u00f3 de \u00e9l, encamin\u00f3 sus pasos hacia la oscura alameda que conduce al Duero, y a\u00fan no hab\u00eda penetrado en ella, cuando de sus labios se escap\u00f3 un grito de j\u00fabilo.<\/p>\n<p>Hab\u00eda visto flotar un instante y desaparecer el extremo del traje blanco, del traje blanco de la mujer de sus sue\u00f1os, de la mujer que ya amaba como un loco.<\/p>\n<p>Corre, corre en su busca; llega al sitio en que la ha visto desaparecer; pero al llegar se detiene, fija los espantados ojos en el suelo, permanece un rato inm\u00f3vil; un ligero temblor nervioso agita sus miembros, un temblor que va creciendo, que va creciendo, y ofrece los s\u00edntomas de una verdadera convulsi\u00f3n, y prorrumpe, al fin, en una carcajada, en una carcajada sonora, estridente, horrible.<\/p>\n<p>Aquella cosa blanca, ligera, flotante, hab\u00eda vuelto a brillar ante sus ojos; pero hab\u00eda brillado a sus pies un instante, no m\u00e1s que un instante.<\/p>\n<p>Era un rayo de luna, un rayo de luna que penetraba a intervalos por entre la verde b\u00f3veda de los \u00e1rboles cuando el viento mov\u00eda las ramas.<\/p>\n<p>&#8230;<\/p>\n<p>Hab\u00edan pasado algunos a\u00f1os. Manrique, sentado en un sitial, junto a la alta chimenea g\u00f3tica de su castillo, inm\u00f3vil casi, y con una mirada vaga e inquieta como la de un idiota, apenas prestaba atenci\u00f3n ni a las caricias de su madre ni a los consuelos de sus servidores.<\/p>\n<p>-T\u00fa eres joven, t\u00fa eres hermoso -le dec\u00eda aqu\u00e9lla-. \u00bfPor qu\u00e9 te consumes en la soledad? \u00bfPor qu\u00e9 no buscas una mujer a quien ames, y am\u00e1ndote pueda hacerte feliz?<\/p>\n<p>-\u00a1El amor!&#8230; El amor es un rayo de luna -murmuraba el joven.<\/p>\n<p>-\u00bfPor qu\u00e9 no despert\u00e1is de ese letargo? -le dec\u00eda uno de sus escuderos-. Os vest\u00eds de hierro de pies a cabeza; mand\u00e1is desplegar al aire vuestro pend\u00f3n de rico hombre, y marchamos a la guerra. En la guerra se encuentra la gloria.<\/p>\n<p>-\u00a1La gloria!&#8230; La gloria es un rayo de luna.<\/p>\n<p>-\u00bfQuer\u00e9is que os diga una cantiga, la \u00faltima que ha compuesto Mos\u00e9n Arnaldo, el trovador provenzal?<\/p>\n<p>-\u00a1No! \u00a1No! -exclam\u00f3 el joven, incorpor\u00e1ndose col\u00e9rico en su sitial-. No quiero nada&#8230;; es decir, s\u00ed quiero: quiero que me dej\u00e9is solo&#8230; Cantigas&#8230;, mujeres&#8230;, glorias&#8230;, felicidad&#8230;, mentiras todo, fantasmas vanos que formamos en nuestra imaginaci\u00f3n y vestimos a nuestro antojo, y los amamos y corremos tras ellos, \u00bfpara qu\u00e9?, \u00bfpara qu\u00e9? Para encontrar un rayo de luna.<\/p>\n<p>Manrique estaba loco; por lo menos, todo el mundo lo cre\u00eda as\u00ed. A m\u00ed, por el contrario, se me figura que lo que hab\u00eda hecho era recuperar el juicio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Leyenda de Soria) Yo no s\u00e9 si esto es una historia que parece cuento o un cuento que parece historia; lo que puedo decir es que en su fondo hay una verdad, una verdad muy triste, de la que acaso yo ser\u00e9 uno de los \u00faltimos en aprovecharme, dadas mis\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[5,1109],"tags":[1010,1069,1016,1012,1018,1034,1017,1058,1044,1060,1045,1057,1051,1025],"class_list":["post-1013","post","type-post","status-publish","format-standard","hentry","category-literatura","category-textos-literarios","tag-amor","tag-animal","tag-arte","tag-ave","tag-ayuda","tag-guerra","tag-historia","tag-hogar","tag-jardin","tag-lengua","tag-leyenda","tag-pensamiento","tag-planta","tag-rosa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/\u201cel-rayo-de-luna\u201d-gustavo-adolfo-becquer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/\u201cel-rayo-de-luna\u201d-gustavo-adolfo-becquer\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-10T16:04:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer]\",\"datePublished\":\"2010-12-10T16:04:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\\\/\"},\"wordCount\":3820,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"keywords\":[\"amor\",\"animal\",\"arte\",\"ave\",\"ayuda\",\"guerra\",\"historia\",\"hogar\",\"jardin\",\"lengua\",\"leyenda\",\"pensamiento\",\"planta\",\"rosa\"],\"articleSection\":[\"Literatura \\\/ Po\u00e9tica\",\"Textos literarios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\\\/\",\"name\":\"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"datePublished\":\"2010-12-10T16:04:42+00:00\",\"description\":\"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa","description":"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/\u201cel-rayo-de-luna\u201d-gustavo-adolfo-becquer\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa","og_description":"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/\u201cel-rayo-de-luna\u201d-gustavo-adolfo-becquer\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2010-12-10T16:04:42+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"19 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer]","datePublished":"2010-12-10T16:04:42+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/"},"wordCount":3820,"commentCount":0,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"keywords":["amor","animal","arte","ave","ayuda","guerra","historia","hogar","jardin","lengua","leyenda","pensamiento","planta","rosa"],"articleSection":["Literatura \/ Po\u00e9tica","Textos literarios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/","url":"https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/","name":"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"datePublished":"2010-12-10T16:04:42+00:00","description":"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9cel-rayo-de-luna%e2%80%9d-gustavo-adolfo-becquer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"\u201cEl rayo de luna\u201d [Gustavo Adolfo B\u00e9cquer]"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":0,"uagb_excerpt":"(Leyenda de Soria) Yo no s\u00e9 si esto es una historia que parece cuento o un cuento que parece historia; lo que puedo decir es que en su fondo hay una verdad, una verdad muy triste, de la que acaso yo ser\u00e9 uno de los \u00faltimos en aprovecharme, dadas mis\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/1013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=1013"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/1013\/revisions"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=1013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=1013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=1013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}