{"id":1002,"date":"2010-12-10T17:51:32","date_gmt":"2010-12-10T15:51:32","guid":{"rendered":"http:\/\/www.cultureduca.com\/blog\/?p=1002"},"modified":"2010-12-10T17:51:32","modified_gmt":"2010-12-10T15:51:32","slug":"%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer","status":"publish","type":"post","link":"https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/","title":{"rendered":"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer]"},"content":{"rendered":"<p>(C\u00c1NTIGA PROVENZAL)\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0 Yo fui el verdadero Teobaldo de Montagut, bar\u00f3n de Fortcastell. Noble o villano, se\u00f1or o pechero, t\u00fa, cualquiera que seas, que te detienes un instante al borde de mi sepultura, cree en Dios como yo he cre\u00eddo y ru\u00e9gale por m\u00ed. Nobles aventureros que, puesta la lanza en la puja, ca\u00edda la visera del casco y jinetes sobre un corcel poderoso, recorr\u00e9is la tierra sin m\u00e1s patrimonio que vuestro nombre clar\u00edsimo y vuestra montante, buscando honra y prez en la profesi\u00f3n de las armas: si al atravesar el quebrado valle de Montagut os ha sorprendido en \u00e9l la tormenta y la noche y hab\u00e9is encontrado un refugio en las ruinas del monasterio que aun se ve en su fondo, o\u00eddme. Pastores que segu\u00e9is con lento paso vuestras blancas ovejas, que pacen derramadas por las colinas y las llanuras; si al conducirlas al borde del transparente riachuelo que corre, forcejea y salta por entre los pe\u00f1ascos del valle de Montagut, en el rigor del verano y en una siesta de fuego, hab\u00e9is encontrado la sombra y el reposo al pie de las derruidas arcadas del monasterio, cuyos musgosos pilares besan las ondas, o\u00eddme. Ni\u00f1as de las cercanas aldeas, lirios silvestres que crec\u00e9is felices al abrigo de vuestra humildad: si en la ma\u00f1ana del santo patrono de estos lugares, al bajar al valle de Montagut a coger tr\u00e9boles y margaritas con que embellecer su retablo, venciendo el amor que os inspira el sombr\u00edo monasterio que se alza entre sus pe\u00f1as, hab\u00e9is penetrado en su claustro mudo y desierto para vagar entre sus abandonadas tumbas, a cuyos bordes crecen las margaritas m\u00e1s nobles y los jacintos m\u00e1s azules, o\u00eddme. T\u00fa, noble caballero, tal vez al resplandor de un rel\u00e1mpago; t\u00fa, pastor errante, calcinado por los rayos del sol; t\u00fa, en fin, hermosa ni\u00f1a, cubierta a\u00fan con gotas de roc\u00edo, semejantes a l\u00e1grimas: todos habr\u00e9is visto en aquel santo lugar una tumba, una tumba humilde. Antes la compon\u00edan una piedra tosca y una cruz de palo; la cruz ha desaparecido y s\u00f3lo queda la piedra. En esa tumba, cuya inscripci\u00f3n es el mote de mi canto, reposa en paz el \u00faltimo var\u00f3n de Fortcastell, Teobaldo de Montagut, del cual voy a referiros la peregrina historia. Cuando la noble condesa de Montagut estaba encinta de su primog\u00e9nito, Teobaldo, tuvo un ensue\u00f1o misterioso y terrible. Acaso un aviso de Dios; tal vez una vana fantas\u00eda que el tiempo realiz\u00f3 m\u00e1s adelante. So\u00f1\u00f3 que en su seno engendraba una serpiente, una serpiente monstruosa que arrojando agudos silbos, y ora arrastr\u00e1ndose entre la menuda hierba, ora repleg\u00e1ndose sobre s\u00ed misma para saltar, huy\u00f3 de su vista, escondi\u00e9ndose, al fin, entre unas zarzas.<\/p>\n<p>-\u00a1All\u00ed est\u00e1, all\u00ed est\u00e1! -gritaba la condesa en su horrible pesadilla, se\u00f1alando a sus servidores la zarza en que se hab\u00eda escondido el asqueroso reptil.<\/p>\n<p>Cuando sus servidores llegaron presurosos al punto que la noble dama, inm\u00f3vil y presa de un profundo terror, le se\u00f1alaba aun con el dedo, una blanca paloma se levant\u00f3 de entre las bre\u00f1as y se remont\u00f3 al as nubes.<\/p>\n<p>La serpiente hab\u00eda desaparecido. Teobaldo vino al mundo. Su madre muri\u00f3 al darlo a luz; su padre pereci\u00f3 algunos a\u00f1os despu\u00e9s en una emboscada, peleando como bueno contra los enemigos de Dios.<\/p>\n<p>Desde este punto, la juventud del primog\u00e9nito de Fortcastell solo puede compararse a un hurac\u00e1n. Por donde pasaba se ve\u00eda se\u00f1alando su camino un rastro de l\u00e1grimas y de sangre. Ahorcaba a sus pecheros, se bat\u00eda con sus iguales, persegu\u00eda a las doncellas, daba de palos a los monjes, y, en sus blasfemias y juramentos, ni dejaba santo en paz ni cosa sagrada de que no maldijese. Un d\u00eda que sali\u00f3 de caza y que, como era su costumbre, hizo a entra a guarecerse de la lluvia a toda su endiablada comitiva de pajes licenciosos, arqueros desalmados y siervos envilecidos, con perros, caballos y con gerifaltes, en la Iglesia de una aldea de sus dominios, un venerable sacerdote, arrostrando su c\u00f3lera\u00a0 y sin temer los violentos arranques de su car\u00e1cter impulsivo, le conjur\u00f3, en nombre del cielo y llevando una hostia consagrada en sus manos, a que abandonase aquel lugar y fuese a pie y con un bord\u00f3n de romero a pedir al Papa la absoluci\u00f3n de sus culpas.<\/p>\n<p>-\u00a1D\u00e9jame en paz, viejo loco! -exclam\u00f3 Teobaldo al o\u00edrlo-; d\u00e9jame en paz o ya que no he encontrado una sola pieza durante el d\u00eda, te suelto mis perros y te cazo como a un jabal\u00ed para distraerme. Teobaldo era hombre de hacer lo que dec\u00eda. El sacerdote, sin embargo, se limit\u00f3 a contestarle.<\/p>\n<p>-Haz lo que quieras; pero ten presente que hay un Dios que castiga y perdona, y que si muero a tus manos borrar\u00e1 mis culpas del libro de su indignaci\u00f3n para escribir tu nombre y hacerte expiar tu crimen.<\/p>\n<p>-\u00a1Un Dios que castiga y perdona! -prorrumpi\u00f3 el sacr\u00edlego bar\u00f3n con una carcajada-. Yo no creo en Dios, y para darte una prueba voy a cumplirte lo que te he prometido, porque aunque poco rezador, soy amigo de no faltar a mis palabras. \u00a1Raimundo! \u00a1Gerardo! \u00a1Pedro! Azuzad la jaur\u00eda, dadme el venablo, tocad el alali en vuestras trompas, que vamos a darle caza a este imb\u00e9cil, aunque se suba a los retablos de sus altares. Ya, despu\u00e9s d dudar un instante y a una nueva orden de su se\u00f1or, comenzaban los pajes a desatar los lebreles, que aturd\u00edan la Iglesia con sus ladridos; ya el bar\u00f3n hab\u00eda armado su ballesta, riendo con una risa de Satan\u00e1s, y el venerable sacerdote, murmurando una plegaria, elevaba sus ojos al cielo y esperaba tranquilo la muerte, cuando se oy\u00f3 fuera del sagrado recinto una vocer\u00eda terrible, bramidos de trompas que hac\u00edan se\u00f1ales de ojeo y gritos de: &lt;&lt;\u00a1Al jabal\u00ed! \u00a1Al jabal\u00ed! \u00a1Por las bre\u00f1as! \u00a1Hacia el monte!&gt;&gt; Teobaldo, al anuncio de la deseada res, corri\u00f3 a las puertas del santuario, ebrio de alegr\u00eda; tras \u00e9l fueron sus servidores, y con sus servidores, los caballos y los lebreles. \u00bfPor donde va el jabal\u00ed? -pregunt\u00f3 el var\u00f3n, subiendo a su corcel sin apoyarse en el estribo ni desarmar la ballesta.<\/p>\n<p>-Por la ca\u00f1ada que se extiende al pie de esa colinas -le respondieron.<\/p>\n<p>Sin escuchar la \u00faltima palabra, el impetuoso cazador hundi\u00f3 su acicate de oro en el ijar del caballo, que parti\u00f3 al escape. Tras \u00e9l partieron todos.<\/p>\n<p>Los habitantes de la aldea, que fueron los primeros en dar la voz de alarma, y que al aproximarse el terrible animal se hab\u00edan guarecido en sus chozas, asomaron t\u00edmidamente la cabeza a los quicios de las ventanas, y cuando vieron desaparecer la infernal comitiva por entre el follaje de la espesura se santiguaron en silencio. Teobaldo iba delante de todos. Su corcel, m\u00e1s ligero o m\u00e1s castigado que los de sus servidores, segu\u00eda tan de cerca la res, que dos o tres veces, dej\u00e1ndole la brida sobre el cuello al fogoso bruto, se hab\u00eda empinado sobre los estribos y ech\u00e1ndose al hombro la ballesta para herirlo. Pero el jabal\u00ed, al que s\u00f3lo divisaba a intervalos entre los espesos matorrales tornaba a desaparecer de su vista para mostr\u00e1rsele de nuevo fuera del alcance de su arma.<\/p>\n<p>As\u00ed corri\u00f3 muchas horas, atraves\u00f3 las ca\u00f1adas, el pedregoso lecho del r\u00edo, e intern\u00e1ndose en un bosque inmenso, se perdi\u00f3 entre sus sombr\u00edas revueltas, siempre fijos los ojos en la codiciada res. Siempre creyendo alcanzarla, siempre vi\u00e9ndose burlado por su agilidad maravillosa.<\/p>\n<p>Por \u00faltimo, pudo encontrar una ocasi\u00f3n propicia; tendi\u00f3 el brazo y vol\u00f3 la saeta, que fue a clavarse temblando en el lomo del terrible animal, que dio un salto y un espantoso bufido.<\/p>\n<p>-\u00a1Muerto est\u00e1 -exclama con un grito de alegr\u00eda el cazador, volviendo a hundir por la cent\u00e9sima vez el acicate en el sangriento ijar de su caballo.- \u00a1Muerto est\u00e1! En balde huye. El rastro de la sangre que arroja marca su camino -y esto diciendo, comenz\u00f3 a hacer en la bocina la se\u00f1al del triunfo para que la oyesen sus servidores.<\/p>\n<p>En aquel instante, el corcel se detuvo, flaquearon sus piernas, in ligero temblor agit\u00f3 sus contra\u00eddos musculosa y cay\u00f3 al suelo desplomado, arrojando por la hinchada nariz, cubierta de espuma, un ca\u00f1o de sangre.<\/p>\n<p>Hab\u00eda muerto de fatiga, hab\u00eda muerto cuando la carrera del herido jabal\u00ed comenzaba a acortarse, cuando bastaba un solo esfuerzo m\u00e1s para alcanzarlo. Pintar la ira del col\u00e9rico Teobaldo ser\u00eda imposible. Repetir sus maldiciones y sus blasfemias, s\u00f3lo repetirlas fuera escandaloso e imp\u00edo. Llam\u00f3 a grandes voces a sus servidores, y \u00fanicamente le contest\u00f3 el eco en aquellas inmensas soledades, y se arranc\u00f3 los cabellos y se mes\u00f3 las barbas, presa d la m\u00e1s espantosa desesperaci\u00f3n.<\/p>\n<p>-Lo seguir\u00e9 a la carrera, aun cuando haya de reventarme -exclam\u00f3, al fin, armando de nuevo su ballesta y disponi\u00e9ndose a seguir a la res; pero en aquel momento sinti\u00f3 ruido a sus espaldas, se entreabrieron las ramas de la espesura y se present\u00f3 a sus ojos un paje que tra\u00eda del diestro un corcel negro como la noche.<\/p>\n<p>-El cielo me lo env\u00eda -dijo el cazador lanz\u00e1ndose sobre sus lomos, \u00e1gil como un gamo.<\/p>\n<p>El paje, que era delgado, muy delgado, y amarillo como la muerte, se sonri\u00f3 de una manera extra\u00f1a al presentarse la brida. El caballo relincho con una fuerza que hizo estremecer el bosque; dio un bote incre\u00edble, un bote en que se levant\u00f3 m\u00e1s de diez varas del suelo, y el aire comenz\u00f3 a zumbar en los o\u00eddos del jinete como zumba una piedra arrojada por la honda. Hab\u00eda partido sal escape; pero aun escape tan r\u00e1pido, que, temeroso de perder los estribos y caer a tierra turbado por el v\u00e9rtigo, tuvo que cerrar los ojos\u00a0 agarrarse con ambas manos a sus flotantes crines.<\/p>\n<p>Y sin agitar sus riendas, sin herirle con el acicate ni animarlo con la voz, el corcel corr\u00eda, corr\u00eda sin detenerse. \u00bfCu\u00e1nto tiempo corri\u00f3 Teobaldo con \u00e9l sin saber por d\u00f3nde, sintiendo que las ramas le abofeteaban el rostro al pasar, y los zarzales desgarraban sus vestidos, y el viento silbaba a su alrededor? Nadie lo sabe. Cuando, recobrado el animo, abri\u00f3 los ojos un instante para arrojar en torno suyo una mirada inquieta, se encontr\u00f3 lejos, muy lejos de Montagut y en unos ligares para \u00e9l completamente extra\u00f1os. El corcel corr\u00eda, corr\u00eda sin detenerse, y \u00e1rboles, rocas, castillos y aldeas pasaban a su lado como una exhalaci\u00f3n. Nuevos y nuevos horizontes se abr\u00edan ante su vista; horizontes que se borraban para dejar lugar a otros m\u00e1s y m\u00e1s desconocidos. Valles angostos, erizados de colosales fragmentos de granito que las tempestades hab\u00edan arrancado de la cumbre de las monta\u00f1as; alegres campi\u00f1as cubiertas de un tapiz de verdura y sembradas de blancos caser\u00edos; desiertos sin limites, donde herv\u00edan las arenas calcinadas por los rayos de un sol de fuego; vastas soledades, llanuras inmensas, regiones de eternas nieves, donde los gigantescos t\u00e9mpanos asemejaban, destac\u00e1ndose sobre un cielo gris y oscuro, blancos fantasmas que extend\u00edan sus brazos para asirle por los cabellos al pasar: todo esto, y mil y mil otras cosas que yo no podr\u00e9 deciros, vio en su fant\u00e1stica carrera, y hasta tanto que, envuelto en una niebla oscura, dejo de percibir el ruido que produc\u00edan los cascos del caballo al herir la tierra. \u00a1Nobles caballeros, sencillos pastores, hermosas ni\u00f1as que escuch\u00e1is mi relato: si os maravilla lo que os cuento, no cre\u00e1is que es una f\u00e1bula tejida a mi antojo para sorprendes vuestra credulidad. De boca en boca ha llegado hasta mi esta tradici\u00f3n, y la leyenda del sepulcro, que aun subsiste en el monasterio de Montagut, es un testimonio irrecusable de la veracidad de mis palabras.<\/p>\n<p>Creed, pues, lo que he dicho, y creed lo que a\u00fan me resta por decir, que es tan cierto como lo anterior, aunque m\u00e1s maravilloso. Yo podr\u00e9 acaso adornar con algunas galas de la poes\u00eda el desnudo esqueleto de esta sencilla y terrible historia; pero nunca me apartare un punto de la verdad a sabiendas. Cuando Teobaldo dejo de percibir las pisadas de su corcel y se sinti\u00f3 lanzado en el vac\u00edo no pudo reprimir un involuntario estremecimiento de terror. Hasta entonces hab\u00eda cre\u00eddo que los objetos que se representaban a sus ojos eran fantasmas de su imaginaci\u00f3n, turbada por el v\u00e9rtigo, y que su corcel corr\u00eda desbocado, es verdad; pero corr\u00eda sin salir del termino de su se\u00f1or\u00edo. Ya no le quedaba duda de que era el juguete de un poder sobrenatural que le arrastraba, sin que supiese ad\u00f3nde, a trav\u00e9s de aquellas nieblas oscuras, de aquellas nubes de formas caprichosas y fant\u00e1sticas, en cuyo seno, que se iluminaba a veces con el resplandor de un rel\u00e1mpago, cre\u00eda distinguir las hirvientes centellas, pr\u00f3ximas a desprenderse.<\/p>\n<p>El corcel corr\u00eda, o, mejor dicho, nadaba en aquel oc\u00e9ano de vapores caliginosos y encendidos, y las maravillas del cielo comenzaron a desplegarse, unas tras otras, ante los espantados ojos de su jinete. Cabalgando sobre las nubes, vestidos de luengas t\u00fanicas con orlas de fuego, suelta al hurac\u00e1n la encendida cabellera y blandiendo sus espadas, que relampagueaban arrojando chispas de c\u00e1rdena luz, vio a los \u00e1ngeles, ministros de la c\u00f3lera del Se\u00f1or, cruzar como un formidable ejercito sobre las alas de la tempestad.<\/p>\n<p>Y subi\u00f3 m\u00e1s alto y crey\u00f3 divisar a lo lejos las tormentosas nubes, semejantes a un mar de lava, y oy\u00f3 mugir el turno a sus pies como muge el Oc\u00e9ano azotando la roca desde cuya cima le contempla el at\u00f3nito peregrino. Y vio al arc\u00e1ngel, blanco como la nieve, que, sentado sobre un inmenso globo de cristal, los dirige por el espacio en las noches serenas, como un bajel\u00a0 de plata sobre la superficie de un lago azul.<\/p>\n<p>Y vio el sol volteando encendido sobre sus ejes de oro en una atm\u00f3sfera de colores y de fuego, y en su foco a los \u00edgneos esp\u00edritus que habitan inc\u00f3lumes entre las llamas y desde su ardiente seno, entonan al Creador himnos de alegr\u00eda.<\/p>\n<p>Vio los hilos de luz imperceptibles que atan los hombres a las estrellas y vio el arco iris, echado como un puente colosal sobre el abismo que separa al primer cielo del segundo. Por una escala misteriosa vio bajar las almas a la\u00a0 tierra; vio bajar muchas y subir pocas. cada una d aquellas almas inocentes iba acompa\u00f1ada de un arc\u00e1ngel pur\u00edsimo, que la cubr\u00eda con las sombras de sus alas. Los que tornaban solos, tornaban en silencio y con l\u00e1grimas en los ojos; los que no , sub\u00edan cantando como suben las alondras en las ma\u00f1anas de abril.<\/p>\n<p>Despu\u00e9s, las nieblas rosadas y azules, que flotaban en le espacio como cortinas de gasa transparente, se rasgaron como el d\u00eda de gloria se rasga en nuestros templos el velo de los altares, y el para\u00edso de los justos se ofreci\u00f3 a sus miradas deslumbrador y magn\u00edfico. All\u00ed estaban los santos profetas que habr\u00e9is visto groseramente esculpidos en las portadas de piedra de nuestras catedrales; all\u00ed las v\u00edrgenes luminosas, que intenta en vano copiar de sus sue\u00f1os el pintor en los vidrios de colores de las ojivas; all\u00ed los querubines con sus largas y flotantes vestiduras y sus nimbos de oro, como los de las tablas de los altares; all\u00ed, en fin, coronada de estrellas, vestida de luz, rodeada de todas las jerarqu\u00edas celestes, y hermosa sobre toda ponderaci\u00f3n, Nuestra Se\u00f1ora de Montserrat, la Madre de Dios, le Reina de los arc\u00e1ngeles, el amparo de los pecadores y el consuelo de los afligidos. M\u00e1s all\u00e1 del para\u00edso de los justos; m\u00e1s all\u00e1 del trono donde se asienta la Virgen Mar\u00eda, el \u00e1nimo de Teobaldo se sobrecogi\u00f3 temeroso, y un hondo pavor se apoder\u00f3 de su alma. La eterna soledad, el eterno silencio, viven en aquellas regiones que conducen al misterioso santuario del Se\u00f1or. De cuando en cuando azotaba su frente una r\u00e1faga de aire, fr\u00edo como la hoja de un pu\u00f1al, que crispaba sus cabellos de horror y penetraba hasta la medula de los huesos, r\u00e1fagas semejantes a las que anunciaban a los profetas la aproximaci\u00f3n del esp\u00edritu divino. Al fin lleg\u00f3 a un punto donde crey\u00f3 percibir un rumor sordo, que pudiera comparase al zumbido lejano de un enjambre de abejas cuando, en las tardes de oto\u00f1o, revolotean en derredor de las \u00faltimas flores. Atravesaba esa fant\u00e1stica regi\u00f3n adonde van todos los acentos de la Tierra, los sonidos que decimos que se desvanecen, las palabras que juzgamos que se pierden en el aire, los lamentos que creemos que nadie oye.<\/p>\n<p>Aqu\u00ed, en un circulo arm\u00f3nico, flotan las plegarias de los ni\u00f1os, las oraciones de las v\u00edrgenes, los salmos de los piadosos eremitas, las peticiones de los humildes, las castas palabras de los limpios de coraz\u00f3n, las resignadas quejas de los que padecen, los ayes de los que sufren y los himnos de los que esperan. Teobaldo oy\u00f3 entre aquellas voces, que palpitaban a\u00fan en el \u00e9ter luminoso, la voz de su santa madre, que ped\u00eda a Dios por \u00e9l; pero no oy\u00f3 la suya. M\u00e1s all\u00e1 hirieron sus o\u00eddos, con un estr\u00e9pito discordante, mil y mil acentos \u00e1speros y roncos, blasfemias, gritos de venganza, cantares de org\u00edas, palabras l\u00fabricas, maldiciones de la desesperaci\u00f3n, amenazas de la impotencia y juramentos sacr\u00edlegos de la impiedad.<\/p>\n<p>Teobaldo atraves\u00f3 el segundo c\u00edrculo con la rapidez que el meteoro cruza el cielo en una tarde de verano, por no o\u00edr su voz, que vibraba all\u00ed sonante y atronadora, sobreponi\u00e9ndose a las otras voces en medio de aquel concierto infernal.<\/p>\n<p>-\u00a1No creo en Dios! \u00a1No creo en Dios! -dec\u00eda a\u00fan su acento, agit\u00e1ndose en aquel oc\u00e9ano de blasfemias; y Teobaldo comenzaba a creer. Dej\u00f3 atr\u00e1s aquellas regiones y atraves\u00f3 otras inmensidades llenas de visiones terribles, que ni \u00e9l pudo comprender ni yo acierto a concebir, y lleg\u00f3, al cabo, al \u00faltimo c\u00edrculo de la espiral de los cielos, donde los serafines adoran al Se\u00f1or, cubierto el rostro con las triples alas y prosternados a sus pies.<\/p>\n<p>\u00c9l quiso mirarlo.<\/p>\n<p>Un aliento de fuego abras\u00f3 su cara, un mar de luz oscureci\u00f3 sus ojos, un trueno gigante retumb\u00f3 en sus o\u00eddos, y arrancado del corcel y lanzado al vac\u00edo como la piedra candente que arroja un volc\u00e1n, se sinti\u00f3 bajar y bajar, sin caer nunca; ciego, abrasado y ensordecido, como caer\u00eda el \u00e1ngel rebelde cuando Dios derrib\u00f3 el pedestal de su orgullo con un soplo de sus labios. La noche hab\u00eda cerrado y el viento gem\u00eda agitando las hojas de los \u00e1rboles, por entre cuyas frondas se deslizaba un suave rayo de luna, cuando Teobaldo incorpor\u00e1ndose sobre el codo y restreg\u00e1ndose los ojos como si despertara de un profundo sue\u00f1o, tendi\u00f3 alrededor una mirada y se encontr\u00f3 en el mismo bosque donde hiri\u00f3 al jabal\u00ed, donde cay\u00f3 muerto su corcel, donde le dieron aquella fant\u00e1stica cabalgadura que le hab\u00eda arrastrado a unas regiones desconocidas y misteriosas.<\/p>\n<p>Un silencio de muerte reinaba a su alrededor; un silencio que s\u00f3lo interrump\u00eda el lejano bramido de los ciervos, el temeroso murmullo de las hojas y el eco de una campana distante que de cuando en cuando tra\u00eda el viento en sus r\u00e1fagas.<\/p>\n<p>-Habr\u00e9 so\u00f1ado -dijo el bar\u00f3n, y emprendi\u00f3 su camino a trav\u00e9s del bosque, y sali\u00f3, al fin, a la llanura. En lontananza, y sobre las rocas de Montagut, vio destacarse la negra silueta de su castillo sobre el fondo azulado y transparente del cielo de la noche.<\/p>\n<p>-Mi castillo est\u00e1 lejos y estoy cansado -murmur\u00f3-; esperar\u00e9 el d\u00eda en un lugar cercano -y se dirigi\u00f3 al lugar. Llam\u00f3 a una puerta.<\/p>\n<p>-\u00bfQui\u00e9n sois? -le preguntaron.<\/p>\n<p>-El bar\u00f3n de Fortcastell -respondi\u00f3, y se le rieron en sus barbas. Llam\u00f3 a otra.<\/p>\n<p>-\u00bfQui\u00e9n sois y que quer\u00e9is? -tornaron a preguntarle.<\/p>\n<p>-Vuestro se\u00f1or -insisti\u00f3 el caballero, sorprendido de que no le conociesen-; Teobaldo de Montagut.<\/p>\n<p>-\u00a1Teobaldo de Montagut! -dijo col\u00e9rica su interlocutora, que lo era una vieja<\/p>\n<p>-. \u00a1Teobaldo de Montagut, el del cuento!&#8230; \u00a1Bah!&#8230; Seguid vuestro camino y no veng\u00e1is a sacar de su sue\u00f1o a las gentes honradas para decirles chanzonetas \u00ednsulas. Teobaldo, lleno de asombro, abandon\u00f3 la aldea y se dirigi\u00f3 al castillo, a cuyas puertas lleg\u00f3 cuando apenas clareaba el d\u00eda. El foso estaba cegado con los sillares de las derruidas almenas; el puente levadizo, in\u00fatil ya, se pudr\u00eda colgado a\u00fan de sus fuertes tirantes de hierro, cubiertos de or\u00edn por la acci\u00f3n de los a\u00f1os; en la torre del homenaje ta\u00f1\u00eda lentamente una campana; frente al arco principal de la fortaleza, y sobre un pedestal de granito se elevaba una cruz; en los muros no se ve\u00eda un solo soldado, y confuso y sordo, parec\u00eda que de su seno se elevaba como un murmullo lejano, un himno religioso, grave, solemne y magn\u00edfico.<\/p>\n<p>-\u00a1Y este es mi castillo, no hay duda! -dec\u00eda Teobaldo, paseando su inquieta mirada de un punto a otro, sin acertar a comprender lo que le pasaba-. \u00a1Aquel es mi escudo grabado a\u00fan sobre la clave del arco! \u00a1Este es el valle de Montagut! \u00a1Estas tierras que domina el se\u00f1or\u00edo de Fortcastell!&#8230;<\/p>\n<p>En aquel instante, las pesadas hojas de la puerta giraron sobre los goznes y apareci\u00f3 en su dintel un religioso. -\u00bfQui\u00e9n sois y qu\u00e9 hac\u00e9is aqu\u00ed? -le pregunto Teobaldo al monje.<\/p>\n<p>-Yo soy -le contesto \u00e9ste- un humilde servidor de Dios, religioso del monasterio de Montagut.<\/p>\n<p>-Pero&#8230; -interrumpi\u00f3 el bar\u00f3n-Montagut \u00bfno es un se\u00f1or\u00edo?<\/p>\n<p>-Lo fue&#8230; -prosigui\u00f3 el monje- hace mucho tiempo&#8230; A su \u00faltimo se\u00f1or, seg\u00fan cuentan, se lo llev\u00f3 el diablo, y como no tenia a nadie que lo sucediese en el feudo, los condes soberanos hicieron donaci\u00f3n de estas tierras a los religiosos de nuestra regla, que est\u00e1n aqu\u00ed desde habr\u00e1 cosa de ciento a ciento veinte a\u00f1os. Y vos, \u00bfqui\u00e9n sois?<\/p>\n<p>-Yo&#8230; -balbuce\u00f3 el se\u00f1or de Fortcastell, despu\u00e9s de un largo rato de silencio-, yo soy&#8230; un miserable pecador que, arrepentido de sus faltas, viene a confesarlas a vuestro abad y a pedirle que lo admita en el seno de su religi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(C\u00c1NTIGA PROVENZAL)\u00a0 \u00a0\u00a0\u00a0 Yo fui el verdadero Teobaldo de Montagut, bar\u00f3n de Fortcastell. Noble o villano, se\u00f1or o pechero, t\u00fa, cualquiera que seas, que te detienes un instante al borde de mi sepultura, cree en Dios como yo he cre\u00eddo y ru\u00e9gale por m\u00ed. Nobles aventureros que, puesta la lanza\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/\">Seguir leyendo&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":75,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_226634691_226634691":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_uag_custom_page_level_css":"","footnotes":""},"categories":[5,1109],"tags":[1010,1069,1016,1012,1015,1017,1052,1045,1145,1138,1025,1033],"class_list":["post-1002","post","type-post","status-publish","format-standard","hentry","category-literatura","category-textos-literarios","tag-amor","tag-animal","tag-arte","tag-ave","tag-flor","tag-historia","tag-iglesia","tag-leyenda","tag-libro","tag-patrimonio-2","tag-rosa","tag-vino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa<\/title>\n<meta name=\"description\" content=\"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natureduca.com\/culturblog\/\u201ccreed-en-dios\u201d-gustavo-adolfo-becquer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa\" \/>\n<meta property=\"og:description\" content=\"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natureduca.com\/culturblog\/\u201ccreed-en-dios\u201d-gustavo-adolfo-becquer\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Cultureduca educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/cultureduca\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-10T15:51:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\"},\"headline\":\"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer]\",\"datePublished\":\"2010-12-10T15:51:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\\\/\"},\"wordCount\":3959,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"keywords\":[\"amor\",\"animal\",\"arte\",\"ave\",\"flor\",\"historia\",\"iglesia\",\"leyenda\",\"libro\",\"patrimonio\",\"rosa\",\"vino\"],\"articleSection\":[\"Literatura \\\/ Po\u00e9tica\",\"Textos literarios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\\\/\",\"name\":\"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\"},\"datePublished\":\"2010-12-10T15:51:32+00:00\",\"description\":\"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#website\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"name\":\"Blog Cultureduca\",\"description\":\"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas\",\"publisher\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\"},\"alternateName\":\"Blog Cultura educativa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#organization\",\"name\":\"ASOCAE\",\"alternateName\":\"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"contentUrl\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/wp-content\\\/uploads\\\/cultureduca_ico_cab.png\",\"width\":22,\"height\":24,\"caption\":\"ASOCAE\"},\"image\":{\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/cultureduca\\\/\",\"https:\\\/\\\/x.com\\\/Cultureduca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/#\\\/schema\\\/person\\\/2ede2c4f1845fa2eef27442aa5aa7200\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/natureduca.com\\\/culturblog\\\/author\\\/jefe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa","description":"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natureduca.com\/culturblog\/\u201ccreed-en-dios\u201d-gustavo-adolfo-becquer\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa","og_description":"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -","og_url":"https:\/\/natureduca.com\/culturblog\/\u201ccreed-en-dios\u201d-gustavo-adolfo-becquer\/","og_site_name":"Blog Cultureduca educativa","article_publisher":"https:\/\/www.facebook.com\/groups\/cultureduca\/","article_published_time":"2010-12-10T15:51:32+00:00","og_image":[{"width":1200,"height":120,"url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cropped-cabecera-culturblog.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/#article","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/"},"author":{"name":"Admin","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200"},"headline":"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer]","datePublished":"2010-12-10T15:51:32+00:00","mainEntityOfPage":{"@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/"},"wordCount":3959,"commentCount":0,"publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"keywords":["amor","animal","arte","ave","flor","historia","iglesia","leyenda","libro","patrimonio","rosa","vino"],"articleSection":["Literatura \/ Po\u00e9tica","Textos literarios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/","url":"https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/","name":"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa","isPartOf":{"@id":"https:\/\/natureduca.com\/culturblog\/#website"},"datePublished":"2010-12-10T15:51:32+00:00","description":"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer] - Blog Cultureduca educativa -","breadcrumb":{"@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/natureduca.com\/culturblog\/%e2%80%9ccreed-en-dios%e2%80%9d-gustavo-adolfo-becquer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/natureduca.com\/culturblog\/"},{"@type":"ListItem","position":2,"name":"\u201cCreed en Dios\u201d [Gustavo Adolfo B\u00e9cquer]"}]},{"@type":"WebSite","@id":"https:\/\/natureduca.com\/culturblog\/#website","url":"https:\/\/natureduca.com\/culturblog\/","name":"Blog Cultureduca","description":"Blog educativo de las Letras y las Artes Pl\u00e1sticas y Est\u00e9ticas","publisher":{"@id":"https:\/\/natureduca.com\/culturblog\/#organization"},"alternateName":"Blog Cultura educativa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natureduca.com\/culturblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/natureduca.com\/culturblog\/#organization","name":"ASOCAE","alternateName":"Asociaci\u00f3n para la Cultura, el Arte y la Educaci\u00f3n","url":"https:\/\/natureduca.com\/culturblog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/","url":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","contentUrl":"https:\/\/natureduca.com\/culturblog\/wp-content\/uploads\/cultureduca_ico_cab.png","width":22,"height":24,"caption":"ASOCAE"},"image":{"@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/cultureduca\/","https:\/\/x.com\/Cultureduca"]},{"@type":"Person","@id":"https:\/\/natureduca.com\/culturblog\/#\/schema\/person\/2ede2c4f1845fa2eef27442aa5aa7200","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/808463f89cd51ccc00a865855b3a170f21d55c755eeccab37eef1fb553f48899?s=96&d=monsterid&r=g","caption":"Admin"},"url":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"custom":false,"gb-block-post-grid-landscape":false,"gb-block-post-grid-square":false,"post-thumbnail":false,"header":false,"slider":false,"columns":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/natureduca.com\/culturblog\/author\/jefe\/"},"uagb_comment_info":0,"uagb_excerpt":"(C\u00c1NTIGA PROVENZAL)\u00a0 \u00a0\u00a0\u00a0 Yo fui el verdadero Teobaldo de Montagut, bar\u00f3n de Fortcastell. Noble o villano, se\u00f1or o pechero, t\u00fa, cualquiera que seas, que te detienes un instante al borde de mi sepultura, cree en Dios como yo he cre\u00eddo y ru\u00e9gale por m\u00ed. Nobles aventureros que, puesta la lanza\u2026 Seguir leyendo...","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/1002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/comments?post=1002"}],"version-history":[{"count":0,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/posts\/1002\/revisions"}],"wp:attachment":[{"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/media?parent=1002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/categories?post=1002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/natureduca.com\/culturblog\/wp-json\/wp\/v2\/tags?post=1002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}